{"id":17272,"date":"2022-05-18T11:27:42","date_gmt":"2022-05-18T09:27:42","guid":{"rendered":"https:\/\/comunicacity.net\/oyace\/?p=17272"},"modified":"2022-06-09T11:04:00","modified_gmt":"2022-06-09T09:04:00","slug":"la-commune-a-lecole","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/oyace\/2022\/05\/18\/la-commune-a-lecole\/","title":{"rendered":"La Commune \u00e0 l&#8217;\u00c9cole"},"content":{"rendered":"<p>La classe unica della scuola dell&#8217;infanzia di Oyace dell&#8217;Istituzione scolastica Grand Combin si \u00e8 aggiudicata il primo premio del concorso &#8220;La Commune \u00e0 l&#8217;\u00c9cole&#8221;. Il concorso era suddiviso in due categorie: la prima, rivolta alla scuola dell&#8217;infanzia, per imparare a conoscere e a collaborare con le associazioni che operano nel comune per garantire la nostra sicurezza; la seconda, per la scuola primaria, portava all&#8217;esplorazione del proprio comune per capire come trasformarlo in un paese a misura di bambino.<br \/>\nA consegnare i riconoscimenti, marted\u00ec 17 maggio 2022, con il ritorno di una cerimonia in presenza nella Sala Maria Ida Viglino di Palazzo regionale, sono stati il Presidente e i Vicepresidenti del Consiglio Valle, l&#8217;Assessore regionale all&#8217;istruzione e il Sindaco di Charvensod in rappresentanza del Celva, promotori del concorso nell&#8217;ambito dei &#8220;Rendez-vous citoyens&#8221; ai sensi della legge regionale n. 6\/2006 per incentivare la partecipazione civica sul territorio.<br \/>\nLa classe di Oyace, che \u00e8 andata alla scoperta dei Vigili del fuoco volontari di Oyace e degli Alpini di Bionaz accompagnata dalla mascotte &#8220;la souris Mim\u00ec&#8221;, ha vinto il primo premio della categoria scuola per l&#8217;infanzia con la seguente motivazione: \u00abIl progetto presentato \u00e8 risultato didatticamente capace di sviluppare negli alunni creativit\u00e0 e problem solving. I bambini hanno potuto sperimentare la loro autonomia e dimostrare responsabilit\u00e0 civica, grazie alla ricaduta sul territorio di cui l\u2019attivit\u00e0 \u201cLa panchina della gentilezza\u201d \u00e8 portatrice. Gli alunni e le maestre hanno saputo, infatti, lavorare costruttivamente in collaborazione con il territorio e le istituzioni comunali.\u00bb<\/p>\n<p><strong><a href=\"https:\/\/youtu.be\/a9FIdWmEjQM\">Clicca qui per vedere il video del lavoro vincitore del concorso&#8230;<\/a><\/strong><\/p>\n<p><a href=\"https:\/\/www.comune.oyace.ao.it\/wp-content\/uploads\/2022\/05\/GruppoTutteClassi-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-17968\" src=\"https:\/\/www.comune.oyace.ao.it\/wp-content\/uploads\/2022\/05\/GruppoTutteClassi-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a> <a href=\"https:\/\/www.comune.oyace.ao.it\/wp-content\/uploads\/2022\/05\/infanziaPrimoPremio_Oyace_03-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-17967\" src=\"https:\/\/www.comune.oyace.ao.it\/wp-content\/uploads\/2022\/05\/infanziaPrimoPremio_Oyace_03-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.comune.oyace.ao.it\/wp-content\/uploads\/2022\/05\/infanziaPrimoPremio_Oyace_02-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-17966\" src=\"https:\/\/www.comune.oyace.ao.it\/wp-content\/uploads\/2022\/05\/infanziaPrimoPremio_Oyace_02-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a> <a href=\"https:\/\/www.comune.oyace.ao.it\/wp-content\/uploads\/2022\/05\/infanziaPrimoPremio_Oyace_01-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-17965\" src=\"https:\/\/www.comune.oyace.ao.it\/wp-content\/uploads\/2022\/05\/infanziaPrimoPremio_Oyace_01-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.comune.oyace.ao.it\/wp-content\/uploads\/2022\/06\/IMG-20220608-WA0001.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-18089\" src=\"https:\/\/www.comune.oyace.ao.it\/wp-content\/uploads\/2022\/06\/IMG-20220608-WA0001-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a> <a href=\"https:\/\/www.comune.oyace.ao.it\/wp-content\/uploads\/2022\/06\/IMG-20220607-WA0076.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-18092\" src=\"https:\/\/www.comune.oyace.ao.it\/wp-content\/uploads\/2022\/06\/IMG-20220607-WA0076-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.comune.oyace.ao.it\/wp-content\/uploads\/2022\/06\/IMG-20220608-WA0002-e1654701055686.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-18101\" src=\"https:\/\/www.comune.oyace.ao.it\/wp-content\/uploads\/2022\/06\/IMG-20220608-WA0002-e1654701055686-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a> <a href=\"https:\/\/www.comune.oyace.ao.it\/wp-content\/uploads\/2022\/06\/IMG-20220608-WA0000-e1654701074485.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-18100\" src=\"https:\/\/www.comune.oyace.ao.it\/wp-content\/uploads\/2022\/06\/IMG-20220608-WA0000-e1654701074485-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_17516\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2022\/06\/GruppoTutteClassi-convertito-compresso-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2022\/06\/GruppoTutteClassi-convertito-compresso-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>GruppoTutteClassi-convertito-compresso (1)<\/a><\/li>\n<li><a id=\"wpba_attachment_list_17517\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2022\/06\/infanziaPrimoPremio_Oyace_03.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2022\/06\/infanziaPrimoPremio_Oyace_03.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>infanziaPrimoPremio_Oyace_03<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La classe unica della scuola dell&#8217;infanzia di Oyace dell&#8217;Istituzione scolastica Grand Combin si \u00e8 aggiudicata il primo premio del concorso &#8220;La Commune \u00e0 l&#8217;\u00c9cole&#8221;. Il concorso era suddiviso in due [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17522,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-17272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Commune \u00e0 l&#039;\u00c9cole - Oyace<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/oyace\/2022\/05\/18\/la-commune-a-lecole\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Commune \u00e0 l&#039;\u00c9cole - Oyace\" \/>\n<meta property=\"og:description\" content=\"La classe unica della scuola dell&#8217;infanzia di Oyace dell&#8217;Istituzione scolastica Grand Combin si \u00e8 aggiudicata il primo premio del concorso &#8220;La Commune \u00e0 l&#8217;\u00c9cole&#8221;. Il concorso era suddiviso in due [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/oyace\/2022\/05\/18\/la-commune-a-lecole\/\" \/>\n<meta property=\"og:site_name\" content=\"Oyace\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-18T09:27:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-09T09:04:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2022\/05\/infanziaPrimoPremio_Oyace_03-scaled-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1709\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2022\\\/05\\\/18\\\/la-commune-a-lecole\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2022\\\/05\\\/18\\\/la-commune-a-lecole\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"La Commune \u00e0 l&#8217;\u00c9cole\",\"datePublished\":\"2022-05-18T09:27:42+00:00\",\"dateModified\":\"2022-06-09T09:04:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2022\\\/05\\\/18\\\/la-commune-a-lecole\\\/\"},\"wordCount\":255,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2022\\\/05\\\/18\\\/la-commune-a-lecole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2022\\\/06\\\/infanziaPrimoPremio_Oyace_03-scaled-3.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2022\\\/05\\\/18\\\/la-commune-a-lecole\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2022\\\/05\\\/18\\\/la-commune-a-lecole\\\/\",\"name\":\"La Commune \u00e0 l'\u00c9cole - Oyace\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2022\\\/05\\\/18\\\/la-commune-a-lecole\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2022\\\/05\\\/18\\\/la-commune-a-lecole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2022\\\/06\\\/infanziaPrimoPremio_Oyace_03-scaled-3.jpg\",\"datePublished\":\"2022-05-18T09:27:42+00:00\",\"dateModified\":\"2022-06-09T09:04:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2022\\\/05\\\/18\\\/la-commune-a-lecole\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2022\\\/05\\\/18\\\/la-commune-a-lecole\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2022\\\/05\\\/18\\\/la-commune-a-lecole\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2022\\\/06\\\/infanziaPrimoPremio_Oyace_03-scaled-3.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2022\\\/06\\\/infanziaPrimoPremio_Oyace_03-scaled-3.jpg\",\"width\":2560,\"height\":1709},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2022\\\/05\\\/18\\\/la-commune-a-lecole\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Commune \u00e0 l&#8217;\u00c9cole\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/\",\"name\":\"ComunicaCity\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Commune \u00e0 l'\u00c9cole - Oyace","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/oyace\/2022\/05\/18\/la-commune-a-lecole\/","og_locale":"it_IT","og_type":"article","og_title":"La Commune \u00e0 l'\u00c9cole - Oyace","og_description":"La classe unica della scuola dell&#8217;infanzia di Oyace dell&#8217;Istituzione scolastica Grand Combin si \u00e8 aggiudicata il primo premio del concorso &#8220;La Commune \u00e0 l&#8217;\u00c9cole&#8221;. Il concorso era suddiviso in due [&hellip;]","og_url":"https:\/\/comunicacity.net\/oyace\/2022\/05\/18\/la-commune-a-lecole\/","og_site_name":"Oyace","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-05-18T09:27:42+00:00","article_modified_time":"2022-06-09T09:04:00+00:00","og_image":[{"width":2560,"height":1709,"url":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2022\/05\/infanziaPrimoPremio_Oyace_03-scaled-3.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/oyace\/2022\/05\/18\/la-commune-a-lecole\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/oyace\/2022\/05\/18\/la-commune-a-lecole\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"La Commune \u00e0 l&#8217;\u00c9cole","datePublished":"2022-05-18T09:27:42+00:00","dateModified":"2022-06-09T09:04:00+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/oyace\/2022\/05\/18\/la-commune-a-lecole\/"},"wordCount":255,"publisher":{"@id":"https:\/\/comunicacity.net\/oyace\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/oyace\/2022\/05\/18\/la-commune-a-lecole\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2022\/06\/infanziaPrimoPremio_Oyace_03-scaled-3.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/oyace\/2022\/05\/18\/la-commune-a-lecole\/","url":"https:\/\/comunicacity.net\/oyace\/2022\/05\/18\/la-commune-a-lecole\/","name":"La Commune \u00e0 l'\u00c9cole - Oyace","isPartOf":{"@id":"https:\/\/comunicacity.net\/oyace\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/oyace\/2022\/05\/18\/la-commune-a-lecole\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/oyace\/2022\/05\/18\/la-commune-a-lecole\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2022\/06\/infanziaPrimoPremio_Oyace_03-scaled-3.jpg","datePublished":"2022-05-18T09:27:42+00:00","dateModified":"2022-06-09T09:04:00+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/oyace\/2022\/05\/18\/la-commune-a-lecole\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/oyace\/2022\/05\/18\/la-commune-a-lecole\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/oyace\/2022\/05\/18\/la-commune-a-lecole\/#primaryimage","url":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2022\/06\/infanziaPrimoPremio_Oyace_03-scaled-3.jpg","contentUrl":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2022\/06\/infanziaPrimoPremio_Oyace_03-scaled-3.jpg","width":2560,"height":1709},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/oyace\/2022\/05\/18\/la-commune-a-lecole\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/oyace\/"},{"@type":"ListItem","position":2,"name":"La Commune \u00e0 l&#8217;\u00c9cole"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/oyace\/#website","url":"https:\/\/comunicacity.net\/oyace\/","name":"ComunicaCity","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/oyace\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/oyace\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/oyace\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/oyace\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"]}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"17975"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts\/17272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/comments?post=17272"}],"version-history":[{"count":4,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts\/17272\/revisions"}],"predecessor-version":[{"id":17514,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts\/17272\/revisions\/17514"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/media\/17522"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/media?parent=17272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/categories?post=17272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/tags?post=17272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}