{"id":17370,"date":"2022-05-24T17:32:25","date_gmt":"2022-05-24T15:32:25","guid":{"rendered":"https:\/\/comunicacity.net\/oyace\/2022\/05\/24\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\/"},"modified":"2022-05-24T17:50:47","modified_gmt":"2022-05-24T15:50:47","slug":"la-fiera-di-santorso-2022-vista-con-i-miei-occhi","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/oyace\/2022\/05\/24\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\/","title":{"rendered":"La Fiera di Sant&#8217;Orso 2022 vista con i miei occhi"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-18022 size-full\" src=\"https:\/\/www.comune.oyace.ao.it\/wp-content\/uploads\/2022\/05\/evento-21-maggio_page-0001-2.jpg\" alt=\"\" width=\"1716\" height=\"344\" \/><\/p>\n<p>L\u2019Amministrazione comunale e la Commissione cultura della Biblioteca comunale \u201cAim\u00e9 Chenal\u201d hanno organizzato per il giorno 21 maggio 2022, alle ore 15.00, presso il Salone comunale \u201cLinda Gorret\u201d un incontro con tutti i partecipanti all\u2019iniziativa \u201cLa Fiera di Sant\u2019Orso 2022 vista con i miei occhi\u201d che hanno avuto l\u2019opportunit\u00e0 di presentare il proprio disegno e ritirare l\u2019omaggio destinato ai partecipanti all\u2019 iniziativa.<\/p>\n<p>L\u2019evento si \u00e8 tenuto alla presenza del Sindaco Stefania Clos, del Vice Sindaco Leone Landry, dell\u2019Assessore all\u2019Istruzione, cultura e Politiche sociali Gilberto Chenal e del Presidente della Commissione cultura Gianna Lisitano. Hanno inoltre partecipato i realizzatori delle sculture nell\u2019ambito del progetto \u201cChez Nous\u201d edizione 2021, Maurizio Bombino, Fernando Di Mauro, Marcel Di\u00e9moz, Fausto Linty e Dante Marquet.<\/p>\n<p>Grandi e piccoli hanno avuto l\u2019opportunit\u00e0 di presentare il proprio disegno, di illustrare tecniche e caratteristiche proprie, e di ritirare un piccolo omaggio.<\/p>\n<p>L\u2019occasione \u00e8 stata gradita per la presentazione dell\u2019opera in legno donata all\u2019Amministrazione comunale da Marcel Di\u00e9moz, sculture e grande amico di Oyace, nella quale saranno incisi ogni anno i nomi dei vincitori del concorso letterario \u201cPerch\u00e9 non TI racconti?\u201d, lanciato nel 2021 con la collaborazione della Commissione cultura della Biblioteca comunale \u201cAim\u00e9 Chenal\u201d e della Libreria Brivio di Aosta. Con grande onore era presente Camilla Pozzi, vincitrice ex equo con Benedetta D\u2019Alessandro, dell\u2019edizione 2021 del concorso.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_17445\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2022\/05\/IMG-20220521-WA0013.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2022\/05\/IMG-20220521-WA0013.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>IMG-20220521-WA0013<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Amministrazione comunale e la Commissione cultura della Biblioteca comunale \u201cAim\u00e9 Chenal\u201d hanno organizzato per il giorno 21 maggio 2022, alle ore 15.00, presso il Salone comunale \u201cLinda Gorret\u201d un incontro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17439,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-17370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Fiera di Sant&#039;Orso 2022 vista con i miei occhi - Oyace<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/oyace\/2022\/05\/24\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Fiera di Sant&#039;Orso 2022 vista con i miei occhi - Oyace\" \/>\n<meta property=\"og:description\" content=\"L\u2019Amministrazione comunale e la Commissione cultura della Biblioteca comunale \u201cAim\u00e9 Chenal\u201d hanno organizzato per il giorno 21 maggio 2022, alle ore 15.00, presso il Salone comunale \u201cLinda Gorret\u201d un incontro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/oyace\/2022\/05\/24\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\/\" \/>\n<meta property=\"og:site_name\" content=\"Oyace\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-24T15:32:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-24T15:50:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2022\/05\/IMG-20220521-WA0017-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2022\\\/05\\\/24\\\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2022\\\/05\\\/24\\\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"La Fiera di Sant&#8217;Orso 2022 vista con i miei occhi\",\"datePublished\":\"2022-05-24T15:32:25+00:00\",\"dateModified\":\"2022-05-24T15:50:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2022\\\/05\\\/24\\\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\\\/\"},\"wordCount\":235,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2022\\\/05\\\/24\\\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2022\\\/05\\\/IMG-20220521-WA0017-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2022\\\/05\\\/24\\\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2022\\\/05\\\/24\\\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\\\/\",\"name\":\"La Fiera di Sant'Orso 2022 vista con i miei occhi - Oyace\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2022\\\/05\\\/24\\\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2022\\\/05\\\/24\\\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2022\\\/05\\\/IMG-20220521-WA0017-1.jpg\",\"datePublished\":\"2022-05-24T15:32:25+00:00\",\"dateModified\":\"2022-05-24T15:50:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2022\\\/05\\\/24\\\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2022\\\/05\\\/24\\\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2022\\\/05\\\/24\\\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2022\\\/05\\\/IMG-20220521-WA0017-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2022\\\/05\\\/IMG-20220521-WA0017-1.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2022\\\/05\\\/24\\\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Fiera di Sant&#8217;Orso 2022 vista con i miei occhi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/\",\"name\":\"ComunicaCity\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Fiera di Sant'Orso 2022 vista con i miei occhi - Oyace","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/oyace\/2022\/05\/24\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\/","og_locale":"it_IT","og_type":"article","og_title":"La Fiera di Sant'Orso 2022 vista con i miei occhi - Oyace","og_description":"L\u2019Amministrazione comunale e la Commissione cultura della Biblioteca comunale \u201cAim\u00e9 Chenal\u201d hanno organizzato per il giorno 21 maggio 2022, alle ore 15.00, presso il Salone comunale \u201cLinda Gorret\u201d un incontro [&hellip;]","og_url":"https:\/\/comunicacity.net\/oyace\/2022\/05\/24\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\/","og_site_name":"Oyace","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-05-24T15:32:25+00:00","article_modified_time":"2022-05-24T15:50:47+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2022\/05\/IMG-20220521-WA0017-1.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/oyace\/2022\/05\/24\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/oyace\/2022\/05\/24\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"La Fiera di Sant&#8217;Orso 2022 vista con i miei occhi","datePublished":"2022-05-24T15:32:25+00:00","dateModified":"2022-05-24T15:50:47+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/oyace\/2022\/05\/24\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\/"},"wordCount":235,"publisher":{"@id":"https:\/\/comunicacity.net\/oyace\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/oyace\/2022\/05\/24\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2022\/05\/IMG-20220521-WA0017-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/oyace\/2022\/05\/24\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\/","url":"https:\/\/comunicacity.net\/oyace\/2022\/05\/24\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\/","name":"La Fiera di Sant'Orso 2022 vista con i miei occhi - Oyace","isPartOf":{"@id":"https:\/\/comunicacity.net\/oyace\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/oyace\/2022\/05\/24\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/oyace\/2022\/05\/24\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2022\/05\/IMG-20220521-WA0017-1.jpg","datePublished":"2022-05-24T15:32:25+00:00","dateModified":"2022-05-24T15:50:47+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/oyace\/2022\/05\/24\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/oyace\/2022\/05\/24\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/oyace\/2022\/05\/24\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\/#primaryimage","url":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2022\/05\/IMG-20220521-WA0017-1.jpg","contentUrl":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2022\/05\/IMG-20220521-WA0017-1.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/oyace\/2022\/05\/24\/la-fiera-di-santorso-2022-vista-con-i-miei-occhi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/oyace\/"},{"@type":"ListItem","position":2,"name":"La Fiera di Sant&#8217;Orso 2022 vista con i miei occhi"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/oyace\/#website","url":"https:\/\/comunicacity.net\/oyace\/","name":"ComunicaCity","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/oyace\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/oyace\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/oyace\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/oyace\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"]}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"18008"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts\/17370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/comments?post=17370"}],"version-history":[{"count":4,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts\/17370\/revisions"}],"predecessor-version":[{"id":17432,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts\/17370\/revisions\/17432"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/media\/17439"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/media?parent=17370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/categories?post=17370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/tags?post=17370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}