{"id":18803,"date":"2024-08-09T10:21:02","date_gmt":"2024-08-09T08:21:02","guid":{"rendered":"https:\/\/comunicacity.net\/oyace\/2024\/08\/08\/incontriamo-lautore-davanti-a-un-caffe\/"},"modified":"2024-08-09T10:21:02","modified_gmt":"2024-08-09T08:21:02","slug":"incontriamo-lautore-davanti-a-un-caffe","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/oyace\/2024\/08\/09\/incontriamo-lautore-davanti-a-un-caffe\/","title":{"rendered":"&#8220;Incontriamo l&#8217;autore davanti a un caff\u00e8&#8221;"},"content":{"rendered":"<p><em>Sala consigliare del comune di Oyace &#8211; Sabato 17 agosto 2024 ore 17:30<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Per il ciclo &#8220;<strong>Incontriamo l&#8217;autore davanti a un caff\u00e8<\/strong>&#8221; l&#8217;Amministrazione comunale, in collaborazione con la Pro loco, vi invita presso la sala consigliare del Comune di Oyace &#8211; <strong>sabato 17 agosto 2024 ore 17:30<\/strong> &#8211; a conoscere una storia di famiglia sotto forma di romanzo; un viaggio dall&#8217;ombra di Brissogne al sole di Caltanissetta alla fine dell&#8217;ottocento. Il tutto alla presenza dell&#8217;autore <strong>Ronny Borbey<\/strong>.<\/p>\n<p>Seguir\u00e0 un aperitivo offerto dalla Pro loco<\/p>\n<p>Prenotarsi tramite WhatsApp o sms al n\u00b0 <strong>3460094218<\/strong> indicando un nominativo e il numero dei partecipanti.&nbsp;<\/p>\n<p><b>Immagini<\/b><\/p>\n<p><img src='https:\/\/www.comune.oyace.ao.it\/wp-content\/uploads\/2024\/08\/1000057377.jpg'><\/img><\/p>\n<p>\n\t\t\t<h4>Inizio<\/h4>\n<p>17\/08\/2024 17:30<\/p>\n\t\t\t\n\t\t\t\t\t\t<h4>Fine<\/h4>\n<p>09\/08\/2024 08:21<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\t\t\t<h4>Indirizzo<\/h4>\n\t\t\t<p>Fraz. La Cretaz, 1\t\t\t\t\t\t\t<iframe \n                                    style=\"max-width: 100%;\"\n\t\t\t\twidth=\"500\" \n\t\t\t\theight=\"200\" \n\t\t\t\tframeborder=\"0\" \n\t\t\t\tscrolling=\"no\" \n\t\t\t\tmarginheight=\"0\" \n\t\t\t\tmarginwidth=\"0\" \n\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=42.6384261,12.674297&z=14&amp;output=embed\"\n\t\t\t >\n\t\t\t\t<\/iframe><\/p>\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Sala consigliare del comune di Oyace &#8211; Sabato 17 agosto 2024 ore 17:30&nbsp; Descrizione&nbsp; Per il ciclo &#8220;Incontriamo l&#8217;autore davanti a un caff\u00e8&#8221; l&#8217;Amministrazione comunale, in collaborazione con la Pro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18822,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-18803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Incontriamo l&#039;autore davanti a un caff\u00e8&quot; - Oyace<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/oyace\/2024\/08\/09\/incontriamo-lautore-davanti-a-un-caffe\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Incontriamo l&#039;autore davanti a un caff\u00e8&quot; - Oyace\" \/>\n<meta property=\"og:description\" content=\"Sala consigliare del comune di Oyace &#8211; Sabato 17 agosto 2024 ore 17:30&nbsp; Descrizione&nbsp; Per il ciclo &#8220;Incontriamo l&#8217;autore davanti a un caff\u00e8&#8221; l&#8217;Amministrazione comunale, in collaborazione con la Pro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/oyace\/2024\/08\/09\/incontriamo-lautore-davanti-a-un-caffe\/\" \/>\n<meta property=\"og:site_name\" content=\"Oyace\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-09T08:21:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2024\/08\/1000057377-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1079\" \/>\n\t<meta property=\"og:image:height\" content=\"1102\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2024\\\/08\\\/09\\\/incontriamo-lautore-davanti-a-un-caffe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2024\\\/08\\\/09\\\/incontriamo-lautore-davanti-a-un-caffe\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"&#8220;Incontriamo l&#8217;autore davanti a un caff\u00e8&#8221;\",\"datePublished\":\"2024-08-09T08:21:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2024\\\/08\\\/09\\\/incontriamo-lautore-davanti-a-un-caffe\\\/\"},\"wordCount\":104,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2024\\\/08\\\/09\\\/incontriamo-lautore-davanti-a-un-caffe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2024\\\/08\\\/1000057377-1.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2024\\\/08\\\/09\\\/incontriamo-lautore-davanti-a-un-caffe\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2024\\\/08\\\/09\\\/incontriamo-lautore-davanti-a-un-caffe\\\/\",\"name\":\"\\\"Incontriamo l'autore davanti a un caff\u00e8\\\" - Oyace\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2024\\\/08\\\/09\\\/incontriamo-lautore-davanti-a-un-caffe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2024\\\/08\\\/09\\\/incontriamo-lautore-davanti-a-un-caffe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2024\\\/08\\\/1000057377-1.jpg\",\"datePublished\":\"2024-08-09T08:21:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2024\\\/08\\\/09\\\/incontriamo-lautore-davanti-a-un-caffe\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2024\\\/08\\\/09\\\/incontriamo-lautore-davanti-a-un-caffe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2024\\\/08\\\/09\\\/incontriamo-lautore-davanti-a-un-caffe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2024\\\/08\\\/1000057377-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2024\\\/08\\\/1000057377-1.jpg\",\"width\":1079,\"height\":1102},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2024\\\/08\\\/09\\\/incontriamo-lautore-davanti-a-un-caffe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Incontriamo l&#8217;autore davanti a un caff\u00e8&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/\",\"name\":\"ComunicaCity\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Incontriamo l'autore davanti a un caff\u00e8\" - Oyace","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/oyace\/2024\/08\/09\/incontriamo-lautore-davanti-a-un-caffe\/","og_locale":"it_IT","og_type":"article","og_title":"\"Incontriamo l'autore davanti a un caff\u00e8\" - Oyace","og_description":"Sala consigliare del comune di Oyace &#8211; Sabato 17 agosto 2024 ore 17:30&nbsp; Descrizione&nbsp; Per il ciclo &#8220;Incontriamo l&#8217;autore davanti a un caff\u00e8&#8221; l&#8217;Amministrazione comunale, in collaborazione con la Pro [&hellip;]","og_url":"https:\/\/comunicacity.net\/oyace\/2024\/08\/09\/incontriamo-lautore-davanti-a-un-caffe\/","og_site_name":"Oyace","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-08-09T08:21:02+00:00","og_image":[{"width":1079,"height":1102,"url":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2024\/08\/1000057377-1.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/oyace\/2024\/08\/09\/incontriamo-lautore-davanti-a-un-caffe\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/oyace\/2024\/08\/09\/incontriamo-lautore-davanti-a-un-caffe\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"&#8220;Incontriamo l&#8217;autore davanti a un caff\u00e8&#8221;","datePublished":"2024-08-09T08:21:02+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/oyace\/2024\/08\/09\/incontriamo-lautore-davanti-a-un-caffe\/"},"wordCount":104,"publisher":{"@id":"https:\/\/comunicacity.net\/oyace\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/oyace\/2024\/08\/09\/incontriamo-lautore-davanti-a-un-caffe\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2024\/08\/1000057377-1.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/oyace\/2024\/08\/09\/incontriamo-lautore-davanti-a-un-caffe\/","url":"https:\/\/comunicacity.net\/oyace\/2024\/08\/09\/incontriamo-lautore-davanti-a-un-caffe\/","name":"\"Incontriamo l'autore davanti a un caff\u00e8\" - Oyace","isPartOf":{"@id":"https:\/\/comunicacity.net\/oyace\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/oyace\/2024\/08\/09\/incontriamo-lautore-davanti-a-un-caffe\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/oyace\/2024\/08\/09\/incontriamo-lautore-davanti-a-un-caffe\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2024\/08\/1000057377-1.jpg","datePublished":"2024-08-09T08:21:02+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/oyace\/2024\/08\/09\/incontriamo-lautore-davanti-a-un-caffe\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/oyace\/2024\/08\/09\/incontriamo-lautore-davanti-a-un-caffe\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/oyace\/2024\/08\/09\/incontriamo-lautore-davanti-a-un-caffe\/#primaryimage","url":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2024\/08\/1000057377-1.jpg","contentUrl":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2024\/08\/1000057377-1.jpg","width":1079,"height":1102},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/oyace\/2024\/08\/09\/incontriamo-lautore-davanti-a-un-caffe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/oyace\/"},{"@type":"ListItem","position":2,"name":"&#8220;Incontriamo l&#8217;autore davanti a un caff\u00e8&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/oyace\/#website","url":"https:\/\/comunicacity.net\/oyace\/","name":"ComunicaCity","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/oyace\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/oyace\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/oyace\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/oyace\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"]}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"17\/08\/2024 17:30","cc4_eve_data_fine":"09\/08\/2024 08:21","cc4_eve_indirizzo":"Fraz. La Cretaz, 1","cc4_eve_posizione":{"latitude":"42.6384261","longitude":"12.674297","zoom":"14"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002380"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts\/18803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/comments?post=18803"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts\/18803\/revisions"}],"predecessor-version":[{"id":18813,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts\/18803\/revisions\/18813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/media\/18822"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/media?parent=18803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/categories?post=18803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/tags?post=18803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}