{"id":19463,"date":"2025-11-07T17:53:21","date_gmt":"2025-11-07T16:53:21","guid":{"rendered":"https:\/\/comunicacity.net\/oyace\/2025\/08\/05\/chez-nous-2025-3\/"},"modified":"2025-11-07T17:53:21","modified_gmt":"2025-11-07T16:53:21","slug":"chez-nous-2025-3","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/oyace\/2025\/11\/07\/chez-nous-2025-3\/","title":{"rendered":"Chez Nous 2025"},"content":{"rendered":"<p style='margin-bottom: 11px;padding-bottom: 0px'><b style='font-size: 16px;color: #333'>Dal 08 Agosto 2025<\/b> <b style='font-size: 16px;color: #333'>al 12 Agosto 2025<\/b><\/p>\n<p><em>Dall\u20198 al 12 agosto, Oyace accoglie la creativit\u00e0 dell&#8217;artigianato di tradizione con il progetto \u201cChez nous\u201d.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>L\u2019Amministrazione comunale ha lanciato, nel 2021, un progetto di valorizzazione del suo territorio.<\/p>\n<p>Questo progetto \u00e8 denominato <strong>OyaceInArt<\/strong>.<\/p>\n<p>Restituire la memoria di un luogo a chi lo abita cos\u00ec come a chi lo frequenta occasionalmente \u00e8 un&#8217;operazione di alto valore sociale, di identit\u00e0 collettiva e di prospettiva culturale.<\/p>\n<p>Ben lo sa il Comune di Oyace che ha fortemente voluto recuperare uno dei simboli del paese, la Tornalla, unitamente al sentiero attiguo, oggetto di uno specifico importante intervento di bonifica (vedasi nel sito \u201cLA TORNALLA DI OYACE E IL CASTRUM AYACY DEL 1187\u201d &#8211; Analisi archeologico &#8211; architettonica di una torre ottagonale di Mauro CORTELAZZO e Renato PERINETTI del 23 marzo 2015).<\/p>\n<p>Nel solco della valorizzazione del territorio e del suo passato, si inserisce il progetto &#8220;Chez nous&#8221;, organizzato dall&#8217;Amministrazione comunale in sinergia con il Consiglio regionale della Valle d&#8217;Aosta, arrivato oggi alla sua terza edizione.<\/p>\n<p>Protagonista dell&#8217;iniziativa \u00e8 stato l&#8217;artigianato di tradizione:<br \/>\nNel 2021 sono stati cinque gli artigiani che hanno realizzato le prime sei sculture del progetto: Maurizio Bombino, Marcel Diemoz, Salvatore Fernando Di Mauro, Fausto Linty e Dante Marquet. Gli artigiani sono stati al lavoro per sei giorni nella Struttura polivalente del Capoluogo di Oyace. Le opere realizzate dovevano inizialmente essere spostate sul sentiero sterrato che porta alla Tornalla, proprio nei pressi della Torre.<\/p>\n<p>Una volta terminate, per\u00f2, considerata la dimensione e l\u2019entusiasmo degli abitanti di Oyace, l\u2019Amministrazione ha ritenuto di posizionarle nel Capoluogo del paese, considerato che lo stesso si inserisce nell\u2019itinerario circolare che, attorno al capoluogo di Oyace, permette la visita della Tornalla e dell&#8217;orrido di B\u00e9tenda, in un tipico ambiente di media montagna valdostana (vedasi nel sito \u201cItinerario \u2013 Tour Tornalla\u201d).<\/p>\n<p>Rupi rocciose e aride, dove prospera il pino silvestre a contatto con abete e frassino, a proprio agio sui fianchi del profondo ed ombreggiato orrido. Uno scenario imperdibile, che nel 2022 si \u00e8 arricchito di altre 6 sculture. Dal 9 al 15 agosto 2022 i cinque artigiani sopramenzionati (Maurizio Bombino, Marcel Diemoz, Salvatore Fernando Di Mauro, Fausto Linty e Dante Marquet) sono tornati ad Oyace e hanno realizzato dal vivo 10 sculture che oggi impreziosiscono il parco giochi \u201cLe Ch\u00e2teau\u201d e il percorso che porta alla Tornalla.<\/p>\n<p>Nel 2023, dal 9 al 14 agosto, quattro artigiani, Marcel Diemoz, Salvatore Fernando Di Mauro, Fausto Linty e Dante Marquet, sono tornati ad Oyace per scolpire dal vivo delle opere che le abili mani dell\u2019artigiano Aldo Motovert hanno trasformato in panchine. Queste panchine le potete ammirare in cinque nicchie che in passato ospitavano i bidoni per la raccolta dei rifiuti nelle frazioni di Pied de Ville, Le Voisinal, Vernosse, Grenier e Le Sergnou.<\/p>\n<p>Oggi, queste nicchie, hanno ripreso vita. Una vita nuova e impreziosita dagli elementi caratterizzanti il nostro territorio, che la creativit\u00e0 di Anastasia Snergireva ha fissato in tre murales, da lei realizzati nelle nicchie prive di pietra a vista.<\/p>\n<p>E non \u00e8 finita. Nel corso dell\u2019anno 2023, con la conclusione dei primi mesi del 2024, il Comune ha realizzato anche un\u2019opera di riqualificazione e l\u2019ammodernamento del Ponte della Betenda e dei percorsi di accesso, grazie al contributo GAL riconosciuto nell\u2019ambito del bando relativo alla sottomisura 7.6, per il restauro del Ponte monumentale della Betenda.<\/p>\n<p>Come gi\u00e0 ricordato, il ponte fa parte di un polo di attrazione turistica basato su un\u2019area di interesse culturale pi\u00f9 ampia, che comprende anche la Torre della Tornalla. Il progetto mira a rafforzare e ampliare l\u2019attuale offerta culturale centrata sulla Torre della Tornalla, creando un\u2019area archeologica ricca e diversificata anche dal punto di vista paesaggistico e naturale. In quanto elemento centrale di alcune leggende locali, il ponte si presta poi all\u2019organizzazione di ricostruzioni storiche e teatralizzazioni per animare le visite turistiche nel sito.<\/p>\n<p>Inoltre, il Ponte della Betenda rappresenta un passaggio obbligato del \u201cTor des G\u00e9ants\u201d, che resta impresso nella memoria dei partecipanti per la sua particolarit\u00e0 paesaggistica. Il ponte ha necessitato quindi di un restauro anche al fine di rendere la sua percorrenza pi\u00f9 sicura possibile in tutti i contesti di utilizzo. Cosa mancava ancora?<\/p>\n<p>Non si poteva non impreziosire questo importante monumento con delle opere. Dal 9 al 12 agosto, quattro artigiani, Maurizio Bombino, Marcel Diemoz, Fausto Linty e Dante Marquet, sono tornati ad Oyace e hanno realizzato 9 nuove opere.<\/p>\n<p>Mentre due opere sono state realizzate su tronchi le cui radici sono ancorate al terreno nei pressi della Tornalla, un\u2019opera \u00e8 stata trasformata dall\u2019abile Aldo Montovert in una panchina nei pressi del Ponte della Betenda. Ma non bastava\u2026 e cos\u00ec, il visitatore viene accolto da altre 4 opere che oggi rendono ancora pi\u00f9 suggestivo il nostro ponte.<\/p>\n<p>E per invogliare gli avventori alla scoperta di Oyace, \u00e8 stato realizzato, nella scala adiacente il municipio, un murales che invita alla scoperta di tutte le opere e dei punti pi\u00f9 significativi del paese. Quest\u2019opera, posizionata sul tradizionale percorso dell\u2019Alta via n. 1 \u00e8 stata arricchita con una scultura, a forma di zaino, che omaggi il passaggio dei \u201cgiganti\u201d a Oyace.<\/p>\n<p>Ma attenzione. Una di queste opere non la troverete a Oyace ma in Alta Savoia, nel comune di La Forclaz, che da fine 2023 \u00e8 gemellaggio con il comune di Oyace. L\u2019opera, simbolo del gemellaggio, omaggia il sentimento che unisce le due popolazioni: l\u2019amicizia.<\/p>\n<p>Nel 2024 l\u2019Amministrazione ha completamente rinnovato il salone comunale \u201cLinda Gorret\u201d, luogo che spesso ospita eventi. All\u2019interno del salone \u00e8 possibile visitare la mostra permanente \u201cBenvenuti ad Oyace, ieri e oggi\u201d.<\/p>\n<p>Pertanto, nel 2025, \u00e8 stato intendimento dell\u2019Amministrazione chiudere il percorso del Tour Tornalla andando a valorizzare proprio l\u2019edificio comunale in un\u2019ottica di accoglienza.<\/p>\n<p>In continuit\u00e0 con le edizioni del 2021, del 2022, del 2023 e del 2024, le opere realizzate sono ispirate al contesto locale e alla storia del paese, raccontata nelle opere e nelle leggende che lo caratterizzano.<\/p>\n<p>In relazione alle leggende \u00e8 importante evidenziare che il progetto ha previsto la realizzazione di un murales che ritrae la leggenda vincitrice del concorso letterario promosso dall\u2019Amministrazione comunale, in collaborazione con la Commissione cultura della Biblioteca comunale \u201cAim\u00e9 Chenal\u201d dal titolo \u201cInventa una leggenda\u201d.<\/p>\n<p>Gli artigiani, invece, hanno realizzato due panchine e due poltrone artistiche in cui l\u2019avventore si potr\u00e0 immergere in Oyace. Alle spalle di queste due poltrone \u00e8 stato riprodotto sul muro il paesaggio che caratterizza Oyace.<\/p>\n<p>Non vi resta che scoprirle\u2026<\/p>\n<p style='font-size: 16px;color: #2E3A46'><b>A chi \u00e8 rivolto:<\/b><\/p>\n<p><span style='font-size: 16px;color: #555'>A tutti<\/span><\/p>\n<p style='font-size: 16px;color: #2E3A46'><b>Costi:<\/b><\/p>\n<ul style='list-style-type: disc;padding-left: 20px;margin-top: 0px!important'>\n<li style='margin-bottom: 3px'><span style='font-size: 16px'>Gratuito: <\/span><\/li>\n<\/ul>\n<p><\/p>\n<p style='font-size: 16px;color: #2E3A46'><b>Contatti:<\/b><\/p>\n<ul style='list-style-type: disc;padding-left: 20px;margin-top: 0px!important'>\n<li style='margin-bottom: 5px'><span>Comune di Oyace<\/span><\/li>\n<p><span style='font-size: 15px'><b>Telefono<\/b>: 0165730013<\/span><br \/><span style='font-size: 15px'><b>Email<\/b>: info@comune.oyace.ao.it<\/span><br \/><span style='font-size: 15px'><b>PEC<\/b>: protocollo@pec.comune.oyace.ao.it<\/span><br \/><span style='font-size: 15px'><b>Indirizzo<\/b>: Fraz. La Cretaz, 1<\/span><br \/><span style='font-size: 15px'><b>Email<\/b>: info@comune.oyace.ao.it<\/span><\/ul>\n\t\t\t<h4>Inizio<\/h4>\n<p>08\/08\/2025 00:00<\/p>\n\t\t\t\n\t\t\t\t\t\t<h4>Fine<\/h4>\n<p>12\/08\/2025 00:00<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_19701\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/11\/MOMENTI-UFFICIALI-E-NON.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/11\/MOMENTI-UFFICIALI-E-NON.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>MOMENTI UFFICIALI E NON<\/a><\/li>\n<li><a id=\"wpba_attachment_list_19702\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/11\/posizionamento-sculture-Chez-Nous-2025.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/11\/posizionamento-sculture-Chez-Nous-2025.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>posizionamento sculture Chez Nous 2025<\/a><\/li>\n<li><a id=\"wpba_attachment_list_19703\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/11\/Come-sono-nate-le-sculture-per-sito.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/11\/Come-sono-nate-le-sculture-per-sito.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Come sono nate le sculture per sito<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dal 08 Agosto 2025 al 12 Agosto 2025 Dall\u20198 al 12 agosto, Oyace accoglie la creativit\u00e0 dell&#8217;artigianato di tradizione con il progetto \u201cChez nous\u201d.&nbsp; Descrizione&nbsp; L\u2019Amministrazione comunale ha lanciato, nel [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19700,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-19463","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chez Nous 2025 - Oyace<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/oyace\/2025\/08\/05\/chez-nous-2025-3\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chez Nous 2025 - Oyace\" \/>\n<meta property=\"og:description\" content=\"Dal 08 Agosto 2025 al 12 Agosto 2025 Dall\u20198 al 12 agosto, Oyace accoglie la creativit\u00e0 dell&#8217;artigianato di tradizione con il progetto \u201cChez nous\u201d.&nbsp; Descrizione&nbsp; L\u2019Amministrazione comunale ha lanciato, nel [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/oyace\/2025\/08\/05\/chez-nous-2025-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Oyace\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-07T16:53:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/08\/OyaceInArt-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"364\" \/>\n\t<meta property=\"og:image:height\" content=\"254\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/08\\\/05\\\/chez-nous-2025-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/08\\\/05\\\/chez-nous-2025-3\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Chez Nous 2025\",\"datePublished\":\"2025-11-07T16:53:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/08\\\/05\\\/chez-nous-2025-3\\\/\"},\"wordCount\":1083,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/08\\\/05\\\/chez-nous-2025-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2025\\\/11\\\/OyaceInArt-1.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/08\\\/05\\\/chez-nous-2025-3\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/08\\\/05\\\/chez-nous-2025-3\\\/\",\"name\":\"Chez Nous 2025 - Oyace\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/08\\\/05\\\/chez-nous-2025-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/08\\\/05\\\/chez-nous-2025-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2025\\\/11\\\/OyaceInArt-1.jpg\",\"datePublished\":\"2025-11-07T16:53:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/08\\\/05\\\/chez-nous-2025-3\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/08\\\/05\\\/chez-nous-2025-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/08\\\/05\\\/chez-nous-2025-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2025\\\/11\\\/OyaceInArt-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2025\\\/11\\\/OyaceInArt-1.jpg\",\"width\":364,\"height\":254},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/08\\\/05\\\/chez-nous-2025-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chez Nous 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/\",\"name\":\"ComunicaCity\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chez Nous 2025 - Oyace","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/oyace\/2025\/08\/05\/chez-nous-2025-3\/","og_locale":"it_IT","og_type":"article","og_title":"Chez Nous 2025 - Oyace","og_description":"Dal 08 Agosto 2025 al 12 Agosto 2025 Dall\u20198 al 12 agosto, Oyace accoglie la creativit\u00e0 dell&#8217;artigianato di tradizione con il progetto \u201cChez nous\u201d.&nbsp; Descrizione&nbsp; L\u2019Amministrazione comunale ha lanciato, nel [&hellip;]","og_url":"https:\/\/comunicacity.net\/oyace\/2025\/08\/05\/chez-nous-2025-3\/","og_site_name":"Oyace","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-11-07T16:53:21+00:00","og_image":[{"width":364,"height":254,"url":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/08\/OyaceInArt-1-1.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/oyace\/2025\/08\/05\/chez-nous-2025-3\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/oyace\/2025\/08\/05\/chez-nous-2025-3\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Chez Nous 2025","datePublished":"2025-11-07T16:53:21+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/oyace\/2025\/08\/05\/chez-nous-2025-3\/"},"wordCount":1083,"publisher":{"@id":"https:\/\/comunicacity.net\/oyace\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/oyace\/2025\/08\/05\/chez-nous-2025-3\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/11\/OyaceInArt-1.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/oyace\/2025\/08\/05\/chez-nous-2025-3\/","url":"https:\/\/comunicacity.net\/oyace\/2025\/08\/05\/chez-nous-2025-3\/","name":"Chez Nous 2025 - Oyace","isPartOf":{"@id":"https:\/\/comunicacity.net\/oyace\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/oyace\/2025\/08\/05\/chez-nous-2025-3\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/oyace\/2025\/08\/05\/chez-nous-2025-3\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/11\/OyaceInArt-1.jpg","datePublished":"2025-11-07T16:53:21+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/oyace\/2025\/08\/05\/chez-nous-2025-3\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/oyace\/2025\/08\/05\/chez-nous-2025-3\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/oyace\/2025\/08\/05\/chez-nous-2025-3\/#primaryimage","url":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/11\/OyaceInArt-1.jpg","contentUrl":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/11\/OyaceInArt-1.jpg","width":364,"height":254},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/oyace\/2025\/08\/05\/chez-nous-2025-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/oyace\/"},{"@type":"ListItem","position":2,"name":"Chez Nous 2025"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/oyace\/#website","url":"https:\/\/comunicacity.net\/oyace\/","name":"ComunicaCity","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/oyace\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/oyace\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/oyace\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/oyace\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"]}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"08\/08\/2025 00:00","cc4_eve_data_fine":"12\/08\/2025 00:00","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":"14"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002719"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts\/19463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/comments?post=19463"}],"version-history":[{"count":4,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts\/19463\/revisions"}],"predecessor-version":[{"id":19699,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts\/19463\/revisions\/19699"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/media\/19700"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/media?parent=19463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/categories?post=19463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/tags?post=19463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}