{"id":19595,"date":"2025-08-28T20:06:10","date_gmt":"2025-08-28T18:06:10","guid":{"rendered":"https:\/\/comunicacity.net\/oyace\/2025\/08\/28\/regolamentazione-viabilita-s-r-n28\/"},"modified":"2025-08-29T15:54:59","modified_gmt":"2025-08-29T13:54:59","slug":"regolamentazione-viabilita-s-r-n28","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/oyace\/2025\/08\/28\/regolamentazione-viabilita-s-r-n28\/","title":{"rendered":"Regolamentazione della viabilit\u00e0 S.R. n\u00b028"},"content":{"rendered":"<p><em>Finestre di transito per venerd\u00ec 29 e sabato 30 agosto 2025<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Con <span style=\"color: #000080\"><strong><a style=\"color: #000080\" href=\"https:\/\/www.comune.oyace.ao.it\/wp-content\/uploads\/2025\/08\/Ordinanza_18_2025.pdf\">Ordinanza n\u00b018\/2025<\/a> <\/strong><\/span>\u00e8 stata nuovamente disposta la chiusura al traffico pedonale e veicolare con decorrenza immediata e fino alla revoca dell&#8217;ordinanza stessa della S.R. n\u00b0 28 dal 15.600 in localit\u00e0 Sergnoux al km 16.500 in localit\u00e0 Condemine nel<br \/>\nComune di Oyace esclusi i mezzi di soccorso e di gestione dell&#8217;emergenza cui l&#8217;accesso \u00e8 consentito fino al km 16.000 in localit\u00e0 Clos\u00e9. La percorribilit\u00e0 del predetto tratto potr\u00e0 essere assicurata, concluse le operazioni di messa in sicurezza del tratto colpito dall&#8217;evento, in fasce orarie stabilite di volta in volta e comunicate alla cittadinanza attraverso i canali di informazione in uso.<\/p>\n<h3><strong>Aggiornamento 29\/08\/2025<\/strong><\/h3>\n<p>Le nuove finestre di transito, a senso unico alternato, sono le seguenti:<br \/>\n<strong>Venerd\u00ec 29 agosto: dalle ore 17.30 alle ore 19.00<\/strong><br \/>\n<strong>Sabato 30 agosto: dalle ore 07.00 alle 13.00<\/strong><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_19613\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/08\/Ordinanza_18_2025.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/08\/Ordinanza_18_2025.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Ordinanza_18_2025<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Finestre di transito per venerd\u00ec 29 e sabato 30 agosto 2025&nbsp; Descrizione&nbsp; Con Ordinanza n\u00b018\/2025 \u00e8 stata nuovamente disposta la chiusura al traffico pedonale e veicolare con decorrenza immediata e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19612,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-19595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Regolamentazione della viabilit\u00e0 S.R. n\u00b028 - Oyace<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/oyace\/2025\/08\/28\/regolamentazione-viabilita-s-r-n28\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Regolamentazione della viabilit\u00e0 S.R. n\u00b028 - Oyace\" \/>\n<meta property=\"og:description\" content=\"Finestre di transito per venerd\u00ec 29 e sabato 30 agosto 2025&nbsp; Descrizione&nbsp; Con Ordinanza n\u00b018\/2025 \u00e8 stata nuovamente disposta la chiusura al traffico pedonale e veicolare con decorrenza immediata e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/oyace\/2025\/08\/28\/regolamentazione-viabilita-s-r-n28\/\" \/>\n<meta property=\"og:site_name\" content=\"Oyace\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-28T18:06:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T13:54:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/08\/logo_Oyace-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"195\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/08\\\/28\\\/regolamentazione-viabilita-s-r-n28\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/08\\\/28\\\/regolamentazione-viabilita-s-r-n28\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Regolamentazione della viabilit\u00e0 S.R. n\u00b028\",\"datePublished\":\"2025-08-28T18:06:10+00:00\",\"dateModified\":\"2025-08-29T13:54:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/08\\\/28\\\/regolamentazione-viabilita-s-r-n28\\\/\"},\"wordCount\":136,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/08\\\/28\\\/regolamentazione-viabilita-s-r-n28\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2025\\\/08\\\/logo_Oyace-4.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/08\\\/28\\\/regolamentazione-viabilita-s-r-n28\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/08\\\/28\\\/regolamentazione-viabilita-s-r-n28\\\/\",\"name\":\"Regolamentazione della viabilit\u00e0 S.R. n\u00b028 - Oyace\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/08\\\/28\\\/regolamentazione-viabilita-s-r-n28\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/08\\\/28\\\/regolamentazione-viabilita-s-r-n28\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2025\\\/08\\\/logo_Oyace-4.jpg\",\"datePublished\":\"2025-08-28T18:06:10+00:00\",\"dateModified\":\"2025-08-29T13:54:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/08\\\/28\\\/regolamentazione-viabilita-s-r-n28\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/08\\\/28\\\/regolamentazione-viabilita-s-r-n28\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/08\\\/28\\\/regolamentazione-viabilita-s-r-n28\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2025\\\/08\\\/logo_Oyace-4.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2025\\\/08\\\/logo_Oyace-4.jpg\",\"width\":195,\"height\":259},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/08\\\/28\\\/regolamentazione-viabilita-s-r-n28\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuova chiusura della viabilit\u00e0 S.R. n\u00b028\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/\",\"name\":\"ComunicaCity\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Regolamentazione della viabilit\u00e0 S.R. n\u00b028 - Oyace","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/oyace\/2025\/08\/28\/regolamentazione-viabilita-s-r-n28\/","og_locale":"it_IT","og_type":"article","og_title":"Regolamentazione della viabilit\u00e0 S.R. n\u00b028 - Oyace","og_description":"Finestre di transito per venerd\u00ec 29 e sabato 30 agosto 2025&nbsp; Descrizione&nbsp; Con Ordinanza n\u00b018\/2025 \u00e8 stata nuovamente disposta la chiusura al traffico pedonale e veicolare con decorrenza immediata e [&hellip;]","og_url":"https:\/\/comunicacity.net\/oyace\/2025\/08\/28\/regolamentazione-viabilita-s-r-n28\/","og_site_name":"Oyace","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-08-28T18:06:10+00:00","article_modified_time":"2025-08-29T13:54:59+00:00","og_image":[{"width":195,"height":259,"url":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/08\/logo_Oyace-5.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/oyace\/2025\/08\/28\/regolamentazione-viabilita-s-r-n28\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/oyace\/2025\/08\/28\/regolamentazione-viabilita-s-r-n28\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Regolamentazione della viabilit\u00e0 S.R. n\u00b028","datePublished":"2025-08-28T18:06:10+00:00","dateModified":"2025-08-29T13:54:59+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/oyace\/2025\/08\/28\/regolamentazione-viabilita-s-r-n28\/"},"wordCount":136,"publisher":{"@id":"https:\/\/comunicacity.net\/oyace\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/oyace\/2025\/08\/28\/regolamentazione-viabilita-s-r-n28\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/08\/logo_Oyace-4.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/oyace\/2025\/08\/28\/regolamentazione-viabilita-s-r-n28\/","url":"https:\/\/comunicacity.net\/oyace\/2025\/08\/28\/regolamentazione-viabilita-s-r-n28\/","name":"Regolamentazione della viabilit\u00e0 S.R. n\u00b028 - Oyace","isPartOf":{"@id":"https:\/\/comunicacity.net\/oyace\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/oyace\/2025\/08\/28\/regolamentazione-viabilita-s-r-n28\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/oyace\/2025\/08\/28\/regolamentazione-viabilita-s-r-n28\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/08\/logo_Oyace-4.jpg","datePublished":"2025-08-28T18:06:10+00:00","dateModified":"2025-08-29T13:54:59+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/oyace\/2025\/08\/28\/regolamentazione-viabilita-s-r-n28\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/oyace\/2025\/08\/28\/regolamentazione-viabilita-s-r-n28\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/oyace\/2025\/08\/28\/regolamentazione-viabilita-s-r-n28\/#primaryimage","url":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/08\/logo_Oyace-4.jpg","contentUrl":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/08\/logo_Oyace-4.jpg","width":195,"height":259},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/oyace\/2025\/08\/28\/regolamentazione-viabilita-s-r-n28\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/oyace\/"},{"@type":"ListItem","position":2,"name":"Nuova chiusura della viabilit\u00e0 S.R. n\u00b028"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/oyace\/#website","url":"https:\/\/comunicacity.net\/oyace\/","name":"ComunicaCity","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/oyace\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/oyace\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/oyace\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/oyace\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"]}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002758"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts\/19595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/comments?post=19595"}],"version-history":[{"count":4,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts\/19595\/revisions"}],"predecessor-version":[{"id":19611,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts\/19595\/revisions\/19611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/media\/19612"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/media?parent=19595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/categories?post=19595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/tags?post=19595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}