{"id":19638,"date":"2025-10-30T14:37:28","date_gmt":"2025-10-30T13:37:28","guid":{"rendered":"https:\/\/comunicacity.net\/oyace\/2025\/10\/30\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\/"},"modified":"2025-10-30T14:53:44","modified_gmt":"2025-10-30T13:53:44","slug":"dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/oyace\/2025\/10\/30\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\/","title":{"rendered":"Stop alla carta di identit\u00e0 cartacea"},"content":{"rendered":"<p><em>In attuazione del Regolamento (UE) n. 1157\/2019, si informa la cittadinanza che a partire dal 3 agosto 2026 la carta d\u2019identit\u00e0 cartacea non sar\u00e0 pi\u00f9 valida, anche se utilizzata come semplice documento di riconoscimento sul territorio nazionale<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p><a href=\"https:\/\/www.comune.oyace.ao.it\/wp-content\/uploads\/2025\/10\/carta_identita_elettronica_jpg.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2836\" src=\"https:\/\/www.comune.oyace.ao.it\/wp-content\/uploads\/2025\/10\/carta_identita_elettronica_jpg-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" \/><\/a><\/p>\n<p><span style=\"color: #000080\"><strong><a style=\"color: #000080\" href=\"https:\/\/www.comune.oyace.ao.it\/servizio\/carta-di-identita-elettronica\/\">Carta di identit\u00e0 elettronica&#8230;<\/a><\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_19645\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/10\/Circolare-76_2025.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/10\/Circolare-76_2025.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Circolare 76_2025<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>In attuazione del Regolamento (UE) n. 1157\/2019, si informa la cittadinanza che a partire dal 3 agosto 2026 la carta d\u2019identit\u00e0 cartacea non sar\u00e0 pi\u00f9 valida, anche se utilizzata come [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19644,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-19638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stop alla carta di identit\u00e0 cartacea - Oyace<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/oyace\/2025\/10\/30\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stop alla carta di identit\u00e0 cartacea - Oyace\" \/>\n<meta property=\"og:description\" content=\"In attuazione del Regolamento (UE) n. 1157\/2019, si informa la cittadinanza che a partire dal 3 agosto 2026 la carta d\u2019identit\u00e0 cartacea non sar\u00e0 pi\u00f9 valida, anche se utilizzata come [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/oyace\/2025\/10\/30\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\/\" \/>\n<meta property=\"og:site_name\" content=\"Oyace\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-30T13:37:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T13:53:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/10\/Stop_carta_id_cartacea.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"286\" \/>\n\t<meta property=\"og:image:height\" content=\"176\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/10\\\/30\\\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/10\\\/30\\\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Stop alla carta di identit\u00e0 cartacea\",\"datePublished\":\"2025-10-30T13:37:28+00:00\",\"dateModified\":\"2025-10-30T13:53:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/10\\\/30\\\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\\\/\"},\"wordCount\":49,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/10\\\/30\\\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2025\\\/10\\\/Stop_carta_id_cartacea.jpeg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/10\\\/30\\\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/10\\\/30\\\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\\\/\",\"name\":\"Stop alla carta di identit\u00e0 cartacea - Oyace\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/10\\\/30\\\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/10\\\/30\\\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2025\\\/10\\\/Stop_carta_id_cartacea.jpeg\",\"datePublished\":\"2025-10-30T13:37:28+00:00\",\"dateModified\":\"2025-10-30T13:53:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/10\\\/30\\\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/10\\\/30\\\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/10\\\/30\\\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2025\\\/10\\\/Stop_carta_id_cartacea.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2025\\\/10\\\/Stop_carta_id_cartacea.jpeg\",\"width\":286,\"height\":176},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2025\\\/10\\\/30\\\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stop alla carta di identit\u00e0 cartacea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/\",\"name\":\"ComunicaCity\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stop alla carta di identit\u00e0 cartacea - Oyace","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/oyace\/2025\/10\/30\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\/","og_locale":"it_IT","og_type":"article","og_title":"Stop alla carta di identit\u00e0 cartacea - Oyace","og_description":"In attuazione del Regolamento (UE) n. 1157\/2019, si informa la cittadinanza che a partire dal 3 agosto 2026 la carta d\u2019identit\u00e0 cartacea non sar\u00e0 pi\u00f9 valida, anche se utilizzata come [&hellip;]","og_url":"https:\/\/comunicacity.net\/oyace\/2025\/10\/30\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\/","og_site_name":"Oyace","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-10-30T13:37:28+00:00","article_modified_time":"2025-10-30T13:53:44+00:00","og_image":[{"width":286,"height":176,"url":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/10\/Stop_carta_id_cartacea.jpeg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/oyace\/2025\/10\/30\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/oyace\/2025\/10\/30\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Stop alla carta di identit\u00e0 cartacea","datePublished":"2025-10-30T13:37:28+00:00","dateModified":"2025-10-30T13:53:44+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/oyace\/2025\/10\/30\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\/"},"wordCount":49,"publisher":{"@id":"https:\/\/comunicacity.net\/oyace\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/oyace\/2025\/10\/30\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/10\/Stop_carta_id_cartacea.jpeg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/oyace\/2025\/10\/30\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\/","url":"https:\/\/comunicacity.net\/oyace\/2025\/10\/30\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\/","name":"Stop alla carta di identit\u00e0 cartacea - Oyace","isPartOf":{"@id":"https:\/\/comunicacity.net\/oyace\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/oyace\/2025\/10\/30\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/oyace\/2025\/10\/30\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/10\/Stop_carta_id_cartacea.jpeg","datePublished":"2025-10-30T13:37:28+00:00","dateModified":"2025-10-30T13:53:44+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/oyace\/2025\/10\/30\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/oyace\/2025\/10\/30\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/oyace\/2025\/10\/30\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\/#primaryimage","url":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/10\/Stop_carta_id_cartacea.jpeg","contentUrl":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2025\/10\/Stop_carta_id_cartacea.jpeg","width":286,"height":176},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/oyace\/2025\/10\/30\/dal-03-agosto-2026-stop-alla-carta-di-identita-cartacea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/oyace\/"},{"@type":"ListItem","position":2,"name":"Stop alla carta di identit\u00e0 cartacea"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/oyace\/#website","url":"https:\/\/comunicacity.net\/oyace\/","name":"ComunicaCity","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/oyace\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/oyace\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/oyace\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/oyace\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"]}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002834"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts\/19638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/comments?post=19638"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts\/19638\/revisions"}],"predecessor-version":[{"id":19640,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts\/19638\/revisions\/19640"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/media\/19644"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/media?parent=19638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/categories?post=19638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/tags?post=19638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}