{"id":19821,"date":"2026-01-15T15:30:44","date_gmt":"2026-01-15T14:30:44","guid":{"rendered":"https:\/\/comunicacity.net\/oyace\/2026\/01\/15\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\/"},"modified":"2026-01-22T15:04:55","modified_gmt":"2026-01-22T14:04:55","slug":"avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/oyace\/2026\/01\/15\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\/","title":{"rendered":"Avviso pubblico riqualificazione e gestione ex Hotel Otemma"},"content":{"rendered":"<p><em>I soggetti interessati devono far pervenire entro e non oltre il giorno 4 maggio 2026 ore 12.00,<br \/>\nesclusivamente via PEC, al seguente indirizzo: protocollo@pec.comune.oyace.ao.it, la<br \/>\ndocumentazione di cui all\u2019art. 3 dell&#8217;avviso pubblico<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p><a href=\"https:\/\/www.servizipubblicaamministrazione.it\/servizi\/saturnweb\/Dettaglio.aspx?Pub=3103&amp;Tipo=14&amp;CE=yc1095\">Avviso pubblico ex art. 193, comma 16, del d. lgs. 36\/2023 e s.m.i., atto a sollecitare i privati interessati a farsi promotori di iniziative volte a realizzare in concessione, mediante finanza di progetto, interventi inclusi negli strumenti di programmazione del ppp, di cui all\u2019art.175, comma 1, volti alla riqualificazione edilizia e gestione del complesso immobiliare, denominato ex hotel Otemma<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I soggetti interessati devono far pervenire entro e non oltre il giorno 4 maggio 2026 ore 12.00, esclusivamente via PEC, al seguente indirizzo: protocollo@pec.comune.oyace.ao.it, la documentazione di cui all\u2019art. 3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19836,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-19821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso pubblico riqualificazione e gestione ex Hotel Otemma - Oyace<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/oyace\/2026\/01\/15\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso pubblico riqualificazione e gestione ex Hotel Otemma - Oyace\" \/>\n<meta property=\"og:description\" content=\"I soggetti interessati devono far pervenire entro e non oltre il giorno 4 maggio 2026 ore 12.00, esclusivamente via PEC, al seguente indirizzo: protocollo@pec.comune.oyace.ao.it, la documentazione di cui all\u2019art. 3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/oyace\/2026\/01\/15\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\/\" \/>\n<meta property=\"og:site_name\" content=\"Oyace\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-15T14:30:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-22T14:04:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2026\/01\/logo_Oyace.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"195\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2026\\\/01\\\/15\\\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2026\\\/01\\\/15\\\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Avviso pubblico riqualificazione e gestione ex Hotel Otemma\",\"datePublished\":\"2026-01-15T14:30:44+00:00\",\"dateModified\":\"2026-01-22T14:04:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2026\\\/01\\\/15\\\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\\\/\"},\"wordCount\":103,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2026\\\/01\\\/15\\\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2026\\\/01\\\/logo_Oyace-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2026\\\/01\\\/15\\\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2026\\\/01\\\/15\\\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\\\/\",\"name\":\"Avviso pubblico riqualificazione e gestione ex Hotel Otemma - Oyace\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2026\\\/01\\\/15\\\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2026\\\/01\\\/15\\\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2026\\\/01\\\/logo_Oyace-1.jpg\",\"datePublished\":\"2026-01-15T14:30:44+00:00\",\"dateModified\":\"2026-01-22T14:04:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2026\\\/01\\\/15\\\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2026\\\/01\\\/15\\\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2026\\\/01\\\/15\\\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2026\\\/01\\\/logo_Oyace-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/wp-content\\\/uploads\\\/sites\\\/205\\\/2026\\\/01\\\/logo_Oyace-1.jpg\",\"width\":195,\"height\":259},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/2026\\\/01\\\/15\\\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso pubblico riqualificazione e gestione ex Hotel Otemma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/\",\"name\":\"ComunicaCity\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/oyace\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso pubblico riqualificazione e gestione ex Hotel Otemma - Oyace","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/oyace\/2026\/01\/15\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso pubblico riqualificazione e gestione ex Hotel Otemma - Oyace","og_description":"I soggetti interessati devono far pervenire entro e non oltre il giorno 4 maggio 2026 ore 12.00, esclusivamente via PEC, al seguente indirizzo: protocollo@pec.comune.oyace.ao.it, la documentazione di cui all\u2019art. 3 [&hellip;]","og_url":"https:\/\/comunicacity.net\/oyace\/2026\/01\/15\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\/","og_site_name":"Oyace","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-01-15T14:30:44+00:00","article_modified_time":"2026-01-22T14:04:55+00:00","og_image":[{"width":195,"height":259,"url":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2026\/01\/logo_Oyace.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/oyace\/2026\/01\/15\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/oyace\/2026\/01\/15\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Avviso pubblico riqualificazione e gestione ex Hotel Otemma","datePublished":"2026-01-15T14:30:44+00:00","dateModified":"2026-01-22T14:04:55+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/oyace\/2026\/01\/15\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\/"},"wordCount":103,"publisher":{"@id":"https:\/\/comunicacity.net\/oyace\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/oyace\/2026\/01\/15\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2026\/01\/logo_Oyace-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/oyace\/2026\/01\/15\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\/","url":"https:\/\/comunicacity.net\/oyace\/2026\/01\/15\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\/","name":"Avviso pubblico riqualificazione e gestione ex Hotel Otemma - Oyace","isPartOf":{"@id":"https:\/\/comunicacity.net\/oyace\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/oyace\/2026\/01\/15\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/oyace\/2026\/01\/15\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2026\/01\/logo_Oyace-1.jpg","datePublished":"2026-01-15T14:30:44+00:00","dateModified":"2026-01-22T14:04:55+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/oyace\/2026\/01\/15\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/oyace\/2026\/01\/15\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/oyace\/2026\/01\/15\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\/#primaryimage","url":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2026\/01\/logo_Oyace-1.jpg","contentUrl":"https:\/\/comunicacity.net\/oyace\/wp-content\/uploads\/sites\/205\/2026\/01\/logo_Oyace-1.jpg","width":195,"height":259},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/oyace\/2026\/01\/15\/avviso-pubblico-riqualificazione-e-gestione-ex-hotel-otemma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/oyace\/"},{"@type":"ListItem","position":2,"name":"Avviso pubblico riqualificazione e gestione ex Hotel Otemma"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/oyace\/#website","url":"https:\/\/comunicacity.net\/oyace\/","name":"ComunicaCity","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/oyace\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/oyace\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/oyace\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/oyace\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/oyace\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"]}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00003047"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts\/19821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/comments?post=19821"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts\/19821\/revisions"}],"predecessor-version":[{"id":19835,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/posts\/19821\/revisions\/19835"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/media\/19836"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/media?parent=19821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/categories?post=19821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/oyace\/wp-json\/wp\/v2\/tags?post=19821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}