{"id":68,"date":"2020-03-24T09:34:34","date_gmt":"2020-03-24T08:34:34","guid":{"rendered":"https:\/\/comunicacity.net\/palmiano\/?p=68"},"modified":"2020-03-24T09:39:10","modified_gmt":"2020-03-24T08:39:10","slug":"__trashed-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/palmiano\/2020\/03\/24\/__trashed-2\/","title":{"rendered":"RITIRO PENSIONI APRILE 2020 A PARTIRE DAL 26 MARZO"},"content":{"rendered":"<table width=\"668\">\n<tbody>\n<tr>\n<td width=\"88\"><\/td>\n<td colspan=\"6\" width=\"580\">CALENDARIO<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td colspan=\"6\">DT = Aperto mattina e pomeriggio &#8211; TU = Aperto mattina<\/td>\n<\/tr>\n<tr>\n<td>Comune<\/td>\n<td width=\"100\">26\/03\/2020<\/td>\n<td width=\"100\">27\/03\/2020<\/td>\n<td width=\"100\">28\/03\/2020<\/td>\n<td width=\"100\">30\/03\/2020<\/td>\n<td width=\"100\">31\/03\/2020<\/td>\n<td width=\"80\">01\/04\/2020<\/td>\n<\/tr>\n<tr>\n<td>PALMIANO<\/td>\n<td>TU<\/td>\n<td><\/td>\n<td>TU<\/td>\n<td><\/td>\n<td>TU<\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_71\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/palmiano\/wp-content\/uploads\/sites\/184\/2020\/03\/0297_avviso-pensioni-2_01.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/palmiano\/wp-content\/uploads\/sites\/184\/2020\/03\/0297_avviso-pensioni-2_01.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>0297_avviso pensioni 2_01<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>CALENDARIO DT = Aperto mattina e pomeriggio &#8211; TU = Aperto mattina Comune 26\/03\/2020 27\/03\/2020 28\/03\/2020 30\/03\/2020 31\/03\/2020 01\/04\/2020 PALMIANO TU TU TU \ud83d\udcce Allegati0297_avviso pensioni 2_01<\/p>\n","protected":false},"author":335,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-68","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RITIRO PENSIONI APRILE 2020 A PARTIRE DAL 26 MARZO - Palmiano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/palmiano\/2020\/03\/24\/__trashed-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RITIRO PENSIONI APRILE 2020 A PARTIRE DAL 26 MARZO - Palmiano\" \/>\n<meta property=\"og:description\" content=\"CALENDARIO DT = Aperto mattina e pomeriggio &#8211; TU = Aperto mattina Comune 26\/03\/2020 27\/03\/2020 28\/03\/2020 30\/03\/2020 31\/03\/2020 01\/04\/2020 PALMIANO TU TU TU \ud83d\udcce Allegati0297_avviso pensioni 2_01\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/palmiano\/2020\/03\/24\/__trashed-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Palmiano\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-24T08:34:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-24T08:39:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/palmiano\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"segreteriapalmiano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"segreteriapalmiano\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/palmiano\\\/2020\\\/03\\\/24\\\/__trashed-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/palmiano\\\/2020\\\/03\\\/24\\\/__trashed-2\\\/\"},\"author\":{\"name\":\"segreteriapalmiano\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/palmiano\\\/#\\\/schema\\\/person\\\/dd64430d7732ec3a70d49fa2927ba61b\"},\"headline\":\"RITIRO PENSIONI APRILE 2020 A PARTIRE DAL 26 MARZO\",\"datePublished\":\"2020-03-24T08:34:34+00:00\",\"dateModified\":\"2020-03-24T08:39:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/palmiano\\\/2020\\\/03\\\/24\\\/__trashed-2\\\/\"},\"wordCount\":22,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/palmiano\\\/#organization\"},\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/palmiano\\\/2020\\\/03\\\/24\\\/__trashed-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/palmiano\\\/2020\\\/03\\\/24\\\/__trashed-2\\\/\",\"name\":\"RITIRO PENSIONI APRILE 2020 A PARTIRE DAL 26 MARZO - Palmiano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/palmiano\\\/#website\"},\"datePublished\":\"2020-03-24T08:34:34+00:00\",\"dateModified\":\"2020-03-24T08:39:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/palmiano\\\/2020\\\/03\\\/24\\\/__trashed-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/palmiano\\\/2020\\\/03\\\/24\\\/__trashed-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/palmiano\\\/2020\\\/03\\\/24\\\/__trashed-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/palmiano\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RITIRO PENSIONI APRILE 2020 A PARTIRE DAL 26 MARZO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/palmiano\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/palmiano\\\/\",\"name\":\"Palmiano\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/palmiano\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/palmiano\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/palmiano\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/palmiano\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/palmiano\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/palmiano\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/palmiano\\\/#\\\/schema\\\/person\\\/dd64430d7732ec3a70d49fa2927ba61b\",\"name\":\"segreteriapalmiano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1dc5b7bff1b2564e587ae7656076c8cd3b862ce22e209709e5af8422bb23d5c1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1dc5b7bff1b2564e587ae7656076c8cd3b862ce22e209709e5af8422bb23d5c1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1dc5b7bff1b2564e587ae7656076c8cd3b862ce22e209709e5af8422bb23d5c1?s=96&d=mm&r=g\",\"caption\":\"segreteriapalmiano\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/palmiano\\\/author\\\/segreteriapalmiano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RITIRO PENSIONI APRILE 2020 A PARTIRE DAL 26 MARZO - Palmiano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/palmiano\/2020\/03\/24\/__trashed-2\/","og_locale":"it_IT","og_type":"article","og_title":"RITIRO PENSIONI APRILE 2020 A PARTIRE DAL 26 MARZO - Palmiano","og_description":"CALENDARIO DT = Aperto mattina e pomeriggio &#8211; TU = Aperto mattina Comune 26\/03\/2020 27\/03\/2020 28\/03\/2020 30\/03\/2020 31\/03\/2020 01\/04\/2020 PALMIANO TU TU TU \ud83d\udcce Allegati0297_avviso pensioni 2_01","og_url":"https:\/\/comunicacity.net\/palmiano\/2020\/03\/24\/__trashed-2\/","og_site_name":"Palmiano","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-03-24T08:34:34+00:00","article_modified_time":"2020-03-24T08:39:10+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/palmiano\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"segreteriapalmiano","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"segreteriapalmiano"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/palmiano\/2020\/03\/24\/__trashed-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/palmiano\/2020\/03\/24\/__trashed-2\/"},"author":{"name":"segreteriapalmiano","@id":"https:\/\/comunicacity.net\/palmiano\/#\/schema\/person\/dd64430d7732ec3a70d49fa2927ba61b"},"headline":"RITIRO PENSIONI APRILE 2020 A PARTIRE DAL 26 MARZO","datePublished":"2020-03-24T08:34:34+00:00","dateModified":"2020-03-24T08:39:10+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/palmiano\/2020\/03\/24\/__trashed-2\/"},"wordCount":22,"publisher":{"@id":"https:\/\/comunicacity.net\/palmiano\/#organization"},"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/palmiano\/2020\/03\/24\/__trashed-2\/","url":"https:\/\/comunicacity.net\/palmiano\/2020\/03\/24\/__trashed-2\/","name":"RITIRO PENSIONI APRILE 2020 A PARTIRE DAL 26 MARZO - Palmiano","isPartOf":{"@id":"https:\/\/comunicacity.net\/palmiano\/#website"},"datePublished":"2020-03-24T08:34:34+00:00","dateModified":"2020-03-24T08:39:10+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/palmiano\/2020\/03\/24\/__trashed-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/palmiano\/2020\/03\/24\/__trashed-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/palmiano\/2020\/03\/24\/__trashed-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/palmiano\/"},{"@type":"ListItem","position":2,"name":"RITIRO PENSIONI APRILE 2020 A PARTIRE DAL 26 MARZO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/palmiano\/#website","url":"https:\/\/comunicacity.net\/palmiano\/","name":"Palmiano","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/palmiano\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/palmiano\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/palmiano\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/palmiano\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/palmiano\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/palmiano\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/palmiano\/#\/schema\/person\/dd64430d7732ec3a70d49fa2927ba61b","name":"segreteriapalmiano","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/1dc5b7bff1b2564e587ae7656076c8cd3b862ce22e209709e5af8422bb23d5c1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1dc5b7bff1b2564e587ae7656076c8cd3b862ce22e209709e5af8422bb23d5c1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1dc5b7bff1b2564e587ae7656076c8cd3b862ce22e209709e5af8422bb23d5c1?s=96&d=mm&r=g","caption":"segreteriapalmiano"},"url":"https:\/\/comunicacity.net\/palmiano\/author\/segreteriapalmiano\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/palmiano\/wp-json\/wp\/v2\/posts\/68","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/palmiano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/palmiano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/palmiano\/wp-json\/wp\/v2\/users\/335"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/palmiano\/wp-json\/wp\/v2\/comments?post=68"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/palmiano\/wp-json\/wp\/v2\/posts\/68\/revisions"}],"predecessor-version":[{"id":70,"href":"https:\/\/comunicacity.net\/palmiano\/wp-json\/wp\/v2\/posts\/68\/revisions\/70"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/palmiano\/wp-json\/wp\/v2\/media?parent=68"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/palmiano\/wp-json\/wp\/v2\/categories?post=68"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/palmiano\/wp-json\/wp\/v2\/tags?post=68"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}