{"id":111,"date":"2024-09-16T12:51:04","date_gmt":"2024-09-16T10:51:04","guid":{"rendered":"https:\/\/comunicacity.net\/pastena\/?p=111"},"modified":"2024-09-16T12:51:05","modified_gmt":"2024-09-16T10:51:05","slug":"determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pastena\/2024\/09\/16\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\/","title":{"rendered":"Determinazione di indizione di nuova manifestazione di interesse e avviso pubblico finalizzati all&#8217;individuazione di operatori economici per l&#8217;affidamento di una fornitura di derrate alimentari destinate al funzionamento del servizio interno di mensa"},"content":{"rendered":"<p><em>Per l&#8217;a.s. 2024\/2025 prorogabile per l&#8217;a.s. 2025\/2026 per gli alunni della scuola di pastena<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<div class=\"flex max-w-full flex-col flex-grow\">\n<div class=\"min-h-[20px] text-message flex w-full flex-col items-end gap-2 whitespace-normal break-words [.text-message+&amp;]:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"9bcba4d8-477a-4317-a82a-39ce584ae589\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p>determinazione di indizione di nuova manifestazione di interesse e avviso pubblico finalizzati all&#8217;individuazione di operatori economici per l&#8217;affidamento di una fornitura di derrate alimentari destinate al funzionamento del servizio interno di mensa per l&#8217;a.s. 2024\/2025 prorogabile per l&#8217;a.s. 2025\/2026 per gli alunni della scuola di Pastena. procedura sotto soglia di rilevanza comunitaria di cui all&#8217;art. 14 del d.lgs. n. 36 del 31 marzo 2023, ai sensi e per gli effetti di quanto disposto e regolato dall&#8217;art. 50, comma 1, lett. b del d.lgs. n. 36\/2023<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_119\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/pastena\/wp-content\/uploads\/sites\/215\/2024\/09\/DETERMINA_GEN_233_Atto-copia-conforme.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/pastena\/wp-content\/uploads\/sites\/215\/2024\/09\/DETERMINA_GEN_233_Atto-copia-conforme.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>DETERMINA_GEN_233_Atto copia conforme<\/a><\/li>\n<li><a id=\"wpba_attachment_list_120\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/pastena\/wp-content\/uploads\/sites\/215\/2024\/09\/DETERMINA_GEN_233_LOTTO-1-Copia.xlsx\" onclick=\"window.open('https:\/\/comunicacity.net\/pastena\/wp-content\/uploads\/sites\/215\/2024\/09\/DETERMINA_GEN_233_LOTTO-1-Copia.xlsx', '_system'); return false;\"><i class='icon attachment'><\/i>DETERMINA_GEN_233_LOTTO 1 &#8211; Copia<\/a><\/li>\n<li><a id=\"wpba_attachment_list_121\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/pastena\/wp-content\/uploads\/sites\/215\/2024\/09\/DETERMINA_GEN_233_MANIFESTAZIONE-DINTERESSE-MENSA.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/pastena\/wp-content\/uploads\/sites\/215\/2024\/09\/DETERMINA_GEN_233_MANIFESTAZIONE-DINTERESSE-MENSA.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>DETERMINA_GEN_233_MANIFESTAZIONE D`INTERESSE MENSA<\/a><\/li>\n<li><a id=\"wpba_attachment_list_122\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/pastena\/wp-content\/uploads\/sites\/215\/2024\/09\/DETERMINA_GEN_233_modello-di-istanza.docx\" onclick=\"window.open('https:\/\/comunicacity.net\/pastena\/wp-content\/uploads\/sites\/215\/2024\/09\/DETERMINA_GEN_233_modello-di-istanza.docx', '_system'); return false;\"><i class='icon attachment'><\/i>DETERMINA_GEN_233_modello di istanza<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Per l&#8217;a.s. 2024\/2025 prorogabile per l&#8217;a.s. 2025\/2026 per gli alunni della scuola di pastena&nbsp; Descrizione&nbsp; determinazione di indizione di nuova manifestazione di interesse e avviso pubblico finalizzati all&#8217;individuazione di operatori [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":118,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-111","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Determinazione di indizione di nuova manifestazione di interesse e avviso pubblico finalizzati all&#039;individuazione di operatori economici per l&#039;affidamento di una fornitura di derrate alimentari destinate al funzionamento del servizio interno di mensa - Pastena<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pastena\/2024\/09\/16\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Determinazione di indizione di nuova manifestazione di interesse e avviso pubblico finalizzati all&#039;individuazione di operatori economici per l&#039;affidamento di una fornitura di derrate alimentari destinate al funzionamento del servizio interno di mensa - Pastena\" \/>\n<meta property=\"og:description\" content=\"Per l&#8217;a.s. 2024\/2025 prorogabile per l&#8217;a.s. 2025\/2026 per gli alunni della scuola di pastena&nbsp; Descrizione&nbsp; determinazione di indizione di nuova manifestazione di interesse e avviso pubblico finalizzati all&#8217;individuazione di operatori [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pastena\/2024\/09\/16\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\/\" \/>\n<meta property=\"og:site_name\" content=\"Pastena\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-16T10:51:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-16T10:51:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pastena\/wp-content\/uploads\/sites\/215\/2024\/09\/Comune-di-Pastena-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/2024\\\/09\\\/16\\\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/2024\\\/09\\\/16\\\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Determinazione di indizione di nuova manifestazione di interesse e avviso pubblico finalizzati all&#8217;individuazione di operatori economici per l&#8217;affidamento di una fornitura di derrate alimentari destinate al funzionamento del servizio interno di mensa\",\"datePublished\":\"2024-09-16T10:51:04+00:00\",\"dateModified\":\"2024-09-16T10:51:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/2024\\\/09\\\/16\\\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\\\/\"},\"wordCount\":129,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/2024\\\/09\\\/16\\\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/wp-content\\\/uploads\\\/sites\\\/215\\\/2024\\\/09\\\/Comune-di-Pastena-2.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/2024\\\/09\\\/16\\\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/2024\\\/09\\\/16\\\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\\\/\",\"name\":\"Determinazione di indizione di nuova manifestazione di interesse e avviso pubblico finalizzati all'individuazione di operatori economici per l'affidamento di una fornitura di derrate alimentari destinate al funzionamento del servizio interno di mensa - Pastena\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/2024\\\/09\\\/16\\\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/2024\\\/09\\\/16\\\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/wp-content\\\/uploads\\\/sites\\\/215\\\/2024\\\/09\\\/Comune-di-Pastena-2.jpg\",\"datePublished\":\"2024-09-16T10:51:04+00:00\",\"dateModified\":\"2024-09-16T10:51:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/2024\\\/09\\\/16\\\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/2024\\\/09\\\/16\\\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/2024\\\/09\\\/16\\\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/wp-content\\\/uploads\\\/sites\\\/215\\\/2024\\\/09\\\/Comune-di-Pastena-2.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/wp-content\\\/uploads\\\/sites\\\/215\\\/2024\\\/09\\\/Comune-di-Pastena-2.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/2024\\\/09\\\/16\\\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Determinazione di indizione di nuova manifestazione di interesse e avviso pubblico finalizzati all&#8217;individuazione di operatori economici per l&#8217;affidamento di una fornitura di derrate alimentari destinate al funzionamento del servizio interno di mensa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Determinazione di indizione di nuova manifestazione di interesse e avviso pubblico finalizzati all'individuazione di operatori economici per l'affidamento di una fornitura di derrate alimentari destinate al funzionamento del servizio interno di mensa - Pastena","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pastena\/2024\/09\/16\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\/","og_locale":"it_IT","og_type":"article","og_title":"Determinazione di indizione di nuova manifestazione di interesse e avviso pubblico finalizzati all'individuazione di operatori economici per l'affidamento di una fornitura di derrate alimentari destinate al funzionamento del servizio interno di mensa - Pastena","og_description":"Per l&#8217;a.s. 2024\/2025 prorogabile per l&#8217;a.s. 2025\/2026 per gli alunni della scuola di pastena&nbsp; Descrizione&nbsp; determinazione di indizione di nuova manifestazione di interesse e avviso pubblico finalizzati all&#8217;individuazione di operatori [&hellip;]","og_url":"https:\/\/comunicacity.net\/pastena\/2024\/09\/16\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\/","og_site_name":"Pastena","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-09-16T10:51:04+00:00","article_modified_time":"2024-09-16T10:51:05+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/comunicacity.net\/pastena\/wp-content\/uploads\/sites\/215\/2024\/09\/Comune-di-Pastena-2.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pastena\/2024\/09\/16\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pastena\/2024\/09\/16\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/pastena\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Determinazione di indizione di nuova manifestazione di interesse e avviso pubblico finalizzati all&#8217;individuazione di operatori economici per l&#8217;affidamento di una fornitura di derrate alimentari destinate al funzionamento del servizio interno di mensa","datePublished":"2024-09-16T10:51:04+00:00","dateModified":"2024-09-16T10:51:05+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pastena\/2024\/09\/16\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\/"},"wordCount":129,"publisher":{"@id":"https:\/\/comunicacity.net\/pastena\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/pastena\/2024\/09\/16\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pastena\/wp-content\/uploads\/sites\/215\/2024\/09\/Comune-di-Pastena-2.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pastena\/2024\/09\/16\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\/","url":"https:\/\/comunicacity.net\/pastena\/2024\/09\/16\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\/","name":"Determinazione di indizione di nuova manifestazione di interesse e avviso pubblico finalizzati all'individuazione di operatori economici per l'affidamento di una fornitura di derrate alimentari destinate al funzionamento del servizio interno di mensa - Pastena","isPartOf":{"@id":"https:\/\/comunicacity.net\/pastena\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pastena\/2024\/09\/16\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pastena\/2024\/09\/16\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pastena\/wp-content\/uploads\/sites\/215\/2024\/09\/Comune-di-Pastena-2.jpg","datePublished":"2024-09-16T10:51:04+00:00","dateModified":"2024-09-16T10:51:05+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/pastena\/2024\/09\/16\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pastena\/2024\/09\/16\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pastena\/2024\/09\/16\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\/#primaryimage","url":"https:\/\/comunicacity.net\/pastena\/wp-content\/uploads\/sites\/215\/2024\/09\/Comune-di-Pastena-2.jpg","contentUrl":"https:\/\/comunicacity.net\/pastena\/wp-content\/uploads\/sites\/215\/2024\/09\/Comune-di-Pastena-2.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pastena\/2024\/09\/16\/determinazione-di-indizione-di-nuova-manifestazione-di-interesse-e-avviso-pubblico-finalizzati-allindividuazione-di-operatori-economici-per-laffidamento-di-una-fornitura-di-derrate-alimentari-dest\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pastena\/"},{"@type":"ListItem","position":2,"name":"Determinazione di indizione di nuova manifestazione di interesse e avviso pubblico finalizzati all&#8217;individuazione di operatori economici per l&#8217;affidamento di una fornitura di derrate alimentari destinate al funzionamento del servizio interno di mensa"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pastena\/#website","url":"https:\/\/comunicacity.net\/pastena\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/pastena\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pastena\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/pastena\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/pastena\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pastena\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/pastena\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pastena\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001257"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pastena\/wp-json\/wp\/v2\/posts\/111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pastena\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pastena\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pastena\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pastena\/wp-json\/wp\/v2\/comments?post=111"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/pastena\/wp-json\/wp\/v2\/posts\/111\/revisions"}],"predecessor-version":[{"id":117,"href":"https:\/\/comunicacity.net\/pastena\/wp-json\/wp\/v2\/posts\/111\/revisions\/117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pastena\/wp-json\/wp\/v2\/media\/118"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pastena\/wp-json\/wp\/v2\/media?parent=111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pastena\/wp-json\/wp\/v2\/categories?post=111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pastena\/wp-json\/wp\/v2\/tags?post=111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}