{"id":52,"date":"2023-10-13T13:45:34","date_gmt":"2023-10-13T11:45:34","guid":{"rendered":"https:\/\/comunicacity.net\/pastena\/2023\/10\/13\/selezione-pubblica-per-il-conferimento-dellincarico-di-istruttore-direttivo-tecnico-settore-lavori-pubblici-ambiente-urbanistica-manutenzione-edilizia-pubblica-e-privata\/"},"modified":"2023-10-13T13:45:34","modified_gmt":"2023-10-13T11:45:34","slug":"selezione-pubblica-per-il-conferimento-dellincarico-di-istruttore-direttivo-tecnico-settore-lavori-pubblici-ambiente-urbanistica-manutenzione-edilizia-pubblica-e-privata","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pastena\/2023\/10\/13\/selezione-pubblica-per-il-conferimento-dellincarico-di-istruttore-direttivo-tecnico-settore-lavori-pubblici-ambiente-urbanistica-manutenzione-edilizia-pubblica-e-privata\/","title":{"rendered":"Selezione pubblica per il conferimento dell&#8217;incarico di istruttore direttivo tecnico settore lavori pubblici, ambiente, urbanistica, manutenzione, edilizia pubblica e privata"},"content":{"rendered":"<p><em>Selezione pubblica per il conferimento dell&#8217;incarico di istruttore direttivo tecnico settore lavori pubblici, ambiente, urbanistica, manutenzione, edilizia pubblica e privata<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Selezione pubblica per il conferimento dell&#8217;incarico di istruttore direttivo tecnico settore lavori pubblici, ambiente, urbanistica, manutenzione, edilizia pubblica e privata, categoria D1 mediante contratto a tempo determinato e part time (18 ore settimanali) ai sensi dell&#8217;art. 110 comma 1 TUEL.- Approvazione avviso pubblico, schema di domanda.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_53\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/pastena\/wp-content\/uploads\/sites\/215\/2024\/04\/determina-selezione-pubblica.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/pastena\/wp-content\/uploads\/sites\/215\/2024\/04\/determina-selezione-pubblica.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>determina selezione pubblica<\/a><\/li>\n<li><a id=\"wpba_attachment_list_54\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/pastena\/wp-content\/uploads\/sites\/215\/2024\/04\/AVVISO.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/pastena\/wp-content\/uploads\/sites\/215\/2024\/04\/AVVISO.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>AVVISO<\/a><\/li>\n<li><a id=\"wpba_attachment_list_55\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/pastena\/wp-content\/uploads\/sites\/215\/2024\/04\/SCHEMA-DOM.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/pastena\/wp-content\/uploads\/sites\/215\/2024\/04\/SCHEMA-DOM.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>SCHEMA-DOM<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Selezione pubblica per il conferimento dell&#8217;incarico di istruttore direttivo tecnico settore lavori pubblici, ambiente, urbanistica, manutenzione, edilizia pubblica e privata&nbsp; Descrizione&nbsp; Selezione pubblica per il conferimento dell&#8217;incarico di istruttore direttivo [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-52","post","type-post","status-publish","format-standard","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Selezione pubblica per il conferimento dell&#039;incarico di istruttore direttivo tecnico settore lavori pubblici, ambiente, urbanistica, manutenzione, edilizia pubblica e privata - Pastena<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pastena\/2023\/10\/13\/selezione-pubblica-per-il-conferimento-dellincarico-di-istruttore-direttivo-tecnico-settore-lavori-pubblici-ambiente-urbanistica-manutenzione-edilizia-pubblica-e-privata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Selezione pubblica per il conferimento dell&#039;incarico di istruttore direttivo tecnico settore lavori pubblici, ambiente, urbanistica, manutenzione, edilizia pubblica e privata - Pastena\" \/>\n<meta property=\"og:description\" content=\"Selezione pubblica per il conferimento dell&#8217;incarico di istruttore direttivo tecnico settore lavori pubblici, ambiente, urbanistica, manutenzione, edilizia pubblica e privata&nbsp; Descrizione&nbsp; Selezione pubblica per il conferimento dell&#8217;incarico di istruttore direttivo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pastena\/2023\/10\/13\/selezione-pubblica-per-il-conferimento-dellincarico-di-istruttore-direttivo-tecnico-settore-lavori-pubblici-ambiente-urbanistica-manutenzione-edilizia-pubblica-e-privata\/\" \/>\n<meta property=\"og:site_name\" content=\"Pastena\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-13T11:45:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pastena\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/manutenzione-e-lavori.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/2023\\\/10\\\/13\\\/selezione-pubblica-per-il-conferimento-dellincarico-di-istruttore-direttivo-tecnico-settore-lavori-pubblici-ambiente-urbanistica-manutenzione-edilizia-pubblica-e-privata\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/2023\\\/10\\\/13\\\/selezione-pubblica-per-il-conferimento-dellincarico-di-istruttore-direttivo-tecnico-settore-lavori-pubblici-ambiente-urbanistica-manutenzione-edilizia-pubblica-e-privata\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Selezione pubblica per il conferimento dell&#8217;incarico di istruttore direttivo tecnico settore lavori pubblici, ambiente, urbanistica, manutenzione, edilizia pubblica e privata\",\"datePublished\":\"2023-10-13T11:45:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/2023\\\/10\\\/13\\\/selezione-pubblica-per-il-conferimento-dellincarico-di-istruttore-direttivo-tecnico-settore-lavori-pubblici-ambiente-urbanistica-manutenzione-edilizia-pubblica-e-privata\\\/\"},\"wordCount\":87,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/#organization\"},\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/2023\\\/10\\\/13\\\/selezione-pubblica-per-il-conferimento-dellincarico-di-istruttore-direttivo-tecnico-settore-lavori-pubblici-ambiente-urbanistica-manutenzione-edilizia-pubblica-e-privata\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/2023\\\/10\\\/13\\\/selezione-pubblica-per-il-conferimento-dellincarico-di-istruttore-direttivo-tecnico-settore-lavori-pubblici-ambiente-urbanistica-manutenzione-edilizia-pubblica-e-privata\\\/\",\"name\":\"Selezione pubblica per il conferimento dell'incarico di istruttore direttivo tecnico settore lavori pubblici, ambiente, urbanistica, manutenzione, edilizia pubblica e privata - Pastena\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/#website\"},\"datePublished\":\"2023-10-13T11:45:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/2023\\\/10\\\/13\\\/selezione-pubblica-per-il-conferimento-dellincarico-di-istruttore-direttivo-tecnico-settore-lavori-pubblici-ambiente-urbanistica-manutenzione-edilizia-pubblica-e-privata\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/2023\\\/10\\\/13\\\/selezione-pubblica-per-il-conferimento-dellincarico-di-istruttore-direttivo-tecnico-settore-lavori-pubblici-ambiente-urbanistica-manutenzione-edilizia-pubblica-e-privata\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/2023\\\/10\\\/13\\\/selezione-pubblica-per-il-conferimento-dellincarico-di-istruttore-direttivo-tecnico-settore-lavori-pubblici-ambiente-urbanistica-manutenzione-edilizia-pubblica-e-privata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Selezione pubblica per il conferimento dell&#8217;incarico di istruttore direttivo tecnico settore lavori pubblici, ambiente, urbanistica, manutenzione, edilizia pubblica e privata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pastena\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Selezione pubblica per il conferimento dell'incarico di istruttore direttivo tecnico settore lavori pubblici, ambiente, urbanistica, manutenzione, edilizia pubblica e privata - Pastena","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pastena\/2023\/10\/13\/selezione-pubblica-per-il-conferimento-dellincarico-di-istruttore-direttivo-tecnico-settore-lavori-pubblici-ambiente-urbanistica-manutenzione-edilizia-pubblica-e-privata\/","og_locale":"it_IT","og_type":"article","og_title":"Selezione pubblica per il conferimento dell'incarico di istruttore direttivo tecnico settore lavori pubblici, ambiente, urbanistica, manutenzione, edilizia pubblica e privata - Pastena","og_description":"Selezione pubblica per il conferimento dell&#8217;incarico di istruttore direttivo tecnico settore lavori pubblici, ambiente, urbanistica, manutenzione, edilizia pubblica e privata&nbsp; Descrizione&nbsp; Selezione pubblica per il conferimento dell&#8217;incarico di istruttore direttivo [&hellip;]","og_url":"https:\/\/comunicacity.net\/pastena\/2023\/10\/13\/selezione-pubblica-per-il-conferimento-dellincarico-di-istruttore-direttivo-tecnico-settore-lavori-pubblici-ambiente-urbanistica-manutenzione-edilizia-pubblica-e-privata\/","og_site_name":"Pastena","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-10-13T11:45:34+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/pastena\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/manutenzione-e-lavori.png","height":600,"width":1200,"type":""}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pastena\/2023\/10\/13\/selezione-pubblica-per-il-conferimento-dellincarico-di-istruttore-direttivo-tecnico-settore-lavori-pubblici-ambiente-urbanistica-manutenzione-edilizia-pubblica-e-privata\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pastena\/2023\/10\/13\/selezione-pubblica-per-il-conferimento-dellincarico-di-istruttore-direttivo-tecnico-settore-lavori-pubblici-ambiente-urbanistica-manutenzione-edilizia-pubblica-e-privata\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/pastena\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Selezione pubblica per il conferimento dell&#8217;incarico di istruttore direttivo tecnico settore lavori pubblici, ambiente, urbanistica, manutenzione, edilizia pubblica e privata","datePublished":"2023-10-13T11:45:34+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pastena\/2023\/10\/13\/selezione-pubblica-per-il-conferimento-dellincarico-di-istruttore-direttivo-tecnico-settore-lavori-pubblici-ambiente-urbanistica-manutenzione-edilizia-pubblica-e-privata\/"},"wordCount":87,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/pastena\/#organization"},"articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pastena\/2023\/10\/13\/selezione-pubblica-per-il-conferimento-dellincarico-di-istruttore-direttivo-tecnico-settore-lavori-pubblici-ambiente-urbanistica-manutenzione-edilizia-pubblica-e-privata\/","url":"https:\/\/comunicacity.net\/pastena\/2023\/10\/13\/selezione-pubblica-per-il-conferimento-dellincarico-di-istruttore-direttivo-tecnico-settore-lavori-pubblici-ambiente-urbanistica-manutenzione-edilizia-pubblica-e-privata\/","name":"Selezione pubblica per il conferimento dell'incarico di istruttore direttivo tecnico settore lavori pubblici, ambiente, urbanistica, manutenzione, edilizia pubblica e privata - Pastena","isPartOf":{"@id":"https:\/\/comunicacity.net\/pastena\/#website"},"datePublished":"2023-10-13T11:45:34+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/pastena\/2023\/10\/13\/selezione-pubblica-per-il-conferimento-dellincarico-di-istruttore-direttivo-tecnico-settore-lavori-pubblici-ambiente-urbanistica-manutenzione-edilizia-pubblica-e-privata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pastena\/2023\/10\/13\/selezione-pubblica-per-il-conferimento-dellincarico-di-istruttore-direttivo-tecnico-settore-lavori-pubblici-ambiente-urbanistica-manutenzione-edilizia-pubblica-e-privata\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pastena\/2023\/10\/13\/selezione-pubblica-per-il-conferimento-dellincarico-di-istruttore-direttivo-tecnico-settore-lavori-pubblici-ambiente-urbanistica-manutenzione-edilizia-pubblica-e-privata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pastena\/"},{"@type":"ListItem","position":2,"name":"Selezione pubblica per il conferimento dell&#8217;incarico di istruttore direttivo tecnico settore lavori pubblici, ambiente, urbanistica, manutenzione, edilizia pubblica e privata"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pastena\/#website","url":"https:\/\/comunicacity.net\/pastena\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/pastena\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pastena\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/pastena\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/pastena\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pastena\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/pastena\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pastena\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"0000894"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pastena\/wp-json\/wp\/v2\/posts\/52","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pastena\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pastena\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pastena\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pastena\/wp-json\/wp\/v2\/comments?post=52"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/pastena\/wp-json\/wp\/v2\/posts\/52\/revisions"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pastena\/wp-json\/wp\/v2\/media?parent=52"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pastena\/wp-json\/wp\/v2\/categories?post=52"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pastena\/wp-json\/wp\/v2\/tags?post=52"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}