{"id":374,"date":"2016-07-13T13:17:46","date_gmt":"2016-07-13T11:17:46","guid":{"rendered":"https:\/\/comunicacity.net\/pescopennataro\/?post_type=info&#038;p=374"},"modified":"2021-04-30T15:06:24","modified_gmt":"2021-04-30T13:06:24","slug":"info-generali","status":"publish","type":"info","link":"https:\/\/comunicacity.net\/pescopennataro\/info\/info-generali\/","title":{"rendered":"Info generali"},"content":{"rendered":"<div class=\"list\">\n<div class=\"item\">\n<p>Provincia<\/p>\n<h2 class=\"ccBold\">Isernia<\/h2>\n<\/div>\n<div class=\"item\">\n<p>Regione<\/p>\n<h2 class=\"ccBold\">Molise<\/h2>\n<\/div>\n<div class=\"item\">\n<p>Popolazione Residente<\/p>\n<h2 class=\"ccBold\"><b>289<\/b><\/h2>\n<\/div>\n<div class=\"item\">\n<p>CAP<\/p>\n<h2 class=\"ccBold\"><b>86080<\/b><\/h2>\n<\/div>\n<div class=\"item\">\n<p>Prefisso Telefonico<\/p>\n<h2 class=\"ccBold\"><b>0865<\/b><\/h2>\n<\/div>\n<div class=\"item\">\n<p>Denominazione Abitanti<\/p>\n<h2 class=\"ccBold\"><b>Pescolani<\/b><\/h2>\n<\/div>\n<div class=\"item\">\n<p>Santo Patrono<\/p>\n<h2 class=\"ccBold\"><b>San Rocco<\/b><\/h2>\n<\/div>\n<div class=\"item\">\n<p>Festa Patronale<\/p>\n<h2 class=\"ccBold\"><b>16 agosto<\/b><\/h2>\n<\/div>\n<div class=\"item\">\n<p>Giorno di Mercato Settimanale<\/p>\n<h2 class=\"ccBold\"><\/h2>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Provincia Isernia Regione Molise Popolazione Residente 289 CAP 86080 Prefisso Telefonico 0865 Denominazione Abitanti Pescolani Santo Patrono San Rocco Festa Patronale 16 agosto Giorno di Mercato Settimanale<\/p>\n","protected":false},"featured_media":3,"parent":0,"menu_order":1,"template":"","meta":[],"class_list":["post-374","info","type-info","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Info generali - Pescopennataro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pescopennataro\/info\/info-generali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Info generali - Pescopennataro\" \/>\n<meta property=\"og:description\" content=\"Provincia Isernia Regione Molise Popolazione Residente 289 CAP 86080 Prefisso Telefonico 0865 Denominazione Abitanti Pescolani Santo Patrono San Rocco Festa Patronale 16 agosto Giorno di Mercato Settimanale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pescopennataro\/info\/info-generali\/\" \/>\n<meta property=\"og:site_name\" content=\"Pescopennataro\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-30T13:06:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2014\/12\/pescopennataro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/info\\\/info-generali\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/info\\\/info-generali\\\/\",\"name\":\"Info generali - Pescopennataro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/info\\\/info-generali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/info\\\/info-generali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2014\\\/12\\\/pescopennataro.jpg\",\"datePublished\":\"2016-07-13T11:17:46+00:00\",\"dateModified\":\"2021-04-30T13:06:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/info\\\/info-generali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/info\\\/info-generali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/info\\\/info-generali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2014\\\/12\\\/pescopennataro.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2014\\\/12\\\/pescopennataro.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/info\\\/info-generali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Info generali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/\",\"name\":\"Pescopennataro\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Info generali - Pescopennataro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pescopennataro\/info\/info-generali\/","og_locale":"it_IT","og_type":"article","og_title":"Info generali - Pescopennataro","og_description":"Provincia Isernia Regione Molise Popolazione Residente 289 CAP 86080 Prefisso Telefonico 0865 Denominazione Abitanti Pescolani Santo Patrono San Rocco Festa Patronale 16 agosto Giorno di Mercato Settimanale","og_url":"https:\/\/comunicacity.net\/pescopennataro\/info\/info-generali\/","og_site_name":"Pescopennataro","article_modified_time":"2021-04-30T13:06:24+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2014\/12\/pescopennataro.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pescopennataro\/info\/info-generali\/","url":"https:\/\/comunicacity.net\/pescopennataro\/info\/info-generali\/","name":"Info generali - Pescopennataro","isPartOf":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/info\/info-generali\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/info\/info-generali\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2014\/12\/pescopennataro.jpg","datePublished":"2016-07-13T11:17:46+00:00","dateModified":"2021-04-30T13:06:24+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/info\/info-generali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pescopennataro\/info\/info-generali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pescopennataro\/info\/info-generali\/#primaryimage","url":"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2014\/12\/pescopennataro.jpg","contentUrl":"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2014\/12\/pescopennataro.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pescopennataro\/info\/info-generali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pescopennataro\/"},{"@type":"ListItem","position":2,"name":"Info generali"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pescopennataro\/#website","url":"https:\/\/comunicacity.net\/pescopennataro\/","name":"Pescopennataro","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pescopennataro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/info\/374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/info"}],"about":[{"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/types\/info"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/media\/3"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/media?parent=374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}