{"id":481,"date":"2020-02-22T18:59:04","date_gmt":"2020-02-22T16:59:04","guid":{"rendered":"https:\/\/comunicacity.net\/pescopennataro\/?p=481"},"modified":"2020-02-22T19:12:18","modified_gmt":"2020-02-22T17:12:18","slug":"coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pescopennataro\/2020\/02\/22\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\/","title":{"rendered":"Coronavirus Covid-19, obbligo di comunicazione anche per quanti provengano dalle aree italiane interessate dall&#8217;epidemia o vi abbiano soggiornato negli ultimi 14 giorni"},"content":{"rendered":"<p>Su informativa della <acronym title=\"Azienda Sanitaria Regionale del Molise\">ASREM<\/acronym>, si rende noto che il Ministero della salute ha emanato, in data 21 febbraio 2020, un&#8217;ulteriore Ordinanza con la quale\u00a0 si precisa che:<br \/>\n&#8211; &#8220;per tutti gli individui che, negli ultimi quattordici giorni, abbiano fatto ingresso in Italia dopo aver soggiornato nelle aree della Cina interessate dall&#8217;epidemia, come identificate dall&#8217;Organizzazione Mondiale della Sanit\u00e0;<br \/>\n&#8211; l&#8217;Autorit\u00e0 sanitaria territorialmente competente provveder\u00e0 all&#8217;adozione della misura della permanenza domiciliare fiduciaria con sorveglianza attiva ovvero, in presenza di condizioni ostative, di misure alternative di efficacia equivalente;<br \/>\n&#8211; vige l&#8217;obbligo di comunicare al Dipartimento di prevenzione dell&#8217;Azienda sanitaria territorialmente competente di aver soggiornato nelle aree suddette.<br \/>\nIl mancato rispetto delle misure previste costituir\u00e0 una violazione dell&#8217;Ordinanza&#8221;.<br \/>\nA\u00a0 seguito degli ultimi avvenimenti che hanno portato alla identificazione del primo caso di infezione Covid-19 acquisito in Italia e, quindi, della individuazione di aree ritenute interessate dall&#8217;epidemia di infezione da nuovo coronavirus in Lombardia e in Veneto, la stessa disposizione si applica agli individui provenienti dalle aree attualmente sottoposte a cordone sanitario delle regioni italiane coinvolte.<br \/>\nPertanto, i soggetti provenienti da tali aree, o che vi abbiano soggiornato negli ultimi 14 giorni e giungano in Molise per motivi di lavoro, di studio, familiari o per qualunque altra ragione, sono tenuti a comunicare la loro presenza sul territorio all&#8217;Autorit\u00e0 sanitaria locale, che provveder\u00e0 a mettere in atto le adeguate misure di prevenzione della diffusione del virus.<br \/>\nLa segnalazione potr\u00e0 essere effettuata al proprio medico curante, al numero del Ministero della salute 1500, al numero del Sistema territoriale 118,\u00a0 cui sar\u00e0 fornito un numero di telefono corrispondente al Servizio di medicina pubblica che avvier\u00e0 la procedura.<br \/>\nInoltre, i medici di medicina generale, i pediatri di libera scelta, i medici di continuit\u00e0 assistenziale che hanno gi\u00e0 ricevuto le istruzioni operative per la gestione del caso sospetto e dei contatti (con comunicazioni successive dell&#8217;<acronym title=\"Azienda Sanitaria Regionale del Molise\">ASREM<\/acronym>, a partire dal 31.01.2020),\u00a0 sono tenuti a consultare costantemente il sito dell&#8217;Azienda Sanitaria Locale per tutti gli aggiornamenti che saranno necessari in rapporto all&#8217;evolversi degli aspetti clinici ed epidemiologici dell&#8217;infezione in corso.<br \/>\nGli eventuali casi posti in isolamento saranno presi in carico anche dalla Protezione civile per tutti i fabbisogni, quali fornitura di alimenti, farmaci etc..<br \/>\nSi confida nel massimo senso di responsabilit\u00e0 dei molisani che, anche al solo sospetto, segnalino alle autorit\u00e0 eventuali contatti con i focolai nazionali ed internazionali.<\/p>\n<p>&nbsp;<\/p>\n<p>Di seguito il link:<\/p>\n<p>http:\/\/www3.regione.molise.it\/flex\/cm\/pages\/ServeBLOB.php\/L\/IT\/IDPagina\/17080<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_483\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2020\/02\/PIEGHEVOLE-CORONAVIRUS.pdf.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2020\/02\/PIEGHEVOLE-CORONAVIRUS.pdf.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>PIEGHEVOLE-CORONAVIRUS.pdf<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Su informativa della ASREM, si rende noto che il Ministero della salute ha emanato, in data 21 febbraio 2020, un&#8217;ulteriore Ordinanza con la quale\u00a0 si precisa che: &#8211; &#8220;per tutti [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":103,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coronavirus Covid-19, obbligo di comunicazione anche per quanti provengano dalle aree italiane interessate dall&#039;epidemia o vi abbiano soggiornato negli ultimi 14 giorni - Pescopennataro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pescopennataro\/2020\/02\/22\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coronavirus Covid-19, obbligo di comunicazione anche per quanti provengano dalle aree italiane interessate dall&#039;epidemia o vi abbiano soggiornato negli ultimi 14 giorni - Pescopennataro\" \/>\n<meta property=\"og:description\" content=\"Su informativa della ASREM, si rende noto che il Ministero della salute ha emanato, in data 21 febbraio 2020, un&#8217;ulteriore Ordinanza con la quale\u00a0 si precisa che: &#8211; &#8220;per tutti [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pescopennataro\/2020\/02\/22\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\/\" \/>\n<meta property=\"og:site_name\" content=\"Pescopennataro\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-22T16:59:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-22T17:12:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2015\/01\/regione-molise.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"316\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pompiliosciulli\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pompiliosciulli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2020\\\/02\\\/22\\\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2020\\\/02\\\/22\\\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\\\/\"},\"author\":{\"name\":\"pompiliosciulli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/#\\\/schema\\\/person\\\/bf4ac27d366a2605a669ff8c0eeec8bb\"},\"headline\":\"Coronavirus Covid-19, obbligo di comunicazione anche per quanti provengano dalle aree italiane interessate dall&#8217;epidemia o vi abbiano soggiornato negli ultimi 14 giorni\",\"datePublished\":\"2020-02-22T16:59:04+00:00\",\"dateModified\":\"2020-02-22T17:12:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2020\\\/02\\\/22\\\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\\\/\"},\"wordCount\":419,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2020\\\/02\\\/22\\\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2015\\\/01\\\/regione-molise.jpg\",\"articleSection\":[\"Sanit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2020\\\/02\\\/22\\\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2020\\\/02\\\/22\\\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\\\/\",\"name\":\"Coronavirus Covid-19, obbligo di comunicazione anche per quanti provengano dalle aree italiane interessate dall'epidemia o vi abbiano soggiornato negli ultimi 14 giorni - Pescopennataro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2020\\\/02\\\/22\\\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2020\\\/02\\\/22\\\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2015\\\/01\\\/regione-molise.jpg\",\"datePublished\":\"2020-02-22T16:59:04+00:00\",\"dateModified\":\"2020-02-22T17:12:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/#\\\/schema\\\/person\\\/bf4ac27d366a2605a669ff8c0eeec8bb\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2020\\\/02\\\/22\\\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2020\\\/02\\\/22\\\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2020\\\/02\\\/22\\\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2015\\\/01\\\/regione-molise.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2015\\\/01\\\/regione-molise.jpg\",\"width\":316,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2020\\\/02\\\/22\\\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coronavirus Covid-19, obbligo di comunicazione anche per quanti provengano dalle aree italiane interessate dall&#8217;epidemia o vi abbiano soggiornato negli ultimi 14 giorni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/\",\"name\":\"Pescopennataro\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/#\\\/schema\\\/person\\\/bf4ac27d366a2605a669ff8c0eeec8bb\",\"name\":\"pompiliosciulli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14005fcc88e3884b0ddbdc7c096db97a44cb3df6f7792be7d4bacd205a30ee42?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14005fcc88e3884b0ddbdc7c096db97a44cb3df6f7792be7d4bacd205a30ee42?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14005fcc88e3884b0ddbdc7c096db97a44cb3df6f7792be7d4bacd205a30ee42?s=96&d=mm&r=g\",\"caption\":\"pompiliosciulli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/author\\\/pompiliosciulli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coronavirus Covid-19, obbligo di comunicazione anche per quanti provengano dalle aree italiane interessate dall'epidemia o vi abbiano soggiornato negli ultimi 14 giorni - Pescopennataro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pescopennataro\/2020\/02\/22\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\/","og_locale":"it_IT","og_type":"article","og_title":"Coronavirus Covid-19, obbligo di comunicazione anche per quanti provengano dalle aree italiane interessate dall'epidemia o vi abbiano soggiornato negli ultimi 14 giorni - Pescopennataro","og_description":"Su informativa della ASREM, si rende noto che il Ministero della salute ha emanato, in data 21 febbraio 2020, un&#8217;ulteriore Ordinanza con la quale\u00a0 si precisa che: &#8211; &#8220;per tutti [&hellip;]","og_url":"https:\/\/comunicacity.net\/pescopennataro\/2020\/02\/22\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\/","og_site_name":"Pescopennataro","article_published_time":"2020-02-22T16:59:04+00:00","article_modified_time":"2020-02-22T17:12:18+00:00","og_image":[{"width":316,"height":400,"url":"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2015\/01\/regione-molise.jpg","type":"image\/jpeg"}],"author":"pompiliosciulli","twitter_misc":{"Scritto da":"pompiliosciulli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pescopennataro\/2020\/02\/22\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/2020\/02\/22\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\/"},"author":{"name":"pompiliosciulli","@id":"https:\/\/comunicacity.net\/pescopennataro\/#\/schema\/person\/bf4ac27d366a2605a669ff8c0eeec8bb"},"headline":"Coronavirus Covid-19, obbligo di comunicazione anche per quanti provengano dalle aree italiane interessate dall&#8217;epidemia o vi abbiano soggiornato negli ultimi 14 giorni","datePublished":"2020-02-22T16:59:04+00:00","dateModified":"2020-02-22T17:12:18+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/2020\/02\/22\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\/"},"wordCount":419,"image":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/2020\/02\/22\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2015\/01\/regione-molise.jpg","articleSection":["Sanit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pescopennataro\/2020\/02\/22\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\/","url":"https:\/\/comunicacity.net\/pescopennataro\/2020\/02\/22\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\/","name":"Coronavirus Covid-19, obbligo di comunicazione anche per quanti provengano dalle aree italiane interessate dall'epidemia o vi abbiano soggiornato negli ultimi 14 giorni - Pescopennataro","isPartOf":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/2020\/02\/22\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/2020\/02\/22\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2015\/01\/regione-molise.jpg","datePublished":"2020-02-22T16:59:04+00:00","dateModified":"2020-02-22T17:12:18+00:00","author":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/#\/schema\/person\/bf4ac27d366a2605a669ff8c0eeec8bb"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/2020\/02\/22\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pescopennataro\/2020\/02\/22\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pescopennataro\/2020\/02\/22\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\/#primaryimage","url":"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2015\/01\/regione-molise.jpg","contentUrl":"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2015\/01\/regione-molise.jpg","width":316,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pescopennataro\/2020\/02\/22\/coronavirus-covid-19-obbligo-di-comunicazione-anche-per-quanti-provengano-dalle-aree-italiane-interessate-dallepidemia-o-vi-abbiano-soggiornato-negli-ultimi-14-giorni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pescopennataro\/"},{"@type":"ListItem","position":2,"name":"Coronavirus Covid-19, obbligo di comunicazione anche per quanti provengano dalle aree italiane interessate dall&#8217;epidemia o vi abbiano soggiornato negli ultimi 14 giorni"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pescopennataro\/#website","url":"https:\/\/comunicacity.net\/pescopennataro\/","name":"Pescopennataro","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pescopennataro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pescopennataro\/#\/schema\/person\/bf4ac27d366a2605a669ff8c0eeec8bb","name":"pompiliosciulli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/14005fcc88e3884b0ddbdc7c096db97a44cb3df6f7792be7d4bacd205a30ee42?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/14005fcc88e3884b0ddbdc7c096db97a44cb3df6f7792be7d4bacd205a30ee42?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14005fcc88e3884b0ddbdc7c096db97a44cb3df6f7792be7d4bacd205a30ee42?s=96&d=mm&r=g","caption":"pompiliosciulli"},"url":"https:\/\/comunicacity.net\/pescopennataro\/author\/pompiliosciulli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/posts\/481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/comments?post=481"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/posts\/481\/revisions"}],"predecessor-version":[{"id":482,"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/posts\/481\/revisions\/482"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/media\/103"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/media?parent=481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/categories?post=481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/tags?post=481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}