{"id":553,"date":"2020-07-17T12:51:55","date_gmt":"2020-07-17T10:51:55","guid":{"rendered":"https:\/\/comunicacity.net\/pescopennataro\/?p=553"},"modified":"2020-07-17T12:51:55","modified_gmt":"2020-07-17T10:51:55","slug":"allerta-meteo-protezione-civile","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pescopennataro\/2020\/07\/17\/allerta-meteo-protezione-civile\/","title":{"rendered":"Allerta Meteo Protezione Civile"},"content":{"rendered":"<p>Si avvisa la cittadinanza che nelle prossime ore sono previsti temporali di forte intensit\u00e0, con fulmini e grandine.<\/p>\n<p>Si raccomanda di fare molta attenzione, evitando di uscire di casa e di mettersi in viaggio per lo stato scivoloso del manto stradale e per le forti riduzioni di visibilit\u00e0.<\/p>\n<p>In allegato l\u2019avviso protocollo 114228\/2020 del 16 luglio 2020, della Regione Molise, IV Dipartimento, Servizio Protezione Civile.<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_554\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2020\/07\/Avviso-allerta-meteo.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2020\/07\/Avviso-allerta-meteo.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Avviso-allerta-meteo<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si avvisa la cittadinanza che nelle prossime ore sono previsti temporali di forte intensit\u00e0, con fulmini e grandine. Si raccomanda di fare molta attenzione, evitando di uscire di casa e [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":3,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-553","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-urgenze-e-allerta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Allerta Meteo Protezione Civile - Pescopennataro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pescopennataro\/2020\/07\/17\/allerta-meteo-protezione-civile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Allerta Meteo Protezione Civile - Pescopennataro\" \/>\n<meta property=\"og:description\" content=\"Si avvisa la cittadinanza che nelle prossime ore sono previsti temporali di forte intensit\u00e0, con fulmini e grandine. Si raccomanda di fare molta attenzione, evitando di uscire di casa e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pescopennataro\/2020\/07\/17\/allerta-meteo-protezione-civile\/\" \/>\n<meta property=\"og:site_name\" content=\"Pescopennataro\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-17T10:51:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2014\/12\/pescopennataro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pompiliosciulli\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pompiliosciulli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2020\\\/07\\\/17\\\/allerta-meteo-protezione-civile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2020\\\/07\\\/17\\\/allerta-meteo-protezione-civile\\\/\"},\"author\":{\"name\":\"pompiliosciulli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/#\\\/schema\\\/person\\\/bf4ac27d366a2605a669ff8c0eeec8bb\"},\"headline\":\"Allerta Meteo Protezione Civile\",\"datePublished\":\"2020-07-17T10:51:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2020\\\/07\\\/17\\\/allerta-meteo-protezione-civile\\\/\"},\"wordCount\":67,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2020\\\/07\\\/17\\\/allerta-meteo-protezione-civile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2014\\\/12\\\/pescopennataro.jpg\",\"articleSection\":[\"Urgenze e Allerta\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2020\\\/07\\\/17\\\/allerta-meteo-protezione-civile\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2020\\\/07\\\/17\\\/allerta-meteo-protezione-civile\\\/\",\"name\":\"Allerta Meteo Protezione Civile - Pescopennataro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2020\\\/07\\\/17\\\/allerta-meteo-protezione-civile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2020\\\/07\\\/17\\\/allerta-meteo-protezione-civile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2014\\\/12\\\/pescopennataro.jpg\",\"datePublished\":\"2020-07-17T10:51:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/#\\\/schema\\\/person\\\/bf4ac27d366a2605a669ff8c0eeec8bb\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2020\\\/07\\\/17\\\/allerta-meteo-protezione-civile\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2020\\\/07\\\/17\\\/allerta-meteo-protezione-civile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2020\\\/07\\\/17\\\/allerta-meteo-protezione-civile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2014\\\/12\\\/pescopennataro.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2014\\\/12\\\/pescopennataro.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2020\\\/07\\\/17\\\/allerta-meteo-protezione-civile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Allerta Meteo Protezione Civile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/\",\"name\":\"Pescopennataro\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/#\\\/schema\\\/person\\\/bf4ac27d366a2605a669ff8c0eeec8bb\",\"name\":\"pompiliosciulli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14005fcc88e3884b0ddbdc7c096db97a44cb3df6f7792be7d4bacd205a30ee42?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14005fcc88e3884b0ddbdc7c096db97a44cb3df6f7792be7d4bacd205a30ee42?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14005fcc88e3884b0ddbdc7c096db97a44cb3df6f7792be7d4bacd205a30ee42?s=96&d=mm&r=g\",\"caption\":\"pompiliosciulli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/author\\\/pompiliosciulli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Allerta Meteo Protezione Civile - Pescopennataro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pescopennataro\/2020\/07\/17\/allerta-meteo-protezione-civile\/","og_locale":"it_IT","og_type":"article","og_title":"Allerta Meteo Protezione Civile - Pescopennataro","og_description":"Si avvisa la cittadinanza che nelle prossime ore sono previsti temporali di forte intensit\u00e0, con fulmini e grandine. Si raccomanda di fare molta attenzione, evitando di uscire di casa e [&hellip;]","og_url":"https:\/\/comunicacity.net\/pescopennataro\/2020\/07\/17\/allerta-meteo-protezione-civile\/","og_site_name":"Pescopennataro","article_published_time":"2020-07-17T10:51:55+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2014\/12\/pescopennataro.jpg","type":"image\/jpeg"}],"author":"pompiliosciulli","twitter_misc":{"Scritto da":"pompiliosciulli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pescopennataro\/2020\/07\/17\/allerta-meteo-protezione-civile\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/2020\/07\/17\/allerta-meteo-protezione-civile\/"},"author":{"name":"pompiliosciulli","@id":"https:\/\/comunicacity.net\/pescopennataro\/#\/schema\/person\/bf4ac27d366a2605a669ff8c0eeec8bb"},"headline":"Allerta Meteo Protezione Civile","datePublished":"2020-07-17T10:51:55+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/2020\/07\/17\/allerta-meteo-protezione-civile\/"},"wordCount":67,"image":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/2020\/07\/17\/allerta-meteo-protezione-civile\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2014\/12\/pescopennataro.jpg","articleSection":["Urgenze e Allerta"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pescopennataro\/2020\/07\/17\/allerta-meteo-protezione-civile\/","url":"https:\/\/comunicacity.net\/pescopennataro\/2020\/07\/17\/allerta-meteo-protezione-civile\/","name":"Allerta Meteo Protezione Civile - Pescopennataro","isPartOf":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/2020\/07\/17\/allerta-meteo-protezione-civile\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/2020\/07\/17\/allerta-meteo-protezione-civile\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2014\/12\/pescopennataro.jpg","datePublished":"2020-07-17T10:51:55+00:00","author":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/#\/schema\/person\/bf4ac27d366a2605a669ff8c0eeec8bb"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/2020\/07\/17\/allerta-meteo-protezione-civile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pescopennataro\/2020\/07\/17\/allerta-meteo-protezione-civile\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pescopennataro\/2020\/07\/17\/allerta-meteo-protezione-civile\/#primaryimage","url":"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2014\/12\/pescopennataro.jpg","contentUrl":"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2014\/12\/pescopennataro.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pescopennataro\/2020\/07\/17\/allerta-meteo-protezione-civile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pescopennataro\/"},{"@type":"ListItem","position":2,"name":"Allerta Meteo Protezione Civile"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pescopennataro\/#website","url":"https:\/\/comunicacity.net\/pescopennataro\/","name":"Pescopennataro","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pescopennataro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pescopennataro\/#\/schema\/person\/bf4ac27d366a2605a669ff8c0eeec8bb","name":"pompiliosciulli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/14005fcc88e3884b0ddbdc7c096db97a44cb3df6f7792be7d4bacd205a30ee42?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/14005fcc88e3884b0ddbdc7c096db97a44cb3df6f7792be7d4bacd205a30ee42?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14005fcc88e3884b0ddbdc7c096db97a44cb3df6f7792be7d4bacd205a30ee42?s=96&d=mm&r=g","caption":"pompiliosciulli"},"url":"https:\/\/comunicacity.net\/pescopennataro\/author\/pompiliosciulli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/posts\/553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/comments?post=553"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/posts\/553\/revisions"}],"predecessor-version":[{"id":555,"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/posts\/553\/revisions\/555"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/media\/3"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/media?parent=553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/categories?post=553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/tags?post=553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}