{"id":93,"date":"2015-01-20T18:09:04","date_gmt":"2015-01-20T18:09:04","guid":{"rendered":"https:\/\/comunicacity.net\/pescopennataro\/?p=93"},"modified":"2015-01-20T18:09:04","modified_gmt":"2015-01-20T18:09:04","slug":"presentazione-raccolta-differenziata","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pescopennataro\/2015\/01\/20\/presentazione-raccolta-differenziata\/","title":{"rendered":"Presentazione raccolta differenziata"},"content":{"rendered":"<p>E&#8217; online una breve presentazione relativa al servizio di raccolta differenziata a Pescopennataro.<\/p>\n<p>I RIFIUTI SI MOLTIPLICANO. DIVIDIAMOLI!!!<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_95\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2015\/01\/Pescopennataro.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2015\/01\/Pescopennataro.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Pescopennataro<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; online una breve presentazione relativa al servizio di raccolta differenziata a Pescopennataro. I RIFIUTI SI MOLTIPLICANO. DIVIDIAMOLI!!! \ud83d\udcce AllegatiPescopennataro<\/p>\n","protected":false},"author":29,"featured_media":94,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-93","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presentazione raccolta differenziata - Pescopennataro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pescopennataro\/2015\/01\/20\/presentazione-raccolta-differenziata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentazione raccolta differenziata - Pescopennataro\" \/>\n<meta property=\"og:description\" content=\"E&#8217; online una breve presentazione relativa al servizio di raccolta differenziata a Pescopennataro. I RIFIUTI SI MOLTIPLICANO. DIVIDIAMOLI!!! \ud83d\udcce AllegatiPescopennataro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pescopennataro\/2015\/01\/20\/presentazione-raccolta-differenziata\/\" \/>\n<meta property=\"og:site_name\" content=\"Pescopennataro\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-20T18:09:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2015\/01\/download.png\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"202\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"pompiliosciulli\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pompiliosciulli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2015\\\/01\\\/20\\\/presentazione-raccolta-differenziata\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2015\\\/01\\\/20\\\/presentazione-raccolta-differenziata\\\/\"},\"author\":{\"name\":\"pompiliosciulli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/#\\\/schema\\\/person\\\/bf4ac27d366a2605a669ff8c0eeec8bb\"},\"headline\":\"Presentazione raccolta differenziata\",\"datePublished\":\"2015-01-20T18:09:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2015\\\/01\\\/20\\\/presentazione-raccolta-differenziata\\\/\"},\"wordCount\":21,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2015\\\/01\\\/20\\\/presentazione-raccolta-differenziata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2015\\\/01\\\/download.png\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2015\\\/01\\\/20\\\/presentazione-raccolta-differenziata\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2015\\\/01\\\/20\\\/presentazione-raccolta-differenziata\\\/\",\"name\":\"Presentazione raccolta differenziata - Pescopennataro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2015\\\/01\\\/20\\\/presentazione-raccolta-differenziata\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2015\\\/01\\\/20\\\/presentazione-raccolta-differenziata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2015\\\/01\\\/download.png\",\"datePublished\":\"2015-01-20T18:09:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/#\\\/schema\\\/person\\\/bf4ac27d366a2605a669ff8c0eeec8bb\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2015\\\/01\\\/20\\\/presentazione-raccolta-differenziata\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2015\\\/01\\\/20\\\/presentazione-raccolta-differenziata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2015\\\/01\\\/20\\\/presentazione-raccolta-differenziata\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2015\\\/01\\\/download.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2015\\\/01\\\/download.png\",\"width\":240,\"height\":202},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/2015\\\/01\\\/20\\\/presentazione-raccolta-differenziata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentazione raccolta differenziata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/\",\"name\":\"Pescopennataro\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/#\\\/schema\\\/person\\\/bf4ac27d366a2605a669ff8c0eeec8bb\",\"name\":\"pompiliosciulli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14005fcc88e3884b0ddbdc7c096db97a44cb3df6f7792be7d4bacd205a30ee42?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14005fcc88e3884b0ddbdc7c096db97a44cb3df6f7792be7d4bacd205a30ee42?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14005fcc88e3884b0ddbdc7c096db97a44cb3df6f7792be7d4bacd205a30ee42?s=96&d=mm&r=g\",\"caption\":\"pompiliosciulli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/pescopennataro\\\/author\\\/pompiliosciulli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentazione raccolta differenziata - Pescopennataro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pescopennataro\/2015\/01\/20\/presentazione-raccolta-differenziata\/","og_locale":"it_IT","og_type":"article","og_title":"Presentazione raccolta differenziata - Pescopennataro","og_description":"E&#8217; online una breve presentazione relativa al servizio di raccolta differenziata a Pescopennataro. I RIFIUTI SI MOLTIPLICANO. DIVIDIAMOLI!!! \ud83d\udcce AllegatiPescopennataro","og_url":"https:\/\/comunicacity.net\/pescopennataro\/2015\/01\/20\/presentazione-raccolta-differenziata\/","og_site_name":"Pescopennataro","article_published_time":"2015-01-20T18:09:04+00:00","og_image":[{"width":240,"height":202,"url":"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2015\/01\/download.png","type":"image\/png"}],"author":"pompiliosciulli","twitter_misc":{"Scritto da":"pompiliosciulli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pescopennataro\/2015\/01\/20\/presentazione-raccolta-differenziata\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/2015\/01\/20\/presentazione-raccolta-differenziata\/"},"author":{"name":"pompiliosciulli","@id":"https:\/\/comunicacity.net\/pescopennataro\/#\/schema\/person\/bf4ac27d366a2605a669ff8c0eeec8bb"},"headline":"Presentazione raccolta differenziata","datePublished":"2015-01-20T18:09:04+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/2015\/01\/20\/presentazione-raccolta-differenziata\/"},"wordCount":21,"image":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/2015\/01\/20\/presentazione-raccolta-differenziata\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2015\/01\/download.png","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pescopennataro\/2015\/01\/20\/presentazione-raccolta-differenziata\/","url":"https:\/\/comunicacity.net\/pescopennataro\/2015\/01\/20\/presentazione-raccolta-differenziata\/","name":"Presentazione raccolta differenziata - Pescopennataro","isPartOf":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/2015\/01\/20\/presentazione-raccolta-differenziata\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/2015\/01\/20\/presentazione-raccolta-differenziata\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2015\/01\/download.png","datePublished":"2015-01-20T18:09:04+00:00","author":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/#\/schema\/person\/bf4ac27d366a2605a669ff8c0eeec8bb"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/pescopennataro\/2015\/01\/20\/presentazione-raccolta-differenziata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pescopennataro\/2015\/01\/20\/presentazione-raccolta-differenziata\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pescopennataro\/2015\/01\/20\/presentazione-raccolta-differenziata\/#primaryimage","url":"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2015\/01\/download.png","contentUrl":"https:\/\/comunicacity.net\/pescopennataro\/wp-content\/uploads\/sites\/18\/2015\/01\/download.png","width":240,"height":202},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pescopennataro\/2015\/01\/20\/presentazione-raccolta-differenziata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pescopennataro\/"},{"@type":"ListItem","position":2,"name":"Presentazione raccolta differenziata"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pescopennataro\/#website","url":"https:\/\/comunicacity.net\/pescopennataro\/","name":"Pescopennataro","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pescopennataro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pescopennataro\/#\/schema\/person\/bf4ac27d366a2605a669ff8c0eeec8bb","name":"pompiliosciulli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/14005fcc88e3884b0ddbdc7c096db97a44cb3df6f7792be7d4bacd205a30ee42?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/14005fcc88e3884b0ddbdc7c096db97a44cb3df6f7792be7d4bacd205a30ee42?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14005fcc88e3884b0ddbdc7c096db97a44cb3df6f7792be7d4bacd205a30ee42?s=96&d=mm&r=g","caption":"pompiliosciulli"},"url":"https:\/\/comunicacity.net\/pescopennataro\/author\/pompiliosciulli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/posts\/93","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/comments?post=93"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/posts\/93\/revisions"}],"predecessor-version":[{"id":96,"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/posts\/93\/revisions\/96"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/media\/94"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/media?parent=93"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/categories?post=93"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pescopennataro\/wp-json\/wp\/v2\/tags?post=93"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}