{"id":3423,"date":"2024-08-29T08:50:05","date_gmt":"2024-08-29T06:50:05","guid":{"rendered":"https:\/\/comunicacity.net\/piansano\/?p=3423"},"modified":"2024-08-29T08:50:05","modified_gmt":"2024-08-29T06:50:05","slug":"avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/piansano\/2024\/08\/29\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\/","title":{"rendered":"AVVISO per la concessione del rimborso totale dell&#8217;abbonamento trasporto di linea agli studenti della scuola secondaria di II grado residenti a Piansano AS 2024\/2025"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3424\" src=\"https:\/\/comunicacity.net\/piansano\/wp-content\/uploads\/sites\/56\/2024\/08\/Bachece-A3abbonamento-cotral-20241_page-0001.jpg\" alt=\"\" width=\"1755\" height=\"2481\" srcset=\"https:\/\/comunicacity.net\/piansano\/wp-content\/uploads\/sites\/56\/2024\/08\/Bachece-A3abbonamento-cotral-20241_page-0001.jpg 1755w, https:\/\/comunicacity.net\/piansano\/wp-content\/uploads\/sites\/56\/2024\/08\/Bachece-A3abbonamento-cotral-20241_page-0001-768x1086.jpg 768w, https:\/\/comunicacity.net\/piansano\/wp-content\/uploads\/sites\/56\/2024\/08\/Bachece-A3abbonamento-cotral-20241_page-0001-1087x1536.jpg 1087w, https:\/\/comunicacity.net\/piansano\/wp-content\/uploads\/sites\/56\/2024\/08\/Bachece-A3abbonamento-cotral-20241_page-0001-1449x2048.jpg 1449w\" sizes=\"auto, (max-width: 1755px) 100vw, 1755px\" \/><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_3426\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/piansano\/wp-content\/uploads\/sites\/56\/2024\/08\/avviso.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/piansano\/wp-content\/uploads\/sites\/56\/2024\/08\/avviso.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>avviso<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcce Allegatiavviso<\/p>\n","protected":false},"author":107,"featured_media":3425,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-concorsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AVVISO per la concessione del rimborso totale dell&#039;abbonamento trasporto di linea agli studenti della scuola secondaria di II grado residenti a Piansano AS 2024\/2025 - Piansano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/piansano\/2024\/08\/29\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AVVISO per la concessione del rimborso totale dell&#039;abbonamento trasporto di linea agli studenti della scuola secondaria di II grado residenti a Piansano AS 2024\/2025 - Piansano\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udcce Allegatiavviso\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/piansano\/2024\/08\/29\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Piansano\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-29T06:50:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/piansano\/wp-content\/uploads\/sites\/56\/2024\/08\/20-102514-22-00.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"797\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Polizia Municipale Piansano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Polizia Municipale Piansano\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/2024\\\/08\\\/29\\\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/2024\\\/08\\\/29\\\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\\\/\"},\"author\":{\"name\":\"Polizia Municipale Piansano\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/#\\\/schema\\\/person\\\/0aa8a50e19c21a9eb51f37c37a2d2423\"},\"headline\":\"AVVISO per la concessione del rimborso totale dell&#8217;abbonamento trasporto di linea agli studenti della scuola secondaria di II grado residenti a Piansano AS 2024\\\/2025\",\"datePublished\":\"2024-08-29T06:50:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/2024\\\/08\\\/29\\\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\\\/\"},\"wordCount\":23,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/2024\\\/08\\\/29\\\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/08\\\/20-102514-22-00.jpg\",\"articleSection\":[\"Bandi e Concorsi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/2024\\\/08\\\/29\\\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/2024\\\/08\\\/29\\\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\\\/\",\"name\":\"AVVISO per la concessione del rimborso totale dell'abbonamento trasporto di linea agli studenti della scuola secondaria di II grado residenti a Piansano AS 2024\\\/2025 - Piansano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/2024\\\/08\\\/29\\\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/2024\\\/08\\\/29\\\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/08\\\/20-102514-22-00.jpg\",\"datePublished\":\"2024-08-29T06:50:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/#\\\/schema\\\/person\\\/0aa8a50e19c21a9eb51f37c37a2d2423\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/2024\\\/08\\\/29\\\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/2024\\\/08\\\/29\\\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/2024\\\/08\\\/29\\\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/08\\\/20-102514-22-00.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/wp-content\\\/uploads\\\/sites\\\/56\\\/2024\\\/08\\\/20-102514-22-00.jpg\",\"width\":1200,\"height\":797},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/2024\\\/08\\\/29\\\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVVISO per la concessione del rimborso totale dell&#8217;abbonamento trasporto di linea agli studenti della scuola secondaria di II grado residenti a Piansano AS 2024\\\/2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/\",\"name\":\"Piansano\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/#\\\/schema\\\/person\\\/0aa8a50e19c21a9eb51f37c37a2d2423\",\"name\":\"Polizia Municipale Piansano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/790937e1f48aad6bb24d80ce54056543aee024360bc52b9e6e0cbc95ec9b277c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/790937e1f48aad6bb24d80ce54056543aee024360bc52b9e6e0cbc95ec9b277c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/790937e1f48aad6bb24d80ce54056543aee024360bc52b9e6e0cbc95ec9b277c?s=96&d=mm&r=g\",\"caption\":\"Polizia Municipale Piansano\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/piansano\\\/author\\\/pmunicipalepainsano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AVVISO per la concessione del rimborso totale dell'abbonamento trasporto di linea agli studenti della scuola secondaria di II grado residenti a Piansano AS 2024\/2025 - Piansano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/piansano\/2024\/08\/29\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\/","og_locale":"it_IT","og_type":"article","og_title":"AVVISO per la concessione del rimborso totale dell'abbonamento trasporto di linea agli studenti della scuola secondaria di II grado residenti a Piansano AS 2024\/2025 - Piansano","og_description":"\ud83d\udcce Allegatiavviso","og_url":"https:\/\/comunicacity.net\/piansano\/2024\/08\/29\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\/","og_site_name":"Piansano","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-08-29T06:50:05+00:00","og_image":[{"width":1200,"height":797,"url":"https:\/\/comunicacity.net\/piansano\/wp-content\/uploads\/sites\/56\/2024\/08\/20-102514-22-00.jpg","type":"image\/jpeg"}],"author":"Polizia Municipale Piansano","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Polizia Municipale Piansano"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/piansano\/2024\/08\/29\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/piansano\/2024\/08\/29\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\/"},"author":{"name":"Polizia Municipale Piansano","@id":"https:\/\/comunicacity.net\/piansano\/#\/schema\/person\/0aa8a50e19c21a9eb51f37c37a2d2423"},"headline":"AVVISO per la concessione del rimborso totale dell&#8217;abbonamento trasporto di linea agli studenti della scuola secondaria di II grado residenti a Piansano AS 2024\/2025","datePublished":"2024-08-29T06:50:05+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/piansano\/2024\/08\/29\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\/"},"wordCount":23,"image":{"@id":"https:\/\/comunicacity.net\/piansano\/2024\/08\/29\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/piansano\/wp-content\/uploads\/sites\/56\/2024\/08\/20-102514-22-00.jpg","articleSection":["Bandi e Concorsi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/piansano\/2024\/08\/29\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\/","url":"https:\/\/comunicacity.net\/piansano\/2024\/08\/29\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\/","name":"AVVISO per la concessione del rimborso totale dell'abbonamento trasporto di linea agli studenti della scuola secondaria di II grado residenti a Piansano AS 2024\/2025 - Piansano","isPartOf":{"@id":"https:\/\/comunicacity.net\/piansano\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/piansano\/2024\/08\/29\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/piansano\/2024\/08\/29\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/piansano\/wp-content\/uploads\/sites\/56\/2024\/08\/20-102514-22-00.jpg","datePublished":"2024-08-29T06:50:05+00:00","author":{"@id":"https:\/\/comunicacity.net\/piansano\/#\/schema\/person\/0aa8a50e19c21a9eb51f37c37a2d2423"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/piansano\/2024\/08\/29\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/piansano\/2024\/08\/29\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/piansano\/2024\/08\/29\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\/#primaryimage","url":"https:\/\/comunicacity.net\/piansano\/wp-content\/uploads\/sites\/56\/2024\/08\/20-102514-22-00.jpg","contentUrl":"https:\/\/comunicacity.net\/piansano\/wp-content\/uploads\/sites\/56\/2024\/08\/20-102514-22-00.jpg","width":1200,"height":797},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/piansano\/2024\/08\/29\/avviso-per-la-concessione-del-rimborso-totale-dellabbonamento-trasporto-di-linea-agli-studenti-della-scuola-secondaria-di-ii-grado-residenti-a-piansano-as-2024-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/piansano\/"},{"@type":"ListItem","position":2,"name":"AVVISO per la concessione del rimborso totale dell&#8217;abbonamento trasporto di linea agli studenti della scuola secondaria di II grado residenti a Piansano AS 2024\/2025"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/piansano\/#website","url":"https:\/\/comunicacity.net\/piansano\/","name":"Piansano","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/piansano\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/piansano\/#\/schema\/person\/0aa8a50e19c21a9eb51f37c37a2d2423","name":"Polizia Municipale Piansano","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/790937e1f48aad6bb24d80ce54056543aee024360bc52b9e6e0cbc95ec9b277c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/790937e1f48aad6bb24d80ce54056543aee024360bc52b9e6e0cbc95ec9b277c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/790937e1f48aad6bb24d80ce54056543aee024360bc52b9e6e0cbc95ec9b277c?s=96&d=mm&r=g","caption":"Polizia Municipale Piansano"},"url":"https:\/\/comunicacity.net\/piansano\/author\/pmunicipalepainsano\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/piansano\/wp-json\/wp\/v2\/posts\/3423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/piansano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/piansano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/piansano\/wp-json\/wp\/v2\/users\/107"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/piansano\/wp-json\/wp\/v2\/comments?post=3423"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/piansano\/wp-json\/wp\/v2\/posts\/3423\/revisions"}],"predecessor-version":[{"id":3427,"href":"https:\/\/comunicacity.net\/piansano\/wp-json\/wp\/v2\/posts\/3423\/revisions\/3427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/piansano\/wp-json\/wp\/v2\/media\/3425"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/piansano\/wp-json\/wp\/v2\/media?parent=3423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/piansano\/wp-json\/wp\/v2\/categories?post=3423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/piansano\/wp-json\/wp\/v2\/tags?post=3423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}