{"id":263,"date":"2016-03-31T12:26:33","date_gmt":"2016-03-31T10:26:33","guid":{"rendered":"https:\/\/comunicacity.net\/piedimontesangermano\/?p=263"},"modified":"2016-03-31T12:26:33","modified_gmt":"2016-03-31T10:26:33","slug":"bando-per-la-concessione-di-finanziamento-per-contrastare-il-disagio-abitativo","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/piedimontesangermano\/2016\/03\/31\/bando-per-la-concessione-di-finanziamento-per-contrastare-il-disagio-abitativo\/","title":{"rendered":"Bando per la concessione di finanziamento per contrastare il disagio abitativo"},"content":{"rendered":"<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_264\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/piedimontesangermano\/wp-content\/uploads\/sites\/37\/2016\/03\/img362.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/piedimontesangermano\/wp-content\/uploads\/sites\/37\/2016\/03\/img362.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>img362<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcce Allegatiimg362<\/p>\n","protected":false},"author":76,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-263","post","type-post","status-publish","format-standard","hentry","category-bandi-e-concorsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bando per la concessione di finanziamento per contrastare il disagio abitativo - Piedimonte San Germano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/piedimontesangermano\/2016\/03\/31\/bando-per-la-concessione-di-finanziamento-per-contrastare-il-disagio-abitativo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bando per la concessione di finanziamento per contrastare il disagio abitativo - Piedimonte San Germano\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udcce Allegatiimg362\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/piedimontesangermano\/2016\/03\/31\/bando-per-la-concessione-di-finanziamento-per-contrastare-il-disagio-abitativo\/\" \/>\n<meta property=\"og:site_name\" content=\"Piedimonte San Germano\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-31T10:26:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/piedimontesangermano\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/bandi-e-concorsi.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Giuseppe Giorgio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giuseppe Giorgio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/2016\\\/03\\\/31\\\/bando-per-la-concessione-di-finanziamento-per-contrastare-il-disagio-abitativo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/2016\\\/03\\\/31\\\/bando-per-la-concessione-di-finanziamento-per-contrastare-il-disagio-abitativo\\\/\"},\"author\":{\"name\":\"Giuseppe Giorgio\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/#\\\/schema\\\/person\\\/87932fb8a8cc1f3e364a1a2f170ba98f\"},\"headline\":\"Bando per la concessione di finanziamento per contrastare il disagio abitativo\",\"datePublished\":\"2016-03-31T10:26:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/2016\\\/03\\\/31\\\/bando-per-la-concessione-di-finanziamento-per-contrastare-il-disagio-abitativo\\\/\"},\"wordCount\":11,\"articleSection\":[\"Bandi e Concorsi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/2016\\\/03\\\/31\\\/bando-per-la-concessione-di-finanziamento-per-contrastare-il-disagio-abitativo\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/2016\\\/03\\\/31\\\/bando-per-la-concessione-di-finanziamento-per-contrastare-il-disagio-abitativo\\\/\",\"name\":\"Bando per la concessione di finanziamento per contrastare il disagio abitativo - Piedimonte San Germano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/#website\"},\"datePublished\":\"2016-03-31T10:26:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/#\\\/schema\\\/person\\\/87932fb8a8cc1f3e364a1a2f170ba98f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/2016\\\/03\\\/31\\\/bando-per-la-concessione-di-finanziamento-per-contrastare-il-disagio-abitativo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/2016\\\/03\\\/31\\\/bando-per-la-concessione-di-finanziamento-per-contrastare-il-disagio-abitativo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/2016\\\/03\\\/31\\\/bando-per-la-concessione-di-finanziamento-per-contrastare-il-disagio-abitativo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bando per la concessione di finanziamento per contrastare il disagio abitativo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/\",\"name\":\"Piedimonte San Germano\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/#\\\/schema\\\/person\\\/87932fb8a8cc1f3e364a1a2f170ba98f\",\"name\":\"Giuseppe Giorgio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8870f4407c0d6a9b6dcbe1e0404d5f4c902b522107bbf3d238ad813c647b8362?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8870f4407c0d6a9b6dcbe1e0404d5f4c902b522107bbf3d238ad813c647b8362?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8870f4407c0d6a9b6dcbe1e0404d5f4c902b522107bbf3d238ad813c647b8362?s=96&d=mm&r=g\",\"caption\":\"Giuseppe Giorgio\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/author\\\/giuseppegiorgio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bando per la concessione di finanziamento per contrastare il disagio abitativo - Piedimonte San Germano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/piedimontesangermano\/2016\/03\/31\/bando-per-la-concessione-di-finanziamento-per-contrastare-il-disagio-abitativo\/","og_locale":"it_IT","og_type":"article","og_title":"Bando per la concessione di finanziamento per contrastare il disagio abitativo - Piedimonte San Germano","og_description":"\ud83d\udcce Allegatiimg362","og_url":"https:\/\/comunicacity.net\/piedimontesangermano\/2016\/03\/31\/bando-per-la-concessione-di-finanziamento-per-contrastare-il-disagio-abitativo\/","og_site_name":"Piedimonte San Germano","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2016-03-31T10:26:33+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/bandi-e-concorsi.png","height":600,"width":1200,"type":""}],"author":"Giuseppe Giorgio","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Giuseppe Giorgio"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/piedimontesangermano\/2016\/03\/31\/bando-per-la-concessione-di-finanziamento-per-contrastare-il-disagio-abitativo\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/piedimontesangermano\/2016\/03\/31\/bando-per-la-concessione-di-finanziamento-per-contrastare-il-disagio-abitativo\/"},"author":{"name":"Giuseppe Giorgio","@id":"https:\/\/comunicacity.net\/piedimontesangermano\/#\/schema\/person\/87932fb8a8cc1f3e364a1a2f170ba98f"},"headline":"Bando per la concessione di finanziamento per contrastare il disagio abitativo","datePublished":"2016-03-31T10:26:33+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/piedimontesangermano\/2016\/03\/31\/bando-per-la-concessione-di-finanziamento-per-contrastare-il-disagio-abitativo\/"},"wordCount":11,"articleSection":["Bandi e Concorsi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/piedimontesangermano\/2016\/03\/31\/bando-per-la-concessione-di-finanziamento-per-contrastare-il-disagio-abitativo\/","url":"https:\/\/comunicacity.net\/piedimontesangermano\/2016\/03\/31\/bando-per-la-concessione-di-finanziamento-per-contrastare-il-disagio-abitativo\/","name":"Bando per la concessione di finanziamento per contrastare il disagio abitativo - Piedimonte San Germano","isPartOf":{"@id":"https:\/\/comunicacity.net\/piedimontesangermano\/#website"},"datePublished":"2016-03-31T10:26:33+00:00","author":{"@id":"https:\/\/comunicacity.net\/piedimontesangermano\/#\/schema\/person\/87932fb8a8cc1f3e364a1a2f170ba98f"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/piedimontesangermano\/2016\/03\/31\/bando-per-la-concessione-di-finanziamento-per-contrastare-il-disagio-abitativo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/piedimontesangermano\/2016\/03\/31\/bando-per-la-concessione-di-finanziamento-per-contrastare-il-disagio-abitativo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/piedimontesangermano\/2016\/03\/31\/bando-per-la-concessione-di-finanziamento-per-contrastare-il-disagio-abitativo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/piedimontesangermano\/"},{"@type":"ListItem","position":2,"name":"Bando per la concessione di finanziamento per contrastare il disagio abitativo"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/piedimontesangermano\/#website","url":"https:\/\/comunicacity.net\/piedimontesangermano\/","name":"Piedimonte San Germano","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/piedimontesangermano\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/piedimontesangermano\/#\/schema\/person\/87932fb8a8cc1f3e364a1a2f170ba98f","name":"Giuseppe Giorgio","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8870f4407c0d6a9b6dcbe1e0404d5f4c902b522107bbf3d238ad813c647b8362?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8870f4407c0d6a9b6dcbe1e0404d5f4c902b522107bbf3d238ad813c647b8362?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8870f4407c0d6a9b6dcbe1e0404d5f4c902b522107bbf3d238ad813c647b8362?s=96&d=mm&r=g","caption":"Giuseppe Giorgio"},"url":"https:\/\/comunicacity.net\/piedimontesangermano\/author\/giuseppegiorgio\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/posts\/263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/users\/76"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/comments?post=263"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/posts\/263\/revisions"}],"predecessor-version":[{"id":265,"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/posts\/263\/revisions\/265"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/media?parent=263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/categories?post=263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/tags?post=263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}