{"id":65,"date":"2015-11-04T13:45:10","date_gmt":"2015-11-04T12:45:10","guid":{"rendered":"https:\/\/comunicacity.net\/piedimontesangermano\/?p=65"},"modified":"2015-11-07T10:40:17","modified_gmt":"2015-11-07T09:40:17","slug":"giornata-dellunita-nazionale-e-delle-forze-armate","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/piedimontesangermano\/2015\/11\/04\/giornata-dellunita-nazionale-e-delle-forze-armate\/","title":{"rendered":"Giornata dell&#8217;Unit\u00e0 Nazionale e delle Forze Armate"},"content":{"rendered":"<p style=\"text-align: justify\">Il\u00a04 novembre di ogni anno ricorre il\u00a0<b>Giorno dell&#8217;Unit\u00e0 nazionale e Giornata delle Forze Armate,<\/b>\u00a0festivit\u00e0 della Repubblica Italiana, che ricorre ogni anno in ricordo del 4 novembre 1918, giorno in cui si ricorda l&#8217;anniversario della vittoria e della fine della prima guerra mondiale per l&#8217;Italia. Stamattina infatti alla presenza dell&#8217;amministrazione comunale, delle autorit\u00e0 intervenute, e delle autorit\u00e0 ecclesiastiche, sono state poste corone di alloro per la commemorazione , sia presso il monumento\u00a0dei caduti italiani che dei caduti polacchi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il\u00a04 novembre di ogni anno ricorre il\u00a0Giorno dell&#8217;Unit\u00e0 nazionale e Giornata delle Forze Armate,\u00a0festivit\u00e0 della Repubblica Italiana, che ricorre ogni anno in ricordo del 4 novembre 1918, giorno in cui [&hellip;]<\/p>\n","protected":false},"author":76,"featured_media":66,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-65","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giornata dell&#039;Unit\u00e0 Nazionale e delle Forze Armate - Piedimonte San Germano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/piedimontesangermano\/2015\/11\/04\/giornata-dellunita-nazionale-e-delle-forze-armate\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giornata dell&#039;Unit\u00e0 Nazionale e delle Forze Armate - Piedimonte San Germano\" \/>\n<meta property=\"og:description\" content=\"Il\u00a04 novembre di ogni anno ricorre il\u00a0Giorno dell&#8217;Unit\u00e0 nazionale e Giornata delle Forze Armate,\u00a0festivit\u00e0 della Repubblica Italiana, che ricorre ogni anno in ricordo del 4 novembre 1918, giorno in cui [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/piedimontesangermano\/2015\/11\/04\/giornata-dellunita-nazionale-e-delle-forze-armate\/\" \/>\n<meta property=\"og:site_name\" content=\"Piedimonte San Germano\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-04T12:45:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-07T09:40:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/piedimontesangermano\/wp-content\/uploads\/sites\/37\/2015\/11\/IMG_2982-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"533\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giuseppe Giorgio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giuseppe Giorgio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/2015\\\/11\\\/04\\\/giornata-dellunita-nazionale-e-delle-forze-armate\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/2015\\\/11\\\/04\\\/giornata-dellunita-nazionale-e-delle-forze-armate\\\/\"},\"author\":{\"name\":\"Giuseppe Giorgio\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/#\\\/schema\\\/person\\\/87932fb8a8cc1f3e364a1a2f170ba98f\"},\"headline\":\"Giornata dell&#8217;Unit\u00e0 Nazionale e delle Forze Armate\",\"datePublished\":\"2015-11-04T12:45:10+00:00\",\"dateModified\":\"2015-11-07T09:40:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/2015\\\/11\\\/04\\\/giornata-dellunita-nazionale-e-delle-forze-armate\\\/\"},\"wordCount\":84,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/2015\\\/11\\\/04\\\/giornata-dellunita-nazionale-e-delle-forze-armate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/wp-content\\\/uploads\\\/sites\\\/37\\\/2015\\\/11\\\/IMG_2982-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/2015\\\/11\\\/04\\\/giornata-dellunita-nazionale-e-delle-forze-armate\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/2015\\\/11\\\/04\\\/giornata-dellunita-nazionale-e-delle-forze-armate\\\/\",\"name\":\"Giornata dell'Unit\u00e0 Nazionale e delle Forze Armate - Piedimonte San Germano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/2015\\\/11\\\/04\\\/giornata-dellunita-nazionale-e-delle-forze-armate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/2015\\\/11\\\/04\\\/giornata-dellunita-nazionale-e-delle-forze-armate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/wp-content\\\/uploads\\\/sites\\\/37\\\/2015\\\/11\\\/IMG_2982-1.jpg\",\"datePublished\":\"2015-11-04T12:45:10+00:00\",\"dateModified\":\"2015-11-07T09:40:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/#\\\/schema\\\/person\\\/87932fb8a8cc1f3e364a1a2f170ba98f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/2015\\\/11\\\/04\\\/giornata-dellunita-nazionale-e-delle-forze-armate\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/2015\\\/11\\\/04\\\/giornata-dellunita-nazionale-e-delle-forze-armate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/2015\\\/11\\\/04\\\/giornata-dellunita-nazionale-e-delle-forze-armate\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/wp-content\\\/uploads\\\/sites\\\/37\\\/2015\\\/11\\\/IMG_2982-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/wp-content\\\/uploads\\\/sites\\\/37\\\/2015\\\/11\\\/IMG_2982-1.jpg\",\"width\":533,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/2015\\\/11\\\/04\\\/giornata-dellunita-nazionale-e-delle-forze-armate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giornata dell&#8217;Unit\u00e0 Nazionale e delle Forze Armate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/\",\"name\":\"Piedimonte San Germano\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/#\\\/schema\\\/person\\\/87932fb8a8cc1f3e364a1a2f170ba98f\",\"name\":\"Giuseppe Giorgio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8870f4407c0d6a9b6dcbe1e0404d5f4c902b522107bbf3d238ad813c647b8362?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8870f4407c0d6a9b6dcbe1e0404d5f4c902b522107bbf3d238ad813c647b8362?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8870f4407c0d6a9b6dcbe1e0404d5f4c902b522107bbf3d238ad813c647b8362?s=96&d=mm&r=g\",\"caption\":\"Giuseppe Giorgio\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/author\\\/giuseppegiorgio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giornata dell'Unit\u00e0 Nazionale e delle Forze Armate - Piedimonte San Germano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/piedimontesangermano\/2015\/11\/04\/giornata-dellunita-nazionale-e-delle-forze-armate\/","og_locale":"it_IT","og_type":"article","og_title":"Giornata dell'Unit\u00e0 Nazionale e delle Forze Armate - Piedimonte San Germano","og_description":"Il\u00a04 novembre di ogni anno ricorre il\u00a0Giorno dell&#8217;Unit\u00e0 nazionale e Giornata delle Forze Armate,\u00a0festivit\u00e0 della Repubblica Italiana, che ricorre ogni anno in ricordo del 4 novembre 1918, giorno in cui [&hellip;]","og_url":"https:\/\/comunicacity.net\/piedimontesangermano\/2015\/11\/04\/giornata-dellunita-nazionale-e-delle-forze-armate\/","og_site_name":"Piedimonte San Germano","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2015-11-04T12:45:10+00:00","article_modified_time":"2015-11-07T09:40:17+00:00","og_image":[{"width":533,"height":400,"url":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-content\/uploads\/sites\/37\/2015\/11\/IMG_2982-1.jpg","type":"image\/jpeg"}],"author":"Giuseppe Giorgio","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Giuseppe Giorgio"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/piedimontesangermano\/2015\/11\/04\/giornata-dellunita-nazionale-e-delle-forze-armate\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/piedimontesangermano\/2015\/11\/04\/giornata-dellunita-nazionale-e-delle-forze-armate\/"},"author":{"name":"Giuseppe Giorgio","@id":"https:\/\/comunicacity.net\/piedimontesangermano\/#\/schema\/person\/87932fb8a8cc1f3e364a1a2f170ba98f"},"headline":"Giornata dell&#8217;Unit\u00e0 Nazionale e delle Forze Armate","datePublished":"2015-11-04T12:45:10+00:00","dateModified":"2015-11-07T09:40:17+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/piedimontesangermano\/2015\/11\/04\/giornata-dellunita-nazionale-e-delle-forze-armate\/"},"wordCount":84,"image":{"@id":"https:\/\/comunicacity.net\/piedimontesangermano\/2015\/11\/04\/giornata-dellunita-nazionale-e-delle-forze-armate\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-content\/uploads\/sites\/37\/2015\/11\/IMG_2982-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/piedimontesangermano\/2015\/11\/04\/giornata-dellunita-nazionale-e-delle-forze-armate\/","url":"https:\/\/comunicacity.net\/piedimontesangermano\/2015\/11\/04\/giornata-dellunita-nazionale-e-delle-forze-armate\/","name":"Giornata dell'Unit\u00e0 Nazionale e delle Forze Armate - Piedimonte San Germano","isPartOf":{"@id":"https:\/\/comunicacity.net\/piedimontesangermano\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/piedimontesangermano\/2015\/11\/04\/giornata-dellunita-nazionale-e-delle-forze-armate\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/piedimontesangermano\/2015\/11\/04\/giornata-dellunita-nazionale-e-delle-forze-armate\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-content\/uploads\/sites\/37\/2015\/11\/IMG_2982-1.jpg","datePublished":"2015-11-04T12:45:10+00:00","dateModified":"2015-11-07T09:40:17+00:00","author":{"@id":"https:\/\/comunicacity.net\/piedimontesangermano\/#\/schema\/person\/87932fb8a8cc1f3e364a1a2f170ba98f"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/piedimontesangermano\/2015\/11\/04\/giornata-dellunita-nazionale-e-delle-forze-armate\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/piedimontesangermano\/2015\/11\/04\/giornata-dellunita-nazionale-e-delle-forze-armate\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/piedimontesangermano\/2015\/11\/04\/giornata-dellunita-nazionale-e-delle-forze-armate\/#primaryimage","url":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-content\/uploads\/sites\/37\/2015\/11\/IMG_2982-1.jpg","contentUrl":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-content\/uploads\/sites\/37\/2015\/11\/IMG_2982-1.jpg","width":533,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/piedimontesangermano\/2015\/11\/04\/giornata-dellunita-nazionale-e-delle-forze-armate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/piedimontesangermano\/"},{"@type":"ListItem","position":2,"name":"Giornata dell&#8217;Unit\u00e0 Nazionale e delle Forze Armate"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/piedimontesangermano\/#website","url":"https:\/\/comunicacity.net\/piedimontesangermano\/","name":"Piedimonte San Germano","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/piedimontesangermano\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/piedimontesangermano\/#\/schema\/person\/87932fb8a8cc1f3e364a1a2f170ba98f","name":"Giuseppe Giorgio","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8870f4407c0d6a9b6dcbe1e0404d5f4c902b522107bbf3d238ad813c647b8362?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8870f4407c0d6a9b6dcbe1e0404d5f4c902b522107bbf3d238ad813c647b8362?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8870f4407c0d6a9b6dcbe1e0404d5f4c902b522107bbf3d238ad813c647b8362?s=96&d=mm&r=g","caption":"Giuseppe Giorgio"},"url":"https:\/\/comunicacity.net\/piedimontesangermano\/author\/giuseppegiorgio\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/posts\/65","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/users\/76"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/comments?post=65"}],"version-history":[{"count":4,"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/posts\/65\/revisions"}],"predecessor-version":[{"id":73,"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/posts\/65\/revisions\/73"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/media\/66"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/media?parent=65"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/categories?post=65"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/tags?post=65"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}