{"id":393,"date":"2016-07-14T14:32:59","date_gmt":"2016-07-14T12:32:59","guid":{"rendered":"https:\/\/comunicacity.net\/piedimontesangermano\/?post_type=turismo&#038;p=393"},"modified":"2016-08-29T17:21:13","modified_gmt":"2016-08-29T15:21:13","slug":"larticolazione-del-paese","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/piedimontesangermano\/turismo\/il-turista-e-il-territorio\/larticolazione-del-paese\/","title":{"rendered":"L&#8217;articolazione del paese"},"content":{"rendered":"<p style=\"text-align: justify;\">Il Comune di Piedimonte San Germano si compone di quattro nuclei abitativi:<\/p>\n<p style=\"text-align: justify;\">Piedimonte Alta con il suo &#8220;centro storico&#8221;. Qui vi \u00e8 il Castello dei Conti d&#8217;Aquino , le chiese, i giardini da cui si pu\u00f2 ammirare tutta la valle.<br \/>\nIl centro. Esso si sviluppa intorno alla via Casilina e allo sbocco della superstrada che lo congiunge pi\u00f9 direttamente allo svincolo autostradale, passando davanti allo stabilimento FIAT. Qui vi \u00e8 il Municipio, i Centro commerciali, la Scuola e la Biblioteca.<br \/>\nLa Volla. Esso costituisce l&#8217;area dell&#8217;insediamento industriale sia della FIAT che delle altre imprese del luogo.<br \/>\nRiuscito. E&#8217; la zona ancora riservata all&#8217;agricoltura e all&#8217;allevamento del bestiame.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Comune di Piedimonte San Germano si compone di quattro nuclei abitativi: Piedimonte Alta con il suo &#8220;centro storico&#8221;. Qui vi \u00e8 il Castello dei Conti d&#8217;Aquino , le chiese, [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":392,"menu_order":1,"template":"","meta":[],"class_list":["post-393","turismo","type-turismo","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;articolazione del paese - Piedimonte San Germano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/piedimontesangermano\/turismo\/il-turista-e-il-territorio\/larticolazione-del-paese\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;articolazione del paese - Piedimonte San Germano\" \/>\n<meta property=\"og:description\" content=\"Il Comune di Piedimonte San Germano si compone di quattro nuclei abitativi: Piedimonte Alta con il suo &#8220;centro storico&#8221;. Qui vi \u00e8 il Castello dei Conti d&#8217;Aquino , le chiese, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/piedimontesangermano\/turismo\/il-turista-e-il-territorio\/larticolazione-del-paese\/\" \/>\n<meta property=\"og:site_name\" content=\"Piedimonte San Germano\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2016-08-29T15:21:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/piedimontesangermano\/wp-content\/uploads\/sites\/37\/2015\/10\/piedimontesangermano.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"50\" \/>\n\t<meta property=\"og:image:height\" content=\"50\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/turismo\\\/il-turista-e-il-territorio\\\/larticolazione-del-paese\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/turismo\\\/il-turista-e-il-territorio\\\/larticolazione-del-paese\\\/\",\"name\":\"L'articolazione del paese - Piedimonte San Germano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/#website\"},\"datePublished\":\"2016-07-14T12:32:59+00:00\",\"dateModified\":\"2016-08-29T15:21:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/turismo\\\/il-turista-e-il-territorio\\\/larticolazione-del-paese\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/turismo\\\/il-turista-e-il-territorio\\\/larticolazione-del-paese\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/turismo\\\/il-turista-e-il-territorio\\\/larticolazione-del-paese\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Turista e il Territorio\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/turismo\\\/il-turista-e-il-territorio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L&#8217;articolazione del paese\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/\",\"name\":\"Piedimonte San Germano\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/piedimontesangermano\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'articolazione del paese - Piedimonte San Germano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/piedimontesangermano\/turismo\/il-turista-e-il-territorio\/larticolazione-del-paese\/","og_locale":"it_IT","og_type":"article","og_title":"L'articolazione del paese - Piedimonte San Germano","og_description":"Il Comune di Piedimonte San Germano si compone di quattro nuclei abitativi: Piedimonte Alta con il suo &#8220;centro storico&#8221;. Qui vi \u00e8 il Castello dei Conti d&#8217;Aquino , le chiese, [&hellip;]","og_url":"https:\/\/comunicacity.net\/piedimontesangermano\/turismo\/il-turista-e-il-territorio\/larticolazione-del-paese\/","og_site_name":"Piedimonte San Germano","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2016-08-29T15:21:13+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-content\/uploads\/sites\/37\/2015\/10\/piedimontesangermano.jpg","height":50,"width":50,"type":""}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/piedimontesangermano\/turismo\/il-turista-e-il-territorio\/larticolazione-del-paese\/","url":"https:\/\/comunicacity.net\/piedimontesangermano\/turismo\/il-turista-e-il-territorio\/larticolazione-del-paese\/","name":"L'articolazione del paese - Piedimonte San Germano","isPartOf":{"@id":"https:\/\/comunicacity.net\/piedimontesangermano\/#website"},"datePublished":"2016-07-14T12:32:59+00:00","dateModified":"2016-08-29T15:21:13+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/piedimontesangermano\/turismo\/il-turista-e-il-territorio\/larticolazione-del-paese\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/piedimontesangermano\/turismo\/il-turista-e-il-territorio\/larticolazione-del-paese\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/piedimontesangermano\/turismo\/il-turista-e-il-territorio\/larticolazione-del-paese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/piedimontesangermano\/"},{"@type":"ListItem","position":2,"name":"Il Turista e il Territorio","item":"https:\/\/comunicacity.net\/piedimontesangermano\/turismo\/il-turista-e-il-territorio\/"},{"@type":"ListItem","position":3,"name":"L&#8217;articolazione del paese"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/piedimontesangermano\/#website","url":"https:\/\/comunicacity.net\/piedimontesangermano\/","name":"Piedimonte San Germano","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/piedimontesangermano\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/turismo\/393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/types\/turismo"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/turismo\/392"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/piedimontesangermano\/wp-json\/wp\/v2\/media?parent=393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}