{"id":17205,"date":"2022-06-13T13:09:04","date_gmt":"2022-06-13T11:09:04","guid":{"rendered":"https:\/\/comunicacity.net\/pofi\/2022\/06\/13\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\/"},"modified":"2022-06-13T13:09:04","modified_gmt":"2022-06-13T11:09:04","slug":"avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pofi\/2022\/06\/13\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\/","title":{"rendered":"Avviso di selezione pubblica per conferimento dell&#8217;incarico di istruttore direttivo tecnico a tempo determinato e a tempo parziale (18 ore)"},"content":{"rendered":"<p>Si allega avviso<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_17207\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/pofi\/wp-content\/uploads\/sites\/172\/2022\/06\/ISTRUTTORE-DIRETTORE-TECNICO-pdf.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/pofi\/wp-content\/uploads\/sites\/172\/2022\/06\/ISTRUTTORE-DIRETTORE-TECNICO-pdf.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>ISTRUTTORE DIRETTORE TECNICO pdf<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si allega avviso \ud83d\udcce AllegatiISTRUTTORE DIRETTORE TECNICO pdf<\/p>\n","protected":false},"author":306,"featured_media":17206,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-17205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-concorsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso di selezione pubblica per conferimento dell&#039;incarico di istruttore direttivo tecnico a tempo determinato e a tempo parziale (18 ore) - Pofi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pofi\/2022\/06\/13\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso di selezione pubblica per conferimento dell&#039;incarico di istruttore direttivo tecnico a tempo determinato e a tempo parziale (18 ore) - Pofi\" \/>\n<meta property=\"og:description\" content=\"Si allega avviso \ud83d\udcce AllegatiISTRUTTORE DIRETTORE TECNICO pdf\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pofi\/2022\/06\/13\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\/\" \/>\n<meta property=\"og:site_name\" content=\"Pofi\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-13T11:09:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pofi\/wp-content\/uploads\/sites\/172\/2022\/06\/BANDI-E-CONCORSI-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"tommasociccone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"tommasociccone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/2022\\\/06\\\/13\\\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/2022\\\/06\\\/13\\\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\\\/\"},\"author\":{\"name\":\"tommasociccone\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#\\\/schema\\\/person\\\/ba404f8819d66f22b843d8a63099a94b\"},\"headline\":\"Avviso di selezione pubblica per conferimento dell&#8217;incarico di istruttore direttivo tecnico a tempo determinato e a tempo parziale (18 ore)\",\"datePublished\":\"2022-06-13T11:09:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/2022\\\/06\\\/13\\\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\\\/\"},\"wordCount\":22,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/2022\\\/06\\\/13\\\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/wp-content\\\/uploads\\\/sites\\\/172\\\/2022\\\/06\\\/BANDI-E-CONCORSI-2.png\",\"articleSection\":[\"Bandi e Concorsi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/2022\\\/06\\\/13\\\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/2022\\\/06\\\/13\\\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\\\/\",\"name\":\"Avviso di selezione pubblica per conferimento dell'incarico di istruttore direttivo tecnico a tempo determinato e a tempo parziale (18 ore) - Pofi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/2022\\\/06\\\/13\\\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/2022\\\/06\\\/13\\\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/wp-content\\\/uploads\\\/sites\\\/172\\\/2022\\\/06\\\/BANDI-E-CONCORSI-2.png\",\"datePublished\":\"2022-06-13T11:09:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/2022\\\/06\\\/13\\\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/2022\\\/06\\\/13\\\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/2022\\\/06\\\/13\\\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/wp-content\\\/uploads\\\/sites\\\/172\\\/2022\\\/06\\\/BANDI-E-CONCORSI-2.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/wp-content\\\/uploads\\\/sites\\\/172\\\/2022\\\/06\\\/BANDI-E-CONCORSI-2.png\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/2022\\\/06\\\/13\\\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso di selezione pubblica per conferimento dell&#8217;incarico di istruttore direttivo tecnico a tempo determinato e a tempo parziale (18 ore)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/\",\"name\":\"Pofi\",\"description\":\"Il Tuo Comune che Comunica\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#\\\/schema\\\/person\\\/ba404f8819d66f22b843d8a63099a94b\",\"name\":\"tommasociccone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/79b723cb3012083017aaa357287adac9b0ea60301db826c066133fe42c8db6d5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/79b723cb3012083017aaa357287adac9b0ea60301db826c066133fe42c8db6d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/79b723cb3012083017aaa357287adac9b0ea60301db826c066133fe42c8db6d5?s=96&d=mm&r=g\",\"caption\":\"tommasociccone\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/author\\\/tommasociccone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso di selezione pubblica per conferimento dell'incarico di istruttore direttivo tecnico a tempo determinato e a tempo parziale (18 ore) - Pofi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pofi\/2022\/06\/13\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso di selezione pubblica per conferimento dell'incarico di istruttore direttivo tecnico a tempo determinato e a tempo parziale (18 ore) - Pofi","og_description":"Si allega avviso \ud83d\udcce AllegatiISTRUTTORE DIRETTORE TECNICO pdf","og_url":"https:\/\/comunicacity.net\/pofi\/2022\/06\/13\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\/","og_site_name":"Pofi","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-06-13T11:09:04+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/comunicacity.net\/pofi\/wp-content\/uploads\/sites\/172\/2022\/06\/BANDI-E-CONCORSI-2.png","type":"image\/png"}],"author":"tommasociccone","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"tommasociccone","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pofi\/2022\/06\/13\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pofi\/2022\/06\/13\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\/"},"author":{"name":"tommasociccone","@id":"https:\/\/comunicacity.net\/pofi\/#\/schema\/person\/ba404f8819d66f22b843d8a63099a94b"},"headline":"Avviso di selezione pubblica per conferimento dell&#8217;incarico di istruttore direttivo tecnico a tempo determinato e a tempo parziale (18 ore)","datePublished":"2022-06-13T11:09:04+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pofi\/2022\/06\/13\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\/"},"wordCount":22,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/pofi\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/pofi\/2022\/06\/13\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pofi\/wp-content\/uploads\/sites\/172\/2022\/06\/BANDI-E-CONCORSI-2.png","articleSection":["Bandi e Concorsi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pofi\/2022\/06\/13\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\/","url":"https:\/\/comunicacity.net\/pofi\/2022\/06\/13\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\/","name":"Avviso di selezione pubblica per conferimento dell'incarico di istruttore direttivo tecnico a tempo determinato e a tempo parziale (18 ore) - Pofi","isPartOf":{"@id":"https:\/\/comunicacity.net\/pofi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pofi\/2022\/06\/13\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pofi\/2022\/06\/13\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pofi\/wp-content\/uploads\/sites\/172\/2022\/06\/BANDI-E-CONCORSI-2.png","datePublished":"2022-06-13T11:09:04+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/pofi\/2022\/06\/13\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pofi\/2022\/06\/13\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pofi\/2022\/06\/13\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\/#primaryimage","url":"https:\/\/comunicacity.net\/pofi\/wp-content\/uploads\/sites\/172\/2022\/06\/BANDI-E-CONCORSI-2.png","contentUrl":"https:\/\/comunicacity.net\/pofi\/wp-content\/uploads\/sites\/172\/2022\/06\/BANDI-E-CONCORSI-2.png","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pofi\/2022\/06\/13\/avviso-di-selezione-pubblica-per-conferimento-dellincarico-di-istruttore-direttivo-tecnico-a-tempo-determinato-e-a-tempo-parziale-18-ore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pofi\/"},{"@type":"ListItem","position":2,"name":"Avviso di selezione pubblica per conferimento dell&#8217;incarico di istruttore direttivo tecnico a tempo determinato e a tempo parziale (18 ore)"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pofi\/#website","url":"https:\/\/comunicacity.net\/pofi\/","name":"Pofi","description":"Il Tuo Comune che Comunica","publisher":{"@id":"https:\/\/comunicacity.net\/pofi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pofi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/pofi\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/pofi\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pofi\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/pofi\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pofi\/#\/schema\/person\/ba404f8819d66f22b843d8a63099a94b","name":"tommasociccone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/79b723cb3012083017aaa357287adac9b0ea60301db826c066133fe42c8db6d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/79b723cb3012083017aaa357287adac9b0ea60301db826c066133fe42c8db6d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/79b723cb3012083017aaa357287adac9b0ea60301db826c066133fe42c8db6d5?s=96&d=mm&r=g","caption":"tommasociccone"},"url":"https:\/\/comunicacity.net\/pofi\/author\/tommasociccone\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"17256"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/posts\/17205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/users\/306"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/comments?post=17205"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/posts\/17205\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/media\/17206"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/media?parent=17205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/categories?post=17205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/tags?post=17205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}