{"id":43,"date":"2019-12-10T12:25:54","date_gmt":"2019-12-10T11:25:54","guid":{"rendered":"https:\/\/comunicacity.net\/pofi\/?post_type=turismo&#038;p=43"},"modified":"2019-12-10T12:35:13","modified_gmt":"2019-12-10T11:35:13","slug":"area-1-sezione-geologica","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/pofi\/turismo\/museo-preistorico-2\/aree-museali\/area-1-sezione-geologica\/","title":{"rendered":"Area 1"},"content":{"rendered":"<h2><strong>Sezione geologica<\/strong><\/h2>\n<p>E\u2019 illustrata da pannelli bilingue italiano-inglese, una ricostruzione stratigrafica effettuata con terreni campionati in vari giacimenti, un plastico del territorio e un espositore con campioni di rocce e fossili.<\/p>\n<p>Sono riassunte le principali tappe dell\u2019evoluzione del pianeta dalla Pangea fino agli aspetti della geologia regionale. Gli eventi che hanno contribuito alla morfologia del paesaggio e che hanno interferito con la presenza dell\u2019uomo, sono legati all\u2019estensione di grandi bacini lacustri ora scomparsi e agli apparati del \u201cVulcanismo Ernico\u201d con centri attivi tra 700.000 e 110.000 anni.<\/p>\n<p>Viene dato particolare risalto all\u2019apparato poligenico di Pofi, attivo tra 430.000 e 110.000 anni, del quale sono ancora oggi visibili, nella morfologia del paesaggio, quattro crateri principali.<\/p>\n<p>Nel museo \u00e8 esposta, tra l\u2019altro, una bomba lavica di considerevoli dimensioni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sezione geologica E\u2019 illustrata da pannelli bilingue italiano-inglese, una ricostruzione stratigrafica effettuata con terreni campionati in vari giacimenti, un plastico del territorio e un espositore con campioni di rocce e [&hellip;]<\/p>\n","protected":false},"featured_media":45,"parent":39,"menu_order":0,"template":"","meta":[],"plugin_turismo":[],"class_list":["post-43","turismo","type-turismo","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Area 1 - Pofi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pofi\/turismo\/museo-preistorico-2\/aree-museali\/area-1-sezione-geologica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Area 1 - Pofi\" \/>\n<meta property=\"og:description\" content=\"Sezione geologica E\u2019 illustrata da pannelli bilingue italiano-inglese, una ricostruzione stratigrafica effettuata con terreni campionati in vari giacimenti, un plastico del territorio e un espositore con campioni di rocce e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pofi\/turismo\/museo-preistorico-2\/aree-museali\/area-1-sezione-geologica\/\" \/>\n<meta property=\"og:site_name\" content=\"Pofi\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-10T11:35:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pofi\/wp-content\/uploads\/sites\/172\/2019\/12\/Interno-del-museo-area-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"175\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/museo-preistorico-2\\\/aree-museali\\\/area-1-sezione-geologica\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/museo-preistorico-2\\\/aree-museali\\\/area-1-sezione-geologica\\\/\",\"name\":\"Area 1 - Pofi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/museo-preistorico-2\\\/aree-museali\\\/area-1-sezione-geologica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/museo-preistorico-2\\\/aree-museali\\\/area-1-sezione-geologica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/wp-content\\\/uploads\\\/sites\\\/172\\\/2019\\\/12\\\/Interno-del-museo-area-1.jpg\",\"datePublished\":\"2019-12-10T11:25:54+00:00\",\"dateModified\":\"2019-12-10T11:35:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/museo-preistorico-2\\\/aree-museali\\\/area-1-sezione-geologica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/museo-preistorico-2\\\/aree-museali\\\/area-1-sezione-geologica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/museo-preistorico-2\\\/aree-museali\\\/area-1-sezione-geologica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/wp-content\\\/uploads\\\/sites\\\/172\\\/2019\\\/12\\\/Interno-del-museo-area-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/wp-content\\\/uploads\\\/sites\\\/172\\\/2019\\\/12\\\/Interno-del-museo-area-1.jpg\",\"width\":350,\"height\":175},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/museo-preistorico-2\\\/aree-museali\\\/area-1-sezione-geologica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Museo Preistorico\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/museo-preistorico-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aree Museali\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/museo-preistorico-2\\\/aree-museali\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Area 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/\",\"name\":\"Pofi\",\"description\":\"Il Tuo Comune che Comunica\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Area 1 - Pofi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pofi\/turismo\/museo-preistorico-2\/aree-museali\/area-1-sezione-geologica\/","og_locale":"it_IT","og_type":"article","og_title":"Area 1 - Pofi","og_description":"Sezione geologica E\u2019 illustrata da pannelli bilingue italiano-inglese, una ricostruzione stratigrafica effettuata con terreni campionati in vari giacimenti, un plastico del territorio e un espositore con campioni di rocce e [&hellip;]","og_url":"https:\/\/comunicacity.net\/pofi\/turismo\/museo-preistorico-2\/aree-museali\/area-1-sezione-geologica\/","og_site_name":"Pofi","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2019-12-10T11:35:13+00:00","og_image":[{"width":350,"height":175,"url":"https:\/\/comunicacity.net\/pofi\/wp-content\/uploads\/sites\/172\/2019\/12\/Interno-del-museo-area-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pofi\/turismo\/museo-preistorico-2\/aree-museali\/area-1-sezione-geologica\/","url":"https:\/\/comunicacity.net\/pofi\/turismo\/museo-preistorico-2\/aree-museali\/area-1-sezione-geologica\/","name":"Area 1 - Pofi","isPartOf":{"@id":"https:\/\/comunicacity.net\/pofi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pofi\/turismo\/museo-preistorico-2\/aree-museali\/area-1-sezione-geologica\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pofi\/turismo\/museo-preistorico-2\/aree-museali\/area-1-sezione-geologica\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pofi\/wp-content\/uploads\/sites\/172\/2019\/12\/Interno-del-museo-area-1.jpg","datePublished":"2019-12-10T11:25:54+00:00","dateModified":"2019-12-10T11:35:13+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/pofi\/turismo\/museo-preistorico-2\/aree-museali\/area-1-sezione-geologica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pofi\/turismo\/museo-preistorico-2\/aree-museali\/area-1-sezione-geologica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pofi\/turismo\/museo-preistorico-2\/aree-museali\/area-1-sezione-geologica\/#primaryimage","url":"https:\/\/comunicacity.net\/pofi\/wp-content\/uploads\/sites\/172\/2019\/12\/Interno-del-museo-area-1.jpg","contentUrl":"https:\/\/comunicacity.net\/pofi\/wp-content\/uploads\/sites\/172\/2019\/12\/Interno-del-museo-area-1.jpg","width":350,"height":175},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pofi\/turismo\/museo-preistorico-2\/aree-museali\/area-1-sezione-geologica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pofi\/"},{"@type":"ListItem","position":2,"name":"Museo Preistorico","item":"https:\/\/comunicacity.net\/pofi\/turismo\/museo-preistorico-2\/"},{"@type":"ListItem","position":3,"name":"Aree Museali","item":"https:\/\/comunicacity.net\/pofi\/turismo\/museo-preistorico-2\/aree-museali\/"},{"@type":"ListItem","position":4,"name":"Area 1"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pofi\/#website","url":"https:\/\/comunicacity.net\/pofi\/","name":"Pofi","description":"Il Tuo Comune che Comunica","publisher":{"@id":"https:\/\/comunicacity.net\/pofi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pofi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/pofi\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/pofi\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pofi\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/pofi\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/turismo\/43","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/types\/turismo"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/turismo\/39"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/media\/45"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/media?parent=43"}],"wp:term":[{"taxonomy":"plugin_turismo","embeddable":true,"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/plugin_turismo?post=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}