{"id":58,"date":"2019-12-10T12:30:05","date_gmt":"2019-12-10T11:30:05","guid":{"rendered":"https:\/\/comunicacity.net\/pofi\/?post_type=turismo&#038;p=58"},"modified":"2019-12-10T12:30:05","modified_gmt":"2019-12-10T11:30:05","slug":"chiesetta-di-s-maria-degli-angeli","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/chiesetta-di-s-maria-degli-angeli\/","title":{"rendered":"Chiesetta di S. Maria degli Angeli"},"content":{"rendered":"<p>Questa Chiesetta si trova in aperta campagna, all\u2019incrocio fra la strada provinciale, che da Pofi immette nella Casilina, e la strada che porta al vicino Camposanto. Questa fu fatta costruire nella seconda met\u00e0 del 1650 ma non \u00e8 chiaro se i denari siano dovuti a pubbliche offerte oppure donati da Domenico Antonio Ferracci.<\/p>\n<p>La celebrazione della festa si ha ogni anno nel luned\u00ec successivo alla domenica di Pasqua in concomitanza di una fiera di merci detta un tempo \u201cla fiera de le musciarelle\u201d.<\/p>\n<p>(Fonte: Felice Campoli, 1982; Pofi: dalle origini al secolo XX, Roma)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questa Chiesetta si trova in aperta campagna, all\u2019incrocio fra la strada provinciale, che da Pofi immette nella Casilina, e la strada che porta al vicino Camposanto. Questa fu fatta costruire [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":49,"menu_order":4,"template":"","meta":[],"plugin_turismo":[],"class_list":["post-58","turismo","type-turismo","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chiesetta di S. Maria degli Angeli - Pofi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/chiesetta-di-s-maria-degli-angeli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chiesetta di S. Maria degli Angeli - Pofi\" \/>\n<meta property=\"og:description\" content=\"Questa Chiesetta si trova in aperta campagna, all\u2019incrocio fra la strada provinciale, che da Pofi immette nella Casilina, e la strada che porta al vicino Camposanto. Questa fu fatta costruire [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/chiesetta-di-s-maria-degli-angeli\/\" \/>\n<meta property=\"og:site_name\" content=\"Pofi\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pofi\/wp-content\/uploads\/sites\/172\/2019\/12\/pofi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"50\" \/>\n\t<meta property=\"og:image:height\" content=\"50\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/le-chiese\\\/chiesetta-di-s-maria-degli-angeli\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/le-chiese\\\/chiesetta-di-s-maria-degli-angeli\\\/\",\"name\":\"Chiesetta di S. Maria degli Angeli - Pofi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#website\"},\"datePublished\":\"2019-12-10T11:30:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/le-chiese\\\/chiesetta-di-s-maria-degli-angeli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/le-chiese\\\/chiesetta-di-s-maria-degli-angeli\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/le-chiese\\\/chiesetta-di-s-maria-degli-angeli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le chiese\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/le-chiese\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chiesetta di S. Maria degli Angeli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/\",\"name\":\"Pofi\",\"description\":\"Il Tuo Comune che Comunica\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chiesetta di S. Maria degli Angeli - Pofi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/chiesetta-di-s-maria-degli-angeli\/","og_locale":"it_IT","og_type":"article","og_title":"Chiesetta di S. Maria degli Angeli - Pofi","og_description":"Questa Chiesetta si trova in aperta campagna, all\u2019incrocio fra la strada provinciale, che da Pofi immette nella Casilina, e la strada che porta al vicino Camposanto. Questa fu fatta costruire [&hellip;]","og_url":"https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/chiesetta-di-s-maria-degli-angeli\/","og_site_name":"Pofi","article_publisher":"http:\/\/facebook.com\/ComunicaCity","og_image":[{"url":"https:\/\/comunicacity.net\/pofi\/wp-content\/uploads\/sites\/172\/2019\/12\/pofi.jpg","height":50,"width":50,"type":""}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/chiesetta-di-s-maria-degli-angeli\/","url":"https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/chiesetta-di-s-maria-degli-angeli\/","name":"Chiesetta di S. Maria degli Angeli - Pofi","isPartOf":{"@id":"https:\/\/comunicacity.net\/pofi\/#website"},"datePublished":"2019-12-10T11:30:05+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/chiesetta-di-s-maria-degli-angeli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/chiesetta-di-s-maria-degli-angeli\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/chiesetta-di-s-maria-degli-angeli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pofi\/"},{"@type":"ListItem","position":2,"name":"Le chiese","item":"https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/"},{"@type":"ListItem","position":3,"name":"Chiesetta di S. Maria degli Angeli"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pofi\/#website","url":"https:\/\/comunicacity.net\/pofi\/","name":"Pofi","description":"Il Tuo Comune che Comunica","publisher":{"@id":"https:\/\/comunicacity.net\/pofi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pofi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/pofi\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/pofi\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pofi\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/pofi\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/turismo\/58","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/types\/turismo"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/turismo\/49"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/media?parent=58"}],"wp:term":[{"taxonomy":"plugin_turismo","embeddable":true,"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/plugin_turismo?post=58"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}