{"id":68,"date":"2019-12-10T12:32:50","date_gmt":"2019-12-10T11:32:50","guid":{"rendered":"https:\/\/comunicacity.net\/pofi\/?post_type=turismo&#038;p=68"},"modified":"2019-12-10T12:42:24","modified_gmt":"2019-12-10T11:42:24","slug":"chiesa-di-santa-croce","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/chiesa-di-santa-croce\/","title":{"rendered":"Chiesa di Santa Croce"},"content":{"rendered":"<p>La Chiesa \u00e8 posta a lato della valle indicata come cratere principale del vulcano spento di Pofi, lungo il tratto di strada che conduce a Ceccano. Le prime notizie risalgono al 1652 quando, nella visita di Argoli, si dice che nella chiesa si cantava messa nelle feste dello stesso Titolo (Invenzione della Croce, 3 Maggio ed Esaltazione della Croce, 14 Settembre).<\/p>\n<p>Successivamente i documenti non forniscono particolari notizie se non che, per il fatto di trovarsi su un vero piedistallo di tufo, la Chiesa, al contrario delle Chiese consorelle, non \u00e8 soggetta ad umidit\u00e0. Durante la Seconda Guerra Mondiale, la Chiesa fu adibita a ricovero di quadrupedi da parte dei militari tedeschi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Chiesa \u00e8 posta a lato della valle indicata come cratere principale del vulcano spento di Pofi, lungo il tratto di strada che conduce a Ceccano. Le prime notizie risalgono [&hellip;]<\/p>\n","protected":false},"featured_media":70,"parent":49,"menu_order":8,"template":"","meta":[],"plugin_turismo":[],"class_list":["post-68","turismo","type-turismo","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chiesa di Santa Croce - Pofi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/chiesa-di-santa-croce\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chiesa di Santa Croce - Pofi\" \/>\n<meta property=\"og:description\" content=\"La Chiesa \u00e8 posta a lato della valle indicata come cratere principale del vulcano spento di Pofi, lungo il tratto di strada che conduce a Ceccano. Le prime notizie risalgono [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/chiesa-di-santa-croce\/\" \/>\n<meta property=\"og:site_name\" content=\"Pofi\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-10T11:42:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pofi\/wp-content\/uploads\/sites\/172\/2019\/12\/Chiesa-di-Santa-Croce-Pofi-FR.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"254\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/le-chiese\\\/chiesa-di-santa-croce\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/le-chiese\\\/chiesa-di-santa-croce\\\/\",\"name\":\"Chiesa di Santa Croce - Pofi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/le-chiese\\\/chiesa-di-santa-croce\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/le-chiese\\\/chiesa-di-santa-croce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/wp-content\\\/uploads\\\/sites\\\/172\\\/2019\\\/12\\\/Chiesa-di-Santa-Croce-Pofi-FR.jpg\",\"datePublished\":\"2019-12-10T11:32:50+00:00\",\"dateModified\":\"2019-12-10T11:42:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/le-chiese\\\/chiesa-di-santa-croce\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/le-chiese\\\/chiesa-di-santa-croce\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/le-chiese\\\/chiesa-di-santa-croce\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/wp-content\\\/uploads\\\/sites\\\/172\\\/2019\\\/12\\\/Chiesa-di-Santa-Croce-Pofi-FR.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/wp-content\\\/uploads\\\/sites\\\/172\\\/2019\\\/12\\\/Chiesa-di-Santa-Croce-Pofi-FR.jpg\",\"width\":200,\"height\":254},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/le-chiese\\\/chiesa-di-santa-croce\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le chiese\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/turismo\\\/le-chiese\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chiesa di Santa Croce\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/\",\"name\":\"Pofi\",\"description\":\"Il Tuo Comune che Comunica\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pofi\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chiesa di Santa Croce - Pofi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/chiesa-di-santa-croce\/","og_locale":"it_IT","og_type":"article","og_title":"Chiesa di Santa Croce - Pofi","og_description":"La Chiesa \u00e8 posta a lato della valle indicata come cratere principale del vulcano spento di Pofi, lungo il tratto di strada che conduce a Ceccano. Le prime notizie risalgono [&hellip;]","og_url":"https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/chiesa-di-santa-croce\/","og_site_name":"Pofi","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2019-12-10T11:42:24+00:00","og_image":[{"width":200,"height":254,"url":"https:\/\/comunicacity.net\/pofi\/wp-content\/uploads\/sites\/172\/2019\/12\/Chiesa-di-Santa-Croce-Pofi-FR.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/chiesa-di-santa-croce\/","url":"https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/chiesa-di-santa-croce\/","name":"Chiesa di Santa Croce - Pofi","isPartOf":{"@id":"https:\/\/comunicacity.net\/pofi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/chiesa-di-santa-croce\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/chiesa-di-santa-croce\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pofi\/wp-content\/uploads\/sites\/172\/2019\/12\/Chiesa-di-Santa-Croce-Pofi-FR.jpg","datePublished":"2019-12-10T11:32:50+00:00","dateModified":"2019-12-10T11:42:24+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/chiesa-di-santa-croce\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/chiesa-di-santa-croce\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/chiesa-di-santa-croce\/#primaryimage","url":"https:\/\/comunicacity.net\/pofi\/wp-content\/uploads\/sites\/172\/2019\/12\/Chiesa-di-Santa-Croce-Pofi-FR.jpg","contentUrl":"https:\/\/comunicacity.net\/pofi\/wp-content\/uploads\/sites\/172\/2019\/12\/Chiesa-di-Santa-Croce-Pofi-FR.jpg","width":200,"height":254},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/chiesa-di-santa-croce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pofi\/"},{"@type":"ListItem","position":2,"name":"Le chiese","item":"https:\/\/comunicacity.net\/pofi\/turismo\/le-chiese\/"},{"@type":"ListItem","position":3,"name":"Chiesa di Santa Croce"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pofi\/#website","url":"https:\/\/comunicacity.net\/pofi\/","name":"Pofi","description":"Il Tuo Comune che Comunica","publisher":{"@id":"https:\/\/comunicacity.net\/pofi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pofi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/pofi\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/pofi\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pofi\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/pofi\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/turismo\/68","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/types\/turismo"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/turismo\/49"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/media\/70"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/media?parent=68"}],"wp:term":[{"taxonomy":"plugin_turismo","embeddable":true,"href":"https:\/\/comunicacity.net\/pofi\/wp-json\/wp\/v2\/plugin_turismo?post=68"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}