{"id":15,"count":77,"description":"","link":"https:\/\/comunicacity.net\/pontecorvo\/category\/interruzione-di-servizio\/","name":"Interruzione di Servizio","slug":"interruzione-di-servizio","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Interruzione di Servizio - Pontecorvo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pontecorvo\/category\/interruzione-di-servizio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interruzione di Servizio - Pontecorvo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pontecorvo\/category\/interruzione-di-servizio\/\" \/>\n<meta property=\"og:site_name\" content=\"Pontecorvo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pontecorvo\/wp-content\/uploads\/sites\/164\/2019\/02\/pontecorvo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"50\" \/>\n\t<meta property=\"og:image:height\" content=\"50\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/category\\\/interruzione-di-servizio\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/category\\\/interruzione-di-servizio\\\/\",\"name\":\"Interruzione di Servizio - Pontecorvo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/category\\\/interruzione-di-servizio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/category\\\/interruzione-di-servizio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interruzione di Servizio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/\",\"name\":\"Pontecorvo\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interruzione di Servizio - Pontecorvo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pontecorvo\/category\/interruzione-di-servizio\/","og_locale":"it_IT","og_type":"article","og_title":"Interruzione di Servizio - Pontecorvo","og_url":"https:\/\/comunicacity.net\/pontecorvo\/category\/interruzione-di-servizio\/","og_site_name":"Pontecorvo","og_image":[{"url":"https:\/\/comunicacity.net\/pontecorvo\/wp-content\/uploads\/sites\/164\/2019\/02\/pontecorvo.jpg","height":50,"width":50,"type":""}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/comunicacity.net\/pontecorvo\/category\/interruzione-di-servizio\/","url":"https:\/\/comunicacity.net\/pontecorvo\/category\/interruzione-di-servizio\/","name":"Interruzione di Servizio - Pontecorvo","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontecorvo\/#website"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/pontecorvo\/category\/interruzione-di-servizio\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pontecorvo\/category\/interruzione-di-servizio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pontecorvo\/"},{"@type":"ListItem","position":2,"name":"Interruzione di Servizio"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pontecorvo\/#website","url":"https:\/\/comunicacity.net\/pontecorvo\/","name":"Pontecorvo","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pontecorvo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/categories\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/posts?categories=15"},{"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/pages?categories=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}