{"id":16809,"date":"2022-06-14T10:49:47","date_gmt":"2022-06-14T08:49:47","guid":{"rendered":"https:\/\/comunicacity.net\/pontecorvo\/2022\/06\/14\/peba-piano-eliminazione-barriere-architettoniche\/"},"modified":"2022-06-14T10:52:16","modified_gmt":"2022-06-14T08:52:16","slug":"peba-piano-eliminazione-barriere-architettoniche","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pontecorvo\/2022\/06\/14\/peba-piano-eliminazione-barriere-architettoniche\/","title":{"rendered":"Peba &#8211; Piano Eliminazione Barriere Architettoniche"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-16990 size-large\" src=\"https:\/\/www.comunepontecorvo.fr.it\/wp-content\/uploads\/2022\/06\/PEBA-logo-1024x542.jpg\" alt=\"\" width=\"1024\" height=\"542\" \/><\/p>\n<p>Il PEBA, previsto dall&#8217;art. 32, comma 21, della Legge 41 \/86 e ss.mm.ii., \u00e8 uno strumento di pianificazione e programmazione degli interventi nell&#8217;ambiente urbano, articolati nelle diverse soluzioni progettuali, per il superamento delle barriere architettoniche.<br \/>\nL&#8217;incontro pubblico sar\u00e0 utile per valutare e condividere le criticit\u00e0 e le proposte di adeguamento relative ad immobili, percorsi e spazi urbani pubblici.<br \/>\nDurante l&#8217;incontro si potranno portare all&#8217;attenzione dell&#8217;amministrazione eventuali criticit\u00e0 esistenti. Sar\u00e0 inoltre consentito, successivamente, ai cittadini e alle associazioni, di proporre osservazioni fino al 07 Luglio 2022, con le modalit\u00e0 che verranno illustrate.<\/p>\n<p>SALUTI:<br \/>\nSindaco &#8211; dott. Anselmo Rotondo<\/p>\n<p>INTERVENGONO:<br \/>\nAssessore Urbanistica: avv. Armando Satini<br \/>\nIl consigliere delegato: arch. Francesca Maini<br \/>\nI tecnici incaricati alla redazione del P.E.B.A. : ing. Chiara Carlomusto, geom. Alfio D&#8217; Aguanno,<br \/>\ncollaboratrice dott.ssa Enrica Figliorelli.<br \/>\nRappresentanti Associazioni e Cittadini.<\/p>\n<p>Fai la tua segnalazione con app ComunicaCity o a pebapontecorvo@libero.it<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_16814\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/pontecorvo\/wp-content\/uploads\/sites\/164\/2022\/06\/PEBA-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/pontecorvo\/wp-content\/uploads\/sites\/164\/2022\/06\/PEBA-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>PEBA<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il PEBA, previsto dall&#8217;art. 32, comma 21, della Legge 41 \/86 e ss.mm.ii., \u00e8 uno strumento di pianificazione e programmazione degli interventi nell&#8217;ambiente urbano, articolati nelle diverse soluzioni progettuali, per [&hellip;]<\/p>\n","protected":false},"author":297,"featured_media":16813,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-16809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Peba - Piano Eliminazione Barriere Architettoniche - Pontecorvo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pontecorvo\/2022\/06\/14\/peba-piano-eliminazione-barriere-architettoniche\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peba - Piano Eliminazione Barriere Architettoniche - Pontecorvo\" \/>\n<meta property=\"og:description\" content=\"Il PEBA, previsto dall&#8217;art. 32, comma 21, della Legge 41 \/86 e ss.mm.ii., \u00e8 uno strumento di pianificazione e programmazione degli interventi nell&#8217;ambiente urbano, articolati nelle diverse soluzioni progettuali, per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pontecorvo\/2022\/06\/14\/peba-piano-eliminazione-barriere-architettoniche\/\" \/>\n<meta property=\"og:site_name\" content=\"Pontecorvo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-14T08:49:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-14T08:52:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pontecorvo\/wp-content\/uploads\/sites\/164\/2022\/06\/Notizie-ed-informazioni-4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"fsantoro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"fsantoro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/2022\\\/06\\\/14\\\/peba-piano-eliminazione-barriere-architettoniche\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/2022\\\/06\\\/14\\\/peba-piano-eliminazione-barriere-architettoniche\\\/\"},\"author\":{\"name\":\"fsantoro\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/#\\\/schema\\\/person\\\/3da6d1b8539354d6b238c334b89e45a4\"},\"headline\":\"Peba &#8211; Piano Eliminazione Barriere Architettoniche\",\"datePublished\":\"2022-06-14T08:49:47+00:00\",\"dateModified\":\"2022-06-14T08:52:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/2022\\\/06\\\/14\\\/peba-piano-eliminazione-barriere-architettoniche\\\/\"},\"wordCount\":148,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/2022\\\/06\\\/14\\\/peba-piano-eliminazione-barriere-architettoniche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/wp-content\\\/uploads\\\/sites\\\/164\\\/2022\\\/06\\\/Notizie-ed-informazioni-4.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/2022\\\/06\\\/14\\\/peba-piano-eliminazione-barriere-architettoniche\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/2022\\\/06\\\/14\\\/peba-piano-eliminazione-barriere-architettoniche\\\/\",\"name\":\"Peba - Piano Eliminazione Barriere Architettoniche - Pontecorvo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/2022\\\/06\\\/14\\\/peba-piano-eliminazione-barriere-architettoniche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/2022\\\/06\\\/14\\\/peba-piano-eliminazione-barriere-architettoniche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/wp-content\\\/uploads\\\/sites\\\/164\\\/2022\\\/06\\\/Notizie-ed-informazioni-4.png\",\"datePublished\":\"2022-06-14T08:49:47+00:00\",\"dateModified\":\"2022-06-14T08:52:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/#\\\/schema\\\/person\\\/3da6d1b8539354d6b238c334b89e45a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/2022\\\/06\\\/14\\\/peba-piano-eliminazione-barriere-architettoniche\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/2022\\\/06\\\/14\\\/peba-piano-eliminazione-barriere-architettoniche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/2022\\\/06\\\/14\\\/peba-piano-eliminazione-barriere-architettoniche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/wp-content\\\/uploads\\\/sites\\\/164\\\/2022\\\/06\\\/Notizie-ed-informazioni-4.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/wp-content\\\/uploads\\\/sites\\\/164\\\/2022\\\/06\\\/Notizie-ed-informazioni-4.png\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/2022\\\/06\\\/14\\\/peba-piano-eliminazione-barriere-architettoniche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Peba &#8211; Piano Eliminazione Barriere Architettoniche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/\",\"name\":\"Pontecorvo\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/#\\\/schema\\\/person\\\/3da6d1b8539354d6b238c334b89e45a4\",\"name\":\"fsantoro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/60057ad1349fdd59ed92dd081853d20df17946c27188a3e99a432486e32f9b46?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/60057ad1349fdd59ed92dd081853d20df17946c27188a3e99a432486e32f9b46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/60057ad1349fdd59ed92dd081853d20df17946c27188a3e99a432486e32f9b46?s=96&d=mm&r=g\",\"caption\":\"fsantoro\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/author\\\/fsantoro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peba - Piano Eliminazione Barriere Architettoniche - Pontecorvo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pontecorvo\/2022\/06\/14\/peba-piano-eliminazione-barriere-architettoniche\/","og_locale":"it_IT","og_type":"article","og_title":"Peba - Piano Eliminazione Barriere Architettoniche - Pontecorvo","og_description":"Il PEBA, previsto dall&#8217;art. 32, comma 21, della Legge 41 \/86 e ss.mm.ii., \u00e8 uno strumento di pianificazione e programmazione degli interventi nell&#8217;ambiente urbano, articolati nelle diverse soluzioni progettuali, per [&hellip;]","og_url":"https:\/\/comunicacity.net\/pontecorvo\/2022\/06\/14\/peba-piano-eliminazione-barriere-architettoniche\/","og_site_name":"Pontecorvo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-06-14T08:49:47+00:00","article_modified_time":"2022-06-14T08:52:16+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/comunicacity.net\/pontecorvo\/wp-content\/uploads\/sites\/164\/2022\/06\/Notizie-ed-informazioni-4.png","type":"image\/png"}],"author":"fsantoro","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"fsantoro","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pontecorvo\/2022\/06\/14\/peba-piano-eliminazione-barriere-architettoniche\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontecorvo\/2022\/06\/14\/peba-piano-eliminazione-barriere-architettoniche\/"},"author":{"name":"fsantoro","@id":"https:\/\/comunicacity.net\/pontecorvo\/#\/schema\/person\/3da6d1b8539354d6b238c334b89e45a4"},"headline":"Peba &#8211; Piano Eliminazione Barriere Architettoniche","datePublished":"2022-06-14T08:49:47+00:00","dateModified":"2022-06-14T08:52:16+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pontecorvo\/2022\/06\/14\/peba-piano-eliminazione-barriere-architettoniche\/"},"wordCount":148,"image":{"@id":"https:\/\/comunicacity.net\/pontecorvo\/2022\/06\/14\/peba-piano-eliminazione-barriere-architettoniche\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontecorvo\/wp-content\/uploads\/sites\/164\/2022\/06\/Notizie-ed-informazioni-4.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pontecorvo\/2022\/06\/14\/peba-piano-eliminazione-barriere-architettoniche\/","url":"https:\/\/comunicacity.net\/pontecorvo\/2022\/06\/14\/peba-piano-eliminazione-barriere-architettoniche\/","name":"Peba - Piano Eliminazione Barriere Architettoniche - Pontecorvo","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontecorvo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pontecorvo\/2022\/06\/14\/peba-piano-eliminazione-barriere-architettoniche\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pontecorvo\/2022\/06\/14\/peba-piano-eliminazione-barriere-architettoniche\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontecorvo\/wp-content\/uploads\/sites\/164\/2022\/06\/Notizie-ed-informazioni-4.png","datePublished":"2022-06-14T08:49:47+00:00","dateModified":"2022-06-14T08:52:16+00:00","author":{"@id":"https:\/\/comunicacity.net\/pontecorvo\/#\/schema\/person\/3da6d1b8539354d6b238c334b89e45a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/pontecorvo\/2022\/06\/14\/peba-piano-eliminazione-barriere-architettoniche\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pontecorvo\/2022\/06\/14\/peba-piano-eliminazione-barriere-architettoniche\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pontecorvo\/2022\/06\/14\/peba-piano-eliminazione-barriere-architettoniche\/#primaryimage","url":"https:\/\/comunicacity.net\/pontecorvo\/wp-content\/uploads\/sites\/164\/2022\/06\/Notizie-ed-informazioni-4.png","contentUrl":"https:\/\/comunicacity.net\/pontecorvo\/wp-content\/uploads\/sites\/164\/2022\/06\/Notizie-ed-informazioni-4.png","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pontecorvo\/2022\/06\/14\/peba-piano-eliminazione-barriere-architettoniche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pontecorvo\/"},{"@type":"ListItem","position":2,"name":"Peba &#8211; Piano Eliminazione Barriere Architettoniche"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pontecorvo\/#website","url":"https:\/\/comunicacity.net\/pontecorvo\/","name":"Pontecorvo","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pontecorvo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pontecorvo\/#\/schema\/person\/3da6d1b8539354d6b238c334b89e45a4","name":"fsantoro","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/60057ad1349fdd59ed92dd081853d20df17946c27188a3e99a432486e32f9b46?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/60057ad1349fdd59ed92dd081853d20df17946c27188a3e99a432486e32f9b46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/60057ad1349fdd59ed92dd081853d20df17946c27188a3e99a432486e32f9b46?s=96&d=mm&r=g","caption":"fsantoro"},"url":"https:\/\/comunicacity.net\/pontecorvo\/author\/fsantoro\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"16989"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/posts\/16809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/users\/297"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/comments?post=16809"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/posts\/16809\/revisions"}],"predecessor-version":[{"id":16812,"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/posts\/16809\/revisions\/16812"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/media\/16813"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/media?parent=16809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/categories?post=16809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/tags?post=16809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}