{"id":88,"date":"2019-01-15T13:26:33","date_gmt":"2019-01-15T12:26:33","guid":{"rendered":"https:\/\/comunicacity.net\/pontecorvo\/?p=88"},"modified":"2019-02-11T13:27:49","modified_gmt":"2019-02-11T12:27:49","slug":"avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pontecorvo\/2019\/01\/15\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\/","title":{"rendered":"Avviso pubblico per il rinnovo del C.d.A. della A.S.M. Pontecorvo"},"content":{"rendered":"<p>Si informa che \u00e8 in pubblicazione all&#8217;Albo On-line del Comune al n. di pubblicazione 44 del 10\/01\/2019 e fino al 31\/01\/2019 l&#8217;Avviso pubblico per il rinnovo del Consiglio di Amministrazione della ASM Pontecorvo Azienda Speciale del Comune di Pontecorvo.<\/p>\n<p><em>Tutte le informazioni nel bando allegato.<\/em><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_89\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/pontecorvo\/wp-content\/uploads\/sites\/164\/2019\/02\/Documento-avv-asm.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/pontecorvo\/wp-content\/uploads\/sites\/164\/2019\/02\/Documento-avv-asm.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Documento avv asm<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si informa che \u00e8 in pubblicazione all&#8217;Albo On-line del Comune al n. di pubblicazione 44 del 10\/01\/2019 e fino al 31\/01\/2019 l&#8217;Avviso pubblico per il rinnovo del Consiglio di Amministrazione [&hellip;]<\/p>\n","protected":false},"author":282,"featured_media":90,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-88","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso pubblico per il rinnovo del C.d.A. della A.S.M. Pontecorvo - Pontecorvo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pontecorvo\/2019\/01\/15\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso pubblico per il rinnovo del C.d.A. della A.S.M. Pontecorvo - Pontecorvo\" \/>\n<meta property=\"og:description\" content=\"Si informa che \u00e8 in pubblicazione all&#8217;Albo On-line del Comune al n. di pubblicazione 44 del 10\/01\/2019 e fino al 31\/01\/2019 l&#8217;Avviso pubblico per il rinnovo del Consiglio di Amministrazione [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pontecorvo\/2019\/01\/15\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\/\" \/>\n<meta property=\"og:site_name\" content=\"Pontecorvo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-15T12:26:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-11T12:27:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pontecorvo\/wp-content\/uploads\/sites\/164\/2019\/02\/agency-worker-team.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"481\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"gestoreyic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"gestoreyic\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/2019\\\/01\\\/15\\\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/2019\\\/01\\\/15\\\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\\\/\"},\"author\":{\"name\":\"gestoreyic\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/#\\\/schema\\\/person\\\/5278c46c2f94b6a18223c1e9f8964196\"},\"headline\":\"Avviso pubblico per il rinnovo del C.d.A. della A.S.M. Pontecorvo\",\"datePublished\":\"2019-01-15T12:26:33+00:00\",\"dateModified\":\"2019-02-11T12:27:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/2019\\\/01\\\/15\\\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\\\/\"},\"wordCount\":55,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/2019\\\/01\\\/15\\\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/wp-content\\\/uploads\\\/sites\\\/164\\\/2019\\\/02\\\/agency-worker-team.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/2019\\\/01\\\/15\\\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/2019\\\/01\\\/15\\\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\\\/\",\"name\":\"Avviso pubblico per il rinnovo del C.d.A. della A.S.M. Pontecorvo - Pontecorvo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/2019\\\/01\\\/15\\\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/2019\\\/01\\\/15\\\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/wp-content\\\/uploads\\\/sites\\\/164\\\/2019\\\/02\\\/agency-worker-team.jpg\",\"datePublished\":\"2019-01-15T12:26:33+00:00\",\"dateModified\":\"2019-02-11T12:27:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/#\\\/schema\\\/person\\\/5278c46c2f94b6a18223c1e9f8964196\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/2019\\\/01\\\/15\\\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/2019\\\/01\\\/15\\\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/2019\\\/01\\\/15\\\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/wp-content\\\/uploads\\\/sites\\\/164\\\/2019\\\/02\\\/agency-worker-team.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/wp-content\\\/uploads\\\/sites\\\/164\\\/2019\\\/02\\\/agency-worker-team.jpg\",\"width\":1000,\"height\":481,\"caption\":\"Business Team Office Worker Entrepreneur Concept\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/2019\\\/01\\\/15\\\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso pubblico per il rinnovo del C.d.A. della A.S.M. Pontecorvo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/\",\"name\":\"Pontecorvo\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/#\\\/schema\\\/person\\\/5278c46c2f94b6a18223c1e9f8964196\",\"name\":\"gestoreyic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g\",\"caption\":\"gestoreyic\"},\"description\":\"Sede Legale: Via Pazzano 112 00118 Roma Sede Operativa: Via A. Savastano 2 03043 Cassino (FR) Telefono: +39 0776-23813 Email: info@yesicode.it\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontecorvo\\\/author\\\/gestoreyic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso pubblico per il rinnovo del C.d.A. della A.S.M. Pontecorvo - Pontecorvo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pontecorvo\/2019\/01\/15\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso pubblico per il rinnovo del C.d.A. della A.S.M. Pontecorvo - Pontecorvo","og_description":"Si informa che \u00e8 in pubblicazione all&#8217;Albo On-line del Comune al n. di pubblicazione 44 del 10\/01\/2019 e fino al 31\/01\/2019 l&#8217;Avviso pubblico per il rinnovo del Consiglio di Amministrazione [&hellip;]","og_url":"https:\/\/comunicacity.net\/pontecorvo\/2019\/01\/15\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\/","og_site_name":"Pontecorvo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-01-15T12:26:33+00:00","article_modified_time":"2019-02-11T12:27:49+00:00","og_image":[{"width":1000,"height":481,"url":"https:\/\/comunicacity.net\/pontecorvo\/wp-content\/uploads\/sites\/164\/2019\/02\/agency-worker-team.jpg","type":"image\/jpeg"}],"author":"gestoreyic","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"gestoreyic"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pontecorvo\/2019\/01\/15\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontecorvo\/2019\/01\/15\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\/"},"author":{"name":"gestoreyic","@id":"https:\/\/comunicacity.net\/pontecorvo\/#\/schema\/person\/5278c46c2f94b6a18223c1e9f8964196"},"headline":"Avviso pubblico per il rinnovo del C.d.A. della A.S.M. Pontecorvo","datePublished":"2019-01-15T12:26:33+00:00","dateModified":"2019-02-11T12:27:49+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pontecorvo\/2019\/01\/15\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\/"},"wordCount":55,"image":{"@id":"https:\/\/comunicacity.net\/pontecorvo\/2019\/01\/15\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontecorvo\/wp-content\/uploads\/sites\/164\/2019\/02\/agency-worker-team.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pontecorvo\/2019\/01\/15\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\/","url":"https:\/\/comunicacity.net\/pontecorvo\/2019\/01\/15\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\/","name":"Avviso pubblico per il rinnovo del C.d.A. della A.S.M. Pontecorvo - Pontecorvo","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontecorvo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pontecorvo\/2019\/01\/15\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pontecorvo\/2019\/01\/15\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontecorvo\/wp-content\/uploads\/sites\/164\/2019\/02\/agency-worker-team.jpg","datePublished":"2019-01-15T12:26:33+00:00","dateModified":"2019-02-11T12:27:49+00:00","author":{"@id":"https:\/\/comunicacity.net\/pontecorvo\/#\/schema\/person\/5278c46c2f94b6a18223c1e9f8964196"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/pontecorvo\/2019\/01\/15\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pontecorvo\/2019\/01\/15\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pontecorvo\/2019\/01\/15\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\/#primaryimage","url":"https:\/\/comunicacity.net\/pontecorvo\/wp-content\/uploads\/sites\/164\/2019\/02\/agency-worker-team.jpg","contentUrl":"https:\/\/comunicacity.net\/pontecorvo\/wp-content\/uploads\/sites\/164\/2019\/02\/agency-worker-team.jpg","width":1000,"height":481,"caption":"Business Team Office Worker Entrepreneur Concept"},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pontecorvo\/2019\/01\/15\/avviso-pubblico-per-il-rinnovo-del-c-d-a-della-a-s-m-pontecorvo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pontecorvo\/"},{"@type":"ListItem","position":2,"name":"Avviso pubblico per il rinnovo del C.d.A. della A.S.M. Pontecorvo"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pontecorvo\/#website","url":"https:\/\/comunicacity.net\/pontecorvo\/","name":"Pontecorvo","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pontecorvo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pontecorvo\/#\/schema\/person\/5278c46c2f94b6a18223c1e9f8964196","name":"gestoreyic","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g","caption":"gestoreyic"},"description":"Sede Legale: Via Pazzano 112 00118 Roma Sede Operativa: Via A. Savastano 2 03043 Cassino (FR) Telefono: +39 0776-23813 Email: info@yesicode.it","url":"https:\/\/comunicacity.net\/pontecorvo\/author\/gestoreyic\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/posts\/88","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/users\/282"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/comments?post=88"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/posts\/88\/revisions"}],"predecessor-version":[{"id":91,"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/posts\/88\/revisions\/91"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/media\/90"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/media?parent=88"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/categories?post=88"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pontecorvo\/wp-json\/wp\/v2\/tags?post=88"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}