{"id":324,"date":"2019-03-19T22:22:25","date_gmt":"2019-03-19T21:22:25","guid":{"rendered":"https:\/\/comunicacity.net\/pontinia\/?post_type=info&#038;p=324"},"modified":"2020-08-19T12:33:35","modified_gmt":"2020-08-19T10:33:35","slug":"orari-servizio-pubblico-cotral","status":"publish","type":"info","link":"https:\/\/comunicacity.net\/pontinia\/info\/mobilita-e-trasporti\/orari-servizio-pubblico-cotral\/","title":{"rendered":"Orari servizio pubblico Cotral"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>ORARI TRASPORTO PUBBLICO COTRAL<\/strong><\/p>\n<p style=\"text-align: center;\">I seguenti orari saranno validi fino al <strong>17\/04\/2019<\/strong>.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-325\" src=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral1.png\" alt=\"\" width=\"982\" height=\"673\" data-wp-pid=\"325\" srcset=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral1.png 982w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral1-300x206.png 300w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral1-768x526.png 768w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral1-680x466.png 680w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral1-800x548.png 800w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral1-600x411.png 600w\" sizes=\"auto, (max-width: 982px) 100vw, 982px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-326\" src=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral2.png\" alt=\"\" width=\"980\" height=\"672\" data-wp-pid=\"326\" srcset=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral2.png 980w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral2-300x206.png 300w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral2-768x527.png 768w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral2-680x466.png 680w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral2-800x549.png 800w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral2-600x411.png 600w\" sizes=\"auto, (max-width: 980px) 100vw, 980px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-327\" src=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral3.png\" alt=\"\" width=\"989\" height=\"602\" data-wp-pid=\"327\" srcset=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral3.png 989w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral3-300x183.png 300w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral3-768x467.png 768w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral3-680x414.png 680w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral3-800x487.png 800w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral3-600x365.png 600w\" sizes=\"auto, (max-width: 989px) 100vw, 989px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-328\" src=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral4.png\" alt=\"\" width=\"984\" height=\"597\" data-wp-pid=\"328\" srcset=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral4.png 984w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral4-300x182.png 300w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral4-768x466.png 768w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral4-680x413.png 680w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral4-800x485.png 800w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral4-600x364.png 600w\" sizes=\"auto, (max-width: 984px) 100vw, 984px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ORARI TRASPORTO PUBBLICO COTRAL I seguenti orari saranno validi fino al 17\/04\/2019.<\/p>\n","protected":false},"featured_media":0,"parent":124,"menu_order":0,"template":"","meta":[],"plugin_info":[],"class_list":["post-324","info","type-info","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Orari servizio pubblico Cotral - Pontinia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pontinia\/info\/mobilita-e-trasporti\/orari-servizio-pubblico-cotral\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Orari servizio pubblico Cotral - Pontinia\" \/>\n<meta property=\"og:description\" content=\"ORARI TRASPORTO PUBBLICO COTRAL I seguenti orari saranno validi fino al 17\/04\/2019.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pontinia\/info\/mobilita-e-trasporti\/orari-servizio-pubblico-cotral\/\" \/>\n<meta property=\"og:site_name\" content=\"Pontinia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-19T10:33:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/info\\\/mobilita-e-trasporti\\\/orari-servizio-pubblico-cotral\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/info\\\/mobilita-e-trasporti\\\/orari-servizio-pubblico-cotral\\\/\",\"name\":\"Orari servizio pubblico Cotral - Pontinia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/info\\\/mobilita-e-trasporti\\\/orari-servizio-pubblico-cotral\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/info\\\/mobilita-e-trasporti\\\/orari-servizio-pubblico-cotral\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/03\\\/cotral1.png\",\"datePublished\":\"2019-03-19T21:22:25+00:00\",\"dateModified\":\"2020-08-19T10:33:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/info\\\/mobilita-e-trasporti\\\/orari-servizio-pubblico-cotral\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/info\\\/mobilita-e-trasporti\\\/orari-servizio-pubblico-cotral\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/info\\\/mobilita-e-trasporti\\\/orari-servizio-pubblico-cotral\\\/#primaryimage\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/03\\\/cotral1.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/03\\\/cotral1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/info\\\/mobilita-e-trasporti\\\/orari-servizio-pubblico-cotral\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mobilit\u00e0 e Trasporti\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/info\\\/mobilita-e-trasporti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Orari servizio pubblico Cotral\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\",\"name\":\"Pontinia\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Orari servizio pubblico Cotral - Pontinia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pontinia\/info\/mobilita-e-trasporti\/orari-servizio-pubblico-cotral\/","og_locale":"it_IT","og_type":"article","og_title":"Orari servizio pubblico Cotral - Pontinia","og_description":"ORARI TRASPORTO PUBBLICO COTRAL I seguenti orari saranno validi fino al 17\/04\/2019.","og_url":"https:\/\/comunicacity.net\/pontinia\/info\/mobilita-e-trasporti\/orari-servizio-pubblico-cotral\/","og_site_name":"Pontinia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2020-08-19T10:33:35+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pontinia\/info\/mobilita-e-trasporti\/orari-servizio-pubblico-cotral\/","url":"https:\/\/comunicacity.net\/pontinia\/info\/mobilita-e-trasporti\/orari-servizio-pubblico-cotral\/","name":"Orari servizio pubblico Cotral - Pontinia","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/info\/mobilita-e-trasporti\/orari-servizio-pubblico-cotral\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/info\/mobilita-e-trasporti\/orari-servizio-pubblico-cotral\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral1.png","datePublished":"2019-03-19T21:22:25+00:00","dateModified":"2020-08-19T10:33:35+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/pontinia\/info\/mobilita-e-trasporti\/orari-servizio-pubblico-cotral\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pontinia\/info\/mobilita-e-trasporti\/orari-servizio-pubblico-cotral\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pontinia\/info\/mobilita-e-trasporti\/orari-servizio-pubblico-cotral\/#primaryimage","url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral1.png","contentUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/03\/cotral1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pontinia\/info\/mobilita-e-trasporti\/orari-servizio-pubblico-cotral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pontinia\/"},{"@type":"ListItem","position":2,"name":"Mobilit\u00e0 e Trasporti","item":"https:\/\/comunicacity.net\/pontinia\/info\/mobilita-e-trasporti\/"},{"@type":"ListItem","position":3,"name":"Orari servizio pubblico Cotral"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pontinia\/#website","url":"https:\/\/comunicacity.net\/pontinia\/","name":"Pontinia","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pontinia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/info\/324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/info"}],"about":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/types\/info"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/info\/124"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media?parent=324"}],"wp:term":[{"taxonomy":"plugin_info","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/plugin_info?post=324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}