{"id":1083,"date":"2019-09-03T23:27:43","date_gmt":"2019-09-03T21:27:43","guid":{"rendered":"https:\/\/comunicacity.net\/pontinia\/?p=1083"},"modified":"2019-09-03T23:27:43","modified_gmt":"2019-09-03T21:27:43","slug":"pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pontinia\/2019\/09\/03\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\/","title":{"rendered":"Pontinia, la Festa dello Sport tra le novit\u00e0 e il successo in piazza"},"content":{"rendered":"<p><strong><b>Pontinia, si chiude con successo la quinta edizione della Festa dello Sport<\/b><br \/>\n<\/strong><\/p>\n<p><strong> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1084 alignnone\" src=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/09\/IMG_2624-300x200.jpg\" alt=\"\" width=\"342\" height=\"228\" srcset=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/09\/IMG_2624-300x200.jpg 300w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/09\/IMG_2624-768x512.jpg 768w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/09\/IMG_2624-1024x683.jpg 1024w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/09\/IMG_2624-680x453.jpg 680w\" sizes=\"auto, (max-width: 342px) 100vw, 342px\" \/><\/strong><\/p>\n<p>La <strong>Festa dello sport di Pontinia<\/strong> che ha avuto luogo lungo le principali vie del centro oltre che in Piazza Indipendenza ha avuto un grande successo probabilmente anche grazie alle riunioni che hanno preceduto l\u2019evento, volte a analizzare criticit\u00e0 e punti di forza rispetto agli anni passati per correggere i primi e rafforzare i secondi.<\/p>\n<p>La manifestazione \u00e8 iniziata in mattinata con l\u2019accesso libero presso la piscina dell\u2019<strong>ASD <\/strong>dell\u2019<strong>Aquaria<\/strong> di Pontinia e con le prime associazioni che hanno potuto usufruire dei\u00a0 campi da basket, volley, calcetto e handball. Sono state molte le novit\u00e0 messe in essere dall\u2019amministrazione comunale supportata anche in modo egregio dalle associazioni sportive del nostro territorio nonch\u00e9 anche dalle associazioni dei paesi limitrofi. Tutti con uno scopo comune: quello di promuovere lo sport e i suoi valori attraverso le proprie discipline. Particolare valore aggiunto alla manifestazione \u00e8 stato dato dal Coni regionale. Lo slogan che ha fatto da sfondo \u00e8 stato \u201c Sport bene comune\u201d . Durante l\u2019evento hanno sfilato circa 50 associazioni sportive lungo le strade della citt\u00e0 guidate dalla banda <strong>De Julis<\/strong> e dalle <strong>Majorettes White Flower<\/strong>, coordinati tutti dalle scuole di danza che hanno dato un tocco di vivacit\u00e0 al corteo che si \u00e8 concluso in Piazza Indipendenza. Qui \u00e8 stato allestito un palco dove ci \u00e8 stato un applauditissimo \u201cflash mob per la vita\u201d promosso dal <strong>Poliambulatorio Sant\u2019Anna<\/strong>. Le associazioni hanno tenuto alta la l\u2019atmosfera con le loro esibizioni dalle 16:30 alle 20 momento in cui sono stati fatti i doverosi riconoscimenti agli atleti che provavano discipine diverse da quelle che svolgevano quotidianamente. Momento clou della manifestazione \u00e8 stato l\u2019arrivo sul palco del capitano della <strong>Top Volley Daniele Sottile<\/strong> con altri giocatori come <strong>Domenico Cavaccini<\/strong>, <strong>Samuel Onwuelo <\/strong>e <strong>Luca Rossato<\/strong> accompagnati dal direttore sportivo <strong>Candido Grande<\/strong>. Dopo una breve presentazione, i ragazzi della <strong>Top <\/strong>si sono cimentati in una partita mista con le associazioni presenti sul campo del volley entusiasmando cos\u00ec gli appassionati che mai avrebbero pensato di poter giocare al fianco di campioni cos\u00ec importanti del panorama internazionale e nazionale del volley italiano. Tutto questo \u00e8 stato possibile grazie alla societ\u00e0 e al responsabile dell\u2019ufficio stampa del club di Latina: <strong>Giuseppe Baratta<\/strong>. Per tutta la durata della manifestazione, il direttivo della consulta dello sport ha girato lungo le strade supportato da 6 mamme coordinate da <strong>Alessandra Di Trapano <\/strong>che hanno lavorato senza sosta per far si che tutte le associazioni potessero avere il supporto necessario in ogni istante.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1085\" src=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/09\/IMG_2913-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/09\/IMG_2913-300x200.jpg 300w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/09\/IMG_2913-768x512.jpg 768w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/09\/IMG_2913-1024x683.jpg 1024w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/09\/IMG_2913-680x453.jpg 680w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>A breve le associazioni si riuniranno per analizzare la festa e per promuovere altre attivit\u00e0 con la consulta comunale dello sport per fare sempre meglio il prossimo anno.<\/p>\n<div class=\"td-header-sp-logo\"><a class=\"td-main-logo\" href=\"https:\/\/www.latinacorriere.it\/\"> <img decoding=\"async\" class=\"td-retina-data\" src=\"https:\/\/latinacorriere.netinprogress.com\/wp-content\/uploads\/2019\/05\/logo.png\" alt=\"\" \/> <span class=\"td-visual-hidden\">LatinaCorriere.it<\/span> <\/a><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pontinia, si chiude con successo la quinta edizione della Festa dello Sport La Festa dello sport di Pontinia che ha avuto luogo lungo le principali vie del centro oltre che [&hellip;]<\/p>\n","protected":false},"author":294,"featured_media":1086,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-1083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pontinia, la Festa dello Sport tra le novit\u00e0 e il successo in piazza - Pontinia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pontinia\/2019\/09\/03\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pontinia, la Festa dello Sport tra le novit\u00e0 e il successo in piazza - Pontinia\" \/>\n<meta property=\"og:description\" content=\"Pontinia, si chiude con successo la quinta edizione della Festa dello Sport La Festa dello sport di Pontinia che ha avuto luogo lungo le principali vie del centro oltre che [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pontinia\/2019\/09\/03\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\/\" \/>\n<meta property=\"og:site_name\" content=\"Pontinia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-03T21:27:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/09\/IMG_2918-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sportpontinia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sportpontinia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/09\\\/03\\\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/09\\\/03\\\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\\\/\"},\"author\":{\"name\":\"sportpontinia\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"headline\":\"Pontinia, la Festa dello Sport tra le novit\u00e0 e il successo in piazza\",\"datePublished\":\"2019-09-03T21:27:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/09\\\/03\\\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\\\/\"},\"wordCount\":458,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/09\\\/03\\\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/09\\\/IMG_2918.jpg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/09\\\/03\\\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/09\\\/03\\\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\\\/\",\"name\":\"Pontinia, la Festa dello Sport tra le novit\u00e0 e il successo in piazza - Pontinia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/09\\\/03\\\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/09\\\/03\\\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/09\\\/IMG_2918.jpg\",\"datePublished\":\"2019-09-03T21:27:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/09\\\/03\\\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/09\\\/03\\\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/09\\\/03\\\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/09\\\/IMG_2918.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/09\\\/IMG_2918.jpg\",\"width\":5184,\"height\":3456},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/09\\\/03\\\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pontinia, la Festa dello Sport tra le novit\u00e0 e il successo in piazza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\",\"name\":\"Pontinia\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\",\"name\":\"sportpontinia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"caption\":\"sportpontinia\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/author\\\/sportpontinia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pontinia, la Festa dello Sport tra le novit\u00e0 e il successo in piazza - Pontinia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pontinia\/2019\/09\/03\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\/","og_locale":"it_IT","og_type":"article","og_title":"Pontinia, la Festa dello Sport tra le novit\u00e0 e il successo in piazza - Pontinia","og_description":"Pontinia, si chiude con successo la quinta edizione della Festa dello Sport La Festa dello sport di Pontinia che ha avuto luogo lungo le principali vie del centro oltre che [&hellip;]","og_url":"https:\/\/comunicacity.net\/pontinia\/2019\/09\/03\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\/","og_site_name":"Pontinia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-09-03T21:27:43+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/09\/IMG_2918-1024x683.jpg","type":"image\/jpeg"}],"author":"sportpontinia","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sportpontinia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pontinia\/2019\/09\/03\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/09\/03\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\/"},"author":{"name":"sportpontinia","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"headline":"Pontinia, la Festa dello Sport tra le novit\u00e0 e il successo in piazza","datePublished":"2019-09-03T21:27:43+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/09\/03\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\/"},"wordCount":458,"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/09\/03\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/09\/IMG_2918.jpg","articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pontinia\/2019\/09\/03\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\/","url":"https:\/\/comunicacity.net\/pontinia\/2019\/09\/03\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\/","name":"Pontinia, la Festa dello Sport tra le novit\u00e0 e il successo in piazza - Pontinia","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/09\/03\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/09\/03\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/09\/IMG_2918.jpg","datePublished":"2019-09-03T21:27:43+00:00","author":{"@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/09\/03\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pontinia\/2019\/09\/03\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pontinia\/2019\/09\/03\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\/#primaryimage","url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/09\/IMG_2918.jpg","contentUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/09\/IMG_2918.jpg","width":5184,"height":3456},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pontinia\/2019\/09\/03\/pontinia-la-festa-dello-sport-tra-le-novita-e-il-successo-in-piazza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pontinia\/"},{"@type":"ListItem","position":2,"name":"Pontinia, la Festa dello Sport tra le novit\u00e0 e il successo in piazza"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pontinia\/#website","url":"https:\/\/comunicacity.net\/pontinia\/","name":"Pontinia","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pontinia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807","name":"sportpontinia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","caption":"sportpontinia"},"url":"https:\/\/comunicacity.net\/pontinia\/author\/sportpontinia\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/1083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/users\/294"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/comments?post=1083"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/1083\/revisions"}],"predecessor-version":[{"id":1088,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/1083\/revisions\/1088"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media\/1086"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media?parent=1083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/categories?post=1083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/tags?post=1083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}