{"id":1880,"date":"2020-06-09T11:39:53","date_gmt":"2020-06-09T09:39:53","guid":{"rendered":"https:\/\/comunicacity.net\/pontinia\/?p=1880"},"modified":"2020-06-09T11:39:53","modified_gmt":"2020-06-09T09:39:53","slug":"asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pontinia\/2020\/06\/09\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\/","title":{"rendered":"ASD Futsal Pontinia 2017: Teana Tittoni nuovo tecnico. Vicini altri colpi di #futsalmercato"},"content":{"rendered":"<div class=\"td-post-content\">\n<p>Con il comunicato 303 del 21 maggio la Lega Nazionale Dilettanti ha definitivamente chiuso la stagione 2019\/20. La voglia di incontrare le nostre ragazze per\u00f2 \u00e8 tanta perch\u00e9 nel cuore del campionato con l\u2019entusiasmo che ci portava ad affrontare ogni partita con il sorriso ed il desiderio di migliorare. E allora? Allora non essendo ancora delineate le regole per riprendere le attivit\u00e0 facciamo una seduta di allenamento individuale presso lo Sport Training Pontino nel rispetto del distanziamento sociale guidati da Giulio Ricciardone (Dott. in scienze motorie e responsabile della scuola calcio)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-1881 aligncenter\" src=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2020\/06\/101821187_2621488211425187_3229172797880139776_n-300x200.jpg\" alt=\"\" width=\"329\" height=\"219\" srcset=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2020\/06\/101821187_2621488211425187_3229172797880139776_n-300x200.jpg 300w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2020\/06\/101821187_2621488211425187_3229172797880139776_n-768x512.jpg 768w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2020\/06\/101821187_2621488211425187_3229172797880139776_n-680x453.jpg 680w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2020\/06\/101821187_2621488211425187_3229172797880139776_n.jpg 960w\" sizes=\"auto, (max-width: 329px) 100vw, 329px\" \/><\/p>\n<p><strong>GUIDA TECNICA \u2013<\/strong> Sar\u00e0 un\u2019occasione importante per rivedere le nostre giocatrici e renderle partecipi di come la societ\u00e0 si sta preparando ad affrontare la prossima stagione con tutte loro. La cosa pi\u00f9 importante sar\u00e0 quella di fargli conoscere il nuovo allenatore, siamo euforici per essere riusciti a portare in granata <strong>Teana Tittoni<\/strong>, nome illustre del calcio a 5 femminile, alla sua prima esperienza su una panchina di una prima squadra, ma gi\u00e0 da anni alla guida di squadre del settore giovanile della blasonata Virtus Ciampino femminile, squadra con la quale \u00e8 stata protagonista in campo vantando nel suo palmares 3 scudetti e 3 coppe Italia citando solo i trofei pi\u00f9 importanti. Riteniamo che il suo arrivo possa dare un valore aggiunto importante sia dal punto di vista tecnico-tattico che per la gestione del gruppo. Stiamo iniziando un percorso nuovo, Teana gode della stima di tutti i dirigenti e delle atlete che gi\u00e0 la conoscono. Pensiamo che con lei possiamo avere un nuovo punto di partenza, per questo stiamo lavorando per definire tutti i ruoli necessari ed importanti da affiancargli affinch\u00e9 la crescita di questo sport per il nostro paese possa essere un punto di riferimento per le ragazze che vorranno avvicinarsi al mondo del calcio a 5 femminile. Non ci fermiamo qui: l\u2019altro obiettivo \u00e8 quello di arricchire la rosa con elementi di valore, alcuni dei quali sono gi\u00e0 vicini a condividere il nostro progetto. Qualsiasi notizia arriver\u00e0 dalla LND noi saremo pronti!<\/p>\n<p><strong>Ufficio Stampa Futsal Pontinia 2017<\/strong><\/p>\n<div class=\"td-banner-wrap-full td-logo-wrap-full\">\n<div class=\"td-container td-header-row td-header-header\">\n<div class=\"td-header-sp-logo\"><a href=\"https:\/\/www.ladyfutsal.com\/\"> <img loading=\"lazy\" decoding=\"async\" class=\"td-retina-data aligncenter\" title=\"calcio a 5 femmile\" src=\"https:\/\/www.ladyfutsal.com\/wp-content\/uploads\/2016\/06\/LF-web90-h.png\" alt=\"Lady Futsal\" width=\"426\" height=\"101\" data-retina=\"https:\/\/www.ladyfutsal.com\/wp-content\/uploads\/2016\/06\/LF-retina-180-h.png\" \/> <\/a><\/div>\n<div class=\"td-header-sp-recs\">\n<div class=\"td-header-rec-wrap\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Con il comunicato 303 del 21 maggio la Lega Nazionale Dilettanti ha definitivamente chiuso la stagione 2019\/20. La voglia di incontrare le nostre ragazze per\u00f2 \u00e8 tanta perch\u00e9 nel cuore [&hellip;]<\/p>\n","protected":false},"author":294,"featured_media":1878,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,24],"tags":[],"class_list":["post-1880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ASD Futsal Pontinia 2017: Teana Tittoni nuovo tecnico. Vicini altri colpi di #futsalmercato - Pontinia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pontinia\/2020\/06\/09\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASD Futsal Pontinia 2017: Teana Tittoni nuovo tecnico. Vicini altri colpi di #futsalmercato - Pontinia\" \/>\n<meta property=\"og:description\" content=\"Con il comunicato 303 del 21 maggio la Lega Nazionale Dilettanti ha definitivamente chiuso la stagione 2019\/20. La voglia di incontrare le nostre ragazze per\u00f2 \u00e8 tanta perch\u00e9 nel cuore [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pontinia\/2020\/06\/09\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\/\" \/>\n<meta property=\"og:site_name\" content=\"Pontinia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-09T09:39:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2020\/06\/71203250_2406378352936175_307192837152178176_o.png\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"sportpontinia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sportpontinia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2020\\\/06\\\/09\\\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2020\\\/06\\\/09\\\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\\\/\"},\"author\":{\"name\":\"sportpontinia\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"headline\":\"ASD Futsal Pontinia 2017: Teana Tittoni nuovo tecnico. Vicini altri colpi di #futsalmercato\",\"datePublished\":\"2020-06-09T09:39:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2020\\\/06\\\/09\\\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\\\/\"},\"wordCount\":342,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2020\\\/06\\\/09\\\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2020\\\/06\\\/71203250_2406378352936175_307192837152178176_o.png\",\"articleSection\":[\"Notizie e Informazioni\",\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2020\\\/06\\\/09\\\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2020\\\/06\\\/09\\\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\\\/\",\"name\":\"ASD Futsal Pontinia 2017: Teana Tittoni nuovo tecnico. Vicini altri colpi di #futsalmercato - Pontinia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2020\\\/06\\\/09\\\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2020\\\/06\\\/09\\\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2020\\\/06\\\/71203250_2406378352936175_307192837152178176_o.png\",\"datePublished\":\"2020-06-09T09:39:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2020\\\/06\\\/09\\\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2020\\\/06\\\/09\\\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2020\\\/06\\\/09\\\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2020\\\/06\\\/71203250_2406378352936175_307192837152178176_o.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2020\\\/06\\\/71203250_2406378352936175_307192837152178176_o.png\",\"width\":960,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2020\\\/06\\\/09\\\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASD Futsal Pontinia 2017: Teana Tittoni nuovo tecnico. Vicini altri colpi di #futsalmercato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\",\"name\":\"Pontinia\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\",\"name\":\"sportpontinia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"caption\":\"sportpontinia\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/author\\\/sportpontinia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASD Futsal Pontinia 2017: Teana Tittoni nuovo tecnico. Vicini altri colpi di #futsalmercato - Pontinia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pontinia\/2020\/06\/09\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\/","og_locale":"it_IT","og_type":"article","og_title":"ASD Futsal Pontinia 2017: Teana Tittoni nuovo tecnico. Vicini altri colpi di #futsalmercato - Pontinia","og_description":"Con il comunicato 303 del 21 maggio la Lega Nazionale Dilettanti ha definitivamente chiuso la stagione 2019\/20. La voglia di incontrare le nostre ragazze per\u00f2 \u00e8 tanta perch\u00e9 nel cuore [&hellip;]","og_url":"https:\/\/comunicacity.net\/pontinia\/2020\/06\/09\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\/","og_site_name":"Pontinia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-06-09T09:39:53+00:00","og_image":[{"width":960,"height":960,"url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2020\/06\/71203250_2406378352936175_307192837152178176_o.png","type":"image\/png"}],"author":"sportpontinia","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sportpontinia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pontinia\/2020\/06\/09\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/2020\/06\/09\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\/"},"author":{"name":"sportpontinia","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"headline":"ASD Futsal Pontinia 2017: Teana Tittoni nuovo tecnico. Vicini altri colpi di #futsalmercato","datePublished":"2020-06-09T09:39:53+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2020\/06\/09\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\/"},"wordCount":342,"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2020\/06\/09\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2020\/06\/71203250_2406378352936175_307192837152178176_o.png","articleSection":["Notizie e Informazioni","Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pontinia\/2020\/06\/09\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\/","url":"https:\/\/comunicacity.net\/pontinia\/2020\/06\/09\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\/","name":"ASD Futsal Pontinia 2017: Teana Tittoni nuovo tecnico. Vicini altri colpi di #futsalmercato - Pontinia","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2020\/06\/09\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2020\/06\/09\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2020\/06\/71203250_2406378352936175_307192837152178176_o.png","datePublished":"2020-06-09T09:39:53+00:00","author":{"@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/pontinia\/2020\/06\/09\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pontinia\/2020\/06\/09\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pontinia\/2020\/06\/09\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\/#primaryimage","url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2020\/06\/71203250_2406378352936175_307192837152178176_o.png","contentUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2020\/06\/71203250_2406378352936175_307192837152178176_o.png","width":960,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pontinia\/2020\/06\/09\/asd-futsal-pontinia-2017-teana-tittoni-nuovo-tecnico-vicini-altri-colpi-di-futsalmercato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pontinia\/"},{"@type":"ListItem","position":2,"name":"ASD Futsal Pontinia 2017: Teana Tittoni nuovo tecnico. Vicini altri colpi di #futsalmercato"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pontinia\/#website","url":"https:\/\/comunicacity.net\/pontinia\/","name":"Pontinia","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pontinia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807","name":"sportpontinia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","caption":"sportpontinia"},"url":"https:\/\/comunicacity.net\/pontinia\/author\/sportpontinia\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/1880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/users\/294"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/comments?post=1880"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/1880\/revisions"}],"predecessor-version":[{"id":1882,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/1880\/revisions\/1882"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media\/1878"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media?parent=1880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/categories?post=1880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/tags?post=1880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}