{"id":2678,"date":"2021-02-22T15:34:57","date_gmt":"2021-02-22T14:34:57","guid":{"rendered":"https:\/\/comunicacity.net\/pontinia\/?p=2678"},"modified":"2021-02-22T15:34:57","modified_gmt":"2021-02-22T14:34:57","slug":"coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pontinia\/2021\/02\/22\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\/","title":{"rendered":"Coppa America: Luna Rossa vince Prada Cup e va in finale"},"content":{"rendered":"<p style=\"text-align: center\"><strong><a href=\"https:\/\/www.ansa.it\/\">Ansa <\/a><a title=\"Sport\" href=\"https:\/\/www.ansa.it\/sito\/notizie\/sport\/sport.shtml\">Sport<\/a><\/strong><\/p>\n<hr \/>\n<p>Luna Rossa vince la Prada Cup e conquista l&#8217;accesso alla finale della Coppa America, dove affronter\u00e0 Team New Zealand. L&#8217;equipaggio azzurro ha dominato le due regate della notte contro l&#8217;imbarcazione britannica Ineos portandosi cos\u00ec sul 7-1 nella serie.<\/p>\n<figure id=\"attachment_2679\" aria-describedby=\"caption-attachment-2679\" style=\"width: 457px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2679\" src=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/02\/0e3a414a5951dc20c02dfe0f7041310.jpg\" alt=\"\" width=\"457\" height=\"305\" srcset=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/02\/0e3a414a5951dc20c02dfe0f7041310.jpg 457w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/02\/0e3a414a5951dc20c02dfe0f7041310-300x200.jpg 300w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/><figcaption id=\"caption-attachment-2679\" class=\"wp-caption-text\">Luna Rossa Prada Pirelli team celebrate after winning the Prada Cup final, the 36th America&#8217;s Cup challenger series, in Auckland on February 21, 2021. (Photo by Gilles Martin-Raget \/ AFP)<\/figcaption><\/figure>\n<hr \/>\n<p>La finale di coppa America si terr\u00e0, sempre nelle acque del Golfo neozelandese di Hauraki, dal 6 al 15 marzo prossimo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.ansa.it\/webimages\/img_700\/2021\/2\/20\/042aca3a20fa77f7fa659d87ffbbbaf.jpg\" alt=\"\" width=\"460\" height=\"307\" \/><br \/>\nGrazie al successo su Ineos Team UK ed alla vittoria della Prada Cup, Luna Rossa \u00e8 lo sfidante per la seconda volta nella storia della America&#8217;s Cup: era successo nel 2000, proprio a Auckland, quando la barca italiana si era meritata il soprannome di Silver Bullet. Patrizio Bertelli dopo quella prima sfida ne ha volute altre cinque, questa attraverso il Circolo della Vela Sicilia. &#8220;Un bravo all&#8217;equipaggio &#8211; ha detto l&#8217;armatore &#8211; ed a tutto il team che ha lavorato senza sosta per ottenere il risultato. Adesso dobbiamo pensare al Match finale dell&#8217;America&#8217;s Cup contro i neozelandesi&#8221;. Le due regate decisive si sono incastonate in una giornata perfetta per l&#8217;equipaggio condotto dai due timonieri Francesco Checco Bruni e James Jimmy Spithill, che ha chiuso ogni porta all&#8217;avversario. Luna Rossa accede al 36\/mo Match dell&#8217;America&#8217;s Cup dopo aver battuto 7-1 Britannia, la barca presentata dal Royal Yacht Squadron di Cowes, uno dei templi della vela. Il super equipaggio di Sir Ben Ainslie, finanziato da Sir Jim Ratcliffe, non ce l&#8217;ha fatta e non potr\u00e0 tentare di riportare la Coppa la dove manca da 170 anni.<\/p>\n<hr \/>\n<p style=\"text-align: center\"><strong><a href=\"https:\/\/www.ansa.it\/\">Ansa <\/a><a title=\"Sport\" href=\"https:\/\/www.ansa.it\/sito\/notizie\/sport\/sport.shtml\">Sport<\/a><\/strong><\/p>\n<p style=\"text-align: center\"><a href=\"https:\/\/www.ansa.it\/\">Il sito Internet dell&#8217;Agenzia ANSA <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ansa Sport Luna Rossa vince la Prada Cup e conquista l&#8217;accesso alla finale della Coppa America, dove affronter\u00e0 Team New Zealand. L&#8217;equipaggio azzurro ha dominato le due regate della notte [&hellip;]<\/p>\n","protected":false},"author":294,"featured_media":2679,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-2678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coppa America: Luna Rossa vince Prada Cup e va in finale - Pontinia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pontinia\/2021\/02\/22\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coppa America: Luna Rossa vince Prada Cup e va in finale - Pontinia\" \/>\n<meta property=\"og:description\" content=\"Ansa Sport Luna Rossa vince la Prada Cup e conquista l&#8217;accesso alla finale della Coppa America, dove affronter\u00e0 Team New Zealand. L&#8217;equipaggio azzurro ha dominato le due regate della notte [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pontinia\/2021\/02\/22\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\/\" \/>\n<meta property=\"og:site_name\" content=\"Pontinia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-22T14:34:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/02\/0e3a414a5951dc20c02dfe0f7041310.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"457\" \/>\n\t<meta property=\"og:image:height\" content=\"305\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sportpontinia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sportpontinia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/02\\\/22\\\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/02\\\/22\\\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\\\/\"},\"author\":{\"name\":\"sportpontinia\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"headline\":\"Coppa America: Luna Rossa vince Prada Cup e va in finale\",\"datePublished\":\"2021-02-22T14:34:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/02\\\/22\\\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\\\/\"},\"wordCount\":292,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/02\\\/22\\\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2021\\\/02\\\/0e3a414a5951dc20c02dfe0f7041310.jpg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/02\\\/22\\\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/02\\\/22\\\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\\\/\",\"name\":\"Coppa America: Luna Rossa vince Prada Cup e va in finale - Pontinia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/02\\\/22\\\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/02\\\/22\\\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2021\\\/02\\\/0e3a414a5951dc20c02dfe0f7041310.jpg\",\"datePublished\":\"2021-02-22T14:34:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/02\\\/22\\\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/02\\\/22\\\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/02\\\/22\\\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2021\\\/02\\\/0e3a414a5951dc20c02dfe0f7041310.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2021\\\/02\\\/0e3a414a5951dc20c02dfe0f7041310.jpg\",\"width\":457,\"height\":305,\"caption\":\"Luna Rossa Prada Pirelli team celebrate after winning the Prada Cup final, the 36th America's Cup challenger series, in Auckland on February 21, 2021. (Photo by Gilles Martin-Raget \\\/ AFP)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/02\\\/22\\\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coppa America: Luna Rossa vince Prada Cup e va in finale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\",\"name\":\"Pontinia\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\",\"name\":\"sportpontinia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"caption\":\"sportpontinia\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/author\\\/sportpontinia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coppa America: Luna Rossa vince Prada Cup e va in finale - Pontinia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pontinia\/2021\/02\/22\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\/","og_locale":"it_IT","og_type":"article","og_title":"Coppa America: Luna Rossa vince Prada Cup e va in finale - Pontinia","og_description":"Ansa Sport Luna Rossa vince la Prada Cup e conquista l&#8217;accesso alla finale della Coppa America, dove affronter\u00e0 Team New Zealand. L&#8217;equipaggio azzurro ha dominato le due regate della notte [&hellip;]","og_url":"https:\/\/comunicacity.net\/pontinia\/2021\/02\/22\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\/","og_site_name":"Pontinia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-02-22T14:34:57+00:00","og_image":[{"width":457,"height":305,"url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/02\/0e3a414a5951dc20c02dfe0f7041310.jpg","type":"image\/jpeg"}],"author":"sportpontinia","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sportpontinia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pontinia\/2021\/02\/22\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/2021\/02\/22\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\/"},"author":{"name":"sportpontinia","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"headline":"Coppa America: Luna Rossa vince Prada Cup e va in finale","datePublished":"2021-02-22T14:34:57+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2021\/02\/22\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\/"},"wordCount":292,"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2021\/02\/22\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/02\/0e3a414a5951dc20c02dfe0f7041310.jpg","articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pontinia\/2021\/02\/22\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\/","url":"https:\/\/comunicacity.net\/pontinia\/2021\/02\/22\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\/","name":"Coppa America: Luna Rossa vince Prada Cup e va in finale - Pontinia","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2021\/02\/22\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2021\/02\/22\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/02\/0e3a414a5951dc20c02dfe0f7041310.jpg","datePublished":"2021-02-22T14:34:57+00:00","author":{"@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/pontinia\/2021\/02\/22\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pontinia\/2021\/02\/22\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pontinia\/2021\/02\/22\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\/#primaryimage","url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/02\/0e3a414a5951dc20c02dfe0f7041310.jpg","contentUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/02\/0e3a414a5951dc20c02dfe0f7041310.jpg","width":457,"height":305,"caption":"Luna Rossa Prada Pirelli team celebrate after winning the Prada Cup final, the 36th America's Cup challenger series, in Auckland on February 21, 2021. (Photo by Gilles Martin-Raget \/ AFP)"},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pontinia\/2021\/02\/22\/coppa-america-luna-rossa-vince-prada-cup-e-va-in-finale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pontinia\/"},{"@type":"ListItem","position":2,"name":"Coppa America: Luna Rossa vince Prada Cup e va in finale"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pontinia\/#website","url":"https:\/\/comunicacity.net\/pontinia\/","name":"Pontinia","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pontinia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807","name":"sportpontinia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","caption":"sportpontinia"},"url":"https:\/\/comunicacity.net\/pontinia\/author\/sportpontinia\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/2678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/users\/294"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/comments?post=2678"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/2678\/revisions"}],"predecessor-version":[{"id":2680,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/2678\/revisions\/2680"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media\/2679"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media?parent=2678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/categories?post=2678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/tags?post=2678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}