{"id":3136,"date":"2021-09-22T16:22:13","date_gmt":"2021-09-22T14:22:13","guid":{"rendered":"https:\/\/comunicacity.net\/pontinia\/?p=3136"},"modified":"2021-09-22T16:22:13","modified_gmt":"2021-09-22T14:22:13","slug":"comunicato-stampa-pallamano-femminile-serie-a-beretta","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pontinia\/2021\/09\/22\/comunicato-stampa-pallamano-femminile-serie-a-beretta\/","title":{"rendered":"Comunicato stampa, pallamano femminile serie A Beretta"},"content":{"rendered":"<p style=\"text-align: center\"><span style=\"color: #ff0000\">Il Jomi Salerno, campione d\u2019Italia in carica, chiede la ripetizione della partita di sabato scorso. Ecco le parole del presidente Mauro Bianchi<\/span><\/p>\n<hr \/>\n<p>PONTINIA \u2013 Di seguito le parole del presidente dell\u2019Handball Club Cassa Rurale Pontinia, Mauro Bianchi, dopo aver appreso della richiesta di ripetizione della partita avanzata dai campioni d\u2019Italia in carica del Jomi Salerno riguardo il match pareggiato all\u2019ultimo respiro (31-31) sabato scorso al palazzetto dello sport Marica Bianchi di Pontinia.<\/p>\n<p>\u00abDopo il pareggio maturato sul campo che, a livello sportivo, ancora brucia a tutta la compagine laziale, apprendo della protesta dei campioni d\u2019Italia del Salerno riguardo il presunto errore tecnico con la richiesta di rigiocare la partita e posso dire che il nostro Club \u00e8 assolutamente orientato al rispetto delle regole e, qualora venisse ravvisato un errore tecnico, saremo prontissimi ad accettare quelle che saranno le scelte degli organi designati: questo perch\u00e9 siamo sicurissimi che chi di dovere potr\u00e0 analizzare con serenit\u00e0 il cosiddetto \u2018fattaccio\u2019 a tutela degli interessi di tutto il movimento. Qualora fosse necessario anche tornare sul campo per rigiocare il match contro la squadra campana accetteremo la decisione senza problemi perch\u00e9 vorr\u00e0 dire che verr\u00e0 dimostrato un errore tecnico che ha inciso sul match.<\/p>\n<p>Non \u00e8 nostro costume parlare degli arbitraggi, siamo sempre stati abituati ad accettare le cose che accadono sul campo poich\u00e9 si possono commettere errori, proprio come i giocatori possono sbagliare un tiro, e soprattutto per questo motivo non mi ero assolutamente permesso di farlo al termine della partita pareggiata 31-31, ma visto che i nostri avversari hanno analizzato attentamente il match, sono sicuro che si saranno anche resi conto di alcune situazioni come quella di un evidentissimo errore di cambio dove una loro giocatrice entra in campo prima che il portiere esca, situazione che avrebbe portato alla perdita di possesso palla ed esclusione della giocatrice in questione, episodio che di certo non ha favorito il Club di Pontinia e qui il rammarico per aver pareggio una partita che, visto come si erano messe le cose in campo, si poteva molto probabilmente concludere con un risultato diverso.<\/p>\n<p>Tutto questo fa parte dello sport e deve insegnarci ad essere campioni dentro e fuori dal campo e sopratutto nella vita, accettiamo con grande serenit\u00e0 quelle che saranno le decisioni degli organismi competenti. Sono altres\u00ec convinto che gli appassionati di Pontinia, qualora la partita dovesse rigiocarsi, avranno molto piacere a tornare ad ammirare la squadra campana nel nostro palazzetto dello sport. Qualora la partita si dovesse rigiocare, in una data che risponder\u00e0 anche alle esigenze e alle disponibilit\u00e0 del nostro impianto, sarebbe un ulteriore spettacolo per i nostri sponsor e per i giovani del nostro vivaio\u00bb.<\/p>\n<p>Per approfondire:\u00a0<strong><a href=\"https:\/\/pdosalerno.it\/errore-tecnico-la-jomi-chiede-la-ripetizione-della-gara-di-pontinia\/?_se=ZXppb2dyY2F0b25lQHlhaG9vLml0&amp;fbclid=IwAR0G2wCegEKB-MF1NxbWPIpmdTVVWoC2dHVna9u_tOChFNV4QLo9LVRWX8s\"><span style=\"color: #ff0000\">il comunicato di PDO Salerno<\/span><\/a><\/strong><\/p>\n<hr \/>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-3137 aligncenter\" src=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/09\/mail-8-1024x682.jpg\" alt=\"\" width=\"640\" height=\"426\" srcset=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/09\/mail-8-1024x682.jpg 1024w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/09\/mail-8-300x200.jpg 300w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/09\/mail-8-768x512.jpg 768w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/09\/mail-8-1536x1024.jpg 1536w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/09\/mail-8.jpg 2000w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Jomi Salerno, campione d\u2019Italia in carica, chiede la ripetizione della partita di sabato scorso. Ecco le parole del presidente Mauro Bianchi PONTINIA \u2013 Di seguito le parole del presidente [&hellip;]<\/p>\n","protected":false},"author":294,"featured_media":3137,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,24],"tags":[],"class_list":["post-3136","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comunicato stampa, pallamano femminile serie A Beretta - Pontinia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pontinia\/2021\/09\/22\/comunicato-stampa-pallamano-femminile-serie-a-beretta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunicato stampa, pallamano femminile serie A Beretta - Pontinia\" \/>\n<meta property=\"og:description\" content=\"Il Jomi Salerno, campione d\u2019Italia in carica, chiede la ripetizione della partita di sabato scorso. Ecco le parole del presidente Mauro Bianchi PONTINIA \u2013 Di seguito le parole del presidente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pontinia\/2021\/09\/22\/comunicato-stampa-pallamano-femminile-serie-a-beretta\/\" \/>\n<meta property=\"og:site_name\" content=\"Pontinia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-22T14:22:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/09\/mail-8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sportpontinia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sportpontinia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/09\\\/22\\\/comunicato-stampa-pallamano-femminile-serie-a-beretta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/09\\\/22\\\/comunicato-stampa-pallamano-femminile-serie-a-beretta\\\/\"},\"author\":{\"name\":\"sportpontinia\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"headline\":\"Comunicato stampa, pallamano femminile serie A Beretta\",\"datePublished\":\"2021-09-22T14:22:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/09\\\/22\\\/comunicato-stampa-pallamano-femminile-serie-a-beretta\\\/\"},\"wordCount\":457,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/09\\\/22\\\/comunicato-stampa-pallamano-femminile-serie-a-beretta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2021\\\/09\\\/mail-8.jpg\",\"articleSection\":[\"Notizie e Informazioni\",\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/09\\\/22\\\/comunicato-stampa-pallamano-femminile-serie-a-beretta\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/09\\\/22\\\/comunicato-stampa-pallamano-femminile-serie-a-beretta\\\/\",\"name\":\"Comunicato stampa, pallamano femminile serie A Beretta - Pontinia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/09\\\/22\\\/comunicato-stampa-pallamano-femminile-serie-a-beretta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/09\\\/22\\\/comunicato-stampa-pallamano-femminile-serie-a-beretta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2021\\\/09\\\/mail-8.jpg\",\"datePublished\":\"2021-09-22T14:22:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/09\\\/22\\\/comunicato-stampa-pallamano-femminile-serie-a-beretta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/09\\\/22\\\/comunicato-stampa-pallamano-femminile-serie-a-beretta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/09\\\/22\\\/comunicato-stampa-pallamano-femminile-serie-a-beretta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2021\\\/09\\\/mail-8.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2021\\\/09\\\/mail-8.jpg\",\"width\":2000,\"height\":1333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/09\\\/22\\\/comunicato-stampa-pallamano-femminile-serie-a-beretta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunicato stampa, pallamano femminile serie A Beretta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\",\"name\":\"Pontinia\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\",\"name\":\"sportpontinia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"caption\":\"sportpontinia\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/author\\\/sportpontinia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comunicato stampa, pallamano femminile serie A Beretta - Pontinia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pontinia\/2021\/09\/22\/comunicato-stampa-pallamano-femminile-serie-a-beretta\/","og_locale":"it_IT","og_type":"article","og_title":"Comunicato stampa, pallamano femminile serie A Beretta - Pontinia","og_description":"Il Jomi Salerno, campione d\u2019Italia in carica, chiede la ripetizione della partita di sabato scorso. Ecco le parole del presidente Mauro Bianchi PONTINIA \u2013 Di seguito le parole del presidente [&hellip;]","og_url":"https:\/\/comunicacity.net\/pontinia\/2021\/09\/22\/comunicato-stampa-pallamano-femminile-serie-a-beretta\/","og_site_name":"Pontinia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-09-22T14:22:13+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/09\/mail-8.jpg","type":"image\/jpeg"}],"author":"sportpontinia","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sportpontinia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pontinia\/2021\/09\/22\/comunicato-stampa-pallamano-femminile-serie-a-beretta\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/2021\/09\/22\/comunicato-stampa-pallamano-femminile-serie-a-beretta\/"},"author":{"name":"sportpontinia","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"headline":"Comunicato stampa, pallamano femminile serie A Beretta","datePublished":"2021-09-22T14:22:13+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2021\/09\/22\/comunicato-stampa-pallamano-femminile-serie-a-beretta\/"},"wordCount":457,"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2021\/09\/22\/comunicato-stampa-pallamano-femminile-serie-a-beretta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/09\/mail-8.jpg","articleSection":["Notizie e Informazioni","Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pontinia\/2021\/09\/22\/comunicato-stampa-pallamano-femminile-serie-a-beretta\/","url":"https:\/\/comunicacity.net\/pontinia\/2021\/09\/22\/comunicato-stampa-pallamano-femminile-serie-a-beretta\/","name":"Comunicato stampa, pallamano femminile serie A Beretta - Pontinia","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2021\/09\/22\/comunicato-stampa-pallamano-femminile-serie-a-beretta\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2021\/09\/22\/comunicato-stampa-pallamano-femminile-serie-a-beretta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/09\/mail-8.jpg","datePublished":"2021-09-22T14:22:13+00:00","author":{"@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/pontinia\/2021\/09\/22\/comunicato-stampa-pallamano-femminile-serie-a-beretta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pontinia\/2021\/09\/22\/comunicato-stampa-pallamano-femminile-serie-a-beretta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pontinia\/2021\/09\/22\/comunicato-stampa-pallamano-femminile-serie-a-beretta\/#primaryimage","url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/09\/mail-8.jpg","contentUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/09\/mail-8.jpg","width":2000,"height":1333},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pontinia\/2021\/09\/22\/comunicato-stampa-pallamano-femminile-serie-a-beretta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pontinia\/"},{"@type":"ListItem","position":2,"name":"Comunicato stampa, pallamano femminile serie A Beretta"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pontinia\/#website","url":"https:\/\/comunicacity.net\/pontinia\/","name":"Pontinia","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pontinia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807","name":"sportpontinia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","caption":"sportpontinia"},"url":"https:\/\/comunicacity.net\/pontinia\/author\/sportpontinia\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/3136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/users\/294"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/comments?post=3136"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/3136\/revisions"}],"predecessor-version":[{"id":3138,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/3136\/revisions\/3138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media\/3137"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media?parent=3136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/categories?post=3136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/tags?post=3136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}