{"id":3185,"date":"2021-11-07T12:04:35","date_gmt":"2021-11-07T11:04:35","guid":{"rendered":"https:\/\/comunicacity.net\/pontinia\/?p=3185"},"modified":"2021-11-07T12:04:35","modified_gmt":"2021-11-07T11:04:35","slug":"lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pontinia\/2021\/11\/07\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\/","title":{"rendered":"L\u2019HC Cassa Rurale supera in trasferta il Casalgrande Padana: quarta vittoria e sesto risultato utile su sette partite."},"content":{"rendered":"<p style=\"text-align: center\"><span style=\"color: #ff0000\">Bianchi: \u00abVittoria di tutti\u00bb. Podda: \u00abContinuiamo a crescere\u00bb<\/span><\/p>\n<hr \/>\n<div>\n<div>\n<div>PONTINIA &#8211; L\u2019HC Cassa Rurale Pontinia supera in trasferta il Casalgrande Padana e blinda il quarto nella classifica della serie A Beretta femminile. La formazione guidata dai coach Giovanni Nasta e Matteo Bellotti ha superato il Casalgrande (27-28) centrando la quarta vittoria stagionale, sesto risultato positivo su sette partite, e viaggia staccata di quattro punti dalla vetta della classifica del massimo campionato di pallamano femminile.<\/div>\n<div><\/div>\n<div>\u00abHo visto una squadra in grande crescita che, con coraggio, determinazione e voglia di lottare fino alla fine, \u00e8 riuscita a portare a casa due punti molto importanti per noi &#8211; chiarisce Mauro Bianchi, il presidente della formazione di Pontinia &#8211; \u00c8 stata la vittoria di un gruppo che sta diventando un vero e proprio team, dove tutte giocatrici sono sempre pi\u00f9 sicure, incitano costantemente le compagne che stanno lottando in campo e soprattutto sanno che devono farsi trovare sempre pronte, consapevoli di quello che possono dare quando sono chiamate a fornire il proprio contributo alla squadra\u00bb. L\u2019HC Cassa Rurale Pontinia ha gestito la gara con autorit\u00e0 nella prima parte, ha chiuso il primo tempo in vantaggio (12-16) e ha mantenuto il vantaggio anche nella seconda parte (20-23, 24-25) fino al 27-28 finale con il brivido finale quando la formazione di casa ha provato a impattare trascinata dalle 10 reti personali di Ilenia Furlanetto, nata a Pontinia ed ex Cassa Rurale, attuale leader della classifica dei marcatori della serie A Beretta femminile con 59 reti.<\/div>\n<div><\/div>\n<div>\u00abNel finale del secondo tempo \u00e8 stato un incontro al cardiopalmo, il risultato nei minuti finali \u00e8 stato in bilico ma alla fine \u00e8 arrivata la vittoria importante per noi che definisco meritata per quello che si \u00e8 visto in campo &#8211; ha aggiunto Bianchi &#8211; Dobbiamo migliorare ancora alcune cose e chiudere prima le partite senza complicarci la strada da soli, ma questo successo \u00e8 molto importante per noi e mi piace definire questa vittoria la vittoria di tutti\u00bb.<\/div>\n<div><\/div>\n<div>Per quanto riguarda il Pontinia Luisella Podda ha totalizzato 9 reti ed \u00e8 stata la top-scorer di squadra, seguita da Mrkikj (6 reti), e Bassanese (3 reti). Curiosit\u00e0, anche il portiere Sara Di Giugno, che ha preso il posto di Romina Ramazzotti, \u00e8 entrata nel tabellina trovando un gol da porta a porta.<\/div>\n<div><\/div>\n<div>\u00abSiamo arrivate a questa partita dopo la prima sconfitta stagionale e due pareggi e penso che da un punto di vista morale non fosse facile, in trasferta e contro una squadra che aveva collezionato i nostri stessi punti in classifica, giocando tutte le partite alla pari con tutte nonostante si tratti di una squadra neopromossa &#8211; afferma Luisella Podda &#8211; Abbiamo giocato un buon primo tempo e anche all\u2019inizio della ripresa siamo state capaci di fare un ottimo lavoro. Nel corso del match poi loro, con la difesa aggressiva, ci hanno messo in difficolt\u00e0 e abbiamo perso tanti palloni che hanno permesso tutte le loro prime fasi che sono state quasi tutte concretizzate e le hanno portate ad arrivare fino al -1. Rispetto alle altre partite siamo riuscite a gestire meglio il momento di difficolt\u00e0 ma c\u2019\u00e8 ancora tanto da lavorare perch\u00e9 penso che la partita si doveva chiudere molto prima. Abbiamo gestito bene l\u2019ultima palla con Giulia Conte che nonostante fosse la pi\u00f9 giovane in campo si \u00e8 presa la responsabilit\u00e0 di quell\u2019attacco, consentendoci di andare due gol sopra e chiuderla\u00bb.<\/div>\n<div><\/div>\n<div>La giocatrice sarda conclude con una lucida analisi del momento della squadra. \u00abDevo ammettere che non \u00e8 stata una bella partita da parte nostra, si pu\u00f2 fare ancora meglio, dobbiamo lavorare di pi\u00f9 da un punto mentale nella gestione dei palloni e nel lavoro di squadra, partendo dal fatto che ogni partita potr\u00e0 essere cos\u00ec e dobbiamo essere preparate a tenere alta la concentrazione per 60 minuti e non solo per la prima mezz\u2019ora &#8211; chiarisce Podda &#8211; abbiamo dovuto rinunciare al nostro terzino mancino Panayotova che durante la settimana sfortunatamente ha riportato un infortunio, poi voglio sottolineare anche che il nostro portiere Di Giugno, giovanissima anche lei, con i suoi interventi ci ha permesso di non subire tutte le loro veloci ripartenze, mentre Mrkikj ci ha dato una grossa mano, senza dimenticare che viene da un infortunio importante ma credo che partita dopo partita diventer\u00e0 un elemento fondamentale per la squadra\u00bb.<\/div>\n<div><\/div>\n<div>CASALGRANDE PADANA &#8211; HC CASSA RURALE PONTINIA 27-28 (12-16 p.t.)<\/div>\n<div>CASALGRANDE PADANA: Bordon, Bonacini, Mangone 2, Giombetti 1, Sausa Mueller 2, Franco 3, Furlanetto 10, Apostol, Artoni S. 4, Mutti, Artoni A. 3, Orlandi 2, Mattioli, Lusetti, Lassouli. All. Agazzani<\/div>\n<div>HC CASSA RURALE PONTINIA: Ramazzotti, Di Giugno 1, Cialei, Podda 9, Squizziato 2, Di Prisco, Conte 2, Colloredo 2, Bernabei, Davoli 2, Rueda, Bassanese 3, Barbosu 1, Mrkikj 6. All. Nasta &#8211; Bellotti<\/div>\n<div>Arbitri: Schiavone e Nicolella (del. Chiarello)<\/div>\n<div>\n<hr \/>\n<\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-3186 aligncenter\" src=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/11\/mail-1-1024x847.jpg\" alt=\"\" width=\"257\" height=\"213\" srcset=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/11\/mail-1-1024x847.jpg 1024w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/11\/mail-1-300x248.jpg 300w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/11\/mail-1-768x635.jpg 768w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/11\/mail-1-1536x1270.jpg 1536w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/11\/mail-1.jpg 1600w\" sizes=\"auto, (max-width: 257px) 100vw, 257px\" \/><\/p>\n<hr \/>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Bianchi: \u00abVittoria di tutti\u00bb. Podda: \u00abContinuiamo a crescere\u00bb PONTINIA &#8211; L\u2019HC Cassa Rurale Pontinia supera in trasferta il Casalgrande Padana e blinda il quarto nella classifica della serie A Beretta [&hellip;]<\/p>\n","protected":false},"author":294,"featured_media":3186,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,24],"tags":[],"class_list":["post-3185","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019HC Cassa Rurale supera in trasferta il Casalgrande Padana: quarta vittoria e sesto risultato utile su sette partite. - Pontinia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pontinia\/2021\/11\/07\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019HC Cassa Rurale supera in trasferta il Casalgrande Padana: quarta vittoria e sesto risultato utile su sette partite. - Pontinia\" \/>\n<meta property=\"og:description\" content=\"Bianchi: \u00abVittoria di tutti\u00bb. Podda: \u00abContinuiamo a crescere\u00bb PONTINIA &#8211; L\u2019HC Cassa Rurale Pontinia supera in trasferta il Casalgrande Padana e blinda il quarto nella classifica della serie A Beretta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pontinia\/2021\/11\/07\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\/\" \/>\n<meta property=\"og:site_name\" content=\"Pontinia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-07T11:04:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/11\/mail-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1323\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sportpontinia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sportpontinia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/11\\\/07\\\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/11\\\/07\\\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\\\/\"},\"author\":{\"name\":\"sportpontinia\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"headline\":\"L\u2019HC Cassa Rurale supera in trasferta il Casalgrande Padana: quarta vittoria e sesto risultato utile su sette partite.\",\"datePublished\":\"2021-11-07T11:04:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/11\\\/07\\\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\\\/\"},\"wordCount\":786,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/11\\\/07\\\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2021\\\/11\\\/mail-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\",\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/11\\\/07\\\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/11\\\/07\\\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\\\/\",\"name\":\"L\u2019HC Cassa Rurale supera in trasferta il Casalgrande Padana: quarta vittoria e sesto risultato utile su sette partite. - Pontinia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/11\\\/07\\\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/11\\\/07\\\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2021\\\/11\\\/mail-1.jpg\",\"datePublished\":\"2021-11-07T11:04:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/11\\\/07\\\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/11\\\/07\\\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/11\\\/07\\\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2021\\\/11\\\/mail-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2021\\\/11\\\/mail-1.jpg\",\"width\":1600,\"height\":1323},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2021\\\/11\\\/07\\\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019HC Cassa Rurale supera in trasferta il Casalgrande Padana: quarta vittoria e sesto risultato utile su sette partite.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\",\"name\":\"Pontinia\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\",\"name\":\"sportpontinia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"caption\":\"sportpontinia\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/author\\\/sportpontinia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019HC Cassa Rurale supera in trasferta il Casalgrande Padana: quarta vittoria e sesto risultato utile su sette partite. - Pontinia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pontinia\/2021\/11\/07\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\/","og_locale":"it_IT","og_type":"article","og_title":"L\u2019HC Cassa Rurale supera in trasferta il Casalgrande Padana: quarta vittoria e sesto risultato utile su sette partite. - Pontinia","og_description":"Bianchi: \u00abVittoria di tutti\u00bb. Podda: \u00abContinuiamo a crescere\u00bb PONTINIA &#8211; L\u2019HC Cassa Rurale Pontinia supera in trasferta il Casalgrande Padana e blinda il quarto nella classifica della serie A Beretta [&hellip;]","og_url":"https:\/\/comunicacity.net\/pontinia\/2021\/11\/07\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\/","og_site_name":"Pontinia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-11-07T11:04:35+00:00","og_image":[{"width":1600,"height":1323,"url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/11\/mail-1.jpg","type":"image\/jpeg"}],"author":"sportpontinia","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sportpontinia","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pontinia\/2021\/11\/07\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/2021\/11\/07\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\/"},"author":{"name":"sportpontinia","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"headline":"L\u2019HC Cassa Rurale supera in trasferta il Casalgrande Padana: quarta vittoria e sesto risultato utile su sette partite.","datePublished":"2021-11-07T11:04:35+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2021\/11\/07\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\/"},"wordCount":786,"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2021\/11\/07\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/11\/mail-1.jpg","articleSection":["Notizie e Informazioni","Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pontinia\/2021\/11\/07\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\/","url":"https:\/\/comunicacity.net\/pontinia\/2021\/11\/07\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\/","name":"L\u2019HC Cassa Rurale supera in trasferta il Casalgrande Padana: quarta vittoria e sesto risultato utile su sette partite. - Pontinia","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2021\/11\/07\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2021\/11\/07\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/11\/mail-1.jpg","datePublished":"2021-11-07T11:04:35+00:00","author":{"@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/pontinia\/2021\/11\/07\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pontinia\/2021\/11\/07\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pontinia\/2021\/11\/07\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\/#primaryimage","url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/11\/mail-1.jpg","contentUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2021\/11\/mail-1.jpg","width":1600,"height":1323},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pontinia\/2021\/11\/07\/lhc-cassa-rurale-supera-in-trasferta-il-casalgrande-padana-quarta-vittoria-e-sesto-risultato-utile-su-sette-partite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pontinia\/"},{"@type":"ListItem","position":2,"name":"L\u2019HC Cassa Rurale supera in trasferta il Casalgrande Padana: quarta vittoria e sesto risultato utile su sette partite."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pontinia\/#website","url":"https:\/\/comunicacity.net\/pontinia\/","name":"Pontinia","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pontinia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807","name":"sportpontinia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","caption":"sportpontinia"},"url":"https:\/\/comunicacity.net\/pontinia\/author\/sportpontinia\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/3185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/users\/294"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/comments?post=3185"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/3185\/revisions"}],"predecessor-version":[{"id":3187,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/3185\/revisions\/3187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media\/3186"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media?parent=3185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/categories?post=3185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/tags?post=3185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}