{"id":3607,"date":"2022-07-14T20:14:20","date_gmt":"2022-07-14T18:14:20","guid":{"rendered":"https:\/\/comunicacity.net\/pontinia\/?p=3607"},"modified":"2022-07-14T20:14:20","modified_gmt":"2022-07-14T18:14:20","slug":"stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pontinia\/2022\/07\/14\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\/","title":{"rendered":"Stefano Petrucci, nuovo capo allenatore della Virtus Basket Pontinia."},"content":{"rendered":"<p><span class=\"d2edcug0 hpfvmrgz qv66sw1b c1et5uql lr9zc1uh a8c37x1j fe6kdd0r mau55g9w c8b282yb keod5gw0 nxhoafnm aigsh9s9 d3f4x2em iv3no6db jq4qci2q a3bd9o3v b1v8xokw oo9gr5id hzawbc8m\" dir=\"auto\">La Virtus Basket Pontinia \u00e8 lieta di annunciare di aver raggiunto un accordo con il tecnico Stefano Petrucci che ricoprir\u00e0 il ruolo di capo allenatore della nostra prima squadra e del gruppo Under 17. Nell\u2019ultima stagione alla Fortitudo Cisterna, in qualit\u00e0 di coach della serie D e del team Under 19, Stefano vanta una ampia esperienza sia nei campionati senior ( Agrigento, Porto Empedocle, Capri ) che in quelli giovanili ( Asso Sport Latina, Futura Cisterna \u2026 ). A Stefano il nostro pi\u00f9 caloroso benvenuto ed un grande in bocca al lupo per una stagione la pi\u00f9 vincente ed entusiasmante possibile .<\/span><\/p>\n<hr \/>\n<div class=\"season_row\"><strong><span style=\"color: #ff0000\">Stefano Petrucci &#8211;<\/span><\/strong><\/div>\n<p>-&#8220;Con un passato da professionista, Stefano Petrucci inizia l&#8217;attivit\u00e0 di istruttore a 19 anni e gi\u00e0 l&#8217;anno seguente entra a far parte di quella che, allora, veniva definita la &#8220;galassia Messaggero&#8221;. La Federazione lo inserisce nei pi\u00f9 prestigiosi programmi di formazione, dai<b> 3 gradi del CNAG <\/b>(Comitato Nazionale per le Attivit\u00e0 Giovanili), al SUPERSTAGE per l&#8217;insegnamento dei fondamentali, alla Scuola d&#8217;Alta Specializzazione di Madonna di Campiglio, fino alla chiamata di coach Sandro Gamba per il MASTER per le attivit\u00e0 giovanili del Centro Tecnico di Riano ed il conseguente inserimento nel serbatoio dei tecnici del Settore Squadre Nazionali. Durante tutta la sua carriera, anche quando impegnato in serie C e B maschile o in serie A femminile, non ha mai trascurato il ruolo dell&#8217;istruttore, mantenendo sempre anche il ruolo di responsabile tecnico del settore giovanile.&#8221;<\/p>\n<p>&#8211; da BASKETINCONTRO By <a class=\"article_author-link\" title=\"Emanuele Bellizzi\" href=\"http:\/\/www.basketincontro.it\/site\/\"> Emanuele Bellizzi \u00a0<\/a>17\/10\/2017.<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Virtus Basket Pontinia \u00e8 lieta di annunciare di aver raggiunto un accordo con il tecnico Stefano Petrucci che ricoprir\u00e0 il ruolo di capo allenatore della nostra prima squadra e [&hellip;]<\/p>\n","protected":false},"author":294,"featured_media":3608,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-3607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stefano Petrucci, nuovo capo allenatore della Virtus Basket Pontinia. - Pontinia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pontinia\/2022\/07\/14\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stefano Petrucci, nuovo capo allenatore della Virtus Basket Pontinia. - Pontinia\" \/>\n<meta property=\"og:description\" content=\"La Virtus Basket Pontinia \u00e8 lieta di annunciare di aver raggiunto un accordo con il tecnico Stefano Petrucci che ricoprir\u00e0 il ruolo di capo allenatore della nostra prima squadra e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pontinia\/2022\/07\/14\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\/\" \/>\n<meta property=\"og:site_name\" content=\"Pontinia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-14T18:14:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2022\/07\/293284338_5661487913864452_7363546045406266441_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"526\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sportpontinia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sportpontinia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/07\\\/14\\\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/07\\\/14\\\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\\\/\"},\"author\":{\"name\":\"sportpontinia\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"headline\":\"Stefano Petrucci, nuovo capo allenatore della Virtus Basket Pontinia.\",\"datePublished\":\"2022-07-14T18:14:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/07\\\/14\\\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\\\/\"},\"wordCount\":246,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/07\\\/14\\\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2022\\\/07\\\/293284338_5661487913864452_7363546045406266441_n.jpg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/07\\\/14\\\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/07\\\/14\\\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\\\/\",\"name\":\"Stefano Petrucci, nuovo capo allenatore della Virtus Basket Pontinia. - Pontinia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/07\\\/14\\\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/07\\\/14\\\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2022\\\/07\\\/293284338_5661487913864452_7363546045406266441_n.jpg\",\"datePublished\":\"2022-07-14T18:14:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/07\\\/14\\\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/07\\\/14\\\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/07\\\/14\\\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2022\\\/07\\\/293284338_5661487913864452_7363546045406266441_n.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2022\\\/07\\\/293284338_5661487913864452_7363546045406266441_n.jpg\",\"width\":526,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/07\\\/14\\\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stefano Petrucci, nuovo capo allenatore della Virtus Basket Pontinia.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\",\"name\":\"Pontinia\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\",\"name\":\"sportpontinia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"caption\":\"sportpontinia\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/author\\\/sportpontinia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stefano Petrucci, nuovo capo allenatore della Virtus Basket Pontinia. - Pontinia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pontinia\/2022\/07\/14\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\/","og_locale":"it_IT","og_type":"article","og_title":"Stefano Petrucci, nuovo capo allenatore della Virtus Basket Pontinia. - Pontinia","og_description":"La Virtus Basket Pontinia \u00e8 lieta di annunciare di aver raggiunto un accordo con il tecnico Stefano Petrucci che ricoprir\u00e0 il ruolo di capo allenatore della nostra prima squadra e [&hellip;]","og_url":"https:\/\/comunicacity.net\/pontinia\/2022\/07\/14\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\/","og_site_name":"Pontinia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-07-14T18:14:20+00:00","og_image":[{"width":526,"height":675,"url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2022\/07\/293284338_5661487913864452_7363546045406266441_n.jpg","type":"image\/jpeg"}],"author":"sportpontinia","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sportpontinia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pontinia\/2022\/07\/14\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/2022\/07\/14\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\/"},"author":{"name":"sportpontinia","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"headline":"Stefano Petrucci, nuovo capo allenatore della Virtus Basket Pontinia.","datePublished":"2022-07-14T18:14:20+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2022\/07\/14\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\/"},"wordCount":246,"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2022\/07\/14\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2022\/07\/293284338_5661487913864452_7363546045406266441_n.jpg","articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pontinia\/2022\/07\/14\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\/","url":"https:\/\/comunicacity.net\/pontinia\/2022\/07\/14\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\/","name":"Stefano Petrucci, nuovo capo allenatore della Virtus Basket Pontinia. - Pontinia","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2022\/07\/14\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2022\/07\/14\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2022\/07\/293284338_5661487913864452_7363546045406266441_n.jpg","datePublished":"2022-07-14T18:14:20+00:00","author":{"@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/pontinia\/2022\/07\/14\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pontinia\/2022\/07\/14\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pontinia\/2022\/07\/14\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\/#primaryimage","url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2022\/07\/293284338_5661487913864452_7363546045406266441_n.jpg","contentUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2022\/07\/293284338_5661487913864452_7363546045406266441_n.jpg","width":526,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pontinia\/2022\/07\/14\/stefano-petrucci-nuovo-capo-allenatore-della-virtus-basket-pontinia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pontinia\/"},{"@type":"ListItem","position":2,"name":"Stefano Petrucci, nuovo capo allenatore della Virtus Basket Pontinia."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pontinia\/#website","url":"https:\/\/comunicacity.net\/pontinia\/","name":"Pontinia","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pontinia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807","name":"sportpontinia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","caption":"sportpontinia"},"url":"https:\/\/comunicacity.net\/pontinia\/author\/sportpontinia\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/3607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/users\/294"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/comments?post=3607"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/3607\/revisions"}],"predecessor-version":[{"id":3609,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/3607\/revisions\/3609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media\/3608"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media?parent=3607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/categories?post=3607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/tags?post=3607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}