{"id":3631,"date":"2022-08-06T18:39:35","date_gmt":"2022-08-06T16:39:35","guid":{"rendered":"https:\/\/comunicacity.net\/pontinia\/?p=3631"},"modified":"2022-08-06T18:42:46","modified_gmt":"2022-08-06T16:42:46","slug":"aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pontinia\/2022\/08\/06\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\/","title":{"rendered":"Alessandro Giorgi\u2026 da giovane sprinter nazionale, a preparatore atletico del calcio a 5 femminile."},"content":{"rendered":"<div class=\"\" dir=\"auto\">\n<div id=\"jsc_c_c4\" class=\"ecm0bbzt hv4rvrfc ihqw7lf3 dati1w0a\" data-ad-comet-preview=\"message\" data-ad-preview=\"message\">\n<div class=\"j83agx80 cbu4d94t ew0dbk1b irj2b8pg\">\n<div class=\"qzhwtbm6 knvmm38d\">\n<div class=\"kvgmc6g5 cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Alessandro Giorgi\u2026 da giovane sprinter nazionale, a preparatore atletico del calcio a 5 femminile\u2026 nel mezzo tanta esperienza, tanta professionalit\u00e0. Grazie a delle conoscenze in comune, dopo averlo visto lavorare nel nostro palazzetto con la squadra di serie A di Pallamano femminile lo abbiamo corteggiato e lui si \u00e8 messo subito a disposizione per questa nuova sfida.<\/div>\n<div dir=\"auto\">In atletica leggera ne ha intraprese molte con grandi risultati ed ora si affaccia al calcio a 5, un ambito nuovo per lui, uno stimolo in pi\u00f9. Accanto a Mister <a class=\"oajrlxb2 g5ia77u1 qu0x051f esr5mh6w e9989ue4 r7d6kgcz rq0escxv nhd2j8a9 nc684nl6 p7hjln8o kvgmc6g5 cxmmr5t8 oygrvhab hcukyx3x jb3vyjys rz4wbd8a qt6c0cv9 a8nywdso i1ao9s8h esuyzwwr f1sip0of lzcic4wl gpro0wi8 q66pz984 b1v8xokw\" role=\"link\" href=\"https:\/\/www.facebook.com\/enrico.grassia.9?__cft__[0]=AZVfP3q1O7sVRJqYoNbSi6e0MhC5oF8uR6Q-4xWIczzuEbfNvEhtm5g044k0fG5HDZ_wOxEyNpkwGguVXkm7DWBpUEnuGeYPcK6mteBMpPhS79JuXNA1DqFmpphvIAplg_9WqM7t6njYZWVldXegxGLos_FrrGySVdw3DYr13uLt8g&amp;__tn__=-]K-R\"><span class=\"nc684nl6\">Enrico Grassia<\/span><\/a> ed al responsabile dell\u2019area tecnica Pasquale Ricciardone hanno gi\u00e0 programmato nel dettaglio tutta la fase di preparazione ed avvicinamento al campionato. Un super benvenuto ad Alessandro da parte di tutta la societ\u00e0<\/div>\n<hr \/>\n<div dir=\"auto\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-3632 aligncenter\" src=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2022\/08\/297699428_437673998377482_2371319765127564303_n-1024x819.jpg\" alt=\"\" width=\"640\" height=\"512\" srcset=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2022\/08\/297699428_437673998377482_2371319765127564303_n-1024x819.jpg 1024w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2022\/08\/297699428_437673998377482_2371319765127564303_n-300x240.jpg 300w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2022\/08\/297699428_437673998377482_2371319765127564303_n-768x614.jpg 768w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2022\/08\/297699428_437673998377482_2371319765127564303_n-1536x1229.jpg 1536w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2022\/08\/297699428_437673998377482_2371319765127564303_n.jpg 1600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<hr \/>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Alessandro Giorgi\u2026 da giovane sprinter nazionale, a preparatore atletico del calcio a 5 femminile\u2026 nel mezzo tanta esperienza, tanta professionalit\u00e0. Grazie a delle conoscenze in comune, dopo averlo visto lavorare [&hellip;]<\/p>\n","protected":false},"author":294,"featured_media":3632,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-3631","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alessandro Giorgi\u2026 da giovane sprinter nazionale, a preparatore atletico del calcio a 5 femminile. - Pontinia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pontinia\/2022\/08\/06\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alessandro Giorgi\u2026 da giovane sprinter nazionale, a preparatore atletico del calcio a 5 femminile. - Pontinia\" \/>\n<meta property=\"og:description\" content=\"Alessandro Giorgi\u2026 da giovane sprinter nazionale, a preparatore atletico del calcio a 5 femminile\u2026 nel mezzo tanta esperienza, tanta professionalit\u00e0. Grazie a delle conoscenze in comune, dopo averlo visto lavorare [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pontinia\/2022\/08\/06\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\/\" \/>\n<meta property=\"og:site_name\" content=\"Pontinia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-06T16:39:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-06T16:42:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2022\/08\/297699428_437673998377482_2371319765127564303_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sportpontinia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sportpontinia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/08\\\/06\\\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/08\\\/06\\\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\\\/\"},\"author\":{\"name\":\"sportpontinia\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"headline\":\"Alessandro Giorgi\u2026 da giovane sprinter nazionale, a preparatore atletico del calcio a 5 femminile.\",\"datePublished\":\"2022-08-06T16:39:35+00:00\",\"dateModified\":\"2022-08-06T16:42:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/08\\\/06\\\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\\\/\"},\"wordCount\":132,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/08\\\/06\\\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2022\\\/08\\\/297699428_437673998377482_2371319765127564303_n.jpg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/08\\\/06\\\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/08\\\/06\\\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\\\/\",\"name\":\"Alessandro Giorgi\u2026 da giovane sprinter nazionale, a preparatore atletico del calcio a 5 femminile. - Pontinia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/08\\\/06\\\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/08\\\/06\\\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2022\\\/08\\\/297699428_437673998377482_2371319765127564303_n.jpg\",\"datePublished\":\"2022-08-06T16:39:35+00:00\",\"dateModified\":\"2022-08-06T16:42:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/08\\\/06\\\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/08\\\/06\\\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/08\\\/06\\\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2022\\\/08\\\/297699428_437673998377482_2371319765127564303_n.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2022\\\/08\\\/297699428_437673998377482_2371319765127564303_n.jpg\",\"width\":1600,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/08\\\/06\\\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alessandro Giorgi\u2026 da giovane sprinter nazionale, a preparatore atletico del calcio a 5 femminile.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\",\"name\":\"Pontinia\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\",\"name\":\"sportpontinia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"caption\":\"sportpontinia\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/author\\\/sportpontinia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alessandro Giorgi\u2026 da giovane sprinter nazionale, a preparatore atletico del calcio a 5 femminile. - Pontinia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pontinia\/2022\/08\/06\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\/","og_locale":"it_IT","og_type":"article","og_title":"Alessandro Giorgi\u2026 da giovane sprinter nazionale, a preparatore atletico del calcio a 5 femminile. - Pontinia","og_description":"Alessandro Giorgi\u2026 da giovane sprinter nazionale, a preparatore atletico del calcio a 5 femminile\u2026 nel mezzo tanta esperienza, tanta professionalit\u00e0. Grazie a delle conoscenze in comune, dopo averlo visto lavorare [&hellip;]","og_url":"https:\/\/comunicacity.net\/pontinia\/2022\/08\/06\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\/","og_site_name":"Pontinia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-08-06T16:39:35+00:00","article_modified_time":"2022-08-06T16:42:46+00:00","og_image":[{"width":1600,"height":1280,"url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2022\/08\/297699428_437673998377482_2371319765127564303_n.jpg","type":"image\/jpeg"}],"author":"sportpontinia","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sportpontinia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pontinia\/2022\/08\/06\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/2022\/08\/06\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\/"},"author":{"name":"sportpontinia","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"headline":"Alessandro Giorgi\u2026 da giovane sprinter nazionale, a preparatore atletico del calcio a 5 femminile.","datePublished":"2022-08-06T16:39:35+00:00","dateModified":"2022-08-06T16:42:46+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2022\/08\/06\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\/"},"wordCount":132,"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2022\/08\/06\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2022\/08\/297699428_437673998377482_2371319765127564303_n.jpg","articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pontinia\/2022\/08\/06\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\/","url":"https:\/\/comunicacity.net\/pontinia\/2022\/08\/06\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\/","name":"Alessandro Giorgi\u2026 da giovane sprinter nazionale, a preparatore atletico del calcio a 5 femminile. - Pontinia","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2022\/08\/06\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2022\/08\/06\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2022\/08\/297699428_437673998377482_2371319765127564303_n.jpg","datePublished":"2022-08-06T16:39:35+00:00","dateModified":"2022-08-06T16:42:46+00:00","author":{"@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/pontinia\/2022\/08\/06\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pontinia\/2022\/08\/06\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pontinia\/2022\/08\/06\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\/#primaryimage","url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2022\/08\/297699428_437673998377482_2371319765127564303_n.jpg","contentUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2022\/08\/297699428_437673998377482_2371319765127564303_n.jpg","width":1600,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pontinia\/2022\/08\/06\/aalessandro-giorgi-da-giovane-sprinter-nazionale-a-preparatore-atletico-del-calcio-a-5-femminile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pontinia\/"},{"@type":"ListItem","position":2,"name":"Alessandro Giorgi\u2026 da giovane sprinter nazionale, a preparatore atletico del calcio a 5 femminile."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pontinia\/#website","url":"https:\/\/comunicacity.net\/pontinia\/","name":"Pontinia","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pontinia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807","name":"sportpontinia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","caption":"sportpontinia"},"url":"https:\/\/comunicacity.net\/pontinia\/author\/sportpontinia\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/3631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/users\/294"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/comments?post=3631"}],"version-history":[{"count":4,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/3631\/revisions"}],"predecessor-version":[{"id":3636,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/3631\/revisions\/3636"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media\/3632"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media?parent=3631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/categories?post=3631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/tags?post=3631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}