{"id":3774,"date":"2022-11-19T16:54:32","date_gmt":"2022-11-19T15:54:32","guid":{"rendered":"https:\/\/comunicacity.net\/pontinia\/?p=3774"},"modified":"2022-11-19T16:54:32","modified_gmt":"2022-11-19T15:54:32","slug":"oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pontinia\/2022\/11\/19\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\/","title":{"rendered":"Oggi (sabato) alle 18:00 l\u2019HC Cassa Rurale Pontinia riceve la corazzata Jomi Salerno."},"content":{"rendered":"<p>Eccovi le parole del presidente Mauro Bianchi<\/p>\n<p>PONTINIA &#8211; Dopo un mese, complice la sosta per le Nazionali, l\u2019HC Cassa Rurale Pontinia torna a giocare davanti al pubblico del palazzetto dello sport Marica Bianchi di Pontinia. Domani (sabato) alle 18:00 la formazione guidata dai coach Laera e Nasta ricever\u00e0 la visita della corazzata Jomi Salerno, formazione che guida la classifica del campionato di serie A1 femminile con sei vittorie su altrettante partite giocate: si tratta del big match dell\u2019ottava giornata visto che in classifica sia Salerno sia Pontinia sono in vetta con 12 punti (in sei match) anche se le campane hanno una partita in meno rispetto al Pontinia che ne ha giocate sette.<\/p>\n<p>\u00abIl grande lavoro che abbiamo fatto in questi anni ci permette di arrivare a giocarci queste partite con la giusta elettricit\u00e0 ma anche con la serenit\u00e0 e la consapevolezza che sfidiamo un avversario dal grande blasone che ha saputo vincere su tutti i palcoscenici e che, in questo momento, \u00e8 al vertice della classifica anche avendo una partita in meno &#8211; chiarisce Mauro Bianchi, il presidente &#8211; Noi vogliamo giocarci la nostra partita e daremo il massimo per creare pi\u00f9 problemi possibile a una corazzata come il Salerno: le nostre avversarie vorranno dominare la sfida e noi dovremo saper soffrire quando servir\u00e0 e soprattutto provare a regalare una grande prestazione ai nostri tifosi\u00bb. In campo si scontrano il miglior attacco della stagione, quello del Pontinia, e la miglior difesa del campionato, quella del Salerno: un match dai contenuti molto interessanti.<\/p>\n<p>\u00abCi saranno tante persone al palazzetto a sostenerci, la nostra realt\u00e0 ha creato molto interesse e regalato tante emozioni sul territorio, per questo mi aspetto che la squadra sappia rispondere sul campo a tutto questo amore lavorando compatta in un\u2019unica direzione &#8211; aggiunge il presidente &#8211; Mi fa piacere sapere che lo spogliatoio sta apprezzando gli sforzi che stiamo facendo e mi aspetto che tutte le risposte arrivino sul campo. Obiettivi? Vogliamo continuare a crescere nelle prestazioni e, in quest\u2019ottica, c\u2019\u00e8 piena sintonia tra la societ\u00e0 e lo staff tecnico: come realt\u00e0 ci siamo sviluppati anche noi e abbiamo le idee molto chiare su dove vogliamo arrivare ma soprattutto in che modo vogliamo farlo. Non abbiamo mai voluto perdere tempo o farci distrarre dal rumore di fondo che \u00e8 presente nello sport come nella vita, vogliamo fare sport, avvicinare i giovani al mondo della pallamano e regalare emozioni ai tifosi e alle realt\u00e0 del territorio che ci supportano\u00bb.<br \/>\nNella classifica dei bomber Colloredo (34) e Gomez (32) hanno totalizzato quota 66 gol in due mentre per il Salerno Ramona Manojlovic \u00e8 la top-scorer del suo club con 33 reti messe a segno.<br \/>\nChi non riuscir\u00e0 a garantirsi il posto all\u2019interno del palazzetto di Pontinia potr\u00e0 seguire in diretta streaming la partita tra Cassa Rurale Pontinia e Jomi Salerno che verr\u00e0 trasmessa sulla piattaforma Elevensports.<\/p>\n<hr \/>\n<p><span style=\"color: #ff0000\">Scontro al vertice ed emozioni assicurate .<\/span><\/p>\n<p><span style=\"color: #ff0000\">Big match dell\u2019ottava giornata di campionato pallamano <\/span><br \/>\n<span style=\"color: #ff0000\">Serie A1 Femminile <\/span><br \/>\n<span style=\"color: #ff0000\">Di fronte Pontinia e Salerno entrambi in vetta alla classifica con 12 punti.<\/span><\/p>\n<p><span style=\"color: #ff0000\">Ci vediamo oggi alle 18:00 al palazzetto dello sport Marica Bianchi<\/span><br \/>\n<span style=\"color: #ff0000\">di Pontinia!<\/span><br \/>\n<span style=\"color: #ff0000\">INSIEME SIAMO PI\u00d9 FORTI <\/span><\/p>\n<p><span style=\"color: #ff0000\">Chi non riuscir\u00e0 a garantirsi il posto all\u2019interno del palazzetto ( ingresso libero) potr\u00e0 seguire in diretta streaming la partita tra Cassa Rurale Pontinia e Jomi Salerno che verr\u00e0 trasmessa sulla piattaforma Elevensports.<\/span><\/p>\n<p><span style=\"color: #ff0000\">Forza Pontinia Carica<\/span><\/p>\n<hr \/>\n<div><a href=\"https:\/\/5fk66.r.a.d.sendibm1.com\/mk\/cl\/f\/CKnyQujjAtRCvMzy1XZA6auCGowbLjUFJLetP6isNoDzxASti4BZ5gouEiCAcMce9NIC0p0rt03j0O3DxiyqCip_WFGljbgywh7WoPTckReV7L8Ne2Rl_cQ0BXaCXEOr6rG9ztmpUtvwGc4SmK9S1d1wzooVIFNPaiuqcSc5vjGxI9kJyJfRkiZwqRmLkdDKyhwRZLoHCE7WUx6auCfb71LZGdjBYeTd0-BbSD7wWrNPpOVQXITA-2W3SwwUVqGiiXA7C3_IinfVuotC4hQFOgm5JIGjZjBrVtJtfpEEmCcSPfetUqPGLOSgy8omaqUEtA\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/ecp.yusercontent.com\/mail?url=https%3A%2F%2F5fk66.img.a.d.sendibm1.com%2Fim%2F3080166%2F5750f4e9939a5fc4b74dd6f42239dfa7320c96c39bb3dca8a440d51ebd03065e.jpg%3Fe%3DCS6ghu85doSvdcnR_QBMlxgJVQk96y-FIpZZRJBRe2vOzBdDgbMozn31NRHY7FQdmATev47njtlYYENYoWJVF_22ILWQW9sW9lnCYTteZeQXLKaHOhydSobBGwyvKvxjGb9djfztv-fPNlMfX78LwPRu-RF_Fko4dHhC-qWzfev03aIpuHJHWv-GOftFgiox1P6HOOAtCcF_G4XBoNnJlRA3GVb0Z43UlYia0A&amp;t=1668873098&amp;ymreqid=bf9afd6f-bd29-6ad5-1c20-4a000001ba00&amp;sig=SlS5QxE3VJaDQZ1arEiV2w--~D\" alt=\"\" width=\"590\" border=\"0\" hspace=\"0\" vspace=\"0\" \/><\/a><\/div>\n<hr \/>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eccovi le parole del presidente Mauro Bianchi PONTINIA &#8211; Dopo un mese, complice la sosta per le Nazionali, l\u2019HC Cassa Rurale Pontinia torna a giocare davanti al pubblico del palazzetto [&hellip;]<\/p>\n","protected":false},"author":294,"featured_media":3459,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-3774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oggi (sabato) alle 18:00 l\u2019HC Cassa Rurale Pontinia riceve la corazzata Jomi Salerno. - Pontinia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pontinia\/2022\/11\/19\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oggi (sabato) alle 18:00 l\u2019HC Cassa Rurale Pontinia riceve la corazzata Jomi Salerno. - Pontinia\" \/>\n<meta property=\"og:description\" content=\"Eccovi le parole del presidente Mauro Bianchi PONTINIA &#8211; Dopo un mese, complice la sosta per le Nazionali, l\u2019HC Cassa Rurale Pontinia torna a giocare davanti al pubblico del palazzetto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pontinia\/2022\/11\/19\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\/\" \/>\n<meta property=\"og:site_name\" content=\"Pontinia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-19T15:54:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2022\/05\/38856E10-F601-4AE4-9564-5DFC83BD7024-1152x1174-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1152\" \/>\n\t<meta property=\"og:image:height\" content=\"1174\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sportpontinia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sportpontinia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/11\\\/19\\\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/11\\\/19\\\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\\\/\"},\"author\":{\"name\":\"sportpontinia\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"headline\":\"Oggi (sabato) alle 18:00 l\u2019HC Cassa Rurale Pontinia riceve la corazzata Jomi Salerno.\",\"datePublished\":\"2022-11-19T15:54:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/11\\\/19\\\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\\\/\"},\"wordCount\":569,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/11\\\/19\\\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2022\\\/05\\\/38856E10-F601-4AE4-9564-5DFC83BD7024-1152x1174-1.jpeg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/11\\\/19\\\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/11\\\/19\\\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\\\/\",\"name\":\"Oggi (sabato) alle 18:00 l\u2019HC Cassa Rurale Pontinia riceve la corazzata Jomi Salerno. - Pontinia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/11\\\/19\\\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/11\\\/19\\\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2022\\\/05\\\/38856E10-F601-4AE4-9564-5DFC83BD7024-1152x1174-1.jpeg\",\"datePublished\":\"2022-11-19T15:54:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/11\\\/19\\\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/11\\\/19\\\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/11\\\/19\\\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2022\\\/05\\\/38856E10-F601-4AE4-9564-5DFC83BD7024-1152x1174-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2022\\\/05\\\/38856E10-F601-4AE4-9564-5DFC83BD7024-1152x1174-1.jpeg\",\"width\":1152,\"height\":1174},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2022\\\/11\\\/19\\\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oggi (sabato) alle 18:00 l\u2019HC Cassa Rurale Pontinia riceve la corazzata Jomi Salerno.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\",\"name\":\"Pontinia\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\",\"name\":\"sportpontinia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"caption\":\"sportpontinia\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/author\\\/sportpontinia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oggi (sabato) alle 18:00 l\u2019HC Cassa Rurale Pontinia riceve la corazzata Jomi Salerno. - Pontinia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pontinia\/2022\/11\/19\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\/","og_locale":"it_IT","og_type":"article","og_title":"Oggi (sabato) alle 18:00 l\u2019HC Cassa Rurale Pontinia riceve la corazzata Jomi Salerno. - Pontinia","og_description":"Eccovi le parole del presidente Mauro Bianchi PONTINIA &#8211; Dopo un mese, complice la sosta per le Nazionali, l\u2019HC Cassa Rurale Pontinia torna a giocare davanti al pubblico del palazzetto [&hellip;]","og_url":"https:\/\/comunicacity.net\/pontinia\/2022\/11\/19\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\/","og_site_name":"Pontinia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-11-19T15:54:32+00:00","og_image":[{"width":1152,"height":1174,"url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2022\/05\/38856E10-F601-4AE4-9564-5DFC83BD7024-1152x1174-1.jpeg","type":"image\/jpeg"}],"author":"sportpontinia","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sportpontinia","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pontinia\/2022\/11\/19\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/2022\/11\/19\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\/"},"author":{"name":"sportpontinia","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"headline":"Oggi (sabato) alle 18:00 l\u2019HC Cassa Rurale Pontinia riceve la corazzata Jomi Salerno.","datePublished":"2022-11-19T15:54:32+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2022\/11\/19\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\/"},"wordCount":569,"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2022\/11\/19\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2022\/05\/38856E10-F601-4AE4-9564-5DFC83BD7024-1152x1174-1.jpeg","articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pontinia\/2022\/11\/19\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\/","url":"https:\/\/comunicacity.net\/pontinia\/2022\/11\/19\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\/","name":"Oggi (sabato) alle 18:00 l\u2019HC Cassa Rurale Pontinia riceve la corazzata Jomi Salerno. - Pontinia","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2022\/11\/19\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2022\/11\/19\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2022\/05\/38856E10-F601-4AE4-9564-5DFC83BD7024-1152x1174-1.jpeg","datePublished":"2022-11-19T15:54:32+00:00","author":{"@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/pontinia\/2022\/11\/19\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pontinia\/2022\/11\/19\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pontinia\/2022\/11\/19\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\/#primaryimage","url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2022\/05\/38856E10-F601-4AE4-9564-5DFC83BD7024-1152x1174-1.jpeg","contentUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2022\/05\/38856E10-F601-4AE4-9564-5DFC83BD7024-1152x1174-1.jpeg","width":1152,"height":1174},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pontinia\/2022\/11\/19\/oggi-sabato-alle-1800-lhc-cassa-rurale-pontinia-riceve-la-corazzata-jomi-salerno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pontinia\/"},{"@type":"ListItem","position":2,"name":"Oggi (sabato) alle 18:00 l\u2019HC Cassa Rurale Pontinia riceve la corazzata Jomi Salerno."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pontinia\/#website","url":"https:\/\/comunicacity.net\/pontinia\/","name":"Pontinia","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pontinia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807","name":"sportpontinia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","caption":"sportpontinia"},"url":"https:\/\/comunicacity.net\/pontinia\/author\/sportpontinia\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/3774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/users\/294"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/comments?post=3774"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/3774\/revisions"}],"predecessor-version":[{"id":3775,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/3774\/revisions\/3775"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media\/3459"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media?parent=3774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/categories?post=3774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/tags?post=3774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}