{"id":3925,"date":"2023-01-08T20:24:27","date_gmt":"2023-01-08T19:24:27","guid":{"rendered":"https:\/\/comunicacity.net\/pontinia\/?p=3925"},"modified":"2023-01-08T20:24:27","modified_gmt":"2023-01-08T19:24:27","slug":"lhc-cassa-rurale-pontinia-supera-lerice","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pontinia\/2023\/01\/08\/lhc-cassa-rurale-pontinia-supera-lerice\/","title":{"rendered":"L\u2019HC Cassa Rurale Pontinia supera l\u2019Erice"},"content":{"rendered":"<p><strong>L\u2019HC Cassa Rurale Pontinia supera l\u2019Erice, centra l\u2019undicesima vittoria di fila e si conferma prima in classifica. La soddisfazione di Bianchi, Nasta, Laera e Bassanese<\/strong><\/p>\n<hr \/>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>PONTINIA &#8211; L\u2019HC Cassa Rurale Pontinia supera con autorit\u00e0 l\u2019Erice in trasferta (22-27), centra l\u2019undicesima vittoria consecutiva in serie A1 e si conferma in testa al massimo campionato di pallamano femminile. Dopo la lunga pausa la formazione pontina, dopo aver conquistato il titolo di campione d\u2019inverno, centra un successo cruciale sul complicato campo siciliano e sale a 22 punti, inseguita da vicino dalla corazzata Jomi Salerno, poi da Erice (18 punti) e Brixen (17). A Pontinia la soddisfazione \u00e8 notevole e il pubblico gi\u00e0 aspetta la prossima sfida al palazzetto dello sport Marica Bianchi in programma sabato prossimo con il Teramo. \u00abSiamo orgogliosi per questa vittoria, centrata con umilt\u00e0, tecnica e determinazione: come sempre ho visto dare il massimo da tutta la squadra &#8211; spiega il presidente Mauro Bianchi &#8211; ci godiamo questo risultato e andiamo avanti consapevoli che il cammino \u00e8 ancora molto lungo: dobbiamo continuare a credere in tutto ci\u00f2 che facciamo perch\u00e9 c\u2019\u00e8 un sogno a Pontinia e c\u2019\u00e8 qualcosa di straordinario anche dentro di ognuno di noi che, insieme, ci rende una squadra grande e capace di puntare dritto al risultato come ha fatto finora\u00bb. Soddisfatti anche i due allenatori. \u00abLa partita \u00e8 stata molto divertente, anche dura e perfettamente interpretata dalle nostre giocatrici che hanno creduto nel risultato gi\u00e0 all\u2019inizio di questa trasferta con le pi\u00f9 giovani al servizio delle pi\u00f9 esperte e loro brave a guidare sul campo &#8211; spiega coach Giovanni Nasta &#8211; \u00e8 stato bello per noi poterle gestire con le rotazioni che alla fine sono state la chiave della vittoria: eravamo molto motivate per lo spessore degli avversari guidati in panchina da un mostro sacro della pallamano europea. Questo gruppo sta maturando e sta diventando squadra e per noi \u00e8 veramente bello lavorare insieme a loro\u00bb. Anche coach Antonj Laera analizza con positivit\u00e0 l\u2019undicesima vittoria del Pontinia. \u00abAbbiamo raccolto i frutti del lavoro che abbiamo svolto in queste settimane in cui sia io sia Giovanni Nasta ci siamo divertiti ad ammirare lo spirito di gruppo e l\u2019attenzione con cui le ragazze si sono applicate nella cura dei dettagli, vogliamo continuare cos\u00ec e sappiamo che i risultati sono frutto del lavoro che facciamo durante la settimana e sappiamo che possiamo crescere ancora\u00bb. Il match \u00e8 stato equilibrato nell\u2019avvio, poi il Pontinia ha iniziato ad allungare e ha chiuso il primo tempo in vantaggio (10-12). Nella ripresa le giocatrici pontine hanno continuato a gestire il gioco trascinate dall\u2019esperienza di Gomez (cinque gol), dalla qualit\u00e0 di Bassanese (cinque gol anche per lei) e dalla determinazione della nuova arrivata Radovic (cinque gol anche per lei). Colloredo ha dato un grande contributo in difesa e la velocissima Giulia Conte ha giocato come al solito con una marcia in pi\u00f9, la sua velocit\u00e0 ha mandato in difficolt\u00e0 le avversarie che sono state costrette a fermarla spesso anche in maniera irregolare come giustamente ravvisato dagli arbitri. I cinque gol di scarto con cui il Pontinia ha vinto la partita sono merito di un lavoro collettivo e dallo spirito di unione di tutta la squadra: determinante anche Romina Ramazzotti che con le sue parate ha fatto spesso la differenza concretizzando quanto di buono fatto dall\u2019intera difesa. \u00abAbbiamo giocato un\u2019ottima partita e interpretato bene tutto quello che avevamo preparato, penso che chi ha visto la partita si sia divertito perch\u00e9 ha visto due squadre che puntano alle prime posizioni &#8211; spiega Alessandra Bassanese &#8211; Avevo tanta voglia di giocare anche perch\u00e9 all\u2019andata non avevo giocato, stavo recuperando dall\u2019infortunio al ginocchio: c\u2019era tanta voglia di fare bene e sono contenta di come sia andata e speriamo di continuare su questa strada. Abbiamo lavorato bene anche per integrare la Radovic, voglio anche sottolineare la prestazione superlativa di Ramazzotti\u00bb.<\/div>\n<div><\/div>\n<div><strong>AC LIFE STYLE ERICE &#8211; HC CASSA RURALE PONTINIA: 22-27 (10-12 p.t.)<\/strong><br \/>\nAC LIFE STYLE ERICE: Masson, Mrkikj 7, Coppola 2, Tarbuch 3, Losio 3, Basolu 1, Cozzi, Pugliara 1, Gorbatsjova 3, Benincasa, Iacovello, Ravasz, Podariu, Landri 2, Storozhuk. All. Borson Szab\u00f2<br \/>\nHC CASSA RURALE PONTINIA: Ramazzotti, Sitzia, Manzo, Podda 3, Conte 3, Colloredo 2, D\u2019Ambrosio, Notarianni, Bassanese 5, Panayotova 2, Radovic 5, Gomez 5, Crosta 2. All. Laera &#8211; Nasta<br \/>\nArbitri: Dionisi e Maccarone. Del. Chiarello<\/div>\n<div>\n<hr \/>\n<p><span style=\"color: #0000cc\">CANALE YOUTUBE\u00a0<a href=\"https:\/\/5fk66.r.a.d.sendibm1.com\/mk\/cl\/f\/KgF-jZisdIj9G7Jtxvc_rrOzzTsHYYc7HoabVcNvVmB-6PFCb7yh5vLSWQNtvx3B-Uk0oKRT66bNrNrEjZKEXTdOnH906Tuq-wrLuBYIlMW0NX-SSte8foRyQa1dC9w_C-yjzDGEZzHEiacGq772jisWiUIXbmpmJxEzb6mqZJ_4bQYfSHEsHkgq4ETtjTwCYIEbJLD_8p5bkFBYeguo7SCHSDQx\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">https:\/\/www.youtube.com\/@pallamanopontinia<\/a><\/span><\/div>\n<div>\n<hr \/>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-3926 aligncenter\" src=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/01\/mail-1024x682.jpg\" alt=\"\" width=\"427\" height=\"284\" srcset=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/01\/mail-1024x682.jpg 1024w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/01\/mail-300x200.jpg 300w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/01\/mail-768x512.jpg 768w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/01\/mail-1536x1024.jpg 1536w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/01\/mail.jpg 2000w\" sizes=\"auto, (max-width: 427px) 100vw, 427px\" \/><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019HC Cassa Rurale Pontinia supera l\u2019Erice, centra l\u2019undicesima vittoria di fila e si conferma prima in classifica. La soddisfazione di Bianchi, Nasta, Laera e Bassanese PONTINIA &#8211; L\u2019HC Cassa Rurale [&hellip;]<\/p>\n","protected":false},"author":294,"featured_media":3926,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-3925","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019HC Cassa Rurale Pontinia supera l\u2019Erice - Pontinia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pontinia\/2023\/01\/08\/lhc-cassa-rurale-pontinia-supera-lerice\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019HC Cassa Rurale Pontinia supera l\u2019Erice - Pontinia\" \/>\n<meta property=\"og:description\" content=\"L\u2019HC Cassa Rurale Pontinia supera l\u2019Erice, centra l\u2019undicesima vittoria di fila e si conferma prima in classifica. La soddisfazione di Bianchi, Nasta, Laera e Bassanese PONTINIA &#8211; L\u2019HC Cassa Rurale [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pontinia\/2023\/01\/08\/lhc-cassa-rurale-pontinia-supera-lerice\/\" \/>\n<meta property=\"og:site_name\" content=\"Pontinia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-08T19:24:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/01\/mail.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sportpontinia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sportpontinia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/01\\\/08\\\/lhc-cassa-rurale-pontinia-supera-lerice\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/01\\\/08\\\/lhc-cassa-rurale-pontinia-supera-lerice\\\/\"},\"author\":{\"name\":\"sportpontinia\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"headline\":\"L\u2019HC Cassa Rurale Pontinia supera l\u2019Erice\",\"datePublished\":\"2023-01-08T19:24:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/01\\\/08\\\/lhc-cassa-rurale-pontinia-supera-lerice\\\/\"},\"wordCount\":727,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/01\\\/08\\\/lhc-cassa-rurale-pontinia-supera-lerice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2023\\\/01\\\/mail.jpg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/01\\\/08\\\/lhc-cassa-rurale-pontinia-supera-lerice\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/01\\\/08\\\/lhc-cassa-rurale-pontinia-supera-lerice\\\/\",\"name\":\"L\u2019HC Cassa Rurale Pontinia supera l\u2019Erice - Pontinia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/01\\\/08\\\/lhc-cassa-rurale-pontinia-supera-lerice\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/01\\\/08\\\/lhc-cassa-rurale-pontinia-supera-lerice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2023\\\/01\\\/mail.jpg\",\"datePublished\":\"2023-01-08T19:24:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/01\\\/08\\\/lhc-cassa-rurale-pontinia-supera-lerice\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/01\\\/08\\\/lhc-cassa-rurale-pontinia-supera-lerice\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/01\\\/08\\\/lhc-cassa-rurale-pontinia-supera-lerice\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2023\\\/01\\\/mail.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2023\\\/01\\\/mail.jpg\",\"width\":2000,\"height\":1333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/01\\\/08\\\/lhc-cassa-rurale-pontinia-supera-lerice\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019HC Cassa Rurale Pontinia supera l\u2019Erice\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\",\"name\":\"Pontinia\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\",\"name\":\"sportpontinia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"caption\":\"sportpontinia\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/author\\\/sportpontinia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019HC Cassa Rurale Pontinia supera l\u2019Erice - Pontinia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pontinia\/2023\/01\/08\/lhc-cassa-rurale-pontinia-supera-lerice\/","og_locale":"it_IT","og_type":"article","og_title":"L\u2019HC Cassa Rurale Pontinia supera l\u2019Erice - Pontinia","og_description":"L\u2019HC Cassa Rurale Pontinia supera l\u2019Erice, centra l\u2019undicesima vittoria di fila e si conferma prima in classifica. La soddisfazione di Bianchi, Nasta, Laera e Bassanese PONTINIA &#8211; L\u2019HC Cassa Rurale [&hellip;]","og_url":"https:\/\/comunicacity.net\/pontinia\/2023\/01\/08\/lhc-cassa-rurale-pontinia-supera-lerice\/","og_site_name":"Pontinia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-01-08T19:24:27+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/01\/mail.jpg","type":"image\/jpeg"}],"author":"sportpontinia","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sportpontinia","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pontinia\/2023\/01\/08\/lhc-cassa-rurale-pontinia-supera-lerice\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/2023\/01\/08\/lhc-cassa-rurale-pontinia-supera-lerice\/"},"author":{"name":"sportpontinia","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"headline":"L\u2019HC Cassa Rurale Pontinia supera l\u2019Erice","datePublished":"2023-01-08T19:24:27+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2023\/01\/08\/lhc-cassa-rurale-pontinia-supera-lerice\/"},"wordCount":727,"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2023\/01\/08\/lhc-cassa-rurale-pontinia-supera-lerice\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/01\/mail.jpg","articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pontinia\/2023\/01\/08\/lhc-cassa-rurale-pontinia-supera-lerice\/","url":"https:\/\/comunicacity.net\/pontinia\/2023\/01\/08\/lhc-cassa-rurale-pontinia-supera-lerice\/","name":"L\u2019HC Cassa Rurale Pontinia supera l\u2019Erice - Pontinia","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2023\/01\/08\/lhc-cassa-rurale-pontinia-supera-lerice\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2023\/01\/08\/lhc-cassa-rurale-pontinia-supera-lerice\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/01\/mail.jpg","datePublished":"2023-01-08T19:24:27+00:00","author":{"@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/pontinia\/2023\/01\/08\/lhc-cassa-rurale-pontinia-supera-lerice\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pontinia\/2023\/01\/08\/lhc-cassa-rurale-pontinia-supera-lerice\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pontinia\/2023\/01\/08\/lhc-cassa-rurale-pontinia-supera-lerice\/#primaryimage","url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/01\/mail.jpg","contentUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/01\/mail.jpg","width":2000,"height":1333},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pontinia\/2023\/01\/08\/lhc-cassa-rurale-pontinia-supera-lerice\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pontinia\/"},{"@type":"ListItem","position":2,"name":"L\u2019HC Cassa Rurale Pontinia supera l\u2019Erice"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pontinia\/#website","url":"https:\/\/comunicacity.net\/pontinia\/","name":"Pontinia","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pontinia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807","name":"sportpontinia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","caption":"sportpontinia"},"url":"https:\/\/comunicacity.net\/pontinia\/author\/sportpontinia\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/3925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/users\/294"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/comments?post=3925"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/3925\/revisions"}],"predecessor-version":[{"id":3927,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/3925\/revisions\/3927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media\/3926"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media?parent=3925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/categories?post=3925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/tags?post=3925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}