{"id":3952,"date":"2023-02-11T17:40:06","date_gmt":"2023-02-11T16:40:06","guid":{"rendered":"https:\/\/comunicacity.net\/pontinia\/?p=3952"},"modified":"2023-02-11T17:40:06","modified_gmt":"2023-02-11T16:40:06","slug":"lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pontinia\/2023\/02\/11\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\/","title":{"rendered":"L\u2019HC Cassa Rurale Pontinia torna a giocare al Marica Bianchi"},"content":{"rendered":"<p>L\u2019HC Cassa Rurale Pontinia torna a giocare al Marica Bianchi: oggi ( sabato11 febbraio ) alle 18:00 arriva il Mezzocorona.<\/p>\n<hr \/>\n<p>Ramazzotti \u00abAvversario difficile\u00bb. Nasta: \u00abSfida delicata\u00bb<\/p>\n<hr \/>\n<p>PONTINIA &#8211; Torna a giocare in casa l\u2019HC Cassa Rurale Pontinia che domani (sabato) alle 18:00 ricever\u00e0 il Mezzocorona al Marica Bianchi di Pontinia. La formazione di Pontinia, guidata dai coach Laera e Nasta, \u00e8 reduce dall\u2019eliminazione in semifinale di Coppa Italia mentre nel campionato di pallamano femminile di serie A1, Gomez e compagne sono reduci da 13 vittorie consecutive. Il Mezzocorona, molto attardato in classifica, \u00e8 una formazione alla ricerca di punti pesanti sul campo della capolista e, anche per questo, sar\u00e0 una partita da vivere con il massimo della concentrazione. \u00abSar\u00e0 sicuramente una partita difficilissima per quel che riguarda l&#8217;aspetto psicologico perch\u00e9 arriviamo dalla sconfitta in Coppa Italia e dobbiamo velocemente cambiare pagina &#8211; ammette Romina Ramazzotti, portiere del Pontinia &#8211; Il Mezzocorona non \u00e8 mai un avversario facile, parliamo di una squadra composta da ragazze che si conoscono bene e cercano di giocare di squadra: contro di noi verrano alla ricerca dei punti perch\u00e9 ne hanno bisogno. Come ci arriviamo noi? A prescindere dell\u2019avversario, dobbiamo mettere in campo il massimo della determinazione: stiamo continuando a lavorare intensamente sui nostri obiettivi, cercando ogni giorno di migliorare quei dettagli che sappiamo che ci porteranno a fare bene in futuro\u00bb. All\u2019andata, era l\u20198 ottobre dello scorso anno, il Pontinia vinse in trasferta (23-33) centrando quella che fu la terza vittoria consecutiva in stagione: Gislimberti e Dalla Valle furono le top-scorer di quella sfida con 13 reti in due, mentre per il Pontinia Panayotova timbr\u00f2 sei volte e Gomez cinque. Proprio la Gislimberti si presenter\u00e0 a Pontinia da miglior realizzatrice dell\u2019intero campionato: con 118 reti totalizzate finora, il bomber del Mezzocorona sar\u00e0 una giocatrice osservata speciale perch\u00e9 capace di spostare gli equilibri con la sua capacit\u00e0 realizzativa, mentre per trovare la prima giocatrice del Pontinia bisogna scendere ai 67 gol di Colloredo, praticamente la met\u00e0.<\/p>\n<p>\u00abSar\u00e0 una partita particolarmente delicata perch\u00e9 affrontiamo una squadra molto motivata per la rincorsa salvezza e che s\u2019\u00e8 ulteriormente rinforzata con altre due straniere che potranno fare la differenza &#8211; aggiunge coach Giovanni Nasta &#8211; Noi arriviamo un po\u2019 delusi per l\u2019eliminazione ai tiri di rigore dalla semifinale di Coppa Italia ma non vediamo l\u2019ora di tornare in campo per riprendere il nostro cammino e confrontarci con avversari validi come il Mezzocorona\u00bb.<\/p>\n<hr \/>\n<p><span style=\"color: #ff0000\">La partita, arbitrata da Scavone e Bocchieri, verr\u00e0 trasmessa anche in diretta streaming sulla piattaforma Elevensports.<\/span><\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019HC Cassa Rurale Pontinia torna a giocare al Marica Bianchi: oggi ( sabato11 febbraio ) alle 18:00 arriva il Mezzocorona. Ramazzotti \u00abAvversario difficile\u00bb. Nasta: \u00abSfida delicata\u00bb PONTINIA &#8211; Torna a [&hellip;]<\/p>\n","protected":false},"author":294,"featured_media":3950,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,24],"tags":[],"class_list":["post-3952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019HC Cassa Rurale Pontinia torna a giocare al Marica Bianchi - Pontinia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pontinia\/2023\/02\/11\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019HC Cassa Rurale Pontinia torna a giocare al Marica Bianchi - Pontinia\" \/>\n<meta property=\"og:description\" content=\"L\u2019HC Cassa Rurale Pontinia torna a giocare al Marica Bianchi: oggi ( sabato11 febbraio ) alle 18:00 arriva il Mezzocorona. Ramazzotti \u00abAvversario difficile\u00bb. Nasta: \u00abSfida delicata\u00bb PONTINIA &#8211; Torna a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pontinia\/2023\/02\/11\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\/\" \/>\n<meta property=\"og:site_name\" content=\"Pontinia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-11T16:40:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/02\/mail1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"810\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sportpontinia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sportpontinia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/02\\\/11\\\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/02\\\/11\\\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\\\/\"},\"author\":{\"name\":\"sportpontinia\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"headline\":\"L\u2019HC Cassa Rurale Pontinia torna a giocare al Marica Bianchi\",\"datePublished\":\"2023-02-11T16:40:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/02\\\/11\\\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\\\/\"},\"wordCount\":427,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/02\\\/11\\\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2023\\\/02\\\/mail1.jpg\",\"articleSection\":[\"Notizie e Informazioni\",\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/02\\\/11\\\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/02\\\/11\\\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\\\/\",\"name\":\"L\u2019HC Cassa Rurale Pontinia torna a giocare al Marica Bianchi - Pontinia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/02\\\/11\\\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/02\\\/11\\\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2023\\\/02\\\/mail1.jpg\",\"datePublished\":\"2023-02-11T16:40:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/02\\\/11\\\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/02\\\/11\\\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/02\\\/11\\\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2023\\\/02\\\/mail1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2023\\\/02\\\/mail1.jpg\",\"width\":810,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/02\\\/11\\\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019HC Cassa Rurale Pontinia torna a giocare al Marica Bianchi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\",\"name\":\"Pontinia\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\",\"name\":\"sportpontinia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"caption\":\"sportpontinia\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/author\\\/sportpontinia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019HC Cassa Rurale Pontinia torna a giocare al Marica Bianchi - Pontinia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pontinia\/2023\/02\/11\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\/","og_locale":"it_IT","og_type":"article","og_title":"L\u2019HC Cassa Rurale Pontinia torna a giocare al Marica Bianchi - Pontinia","og_description":"L\u2019HC Cassa Rurale Pontinia torna a giocare al Marica Bianchi: oggi ( sabato11 febbraio ) alle 18:00 arriva il Mezzocorona. Ramazzotti \u00abAvversario difficile\u00bb. Nasta: \u00abSfida delicata\u00bb PONTINIA &#8211; Torna a [&hellip;]","og_url":"https:\/\/comunicacity.net\/pontinia\/2023\/02\/11\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\/","og_site_name":"Pontinia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-02-11T16:40:06+00:00","og_image":[{"width":810,"height":540,"url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/02\/mail1.jpg","type":"image\/jpeg"}],"author":"sportpontinia","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sportpontinia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pontinia\/2023\/02\/11\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/2023\/02\/11\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\/"},"author":{"name":"sportpontinia","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"headline":"L\u2019HC Cassa Rurale Pontinia torna a giocare al Marica Bianchi","datePublished":"2023-02-11T16:40:06+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2023\/02\/11\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\/"},"wordCount":427,"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2023\/02\/11\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/02\/mail1.jpg","articleSection":["Notizie e Informazioni","Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pontinia\/2023\/02\/11\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\/","url":"https:\/\/comunicacity.net\/pontinia\/2023\/02\/11\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\/","name":"L\u2019HC Cassa Rurale Pontinia torna a giocare al Marica Bianchi - Pontinia","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2023\/02\/11\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2023\/02\/11\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/02\/mail1.jpg","datePublished":"2023-02-11T16:40:06+00:00","author":{"@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/pontinia\/2023\/02\/11\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pontinia\/2023\/02\/11\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pontinia\/2023\/02\/11\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\/#primaryimage","url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/02\/mail1.jpg","contentUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/02\/mail1.jpg","width":810,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pontinia\/2023\/02\/11\/lhc-cassa-rurale-pontinia-torna-a-giocare-al-marica-bianchi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pontinia\/"},{"@type":"ListItem","position":2,"name":"L\u2019HC Cassa Rurale Pontinia torna a giocare al Marica Bianchi"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pontinia\/#website","url":"https:\/\/comunicacity.net\/pontinia\/","name":"Pontinia","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pontinia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807","name":"sportpontinia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","caption":"sportpontinia"},"url":"https:\/\/comunicacity.net\/pontinia\/author\/sportpontinia\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/3952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/users\/294"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/comments?post=3952"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/3952\/revisions"}],"predecessor-version":[{"id":3953,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/3952\/revisions\/3953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media\/3950"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media?parent=3952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/categories?post=3952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/tags?post=3952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}