{"id":4048,"date":"2023-09-06T12:07:29","date_gmt":"2023-09-06T10:07:29","guid":{"rendered":"https:\/\/comunicacity.net\/pontinia\/?p=4048"},"modified":"2023-09-06T12:07:29","modified_gmt":"2023-09-06T10:07:29","slug":"campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pontinia\/2023\/09\/06\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\/","title":{"rendered":"Campionato, conto alla rovescia. Bianchi: \u00abIl nostro progetto coinvolge il territorio e richiede una sinergia tra settore pubblico e privato per continuare ad avere successo\u00bb"},"content":{"rendered":"<p class=\"p1\">PONTINIA \u2013 Il prossimo 16 settembre, con la trasferta di Padova, per l\u2019HC Cassa Rurale Pontinia inizier\u00e0 la sua quarta stagione in serie A1, un traguardo importante per una societ\u00e0 che da decenni \u00e8 in prima linea per promuovere lo sport giovanile e quello di alto livello. Le sfide sono quotidiane per chi porta avanti un progetto cos\u00ec ambizioso e anche gli ostacoli da superare. \u00abLa quarta stagione nella massima serie rappresenta, per noi, un traguardo che va ben oltre il semplice successo sportivo \u2013 assicura con orgoglio il presidente Mauro Bianchi \u2013 Questi traguardi sono il risultato di anni di costante impegno e dedizione da parte di chi va in campo, dello staff tecnico e di tutti coloro che hanno condiviso la nostra visione: abbiamo investito non solo in risorse materiali, ma anche nella crescita di tutti i nostri atleti perch\u00e9 la costruzione di una squadra competitiva richiede una pianificazione lungimirante e un incessante impegno e va riconosciuto che il sostegno prezioso degli sponsor \u00e8 stato fondamentale per garantire alle nostre leve le risorse necessarie per competere a livello massimo\u00bb.<\/p>\n<p class=\"p1\">Tuttavia, il successo sportivo \u00e8 soltanto uno dei tanti aspetti di questa stimolante avventura. \u00abLa presenza di Pontinia nella serie A costituisce un\u2019opportunit\u00e0 straordinaria per la nostra citt\u00e0 e per il nostro territorio \u2013 riprende Bianchi \u2013 Richiamiamo l\u2019attenzione di migliaia di appassionati, molti dei quali ci seguono anche dal vivo, senza dimenticare la grande visibilit\u00e0 che arriva dai media locali e nazionali e cos\u00ec il nostro impegno coinvolge anche tutto il settore giovanile e intendiamo far conoscere la cultura e l\u2019identit\u00e0 uniche che caratterizzano Pontinia, rendendo la citt\u00e0 orgogliosa di questa rappresentazione questo perch\u00e9 quando i nostri giocatori scendono in campo, trasmettono il calore e il sostegno dell\u2019intera comunit\u00e0 e le partite sono momenti di aggregazione, celebrazione e dimostrazione del nostro attaccamento ai nostri colori\u00bb.<\/p>\n<p class=\"p1\">Un aspetto che non pu\u00f2 essere trascurato \u00e8 l\u2019impatto economico. \u00abLe partite di Serie A, ma non solo di Serie A attirano appassionati da diverse localit\u00e0, generando un incremento nel turismo sportivo \u2013 sottolinea il presidente \u2013 Questo impulso si traduce in un vantaggio economico concreto per Pontinia visto che gli alberghi, i ristoranti e i negozi traggono beneficio dall\u2019arrivo di visitatori entusiasti. Non possiamo dimenticare quanto sia fondamentale un supporto collaborativo anche da parte delle istituzioni locali: questa \u00e8 una sfida che coinvolge l\u2019intera comunit\u00e0 e richiede una sinergia tra settore pubblico e privato per continuare ad avere successo e trarne i massimi benefici che da al paese una squadra di Serie A\u00bb.<\/p>\n<hr \/>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-4050 aligncenter\" src=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/09\/374567069_774799191319206_5571658620359333501_n-1024x936.jpg\" alt=\"\" width=\"640\" height=\"585\" srcset=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/09\/374567069_774799191319206_5571658620359333501_n-1024x936.jpg 1024w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/09\/374567069_774799191319206_5571658620359333501_n-300x274.jpg 300w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/09\/374567069_774799191319206_5571658620359333501_n-768x702.jpg 768w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/09\/374567069_774799191319206_5571658620359333501_n.jpg 1170w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PONTINIA \u2013 Il prossimo 16 settembre, con la trasferta di Padova, per l\u2019HC Cassa Rurale Pontinia inizier\u00e0 la sua quarta stagione in serie A1, un traguardo importante per una societ\u00e0 [&hellip;]<\/p>\n","protected":false},"author":294,"featured_media":4049,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,24],"tags":[],"class_list":["post-4048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campionato, conto alla rovescia. Bianchi: \u00abIl nostro progetto coinvolge il territorio e richiede una sinergia tra settore pubblico e privato per continuare ad avere successo\u00bb - Pontinia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pontinia\/2023\/09\/06\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campionato, conto alla rovescia. Bianchi: \u00abIl nostro progetto coinvolge il territorio e richiede una sinergia tra settore pubblico e privato per continuare ad avere successo\u00bb - Pontinia\" \/>\n<meta property=\"og:description\" content=\"PONTINIA \u2013 Il prossimo 16 settembre, con la trasferta di Padova, per l\u2019HC Cassa Rurale Pontinia inizier\u00e0 la sua quarta stagione in serie A1, un traguardo importante per una societ\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pontinia\/2023\/09\/06\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\/\" \/>\n<meta property=\"og:site_name\" content=\"Pontinia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-06T10:07:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/09\/29e4be35-7e39-46f0-88f0-0ef0f2aa5cb5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1364\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sportpontinia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sportpontinia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/09\\\/06\\\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/09\\\/06\\\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\\\/\"},\"author\":{\"name\":\"sportpontinia\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"headline\":\"Campionato, conto alla rovescia. Bianchi: \u00abIl nostro progetto coinvolge il territorio e richiede una sinergia tra settore pubblico e privato per continuare ad avere successo\u00bb\",\"datePublished\":\"2023-09-06T10:07:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/09\\\/06\\\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\\\/\"},\"wordCount\":441,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/09\\\/06\\\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2023\\\/09\\\/29e4be35-7e39-46f0-88f0-0ef0f2aa5cb5.jpg\",\"articleSection\":[\"Notizie e Informazioni\",\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/09\\\/06\\\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/09\\\/06\\\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\\\/\",\"name\":\"Campionato, conto alla rovescia. Bianchi: \u00abIl nostro progetto coinvolge il territorio e richiede una sinergia tra settore pubblico e privato per continuare ad avere successo\u00bb - Pontinia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/09\\\/06\\\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/09\\\/06\\\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2023\\\/09\\\/29e4be35-7e39-46f0-88f0-0ef0f2aa5cb5.jpg\",\"datePublished\":\"2023-09-06T10:07:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/09\\\/06\\\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/09\\\/06\\\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/09\\\/06\\\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2023\\\/09\\\/29e4be35-7e39-46f0-88f0-0ef0f2aa5cb5.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2023\\\/09\\\/29e4be35-7e39-46f0-88f0-0ef0f2aa5cb5.jpg\",\"width\":2048,\"height\":1364},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2023\\\/09\\\/06\\\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campionato, conto alla rovescia. Bianchi: \u00abIl nostro progetto coinvolge il territorio e richiede una sinergia tra settore pubblico e privato per continuare ad avere successo\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\",\"name\":\"Pontinia\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\",\"name\":\"sportpontinia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"caption\":\"sportpontinia\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/author\\\/sportpontinia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campionato, conto alla rovescia. Bianchi: \u00abIl nostro progetto coinvolge il territorio e richiede una sinergia tra settore pubblico e privato per continuare ad avere successo\u00bb - Pontinia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pontinia\/2023\/09\/06\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\/","og_locale":"it_IT","og_type":"article","og_title":"Campionato, conto alla rovescia. Bianchi: \u00abIl nostro progetto coinvolge il territorio e richiede una sinergia tra settore pubblico e privato per continuare ad avere successo\u00bb - Pontinia","og_description":"PONTINIA \u2013 Il prossimo 16 settembre, con la trasferta di Padova, per l\u2019HC Cassa Rurale Pontinia inizier\u00e0 la sua quarta stagione in serie A1, un traguardo importante per una societ\u00e0 [&hellip;]","og_url":"https:\/\/comunicacity.net\/pontinia\/2023\/09\/06\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\/","og_site_name":"Pontinia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-09-06T10:07:29+00:00","og_image":[{"width":2048,"height":1364,"url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/09\/29e4be35-7e39-46f0-88f0-0ef0f2aa5cb5.jpg","type":"image\/jpeg"}],"author":"sportpontinia","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sportpontinia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pontinia\/2023\/09\/06\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/2023\/09\/06\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\/"},"author":{"name":"sportpontinia","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"headline":"Campionato, conto alla rovescia. Bianchi: \u00abIl nostro progetto coinvolge il territorio e richiede una sinergia tra settore pubblico e privato per continuare ad avere successo\u00bb","datePublished":"2023-09-06T10:07:29+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2023\/09\/06\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\/"},"wordCount":441,"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2023\/09\/06\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/09\/29e4be35-7e39-46f0-88f0-0ef0f2aa5cb5.jpg","articleSection":["Notizie e Informazioni","Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pontinia\/2023\/09\/06\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\/","url":"https:\/\/comunicacity.net\/pontinia\/2023\/09\/06\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\/","name":"Campionato, conto alla rovescia. Bianchi: \u00abIl nostro progetto coinvolge il territorio e richiede una sinergia tra settore pubblico e privato per continuare ad avere successo\u00bb - Pontinia","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2023\/09\/06\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2023\/09\/06\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/09\/29e4be35-7e39-46f0-88f0-0ef0f2aa5cb5.jpg","datePublished":"2023-09-06T10:07:29+00:00","author":{"@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/pontinia\/2023\/09\/06\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pontinia\/2023\/09\/06\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pontinia\/2023\/09\/06\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\/#primaryimage","url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/09\/29e4be35-7e39-46f0-88f0-0ef0f2aa5cb5.jpg","contentUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2023\/09\/29e4be35-7e39-46f0-88f0-0ef0f2aa5cb5.jpg","width":2048,"height":1364},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pontinia\/2023\/09\/06\/campionato-conto-alla-rovescia-bianchi-il-nostro-progetto-coinvolge-il-territorio-e-richiede-una-sinergia-tra-settore-pubblico-e-privato-per-continuare-ad-avere-successo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pontinia\/"},{"@type":"ListItem","position":2,"name":"Campionato, conto alla rovescia. Bianchi: \u00abIl nostro progetto coinvolge il territorio e richiede una sinergia tra settore pubblico e privato per continuare ad avere successo\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pontinia\/#website","url":"https:\/\/comunicacity.net\/pontinia\/","name":"Pontinia","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pontinia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807","name":"sportpontinia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","caption":"sportpontinia"},"url":"https:\/\/comunicacity.net\/pontinia\/author\/sportpontinia\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/4048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/users\/294"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/comments?post=4048"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/4048\/revisions"}],"predecessor-version":[{"id":4051,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/4048\/revisions\/4051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media\/4049"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media?parent=4048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/categories?post=4048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/tags?post=4048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}