{"id":4296,"date":"2025-02-03T14:36:33","date_gmt":"2025-02-03T13:36:33","guid":{"rendered":"https:\/\/comunicacity.net\/pontinia\/?p=4296"},"modified":"2025-02-03T14:36:33","modified_gmt":"2025-02-03T13:36:33","slug":"ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pontinia\/2025\/02\/03\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\/","title":{"rendered":"L\u2019Adattiva Pontinia espugna il campo del Lions Sassari (24-44) e centra la vittoria numero 13."},"content":{"rendered":"<p><strong>L\u2019analisi di Luisella Podda<\/strong><\/p>\n<hr \/>\n<p>PONTINIA &#8211; L\u2019Adattiva Pontinia supera 24-44, in trasferta, il Lions Sassari e sale a 26 punti toccando ancora una volta, provvisoriamente, la vetta della classifica del campionato di pallamano di serie A1 femminile nell\u2019attesa del match serale dell\u2019Erice impegnato a Padova. I 44 gol realizzati portano l\u2019Adattiva Pontinia alla cifra tonda di 500 centri stagionali in campionato, consolidando il primo posto nella classifica dei gol fatti mentre il numero di vittorie in regular season tocca quota 13 su 15 partite disputate.<\/p>\n<p>\u00abLa partita \u00e8 andata come ci aspettavamo, \u00e8 stata una trasferta impegnativa e non eravamo decisamente al meglio ma siamo comunque riuscite ad essere concrete nella fase offensiva &#8211; ha chiarito capitan Luisella Podda a fine match &#8211; Avremmo forse potuto fare qualcosina di pi\u00f9 in difesa ma era complicato oggi tenere la concentrazione per tutti i 60 minuti . Adesso ci aspetta un\u2019altra gara fuori casa piuttosto complicata contro un Teramo che pu\u00f2 sicuramente metterci in difficolt\u00e0. Servir\u00e0 ancora di pi\u00f9 tenere la lucidit\u00e0 ed essere pi\u00f9 aggressive nelle fasi difensive. Torniamo a casa con due punti e pensiamo gi\u00e0 ai prossimi impegni prima della Coppa Italia che , speriamo , possa vederci fare un torneo di livello\u00bb.<\/p>\n<p>A Sassari il Pontinia \u00e8 praticamente sempre in controllo, trascinato dalle accelerazioni di Luisella Podda, giocatrice sarda, che davanti al pubblico della sua regione timbra 10 volte. Il Pontinia chiude il primo primo parziale in vantaggio 10-20 per poi arrivare fino al 24-44 finale su cui pesano anche gli otto gol realizzati da Suleiky Gomez.<\/p>\n<p>L\u2019Adattiva Pontinia torner\u00e0 in campo l\u20198 febbraio, ancora in trasferta, in casa del Teramo per poi tornare a giocare al palazzetto dello sport Marica Bianchi di Pontinia il prossimo 15 febbraio nel match con il Salerno.<\/p>\n<hr \/>\n<p>LIONS SASSARI &#8211; ADATTIVA PONTINIA 24-44 (10-20 p.t.)<br \/>\nLIONS SASSARI: Obinu, Scanu, Olivieri, Currelli, Onesti 5, Doneddu, Zanotto, Mazzitelli 2, Bonnet 1, Biondi 4, Balata, Rivetti, Munoz Videla 1, Sallami 11, Pes, Furesi. All. Pastor<br \/>\nADATTIVA PONTINIA: Piantini, Sitzia, Peppe, Podda 10, Colloredo 2, Manojlovic 9, Apuzzo, D\u2019Ambrosio 3, Stefanelli 5, Giardino 1, Radovic, Gomez 8. All. Manojlovic<br \/>\nArbitri: Fato e Guarini (del. Cozzulla)<\/p>\n<hr \/>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4297 aligncenter\" src=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/02\/podda.jpeg\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/02\/podda.jpeg 800w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/02\/podda-300x200.jpeg 300w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/02\/podda-768x512.jpeg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p style=\"text-align: center\"><strong>Sopra Luisella Podda in azione durante un allenamento<\/strong><\/p>\n<p style=\"text-align: center\"><strong>(ph Mirko Lauretti )<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019analisi di Luisella Podda PONTINIA &#8211; L\u2019Adattiva Pontinia supera 24-44, in trasferta, il Lions Sassari e sale a 26 punti toccando ancora una volta, provvisoriamente, la vetta della classifica del [&hellip;]<\/p>\n","protected":false},"author":285,"featured_media":4269,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-4296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019Adattiva Pontinia espugna il campo del Lions Sassari (24-44) e centra la vittoria numero 13. - Pontinia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pontinia\/2025\/02\/03\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019Adattiva Pontinia espugna il campo del Lions Sassari (24-44) e centra la vittoria numero 13. - Pontinia\" \/>\n<meta property=\"og:description\" content=\"L\u2019analisi di Luisella Podda PONTINIA &#8211; L\u2019Adattiva Pontinia supera 24-44, in trasferta, il Lions Sassari e sale a 26 punti toccando ancora una volta, provvisoriamente, la vetta della classifica del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pontinia\/2025\/02\/03\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\/\" \/>\n<meta property=\"og:site_name\" content=\"Pontinia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-03T13:36:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/01\/474912858_1147410014058120_6165597152670620905_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"810\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ecatone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ecatone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2025\\\/02\\\/03\\\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2025\\\/02\\\/03\\\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\\\/\"},\"author\":{\"name\":\"ecatone\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/8bb345c6fdb12c64e72ba21b4ca1bfe0\"},\"headline\":\"L\u2019Adattiva Pontinia espugna il campo del Lions Sassari (24-44) e centra la vittoria numero 13.\",\"datePublished\":\"2025-02-03T13:36:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2025\\\/02\\\/03\\\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\\\/\"},\"wordCount\":367,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2025\\\/02\\\/03\\\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2025\\\/01\\\/474912858_1147410014058120_6165597152670620905_n.jpg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2025\\\/02\\\/03\\\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2025\\\/02\\\/03\\\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\\\/\",\"name\":\"L\u2019Adattiva Pontinia espugna il campo del Lions Sassari (24-44) e centra la vittoria numero 13. - Pontinia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2025\\\/02\\\/03\\\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2025\\\/02\\\/03\\\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2025\\\/01\\\/474912858_1147410014058120_6165597152670620905_n.jpg\",\"datePublished\":\"2025-02-03T13:36:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/8bb345c6fdb12c64e72ba21b4ca1bfe0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2025\\\/02\\\/03\\\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2025\\\/02\\\/03\\\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2025\\\/02\\\/03\\\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2025\\\/01\\\/474912858_1147410014058120_6165597152670620905_n.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2025\\\/01\\\/474912858_1147410014058120_6165597152670620905_n.jpg\",\"width\":810,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2025\\\/02\\\/03\\\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019Adattiva Pontinia espugna il campo del Lions Sassari (24-44) e centra la vittoria numero 13.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\",\"name\":\"Pontinia\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/8bb345c6fdb12c64e72ba21b4ca1bfe0\",\"name\":\"ecatone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/404710f7e355752c728e407cc73aee397ad168746406a0c885d6d1d63b5632da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/404710f7e355752c728e407cc73aee397ad168746406a0c885d6d1d63b5632da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/404710f7e355752c728e407cc73aee397ad168746406a0c885d6d1d63b5632da?s=96&d=mm&r=g\",\"caption\":\"ecatone\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/author\\\/ecatone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019Adattiva Pontinia espugna il campo del Lions Sassari (24-44) e centra la vittoria numero 13. - Pontinia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pontinia\/2025\/02\/03\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\/","og_locale":"it_IT","og_type":"article","og_title":"L\u2019Adattiva Pontinia espugna il campo del Lions Sassari (24-44) e centra la vittoria numero 13. - Pontinia","og_description":"L\u2019analisi di Luisella Podda PONTINIA &#8211; L\u2019Adattiva Pontinia supera 24-44, in trasferta, il Lions Sassari e sale a 26 punti toccando ancora una volta, provvisoriamente, la vetta della classifica del [&hellip;]","og_url":"https:\/\/comunicacity.net\/pontinia\/2025\/02\/03\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\/","og_site_name":"Pontinia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-02-03T13:36:33+00:00","og_image":[{"width":810,"height":540,"url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/01\/474912858_1147410014058120_6165597152670620905_n.jpg","type":"image\/jpeg"}],"author":"ecatone","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"ecatone","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pontinia\/2025\/02\/03\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/2025\/02\/03\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\/"},"author":{"name":"ecatone","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/8bb345c6fdb12c64e72ba21b4ca1bfe0"},"headline":"L\u2019Adattiva Pontinia espugna il campo del Lions Sassari (24-44) e centra la vittoria numero 13.","datePublished":"2025-02-03T13:36:33+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2025\/02\/03\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\/"},"wordCount":367,"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2025\/02\/03\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/01\/474912858_1147410014058120_6165597152670620905_n.jpg","articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pontinia\/2025\/02\/03\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\/","url":"https:\/\/comunicacity.net\/pontinia\/2025\/02\/03\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\/","name":"L\u2019Adattiva Pontinia espugna il campo del Lions Sassari (24-44) e centra la vittoria numero 13. - Pontinia","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2025\/02\/03\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2025\/02\/03\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/01\/474912858_1147410014058120_6165597152670620905_n.jpg","datePublished":"2025-02-03T13:36:33+00:00","author":{"@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/8bb345c6fdb12c64e72ba21b4ca1bfe0"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/pontinia\/2025\/02\/03\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pontinia\/2025\/02\/03\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pontinia\/2025\/02\/03\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\/#primaryimage","url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/01\/474912858_1147410014058120_6165597152670620905_n.jpg","contentUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/01\/474912858_1147410014058120_6165597152670620905_n.jpg","width":810,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pontinia\/2025\/02\/03\/ladattiva-pontinia-espugna-il-campo-del-lions-sassari-24-44-e-centra-la-vittoria-numero-13\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pontinia\/"},{"@type":"ListItem","position":2,"name":"L\u2019Adattiva Pontinia espugna il campo del Lions Sassari (24-44) e centra la vittoria numero 13."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pontinia\/#website","url":"https:\/\/comunicacity.net\/pontinia\/","name":"Pontinia","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pontinia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/8bb345c6fdb12c64e72ba21b4ca1bfe0","name":"ecatone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/404710f7e355752c728e407cc73aee397ad168746406a0c885d6d1d63b5632da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/404710f7e355752c728e407cc73aee397ad168746406a0c885d6d1d63b5632da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/404710f7e355752c728e407cc73aee397ad168746406a0c885d6d1d63b5632da?s=96&d=mm&r=g","caption":"ecatone"},"url":"https:\/\/comunicacity.net\/pontinia\/author\/ecatone\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/4296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/users\/285"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/comments?post=4296"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/4296\/revisions"}],"predecessor-version":[{"id":4298,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/4296\/revisions\/4298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media\/4269"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media?parent=4296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/categories?post=4296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/tags?post=4296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}