{"id":4397,"date":"2025-05-10T16:48:46","date_gmt":"2025-05-10T14:48:46","guid":{"rendered":"https:\/\/comunicacity.net\/pontinia\/?p=4397"},"modified":"2025-05-10T16:50:35","modified_gmt":"2025-05-10T14:50:35","slug":"serie-a1-semifinali-a-gara-2-primo-match-point-pontinia","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pontinia\/2025\/05\/10\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\/","title":{"rendered":"Serie A1 &#8211; Semifinali a Gara 2: primo match point Pontinia"},"content":{"rendered":"<div class=\"xdj266r x11i5rnm xat24cr x1mh8g0r x1vvkbs x126k92a\">\n<div dir=\"auto\" style=\"text-align: center\"><strong>JOMI Salerno vs\u00a0 Pontinia<\/strong><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: center\">\n<div dir=\"auto\"><strong>Oggi\u00a0 Sabato 10 Maggio <\/strong><strong>Ore 19:00<\/strong><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: center\">\n<div dir=\"auto\"><strong>\ud835\udc0b\ud835\udc22\ud835\udc27\ud835\udc24 \ud835\udc2c\ud835\udc2d\ud835\udc2b\ud835\udc1e\ud835\udc1a\ud835\udc26\ud835\udc22\ud835\udc27\ud835\udc20:<\/strong><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: center\">\n<div dir=\"auto\"><strong><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><a class=\"x1i10hfl xjbqb8w x1ejq31n xd10rxx x1sy0etr x17r0tee x972fbf xcfux6l x1qhh985 xm0m39n x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz xkrqix3 x1sur9pj x1fey0fg x1s688f\" role=\"link\" href=\"https:\/\/www.youtube.com\/live\/MW4NfHpC2F4?si=ljBwljqUmqamhgzn&amp;fbclid=IwZXh0bgNhZW0CMTAAYnJpZBEwRHJHc0lJZldjTUJhOGFJSgEe-shybdJUzhmPQsmjarLgV8pDEAQIjE4jaC5Ai5Py8mRYenmOamHhNXqSzLA_aem_hNu3h7axBNs9BOmUuea7qw\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">https:\/\/www.youtube.com\/live\/MW4NfHpC2F4?si=ljBwljqUmqamhgzn<\/a><\/span><\/strong><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\" style=\"text-align: center\"><strong>Forza ragazze<\/strong><\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<p style=\"text-align: center\"><strong><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-4400 aligncenter\" src=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/05\/495342623_1228310629303606_3832371039420663893_n.jpg\" alt=\"\" width=\"519\" height=\"519\" srcset=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/05\/495342623_1228310629303606_3832371039420663893_n.jpg 800w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/05\/495342623_1228310629303606_3832371039420663893_n-300x300.jpg 300w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/05\/495342623_1228310629303606_3832371039420663893_n-150x150.jpg 150w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/05\/495342623_1228310629303606_3832371039420663893_n-768x768.jpg 768w\" sizes=\"auto, (max-width: 519px) 100vw, 519px\" \/><\/strong><\/p>\n<p style=\"text-align: center\"><strong>Adattiva Pontinia a un passo dalla finale scudetto: oggi alle 19:00 match point decisivo a Salerno.\u00a0<\/strong><\/p>\n<hr \/>\n<p>Le semifinali Scudetto del campionato di Serie A1 giungono al secondo episodio. E potrebbe gi\u00e0 essere l\u2019epilogo, in caso di risultati favorevoli (vittoria o pari) per chi, leggi AC Life Style Erice e Adattiva Pontinia, ha guadagnato nei primi 60\u2019, con una vittoria, il vantaggio. Si gioca tra le 18:00 e le 19:00, tra il Pala Tacca e il Pala Palumbo. Come sempre con copertura in diretta su PallamanoTV.<\/p>\n<p><strong>LA SERIE A IN DIRETTA<\/strong>.\u00a0Le gare di Serie A Gold, Serie A1 e Serie A Silver saranno tutte trasmesse sulla piattaforma\u00a0<a href=\"https:\/\/www.federhandball.it\/pallamanotv\" data-cmp-ab=\"2\">PallamanoTV<\/a>, in chiaro e gratuitamente. La piattaforma \u00e8 raggiungibile al link\u00a0<a href=\"https:\/\/www.federhandball.it\/pallamanotvfigh\" data-cmp-ab=\"2\">federhandball.it\/pallamanotvfigh<\/a>. <strong>In parallelo, tutti gli incontri saranno visibili sul canale\u00a0<a href=\"https:\/\/www.youtube.com\/pallamanotvfigh\" data-cmp-ab=\"2\">YouTube<\/a>\u00a0della Federhandball.\u00a0<\/strong><\/p>\n<hr \/>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4402 aligncenter\" src=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/05\/495715508_701376175734345_6456473198307581005_n.jpg\" alt=\"\" width=\"595\" height=\"400\" srcset=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/05\/495715508_701376175734345_6456473198307581005_n.jpg 960w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/05\/495715508_701376175734345_6456473198307581005_n-300x202.jpg 300w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/05\/495715508_701376175734345_6456473198307581005_n-768x517.jpg 768w\" sizes=\"auto, (max-width: 595px) 100vw, 595px\" \/><\/strong><\/p>\n<p style=\"text-align: center\"><strong>Semifinale (Gara 2)<\/strong><br \/>\n<strong>JOMI SALERNO \u2013 ADATTIVA PONTINIA (0-1)<\/strong><br \/>\n<strong>sabato 10 maggio, h 19:00<\/strong><\/p>\n<ul>\n<li>Pontinia ha vinto 20-18 in Gara 1 al Pala Marica Bianchi, trovando nel finale, con Manojlovic e Gomez, le reti necessarie per il mini break risolutivo (2-0)<\/li>\n<li>Salerno ha l\u2019obbligo di vincere per allungare la serie a Gara 3, eventualit\u00e0 che riporterebbe in giochi a Pontinia, con le laziali forti del migliore piazzamento in regular season<\/li>\n<li>Salerno ha disputato sei finali Scudetto sulle ultime sette stagioni di Serie A1 (ad eccezione della stagione 2019\/20 non conclusa), vincendone cinque; per Pontinia sarebbe invece la prima volta, raggiungibile gi\u00e0 domani con un successo o con un pari<\/li>\n<li>In una Gara 1 avara di gol, il pivot Eleonora Colloredo \u00e8 stata la migliore marcatrice con sette reti<\/li>\n<li>Gara 2 sar\u00e0 arbitrata dalla coppia Dionisi-Maccarone<\/li>\n<li>\n<hr \/>\n<\/li>\n<\/ul>\n<p>Karin Bujnochova, centrale della Jomi Salerno:\u00a0<em>\u00abSabato scorso la partita \u00e8 stata difficile cos\u00ec come ci aspettavamo ma credo che l\u2019abbiamo resa ancora pi\u00f9 difficile a causa dei nostri stessi errori. In gara 2 avremo l\u2019opportunit\u00e0 di cambiare questo aspetto. Con una settimana a disposizione per prepararci, vogliamo allenare il nostro stile di gioco. Stiamo lavorando sodo in questi giorni e spero davvero che questo impegno venga ripagato nel fine settimana\u00bb.<\/em><\/p>\n<hr \/>\n<p>Nikola Manojlovic, tecnico dell&#8217;Adattiva Pontinia:\u00a0<em>\u00abOgni partita \u00e8 una storia a se, noi abbiamo fatto un passo verso la finale e ai nostri avversari ora toccher\u00e0 la pressione di dover fare due passi per provare a ribaltare la situazione, loro giustamente avranno la pressione addosso e noi abbiamo la consapevolezza di poterle battere nuovamente Sono molto ottimista per il fatto che faremo una buona prestazione: ogni partita con Salerno \u00e8 stata molto tirata perch\u00e9 affrontiamo un roster creato per vincere e sono un\u2019ottima squadra. Ci metteranno in difficolt\u00e0 ma noi ci siamo preparati per questa partita lavorando sugli errori che abbiamo commesso nella sfida di andata. Il nostro obiettivo \u00e8 quello di provare a limare i difetti che sono emersi e abbiamo preparato qualcosa proprio come avranno fatto anche le nostre avversarie per provare a sorprenderci\u00bb.<\/em><\/p>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\"><\/div>\n<div dir=\"auto\">\n<div class=\"xdj266r x11i5rnm xat24cr x1mh8g0r x1vvkbs x126k92a\">\n<div dir=\"auto\" style=\"text-align: center\"><strong>JOMI Salerno vs\u00a0 Pontinia<\/strong><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: center\">\n<div dir=\"auto\"><strong>Oggi\u00a0 Sabato 10 Maggio <\/strong><strong>Ore 19:00<\/strong><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: center\">\n<div dir=\"auto\"><strong>\ud835\udc0b\ud835\udc22\ud835\udc27\ud835\udc24 \ud835\udc2c\ud835\udc2d\ud835\udc2b\ud835\udc1e\ud835\udc1a\ud835\udc26\ud835\udc22\ud835\udc27\ud835\udc20:<\/strong><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\" style=\"text-align: center\">\n<div dir=\"auto\"><strong><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><a class=\"x1i10hfl xjbqb8w x1ejq31n xd10rxx x1sy0etr x17r0tee x972fbf xcfux6l x1qhh985 xm0m39n x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz xkrqix3 x1sur9pj x1fey0fg x1s688f\" role=\"link\" href=\"https:\/\/www.youtube.com\/live\/MW4NfHpC2F4?si=ljBwljqUmqamhgzn&amp;fbclid=IwZXh0bgNhZW0CMTAAYnJpZBEwRHJHc0lJZldjTUJhOGFJSgEe-shybdJUzhmPQsmjarLgV8pDEAQIjE4jaC5Ai5Py8mRYenmOamHhNXqSzLA_aem_hNu3h7axBNs9BOmUuea7qw\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">https:\/\/www.youtube.com\/live\/MW4NfHpC2F4?si=ljBwljqUmqamhgzn<\/a><\/span><\/strong><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\" style=\"text-align: center\"><strong>Forza ragazze<\/strong><\/div>\n<div dir=\"auto\">\n<hr \/>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-4399 aligncenter\" src=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/05\/495259477_1228310392636963_5442719115304698841_n-1.jpg\" alt=\"\" width=\"586\" height=\"586\" srcset=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/05\/495259477_1228310392636963_5442719115304698841_n-1.jpg 800w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/05\/495259477_1228310392636963_5442719115304698841_n-1-300x300.jpg 300w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/05\/495259477_1228310392636963_5442719115304698841_n-1-150x150.jpg 150w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/05\/495259477_1228310392636963_5442719115304698841_n-1-768x768.jpg 768w\" sizes=\"auto, (max-width: 586px) 100vw, 586px\" \/><\/p>\n<\/div>\n<div dir=\"auto\">\n<hr \/>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>JOMI Salerno vs\u00a0 Pontinia Oggi\u00a0 Sabato 10 Maggio Ore 19:00 \ud835\udc0b\ud835\udc22\ud835\udc27\ud835\udc24 \ud835\udc2c\ud835\udc2d\ud835\udc2b\ud835\udc1e\ud835\udc1a\ud835\udc26\ud835\udc22\ud835\udc27\ud835\udc20: https:\/\/www.youtube.com\/live\/MW4NfHpC2F4?si=ljBwljqUmqamhgzn Forza ragazze Adattiva Pontinia a un passo dalla finale scudetto: oggi alle 19:00 match point decisivo a [&hellip;]<\/p>\n","protected":false},"author":285,"featured_media":4401,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-4397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Serie A1 - Semifinali a Gara 2: primo match point Pontinia - Pontinia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pontinia\/2025\/05\/10\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Serie A1 - Semifinali a Gara 2: primo match point Pontinia - Pontinia\" \/>\n<meta property=\"og:description\" content=\"JOMI Salerno vs\u00a0 Pontinia Oggi\u00a0 Sabato 10 Maggio Ore 19:00 \ud835\udc0b\ud835\udc22\ud835\udc27\ud835\udc24 \ud835\udc2c\ud835\udc2d\ud835\udc2b\ud835\udc1e\ud835\udc1a\ud835\udc26\ud835\udc22\ud835\udc27\ud835\udc20: https:\/\/www.youtube.com\/live\/MW4NfHpC2F4?si=ljBwljqUmqamhgzn Forza ragazze Adattiva Pontinia a un passo dalla finale scudetto: oggi alle 19:00 match point decisivo a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pontinia\/2025\/05\/10\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\/\" \/>\n<meta property=\"og:site_name\" content=\"Pontinia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-10T14:48:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-10T14:50:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/05\/495338392_1240023154783640_4556740113536994993_n-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1638\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ecatone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ecatone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2025\\\/05\\\/10\\\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2025\\\/05\\\/10\\\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\\\/\"},\"author\":{\"name\":\"ecatone\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/8bb345c6fdb12c64e72ba21b4ca1bfe0\"},\"headline\":\"Serie A1 &#8211; Semifinali a Gara 2: primo match point Pontinia\",\"datePublished\":\"2025-05-10T14:48:46+00:00\",\"dateModified\":\"2025-05-10T14:50:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2025\\\/05\\\/10\\\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\\\/\"},\"wordCount\":510,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2025\\\/05\\\/10\\\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2025\\\/05\\\/495338392_1240023154783640_4556740113536994993_n-1.jpg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2025\\\/05\\\/10\\\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2025\\\/05\\\/10\\\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\\\/\",\"name\":\"Serie A1 - Semifinali a Gara 2: primo match point Pontinia - Pontinia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2025\\\/05\\\/10\\\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2025\\\/05\\\/10\\\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2025\\\/05\\\/495338392_1240023154783640_4556740113536994993_n-1.jpg\",\"datePublished\":\"2025-05-10T14:48:46+00:00\",\"dateModified\":\"2025-05-10T14:50:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/8bb345c6fdb12c64e72ba21b4ca1bfe0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2025\\\/05\\\/10\\\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2025\\\/05\\\/10\\\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2025\\\/05\\\/10\\\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2025\\\/05\\\/495338392_1240023154783640_4556740113536994993_n-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2025\\\/05\\\/495338392_1240023154783640_4556740113536994993_n-1.jpg\",\"width\":1638,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2025\\\/05\\\/10\\\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Serie A1 &#8211; Semifinali a Gara 2: primo match point Pontinia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\",\"name\":\"Pontinia\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/8bb345c6fdb12c64e72ba21b4ca1bfe0\",\"name\":\"ecatone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/404710f7e355752c728e407cc73aee397ad168746406a0c885d6d1d63b5632da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/404710f7e355752c728e407cc73aee397ad168746406a0c885d6d1d63b5632da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/404710f7e355752c728e407cc73aee397ad168746406a0c885d6d1d63b5632da?s=96&d=mm&r=g\",\"caption\":\"ecatone\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/author\\\/ecatone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Serie A1 - Semifinali a Gara 2: primo match point Pontinia - Pontinia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pontinia\/2025\/05\/10\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\/","og_locale":"it_IT","og_type":"article","og_title":"Serie A1 - Semifinali a Gara 2: primo match point Pontinia - Pontinia","og_description":"JOMI Salerno vs\u00a0 Pontinia Oggi\u00a0 Sabato 10 Maggio Ore 19:00 \ud835\udc0b\ud835\udc22\ud835\udc27\ud835\udc24 \ud835\udc2c\ud835\udc2d\ud835\udc2b\ud835\udc1e\ud835\udc1a\ud835\udc26\ud835\udc22\ud835\udc27\ud835\udc20: https:\/\/www.youtube.com\/live\/MW4NfHpC2F4?si=ljBwljqUmqamhgzn Forza ragazze Adattiva Pontinia a un passo dalla finale scudetto: oggi alle 19:00 match point decisivo a [&hellip;]","og_url":"https:\/\/comunicacity.net\/pontinia\/2025\/05\/10\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\/","og_site_name":"Pontinia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-05-10T14:48:46+00:00","article_modified_time":"2025-05-10T14:50:35+00:00","og_image":[{"width":1638,"height":2048,"url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/05\/495338392_1240023154783640_4556740113536994993_n-1.jpg","type":"image\/jpeg"}],"author":"ecatone","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"ecatone","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pontinia\/2025\/05\/10\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/2025\/05\/10\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\/"},"author":{"name":"ecatone","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/8bb345c6fdb12c64e72ba21b4ca1bfe0"},"headline":"Serie A1 &#8211; Semifinali a Gara 2: primo match point Pontinia","datePublished":"2025-05-10T14:48:46+00:00","dateModified":"2025-05-10T14:50:35+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2025\/05\/10\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\/"},"wordCount":510,"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2025\/05\/10\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/05\/495338392_1240023154783640_4556740113536994993_n-1.jpg","articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pontinia\/2025\/05\/10\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\/","url":"https:\/\/comunicacity.net\/pontinia\/2025\/05\/10\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\/","name":"Serie A1 - Semifinali a Gara 2: primo match point Pontinia - Pontinia","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2025\/05\/10\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2025\/05\/10\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/05\/495338392_1240023154783640_4556740113536994993_n-1.jpg","datePublished":"2025-05-10T14:48:46+00:00","dateModified":"2025-05-10T14:50:35+00:00","author":{"@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/8bb345c6fdb12c64e72ba21b4ca1bfe0"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/pontinia\/2025\/05\/10\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pontinia\/2025\/05\/10\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pontinia\/2025\/05\/10\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\/#primaryimage","url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/05\/495338392_1240023154783640_4556740113536994993_n-1.jpg","contentUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2025\/05\/495338392_1240023154783640_4556740113536994993_n-1.jpg","width":1638,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pontinia\/2025\/05\/10\/serie-a1-semifinali-a-gara-2-primo-match-point-pontinia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pontinia\/"},{"@type":"ListItem","position":2,"name":"Serie A1 &#8211; Semifinali a Gara 2: primo match point Pontinia"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pontinia\/#website","url":"https:\/\/comunicacity.net\/pontinia\/","name":"Pontinia","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pontinia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/8bb345c6fdb12c64e72ba21b4ca1bfe0","name":"ecatone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/404710f7e355752c728e407cc73aee397ad168746406a0c885d6d1d63b5632da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/404710f7e355752c728e407cc73aee397ad168746406a0c885d6d1d63b5632da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/404710f7e355752c728e407cc73aee397ad168746406a0c885d6d1d63b5632da?s=96&d=mm&r=g","caption":"ecatone"},"url":"https:\/\/comunicacity.net\/pontinia\/author\/ecatone\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/4397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/users\/285"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/comments?post=4397"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/4397\/revisions"}],"predecessor-version":[{"id":4405,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/4397\/revisions\/4405"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media\/4401"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media?parent=4397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/categories?post=4397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/tags?post=4397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}