{"id":609,"date":"2019-05-19T19:58:59","date_gmt":"2019-05-19T17:58:59","guid":{"rendered":"https:\/\/comunicacity.net\/pontinia\/?p=609"},"modified":"2019-05-19T19:58:59","modified_gmt":"2019-05-19T17:58:59","slug":"atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\/","title":{"rendered":"Atl. Pontinia il Direttore Generale Mondino Roscioli&#8221; Adesso il pensiero \u00e8 tutto per la Coppa Lazio&#8221;"},"content":{"rendered":"<p style=\"text-align: left\">\nMondino Roscioli<br \/>\nIn questo momento sono le ore 17.16 l&#8217;amarezza comincia a diminuire, si torna a vedere qualche sorriso, il primo \u00e8 quello del direttore generale Raimondo ( Mondino ) Roscioli. &#8221; Bisogna andare avanti &#8211; dice Mondino Roscioli &#8211; Ognuno si prende le sue responsabilit\u00e0 nei comportamenti. Adesso stiamo pensando alla coppa Lazio, Pontinia sta rispondendo. Abbiamo gi\u00e0 riempito due pulmann e forse un altro ( come ci dicono le segretarie Cristiana e Katia responsabili della logistica). Sar\u00e0 difficile e allo stesso tempo bella. Stiamo cercando di curare tutto nei minimi particolari. Le finali sono sempre una lotteria e soprattutto bisogna vincerla. Ho visto la Sorianese giocare davanti hanno un grande reparto offensivo. In finale non ci arrivi per caso. Durante la settimana non ci sar\u00e0 nessuna pressione da parte nostra. La cosa che mi rende felice e che a Pontinia si sta parlando di questa finale, mi riallaccio a mio fratello nel fare i complimenti a mister Cencia per il playoff del pomeriggio. Vogliamo entrare nella storia, queste sono capitano tutti i giorni. Da ex calciatore dico che a Pontinia non c&#8217;\u00e8 mai stata una finale di coppa, al massimo siamo arrivati ai quarti di finale. Sabato andiamo in ritiro a Rocca di Papa, e questo solo grazie ai nostri amici che ci sostengono in tutti i modi. Sia a livello economico, e morale. Abbiamo questa opportunit\u00e0 e non la vogliamo fallire. Clementi Palmieri? E&#8217; stato un grande giocatore e dalla mia esperienza devo dire che \u00e8 anche un bravo allenatore. Ha mantenuto la promessa, gli avevamo chiesto la Prima categoria, cos\u00ec \u00e8 stato&#8221;. <img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-610 aligncenter\" src=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/05\/E0D2ABA9-1403-4B21-B833-62EF9DBD76AC.jpeg\" alt=\"\" width=\"260\" height=\"260\" srcset=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/05\/E0D2ABA9-1403-4B21-B833-62EF9DBD76AC.jpeg 260w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/05\/E0D2ABA9-1403-4B21-B833-62EF9DBD76AC-150x150.jpeg 150w\" sizes=\"auto, (max-width: 260px) 100vw, 260px\" \/><\/p>\n<p style=\"text-align: left\">tuttocalciopontino.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mondino Roscioli In questo momento sono le ore 17.16 l&#8217;amarezza comincia a diminuire, si torna a vedere qualche sorriso, il primo \u00e8 quello del direttore generale Raimondo ( Mondino ) [&hellip;]<\/p>\n","protected":false},"author":294,"featured_media":611,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,24],"tags":[],"class_list":["post-609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atl. Pontinia il Direttore Generale Mondino Roscioli&quot; Adesso il pensiero \u00e8 tutto per la Coppa Lazio&quot; - Pontinia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atl. Pontinia il Direttore Generale Mondino Roscioli&quot; Adesso il pensiero \u00e8 tutto per la Coppa Lazio&quot; - Pontinia\" \/>\n<meta property=\"og:description\" content=\"Mondino Roscioli In questo momento sono le ore 17.16 l&#8217;amarezza comincia a diminuire, si torna a vedere qualche sorriso, il primo \u00e8 quello del direttore generale Raimondo ( Mondino ) [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\/\" \/>\n<meta property=\"og:site_name\" content=\"Pontinia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-19T17:58:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/05\/05B349B4-FB9E-4C0E-820E-9BF65536F325.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"260\" \/>\n\t<meta property=\"og:image:height\" content=\"260\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sportpontinia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sportpontinia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/05\\\/19\\\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/05\\\/19\\\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\\\/\"},\"author\":{\"name\":\"sportpontinia\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"headline\":\"Atl. Pontinia il Direttore Generale Mondino Roscioli&#8221; Adesso il pensiero \u00e8 tutto per la Coppa Lazio&#8221;\",\"datePublished\":\"2019-05-19T17:58:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/05\\\/19\\\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\\\/\"},\"wordCount\":275,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/05\\\/19\\\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/05\\\/05B349B4-FB9E-4C0E-820E-9BF65536F325.jpeg\",\"articleSection\":[\"Notizie e Informazioni\",\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/05\\\/19\\\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/05\\\/19\\\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\\\/\",\"name\":\"Atl. Pontinia il Direttore Generale Mondino Roscioli\\\" Adesso il pensiero \u00e8 tutto per la Coppa Lazio\\\" - Pontinia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/05\\\/19\\\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/05\\\/19\\\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/05\\\/05B349B4-FB9E-4C0E-820E-9BF65536F325.jpeg\",\"datePublished\":\"2019-05-19T17:58:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/05\\\/19\\\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/05\\\/19\\\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/05\\\/19\\\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/05\\\/05B349B4-FB9E-4C0E-820E-9BF65536F325.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/05\\\/05B349B4-FB9E-4C0E-820E-9BF65536F325.jpeg\",\"width\":260,\"height\":260},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/05\\\/19\\\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atl. Pontinia il Direttore Generale Mondino Roscioli&#8221; Adesso il pensiero \u00e8 tutto per la Coppa Lazio&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\",\"name\":\"Pontinia\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\",\"name\":\"sportpontinia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"caption\":\"sportpontinia\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/author\\\/sportpontinia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atl. Pontinia il Direttore Generale Mondino Roscioli\" Adesso il pensiero \u00e8 tutto per la Coppa Lazio\" - Pontinia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\/","og_locale":"it_IT","og_type":"article","og_title":"Atl. Pontinia il Direttore Generale Mondino Roscioli\" Adesso il pensiero \u00e8 tutto per la Coppa Lazio\" - Pontinia","og_description":"Mondino Roscioli In questo momento sono le ore 17.16 l&#8217;amarezza comincia a diminuire, si torna a vedere qualche sorriso, il primo \u00e8 quello del direttore generale Raimondo ( Mondino ) [&hellip;]","og_url":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\/","og_site_name":"Pontinia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-05-19T17:58:59+00:00","og_image":[{"width":260,"height":260,"url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/05\/05B349B4-FB9E-4C0E-820E-9BF65536F325.jpeg","type":"image\/jpeg"}],"author":"sportpontinia","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sportpontinia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\/"},"author":{"name":"sportpontinia","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"headline":"Atl. Pontinia il Direttore Generale Mondino Roscioli&#8221; Adesso il pensiero \u00e8 tutto per la Coppa Lazio&#8221;","datePublished":"2019-05-19T17:58:59+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\/"},"wordCount":275,"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/05\/05B349B4-FB9E-4C0E-820E-9BF65536F325.jpeg","articleSection":["Notizie e Informazioni","Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\/","url":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\/","name":"Atl. Pontinia il Direttore Generale Mondino Roscioli\" Adesso il pensiero \u00e8 tutto per la Coppa Lazio\" - Pontinia","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/05\/05B349B4-FB9E-4C0E-820E-9BF65536F325.jpeg","datePublished":"2019-05-19T17:58:59+00:00","author":{"@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\/#primaryimage","url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/05\/05B349B4-FB9E-4C0E-820E-9BF65536F325.jpeg","contentUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/05\/05B349B4-FB9E-4C0E-820E-9BF65536F325.jpeg","width":260,"height":260},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/atl-pontinia-il-direttore-generale-mondino-roscioli-adesso-il-pensiero-e-tutto-per-la-coppa-lazio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pontinia\/"},{"@type":"ListItem","position":2,"name":"Atl. Pontinia il Direttore Generale Mondino Roscioli&#8221; Adesso il pensiero \u00e8 tutto per la Coppa Lazio&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pontinia\/#website","url":"https:\/\/comunicacity.net\/pontinia\/","name":"Pontinia","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pontinia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807","name":"sportpontinia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","caption":"sportpontinia"},"url":"https:\/\/comunicacity.net\/pontinia\/author\/sportpontinia\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/users\/294"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/comments?post=609"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/609\/revisions"}],"predecessor-version":[{"id":612,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/609\/revisions\/612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media\/611"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media?parent=609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/categories?post=609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/tags?post=609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}