{"id":614,"date":"2019-05-19T20:09:21","date_gmt":"2019-05-19T18:09:21","guid":{"rendered":"https:\/\/comunicacity.net\/pontinia\/?p=614"},"modified":"2019-05-19T20:09:21","modified_gmt":"2019-05-19T18:09:21","slug":"basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\/","title":{"rendered":"BASKET serie C &#8211; playoff- semifinale &#8211; gara 3- Vigna Pia vs Officine Ceccacci Virtus Pontinia"},"content":{"rendered":"<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-616 aligncenter\" src=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/05\/D973357B-ED2E-4771-ABD6-AB3767DBA2C2-179x300.jpeg\" alt=\"\" width=\"179\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/05\/D973357B-ED2E-4771-ABD6-AB3767DBA2C2-179x300.jpeg 179w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/05\/D973357B-ED2E-4771-ABD6-AB3767DBA2C2.jpeg 572w\" sizes=\"auto, (max-width: 179px) 100vw, 179px\" \/>Vigna Pia 52 &#8211; Virtus Pontinia 54<br \/>\nParziali: 20-15; 34-31; 40-40 Arbitri: Panatta e Iurato<\/p>\n<p>Vigna Pia: Guadagnini 14, Forni n.e., Olivi n.e., Troiani 7, Chiminello 11, Ralli 3, Conforti 8, Sernicola 7, Arrighini, Zen El Din n.e., De Marchi, Cavarocchi 2. All. Fabbri Ass. Pietrelli<\/p>\n<p>Virtus Pontinia: Nardin 21, D\u2019Orazio 5, D\u2019Anolfo 17, Saggese 2, Cassandra 2, Laera n.e., Tricarico, Caldarozzi 6, Fabbri, Berardi 1, Picarazzi n.e. All. Morassi<\/p>\n<p>PONTINIA PARTENZA SPRINT, POI REAZIONE VIGNA PIA- Il sabato della verit\u00e0 per Vigna Pia e Virtus Pontinia che affrontano i 40\u2019 pi\u00f9 importanti della stagione, quelli che regaleranno ad una sola delle due contendenti il sogno di giocarsi la finale per la promozione in C Gold; tifo caldissimo in un Pala Cerioli dove non entra neanche uno spillo, si parte con la mossa a sorpresa di coach Morassi che tiene D\u2019Orazio fuori dal quintetto base (anche se l&#8217;ex Velletri non \u00e8 al meglio fisicamente), la partenza \u00e8 per\u00f2 tutta di marca ospite con un 0-9 firmato D\u2019Anolfo-Nardin che costringono coach Fabbri al primo time out di serata. Avvio contratto del Vigna Pia che si scuote con l\u2019ingresso di Guadagnini, due triple dell\u2019ex Stella Azzurra mettono in partita i padroni di casa che impattano poi con il canestro dalla distanza di Troiani sul 13-13; inerzia che cambia e Vigna Pia che si scioglie col passare dei minuti, entra in partita anche Chiminello ed arriva il sorpasso dei capitolini che chiudono avanti al primo riposo sul 20-15.<\/p>\n<p>PARTITA FISICA E TESA- Cambia il match nel 2\u00b0 quarto perch\u00e9 sale il livello di fisicit\u00e0 con un\u2019infinit\u00e0 di contatti che spezzettano il gioco di continuo, gara nervosa (ne fa le spese Cassandra fuori per una botta al labbro) con pochi canestri ma sempre molto combattuta con D\u2019Anolfo e Nardin a tenere le due formazioni vicine (25-22); squadre tesissime con la pressione per la posta in palio che si fa sentire, la quantit\u00e0 industriale di errori dalla lunetta da entrambe le parti (il Vigna Pia addirittura 10 errori nel solo 2\u00b0 quarto) testimoniano la difficolt\u00e0 soprattutto dal punto di vista psicologico di questo match, prima della sirena ritrova la retina Sernicola con una tripla importante che consente ai suoi di chiudere avanti 34-31 una prima met\u00e0 combattutissima.<\/p>\n<p>POCHI CANESTRI, INTENSITA\u2019 A MILLE- Si riparte sulla stessa falsariga, primi 4\u2019 senza canestri con gli attacchi letteralmente in panne con la tensione che si taglia a fette, a sbloccare la situazione ci pensa Nardin con 6 punti in fila che valgono il contro-sorpasso sul 34-37; il Vigna Pia fatica contro la zona ospite e segna i primi punti della ripresa dopo 6\u2019 con Conforti che resta sempre difficilissimo da marcare per una Virtus Pontinia senza lunghi stante l\u2019assenza di Picarazzi, si arriva comunque in perfetta parit\u00e0 sul 40-40 all\u2019ultimo riposo in un 3\u00b0 quarto interlocutorio in attesa della volata finale.<\/p>\n<p>PONTINIA DA URLO, E\u2019 FINALE!- Si segna col contagocce ed ogni canestro diventa pesantissimo, come quelli di Caldarozzi da 3 e subito dopo di D\u2019Anolfo che danno due possessi di vantaggio agli ospiti (41-45) che perdono per\u00f2 Saggese per 5 falli, ultimo dei quali tecnico per proteste, una vera ingenuit\u00e0 in una fase della partita cos\u00ec calda; il Vigna Pia continua per\u00f2 a non segnare veramente mai e soprattutto a lasciare una quantit\u00e0 di punti per strada sbagliando dalla lunetta un\u2019infinit\u00e0 di tiri liberi, Nardin invece \u00e8 glaciale e regala ai suoi il +5 a 4\u2019 dalla sirena (42-47). La squadra di coach Fabbri ha per\u00f2 giocatori di esperienza e classe come Chiminello e Guadagnini che in un amen producono un break di 6-0 che vale il nuovo vantaggio interno sul 48-47, con coach Morassi che perde per falli anche Cassandra ma vede D\u2019Orazio (non al meglio) iscriversi a referto col primo canestro dal campo della sua partita (48-49). Sernicola in entrata realizza il nuovo contro-sorpasso (50-49), il Vigna Pia avrebbe poi anche i possessi per chiuderla ma la difesa della Virtus regge e nell\u2019ultimo minuto \u00e8 Caldarozzi a piazzare una tripla fondamentale in transizione per il 50-52 a 40\u2019\u2019 dalla fine; dall\u2019altra parte subisce fallo Troiani che in lunetta stavolta non fallisce, 52-52 e di nuovo parit\u00e0 ma l\u2019ultima azione \u00e8 per la Virtus Pontinia che va da Nardin. Il capitano subisce fallo a 5\u2019\u2019 dalla sirena e fa esultare i suoi tifosi con un 2\/2 decisivo, l\u2019ultima chance del Vigna Pia con Guadagnani non tocca nemmeno il ferro ed allora la Virtus Pontinia completa l\u2019impresa vincendo gara 3 e volando in finale.<\/p>\n<p>E\u2019 dunque festa grande per la Virtus Pontinia che ha trovato la forza di ribaltare una serie che era partita malissimo in gara1, stasera invece nonostante un D\u2019Orazio non al meglio con solo un canestro dal campo, la squadra di coach Morassi ha espugnato uno dei campi pi\u00f9 difficili di tutta la C Silver meritando cos\u00ec l\u2019accesso alla Finale.<br \/>\nGrande amarezza invece in casa Vigna Pia, che ha pagato probabilmente la tensione con troppi, davvero troppi errori soprattutto dalla lunetta che sono costati la sconfitta in un match cos\u00ec tirato.<\/p>\n<p>MVP: Nardin<\/p>\n<p>Quintetto ideale: Caldarozzi, D\u2019Anolfo, Guadagnini, Nardin, Chiminello<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vigna Pia 52 &#8211; Virtus Pontinia 54 Parziali: 20-15; 34-31; 40-40 Arbitri: Panatta e Iurato Vigna Pia: Guadagnini 14, Forni n.e., Olivi n.e., Troiani 7, Chiminello 11, Ralli 3, Conforti [&hellip;]<\/p>\n","protected":false},"author":294,"featured_media":615,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BASKET serie C - playoff- semifinale - gara 3- Vigna Pia vs Officine Ceccacci Virtus Pontinia - Pontinia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BASKET serie C - playoff- semifinale - gara 3- Vigna Pia vs Officine Ceccacci Virtus Pontinia - Pontinia\" \/>\n<meta property=\"og:description\" content=\"Vigna Pia 52 &#8211; Virtus Pontinia 54 Parziali: 20-15; 34-31; 40-40 Arbitri: Panatta e Iurato Vigna Pia: Guadagnini 14, Forni n.e., Olivi n.e., Troiani 7, Chiminello 11, Ralli 3, Conforti [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\/\" \/>\n<meta property=\"og:site_name\" content=\"Pontinia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-19T18:09:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/05\/F71E2E1E-C5E0-4098-B54C-DF4A1A2F4649.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"870\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sportpontinia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sportpontinia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/05\\\/19\\\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/05\\\/19\\\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\\\/\"},\"author\":{\"name\":\"sportpontinia\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"headline\":\"BASKET serie C &#8211; playoff- semifinale &#8211; gara 3- Vigna Pia vs Officine Ceccacci Virtus Pontinia\",\"datePublished\":\"2019-05-19T18:09:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/05\\\/19\\\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\\\/\"},\"wordCount\":852,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/05\\\/19\\\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/05\\\/F71E2E1E-C5E0-4098-B54C-DF4A1A2F4649.jpeg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/05\\\/19\\\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/05\\\/19\\\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\\\/\",\"name\":\"BASKET serie C - playoff- semifinale - gara 3- Vigna Pia vs Officine Ceccacci Virtus Pontinia - Pontinia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/05\\\/19\\\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/05\\\/19\\\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/05\\\/F71E2E1E-C5E0-4098-B54C-DF4A1A2F4649.jpeg\",\"datePublished\":\"2019-05-19T18:09:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/05\\\/19\\\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/05\\\/19\\\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/05\\\/19\\\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/05\\\/F71E2E1E-C5E0-4098-B54C-DF4A1A2F4649.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/05\\\/F71E2E1E-C5E0-4098-B54C-DF4A1A2F4649.jpeg\",\"width\":960,\"height\":870},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/05\\\/19\\\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BASKET serie C &#8211; playoff- semifinale &#8211; gara 3- Vigna Pia vs Officine Ceccacci Virtus Pontinia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\",\"name\":\"Pontinia\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\",\"name\":\"sportpontinia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"caption\":\"sportpontinia\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/author\\\/sportpontinia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BASKET serie C - playoff- semifinale - gara 3- Vigna Pia vs Officine Ceccacci Virtus Pontinia - Pontinia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\/","og_locale":"it_IT","og_type":"article","og_title":"BASKET serie C - playoff- semifinale - gara 3- Vigna Pia vs Officine Ceccacci Virtus Pontinia - Pontinia","og_description":"Vigna Pia 52 &#8211; Virtus Pontinia 54 Parziali: 20-15; 34-31; 40-40 Arbitri: Panatta e Iurato Vigna Pia: Guadagnini 14, Forni n.e., Olivi n.e., Troiani 7, Chiminello 11, Ralli 3, Conforti [&hellip;]","og_url":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\/","og_site_name":"Pontinia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-05-19T18:09:21+00:00","og_image":[{"width":960,"height":870,"url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/05\/F71E2E1E-C5E0-4098-B54C-DF4A1A2F4649.jpeg","type":"image\/jpeg"}],"author":"sportpontinia","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sportpontinia","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\/"},"author":{"name":"sportpontinia","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"headline":"BASKET serie C &#8211; playoff- semifinale &#8211; gara 3- Vigna Pia vs Officine Ceccacci Virtus Pontinia","datePublished":"2019-05-19T18:09:21+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\/"},"wordCount":852,"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/05\/F71E2E1E-C5E0-4098-B54C-DF4A1A2F4649.jpeg","articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\/","url":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\/","name":"BASKET serie C - playoff- semifinale - gara 3- Vigna Pia vs Officine Ceccacci Virtus Pontinia - Pontinia","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/05\/F71E2E1E-C5E0-4098-B54C-DF4A1A2F4649.jpeg","datePublished":"2019-05-19T18:09:21+00:00","author":{"@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\/#primaryimage","url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/05\/F71E2E1E-C5E0-4098-B54C-DF4A1A2F4649.jpeg","contentUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/05\/F71E2E1E-C5E0-4098-B54C-DF4A1A2F4649.jpeg","width":960,"height":870},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pontinia\/2019\/05\/19\/basket-serie-c-playoff-semifinale-gara-3-vigna-pia-vs-officine-ceccacci-virtus-pontinia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pontinia\/"},{"@type":"ListItem","position":2,"name":"BASKET serie C &#8211; playoff- semifinale &#8211; gara 3- Vigna Pia vs Officine Ceccacci Virtus Pontinia"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pontinia\/#website","url":"https:\/\/comunicacity.net\/pontinia\/","name":"Pontinia","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pontinia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807","name":"sportpontinia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","caption":"sportpontinia"},"url":"https:\/\/comunicacity.net\/pontinia\/author\/sportpontinia\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/users\/294"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/comments?post=614"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/614\/revisions"}],"predecessor-version":[{"id":617,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/614\/revisions\/617"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media\/615"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media?parent=614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/categories?post=614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/tags?post=614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}