{"id":861,"date":"2019-07-05T23:05:47","date_gmt":"2019-07-05T21:05:47","guid":{"rendered":"https:\/\/comunicacity.net\/pontinia\/?p=861"},"modified":"2019-07-05T23:13:49","modified_gmt":"2019-07-05T21:13:49","slug":"a-pontinia-un-anno-da-record","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pontinia\/2019\/07\/05\/a-pontinia-un-anno-da-record\/","title":{"rendered":"A PONTINIA\u2026 UN ANNO DA RECORD!"},"content":{"rendered":"<div class=\"entry-content\">\n<p>&nbsp;<\/p>\n<figure id=\"attachment_862\" aria-describedby=\"caption-attachment-862\" style=\"width: 120px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-862\" src=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/07\/CiaoPontinia-Avatar-FB-300x300.jpg\" alt=\"\" width=\"120\" height=\"120\" srcset=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/07\/CiaoPontinia-Avatar-FB-300x300.jpg 300w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/07\/CiaoPontinia-Avatar-FB-150x150.jpg 150w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/07\/CiaoPontinia-Avatar-FB.jpg 360w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><figcaption id=\"caption-attachment-862\" class=\"wp-caption-text\"><a href=\"https:\/\/www.ciaopontinia.it\/a-pontinia-una-anno-da-record\/\">www.ciaopontinia.it<\/a><\/figcaption><\/figure>\n<p style=\"text-align: center\"><strong><span style=\"color: #0000ff\">CIAOPONTINIA<\/span><\/strong><\/p>\n<p style=\"text-align: center\">Un\u2019annata di successi per lo sport a Pontinia!<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class=\"entry-content\">\n<h4>29 maggio 2019<br \/>\nNon \u00e8 tutto oro ci\u00f2 che luccica, ma la serie C Gold brilla per davvero per il basket a Pontinia. <span style=\"color: #ff0000\"><strong>Officine<\/strong> <strong>Ceccacci<\/strong> <strong>Virtus<\/strong> <strong>Pontinia<\/strong><\/span> vince la finale di playoff di Serie C Silver e compie un\u2019autentica impresa: in soli due anni, la giovane societ\u00e0 cestitica di Pontinia fa un doppio salto di categoria dalla serie D alla serie C Gold, il massimo campionato regionale non professionistico. Sabato 8 giugno, tutti i giocatori e i membri della societ\u00e0 sono stati ospitati nell\u2019Aula Consiliare del Comune di Pontinia per la premiazione da parte del Sindaco @carlo medici a nome di tutta la citt\u00e0.<\/h4>\n<h4>31 maggio 2019<br \/>\nAl solo terzo anno di vita, l\u2019 <span style=\"color: #ff0000\"><strong>ASD<\/strong> <strong>Atletico<\/strong> <strong>Pontinia<\/strong><\/span> guadagna un posto in Prima categoria. Dopo la sfortunata finale della Coppa Lazio, la giovane squadra non si perde d\u2019animo e raccoglie entusiasmo e ambizioni per il salto di categoria dell\u2019anno prossimo. Sempre pi\u00f9 seguita, l\u2019Atletico Pontinia non fa previsioni: metter\u00e0 il massimo impegno in ogni singola partita per regalare un altro emozionante campionato ai tifosi.<\/h4>\n<h4>9 giugno 2019<br \/>\nTermina la stagione calcistica e il <span style=\"color: #ff0000\"><strong>Pontinia<\/strong> <strong>Calcio<\/strong> <strong>ASD<\/strong> <\/span>tinge di amaranto l\u2019Eccellenza, la massima categoria a livello regionale prima della serie D. Con la vittoria del 2 giugno, infatti, il pontinia calcio si concede un incredibile regalo nell\u2019anno del suo venticinquesimo: una promozione inaspettata che segna per la prima volta la storia della societ\u00e0.<\/h4>\n<h4>9 giugno 2019<br \/>\nCon l\u2019inaugurazione del Palasport Marica Bianchi, per la <span style=\"color: #ff0000\"><strong>Pallamano\u00a0Handball Club Cassa Rurale Pontinia<\/strong><\/span> pi\u00f9 che la fine della stagione, \u00e8 un nuovo inizio. La Serie A2 Femminile termina il campionato al sesto posto, dopo una stagione pi\u00f9 che travagliata: la prima senza il capitano, la prima senza la propria casa, a causa di una tromba d\u2019aria che da ottobre ha reso inagibile il Palazzetto dello Sport. Nel dolore e nelle difficolt\u00e0 ci si unisce ancor di pi\u00f9, ed \u00e8 per questo che le ragazze non smettono di guardare avanti con la forza e la speranza che le ha sempre contraddistinte. Alla Pallamano Cassa Rurale Pontinia dedica una breve intervista anche Ilenia Furlanetto della \u201cCasalgrande Padana\u201d, miglior giocatrice di serie A , che ha esordito la sua carriera proprio con la societ\u00e0 di pallamano della sua citt\u00e0 Pontinia:<\/h4>\n<h4><em>Qual \u00e8 la prima cosa che hai pensato quando hai ricevuto il premio di miglior giocatrice di serie A?<\/em><br \/>\nIl mio allenatore mi ha fatto sapere che avevo vinto il premio mentre rientravo dalle vacanze di Natale. Ricordo ancora il momento\u2026 \u00c8 stata una sorpresa inaspettata, ovviamente \u00e8 una bella soddisfazione che ripaga dei sacrifici e scelte fatte negli anni. Sicuramente non l\u2019ho mai pensato come un punto di arrivo e di appagamento.<\/h4>\n<h4><em>Cosa significa per te (per la tua storia, per i tuoi successi) Pontinia?<\/em><br \/>\nPontinia rimarr\u00e0 sempre nel cuore. Da l\u00ec \u00e8 iniziato tutto: gli allenamenti sull\u2019 asfalto quando ancora non c\u2019era il palazzetto. La squadra con cui ho i ricordi pi\u00f9 belli, i 4 scudetti giovanili e le tantissime avventure con le mie compagne di squadra. Era davvero una famiglia. Trani aveva fatto davvero un lavoro incredibile e merita di essere ringraziato pubblicamente anche perch\u00e9 adesso che alleno anch\u2019io so cosa significa dare cos\u00ec tanto a una squadra.<\/h4>\n<h4><em>Sai che per le ragazze della squadra di Pontinia \u00e8 stata un\u2019annata difficile. Hai qualche consiglio per loro?<\/em><br \/>\nSi certo. Le seguo anche se fisicamente sono lontana. Posso dire solo che dalle difficolt\u00e0 ci si rialza sempre pi\u00f9 forti. Auguro a loro un grosso in bocca a lupo per la prossima stagione.<\/h4>\n<h4>23 giugno 2019<br \/>\n\u201c\u00c8 incredibile come cambia la vita se la palla va oltre la rete o torna indietro, no?\u201d (da Match Point, di Woody Allen)<br \/>\nE per il <strong>TC<\/strong> <span style=\"color: #ff0000\"><strong>Prato<\/strong> <strong>Verde<\/strong> di Pontinia<\/span>, con una traiettoria a forma di C, la pallina va oltre la rete. La squadra di Diego franco, infatti, vince il campionato a squadre e per la prima volta approda in serie C.<br \/>\nUn girone eliminatorio difficile e le domeniche di pioggia non hanno di certo fermato il TC Prato Verde di Pontinia: la squadra conquista la seconda promozione in soli tre anni, rivelandosi non pi\u00f9 una sorpresa, ma una vera e propria conferma nel panorama del tennis pontino. Oltre la rete, oltre le aspettative.<\/h4>\n<h4>29 giugno 2019:<br \/>\nDeterminazione, tenacia e sacrifici: queste sono le caratteristiche per praticare il culturismo, uno sport che ha portato risultati positivi a Pontinia.<br \/>\nIl Bodybuilding \u00e8 uno sport che richiede duro lavoro e un\u2019alimentazione specifica per ottenere grandi soddisfazioni, come dimostra il <strong>campione<\/strong> <span style=\"color: #ff0000\"><strong>Dario<\/strong> <strong>Paolozzi<\/strong><\/span> che si \u00e8 aggiudicato la categoria Supermassimi +100kg al Campionato Italiano IFBB.<br \/>\nUn grande obiettivo raggiunto dal personal trainer e titolare della palestra K-Fit.<\/h4>\n<h4>Coming soon<br \/>\nDa non dimenticare \u00e8 anche <strong>Pontinia<\/strong> <strong>Cricket<\/strong> <strong>Club<\/strong>, che si sta preparando per l\u2019anno prossimo e che si sta impegnando a far conoscere questo sport con tanti appuntamenti.<\/h4>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; CIAOPONTINIA Un\u2019annata di successi per lo sport a Pontinia! &nbsp; &nbsp; &nbsp; 29 maggio 2019 Non \u00e8 tutto oro ci\u00f2 che luccica, ma la serie C Gold brilla per [&hellip;]<\/p>\n","protected":false},"author":294,"featured_media":862,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A PONTINIA\u2026 UN ANNO DA RECORD! - Pontinia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pontinia\/2019\/07\/05\/a-pontinia-un-anno-da-record\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A PONTINIA\u2026 UN ANNO DA RECORD! - Pontinia\" \/>\n<meta property=\"og:description\" content=\"&nbsp; CIAOPONTINIA Un\u2019annata di successi per lo sport a Pontinia! &nbsp; &nbsp; &nbsp; 29 maggio 2019 Non \u00e8 tutto oro ci\u00f2 che luccica, ma la serie C Gold brilla per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pontinia\/2019\/07\/05\/a-pontinia-un-anno-da-record\/\" \/>\n<meta property=\"og:site_name\" content=\"Pontinia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-05T21:05:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-05T21:13:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/07\/CiaoPontinia-Avatar-FB.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sportpontinia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sportpontinia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/07\\\/05\\\/a-pontinia-un-anno-da-record\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/07\\\/05\\\/a-pontinia-un-anno-da-record\\\/\"},\"author\":{\"name\":\"sportpontinia\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"headline\":\"A PONTINIA\u2026 UN ANNO DA RECORD!\",\"datePublished\":\"2019-07-05T21:05:47+00:00\",\"dateModified\":\"2019-07-05T21:13:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/07\\\/05\\\/a-pontinia-un-anno-da-record\\\/\"},\"wordCount\":821,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/07\\\/05\\\/a-pontinia-un-anno-da-record\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/07\\\/CiaoPontinia-Avatar-FB.jpg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/07\\\/05\\\/a-pontinia-un-anno-da-record\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/07\\\/05\\\/a-pontinia-un-anno-da-record\\\/\",\"name\":\"A PONTINIA\u2026 UN ANNO DA RECORD! - Pontinia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/07\\\/05\\\/a-pontinia-un-anno-da-record\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/07\\\/05\\\/a-pontinia-un-anno-da-record\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/07\\\/CiaoPontinia-Avatar-FB.jpg\",\"datePublished\":\"2019-07-05T21:05:47+00:00\",\"dateModified\":\"2019-07-05T21:13:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/07\\\/05\\\/a-pontinia-un-anno-da-record\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/07\\\/05\\\/a-pontinia-un-anno-da-record\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/07\\\/05\\\/a-pontinia-un-anno-da-record\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/07\\\/CiaoPontinia-Avatar-FB.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/07\\\/CiaoPontinia-Avatar-FB.jpg\",\"width\":360,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/07\\\/05\\\/a-pontinia-un-anno-da-record\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A PONTINIA\u2026 UN ANNO DA RECORD!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\",\"name\":\"Pontinia\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\",\"name\":\"sportpontinia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"caption\":\"sportpontinia\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/author\\\/sportpontinia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A PONTINIA\u2026 UN ANNO DA RECORD! - Pontinia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pontinia\/2019\/07\/05\/a-pontinia-un-anno-da-record\/","og_locale":"it_IT","og_type":"article","og_title":"A PONTINIA\u2026 UN ANNO DA RECORD! - Pontinia","og_description":"&nbsp; CIAOPONTINIA Un\u2019annata di successi per lo sport a Pontinia! &nbsp; &nbsp; &nbsp; 29 maggio 2019 Non \u00e8 tutto oro ci\u00f2 che luccica, ma la serie C Gold brilla per [&hellip;]","og_url":"https:\/\/comunicacity.net\/pontinia\/2019\/07\/05\/a-pontinia-un-anno-da-record\/","og_site_name":"Pontinia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-07-05T21:05:47+00:00","article_modified_time":"2019-07-05T21:13:49+00:00","og_image":[{"width":360,"height":360,"url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/07\/CiaoPontinia-Avatar-FB.jpg","type":"image\/jpeg"}],"author":"sportpontinia","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sportpontinia","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pontinia\/2019\/07\/05\/a-pontinia-un-anno-da-record\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/07\/05\/a-pontinia-un-anno-da-record\/"},"author":{"name":"sportpontinia","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"headline":"A PONTINIA\u2026 UN ANNO DA RECORD!","datePublished":"2019-07-05T21:05:47+00:00","dateModified":"2019-07-05T21:13:49+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/07\/05\/a-pontinia-un-anno-da-record\/"},"wordCount":821,"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/07\/05\/a-pontinia-un-anno-da-record\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/07\/CiaoPontinia-Avatar-FB.jpg","articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pontinia\/2019\/07\/05\/a-pontinia-un-anno-da-record\/","url":"https:\/\/comunicacity.net\/pontinia\/2019\/07\/05\/a-pontinia-un-anno-da-record\/","name":"A PONTINIA\u2026 UN ANNO DA RECORD! - Pontinia","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/07\/05\/a-pontinia-un-anno-da-record\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/07\/05\/a-pontinia-un-anno-da-record\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/07\/CiaoPontinia-Avatar-FB.jpg","datePublished":"2019-07-05T21:05:47+00:00","dateModified":"2019-07-05T21:13:49+00:00","author":{"@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/07\/05\/a-pontinia-un-anno-da-record\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pontinia\/2019\/07\/05\/a-pontinia-un-anno-da-record\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pontinia\/2019\/07\/05\/a-pontinia-un-anno-da-record\/#primaryimage","url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/07\/CiaoPontinia-Avatar-FB.jpg","contentUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/07\/CiaoPontinia-Avatar-FB.jpg","width":360,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pontinia\/2019\/07\/05\/a-pontinia-un-anno-da-record\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pontinia\/"},{"@type":"ListItem","position":2,"name":"A PONTINIA\u2026 UN ANNO DA RECORD!"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pontinia\/#website","url":"https:\/\/comunicacity.net\/pontinia\/","name":"Pontinia","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pontinia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807","name":"sportpontinia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","caption":"sportpontinia"},"url":"https:\/\/comunicacity.net\/pontinia\/author\/sportpontinia\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/users\/294"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/comments?post=861"}],"version-history":[{"count":8,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/861\/revisions"}],"predecessor-version":[{"id":870,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/861\/revisions\/870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media\/862"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media?parent=861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/categories?post=861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/tags?post=861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}