{"id":948,"date":"2019-08-01T12:53:55","date_gmt":"2019-08-01T10:53:55","guid":{"rendered":"https:\/\/comunicacity.net\/pontinia\/?p=948"},"modified":"2019-08-01T12:53:55","modified_gmt":"2019-08-01T10:53:55","slug":"cinema-cotral-piazza-indipendenza-questa-sera","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/01\/cinema-cotral-piazza-indipendenza-questa-sera\/","title":{"rendered":"&#8220;CINEMA COTRAL&#8221; &#8211; PIAZZA INDIPENDENZA | QUESTA SERA"},"content":{"rendered":"<div class=\"\">\n<div class=\"_1mf _1mj\"><span class=\"_3gl1 _5zz4\"><span class=\"_ncl\"><span>?<\/span><\/span><\/span><span><strong> Questa<\/strong> <strong>sera<\/strong> alle <strong>ore<\/strong> <strong>21<\/strong> ultima visione del &#8220;<strong>Cinema Cotral<\/strong>&#8221; in <strong>Piazza<\/strong> <strong>Indipendenza<\/strong> a Pontinia!<\/span><\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span>\u00a0<\/span><\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span class=\"_3gl1 _5zz4\"><span class=\"_ncl\"><span>?<\/span><\/span><\/span><span> Un&#8217;arena gratuita e un Cotral modificato vi aspettano per mostrarvi l&#8217;allegra commedia di Stephan Elliott, &#8220;<\/span><span style=\"font-size: 1rem\"><strong>Priscilla la regina del Deserto<\/strong>&#8220;<\/span><span style=\"font-size: 1rem\">. Una vivace colonna sonora, costumi sgargianti, dialoghi molto spiritosi e un terzetto di attori strepitosi, vi riserveranno una serata imperdibile.<\/span><\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span>\u00a0<\/span><\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span>Non mancate!<\/span><\/div>\n<div class=\"_1mf _1mj\"><\/div>\n<div class=\"_1mf _1mj\"><\/div>\n<div class=\"_1mf _1mj\"><span><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-930\" src=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/07\/cinema-cotral-300x136.jpg\" alt=\"\" width=\"300\" height=\"136\" srcset=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/07\/cinema-cotral-300x136.jpg 300w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/07\/cinema-cotral-768x348.jpg 768w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/07\/cinema-cotral-680x308.jpg 680w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/07\/cinema-cotral.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/span><\/div>\n<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>? Questa sera alle ore 21 ultima visione del &#8220;Cinema Cotral&#8221; in Piazza Indipendenza a Pontinia! \u00a0 ? Un&#8217;arena gratuita e un Cotral modificato vi aspettano per mostrarvi l&#8217;allegra commedia [&hellip;]<\/p>\n","protected":false},"author":292,"featured_media":949,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;CINEMA COTRAL&quot; - PIAZZA INDIPENDENZA | QUESTA SERA - Pontinia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pontinia\/2019\/08\/01\/cinema-cotral-piazza-indipendenza-questa-sera\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;CINEMA COTRAL&quot; - PIAZZA INDIPENDENZA | QUESTA SERA - Pontinia\" \/>\n<meta property=\"og:description\" content=\"? Questa sera alle ore 21 ultima visione del &#8220;Cinema Cotral&#8221; in Piazza Indipendenza a Pontinia! \u00a0 ? Un&#8217;arena gratuita e un Cotral modificato vi aspettano per mostrarvi l&#8217;allegra commedia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pontinia\/2019\/08\/01\/cinema-cotral-piazza-indipendenza-questa-sera\/\" \/>\n<meta property=\"og:site_name\" content=\"Pontinia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-01T10:53:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/08\/WhatsApp-Image-2019-07-30-at-13.08.09.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pontinia10\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pontinia10\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/08\\\/01\\\/cinema-cotral-piazza-indipendenza-questa-sera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/08\\\/01\\\/cinema-cotral-piazza-indipendenza-questa-sera\\\/\"},\"author\":{\"name\":\"pontinia10\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/a4367ac2e0d25de694eb5fe9f07b7d62\"},\"headline\":\"&#8220;CINEMA COTRAL&#8221; &#8211; PIAZZA INDIPENDENZA | QUESTA SERA\",\"datePublished\":\"2019-08-01T10:53:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/08\\\/01\\\/cinema-cotral-piazza-indipendenza-questa-sera\\\/\"},\"wordCount\":63,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/08\\\/01\\\/cinema-cotral-piazza-indipendenza-questa-sera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/08\\\/WhatsApp-Image-2019-07-30-at-13.08.09.jpeg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/08\\\/01\\\/cinema-cotral-piazza-indipendenza-questa-sera\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/08\\\/01\\\/cinema-cotral-piazza-indipendenza-questa-sera\\\/\",\"name\":\"\\\"CINEMA COTRAL\\\" - PIAZZA INDIPENDENZA | QUESTA SERA - Pontinia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/08\\\/01\\\/cinema-cotral-piazza-indipendenza-questa-sera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/08\\\/01\\\/cinema-cotral-piazza-indipendenza-questa-sera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/08\\\/WhatsApp-Image-2019-07-30-at-13.08.09.jpeg\",\"datePublished\":\"2019-08-01T10:53:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/a4367ac2e0d25de694eb5fe9f07b7d62\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/08\\\/01\\\/cinema-cotral-piazza-indipendenza-questa-sera\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/08\\\/01\\\/cinema-cotral-piazza-indipendenza-questa-sera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/08\\\/01\\\/cinema-cotral-piazza-indipendenza-questa-sera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/08\\\/WhatsApp-Image-2019-07-30-at-13.08.09.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/08\\\/WhatsApp-Image-2019-07-30-at-13.08.09.jpeg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/08\\\/01\\\/cinema-cotral-piazza-indipendenza-questa-sera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;CINEMA COTRAL&#8221; &#8211; PIAZZA INDIPENDENZA | QUESTA SERA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\",\"name\":\"Pontinia\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/a4367ac2e0d25de694eb5fe9f07b7d62\",\"name\":\"pontinia10\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be17626afd790e5340de7f17abc901a484955bf057704dfdc7eae6d55eb80317?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be17626afd790e5340de7f17abc901a484955bf057704dfdc7eae6d55eb80317?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be17626afd790e5340de7f17abc901a484955bf057704dfdc7eae6d55eb80317?s=96&d=mm&r=g\",\"caption\":\"pontinia10\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/author\\\/pontinia10\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"CINEMA COTRAL\" - PIAZZA INDIPENDENZA | QUESTA SERA - Pontinia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/01\/cinema-cotral-piazza-indipendenza-questa-sera\/","og_locale":"it_IT","og_type":"article","og_title":"\"CINEMA COTRAL\" - PIAZZA INDIPENDENZA | QUESTA SERA - Pontinia","og_description":"? Questa sera alle ore 21 ultima visione del &#8220;Cinema Cotral&#8221; in Piazza Indipendenza a Pontinia! \u00a0 ? Un&#8217;arena gratuita e un Cotral modificato vi aspettano per mostrarvi l&#8217;allegra commedia [&hellip;]","og_url":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/01\/cinema-cotral-piazza-indipendenza-questa-sera\/","og_site_name":"Pontinia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-08-01T10:53:55+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/08\/WhatsApp-Image-2019-07-30-at-13.08.09.jpeg","type":"image\/jpeg"}],"author":"pontinia10","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pontinia10"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/01\/cinema-cotral-piazza-indipendenza-questa-sera\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/01\/cinema-cotral-piazza-indipendenza-questa-sera\/"},"author":{"name":"pontinia10","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/a4367ac2e0d25de694eb5fe9f07b7d62"},"headline":"&#8220;CINEMA COTRAL&#8221; &#8211; PIAZZA INDIPENDENZA | QUESTA SERA","datePublished":"2019-08-01T10:53:55+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/01\/cinema-cotral-piazza-indipendenza-questa-sera\/"},"wordCount":63,"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/01\/cinema-cotral-piazza-indipendenza-questa-sera\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/08\/WhatsApp-Image-2019-07-30-at-13.08.09.jpeg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/01\/cinema-cotral-piazza-indipendenza-questa-sera\/","url":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/01\/cinema-cotral-piazza-indipendenza-questa-sera\/","name":"\"CINEMA COTRAL\" - PIAZZA INDIPENDENZA | QUESTA SERA - Pontinia","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/01\/cinema-cotral-piazza-indipendenza-questa-sera\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/01\/cinema-cotral-piazza-indipendenza-questa-sera\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/08\/WhatsApp-Image-2019-07-30-at-13.08.09.jpeg","datePublished":"2019-08-01T10:53:55+00:00","author":{"@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/a4367ac2e0d25de694eb5fe9f07b7d62"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/01\/cinema-cotral-piazza-indipendenza-questa-sera\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pontinia\/2019\/08\/01\/cinema-cotral-piazza-indipendenza-questa-sera\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/01\/cinema-cotral-piazza-indipendenza-questa-sera\/#primaryimage","url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/08\/WhatsApp-Image-2019-07-30-at-13.08.09.jpeg","contentUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/08\/WhatsApp-Image-2019-07-30-at-13.08.09.jpeg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/01\/cinema-cotral-piazza-indipendenza-questa-sera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pontinia\/"},{"@type":"ListItem","position":2,"name":"&#8220;CINEMA COTRAL&#8221; &#8211; PIAZZA INDIPENDENZA | QUESTA SERA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pontinia\/#website","url":"https:\/\/comunicacity.net\/pontinia\/","name":"Pontinia","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pontinia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/a4367ac2e0d25de694eb5fe9f07b7d62","name":"pontinia10","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/be17626afd790e5340de7f17abc901a484955bf057704dfdc7eae6d55eb80317?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/be17626afd790e5340de7f17abc901a484955bf057704dfdc7eae6d55eb80317?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/be17626afd790e5340de7f17abc901a484955bf057704dfdc7eae6d55eb80317?s=96&d=mm&r=g","caption":"pontinia10"},"url":"https:\/\/comunicacity.net\/pontinia\/author\/pontinia10\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/users\/292"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/comments?post=948"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/948\/revisions"}],"predecessor-version":[{"id":950,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/948\/revisions\/950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media\/949"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media?parent=948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/categories?post=948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/tags?post=948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}