{"id":962,"date":"2019-08-05T18:12:48","date_gmt":"2019-08-05T16:12:48","guid":{"rendered":"https:\/\/comunicacity.net\/pontinia\/?p=962"},"modified":"2019-08-05T18:12:48","modified_gmt":"2019-08-05T16:12:48","slug":"festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/05\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\/","title":{"rendered":"FESTA DELLO SPORT &#8211; PONTINIA 2019 &#8211; ASD GINNASTICA ARTISTICA ENRICO MATTEI"},"content":{"rendered":"<p style=\"text-align: center\"><span style=\"color: #000000\">5^ EDIZIONE FESTA DELLO SPORT &#8211; PONTINIA 2019 <\/span><\/p>\n<p style=\"text-align: center\"><span style=\"color: #000000\">&#8220;SPORT BENE COMUNE&#8221;<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"color: #000000\">DOMENICA 1 SETTEMBRE 2019<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"color: #ff0000\">ASD GINNASTICA ARTISTICA ENRICO MATTEI<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000\">Si tratta un\u2019Associazione sportiva non a fini di lucro, nata nel 1970 ed iscritta alla Federazione Ginnastica d\u2019Italia dal 1972, riconosciuta quale \u201c Scuola Nazionale di Ginnastica Artistica \u201c ed insignita della benemerenza federale di \u201c DIPLOMA DI FEDELTA\u2019 E MEDAGLIA DI BRONZO \u201c dove gli atleti iscritti oltre a perseguire gli obiettivi sportivi, beneficiano anche di un ambiente capace di trasmettere valori educativi, etici, salutistici e di disciplina. Questo modello educativo e di insegnamento, da 10 anni \u00e8 stato portato nelle scuole elementari del Comune di Latina dove la nostra Associazione collabora attivamente, realizzando progetti specifici nell\u2019ambito dell\u2019educazione motoria (corsi di ginnastica di base) per i bambini frequentanti. Con lo spirito di rendere aperta e accessibile a tutti la nostra disciplina, l\u2019Associazione Sportiva Dilettantistica Ginnastica Enrico Mattei si impegna continuamente a mantenere attivi corsi di ginnastica motoria di base ,ginnastica di base per giovani e adulti, ginnastica artistica a livello promozionale per ragazzi e ragazze (corsi a partire dai 3 anni) e ginnastica artistica a livello regionale e nazionale agonistico sia nel settore maschile che femminile raggiungendo sempre ottimi risultati in campo e fuori dal campo di gara.<\/span><br \/>\n<span style=\"color: #000000\">Ad oggi la nostra Associazione conta pi\u00f9 di 200 soci\/iscritti ed un palmares di prestigio nelle competizioni sportive e campionati della Federazione Ginnastica d\u2019Italia, sia a livello nazionale, che regionale sia a livello di squadra che individuale, rendendola di fatto il punto di riferimento a livello provinciale per i ragazzi e le ragazze che vogliono intraprendere un percorso sportivo di ginnastica artistica amatoriale,promozionale o agonistica. La forza e la determinazione con cui la nostra Associazione persegue i propri obiettivi formativi, \u00e8 anche nelle scelte che facciamo e che ci hanno portato nel 2016, attraverso grandi sacrifici ed impegni anche individuali, a realizzare un<\/span><br \/>\n<span style=\"color: #000000\">nuovo e pi\u00f9 moderno impianto sportivo adeguando profondamente un locale che abbiamo affittato.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-964 aligncenter\" src=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/08\/logo-mattei-con-indirizzo1-253x300.jpg\" alt=\"\" width=\"391\" height=\"464\" srcset=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/08\/logo-mattei-con-indirizzo1-253x300.jpg 253w, https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/08\/logo-mattei-con-indirizzo1.jpg 382w\" sizes=\"auto, (max-width: 391px) 100vw, 391px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>5^ EDIZIONE FESTA DELLO SPORT &#8211; PONTINIA 2019 &#8220;SPORT BENE COMUNE&#8221; DOMENICA 1 SETTEMBRE 2019 ASD GINNASTICA ARTISTICA ENRICO MATTEI &nbsp; Si tratta un\u2019Associazione sportiva non a fini di lucro, [&hellip;]<\/p>\n","protected":false},"author":294,"featured_media":964,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-962","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FESTA DELLO SPORT - PONTINIA 2019 - ASD GINNASTICA ARTISTICA ENRICO MATTEI - Pontinia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/pontinia\/2019\/08\/05\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FESTA DELLO SPORT - PONTINIA 2019 - ASD GINNASTICA ARTISTICA ENRICO MATTEI - Pontinia\" \/>\n<meta property=\"og:description\" content=\"5^ EDIZIONE FESTA DELLO SPORT &#8211; PONTINIA 2019 &#8220;SPORT BENE COMUNE&#8221; DOMENICA 1 SETTEMBRE 2019 ASD GINNASTICA ARTISTICA ENRICO MATTEI &nbsp; Si tratta un\u2019Associazione sportiva non a fini di lucro, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/pontinia\/2019\/08\/05\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\/\" \/>\n<meta property=\"og:site_name\" content=\"Pontinia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-05T16:12:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/08\/logo-mattei-con-indirizzo1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"382\" \/>\n\t<meta property=\"og:image:height\" content=\"453\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sportpontinia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sportpontinia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/08\\\/05\\\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/08\\\/05\\\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\\\/\"},\"author\":{\"name\":\"sportpontinia\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"headline\":\"FESTA DELLO SPORT &#8211; PONTINIA 2019 &#8211; ASD GINNASTICA ARTISTICA ENRICO MATTEI\",\"datePublished\":\"2019-08-05T16:12:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/08\\\/05\\\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\\\/\"},\"wordCount\":329,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/08\\\/05\\\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/08\\\/logo-mattei-con-indirizzo1.jpg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/08\\\/05\\\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/08\\\/05\\\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\\\/\",\"name\":\"FESTA DELLO SPORT - PONTINIA 2019 - ASD GINNASTICA ARTISTICA ENRICO MATTEI - Pontinia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/08\\\/05\\\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/08\\\/05\\\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/08\\\/logo-mattei-con-indirizzo1.jpg\",\"datePublished\":\"2019-08-05T16:12:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/08\\\/05\\\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/08\\\/05\\\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/08\\\/05\\\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/08\\\/logo-mattei-con-indirizzo1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/wp-content\\\/uploads\\\/sites\\\/158\\\/2019\\\/08\\\/logo-mattei-con-indirizzo1.jpg\",\"width\":382,\"height\":453},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/2019\\\/08\\\/05\\\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FESTA DELLO SPORT &#8211; PONTINIA 2019 &#8211; ASD GINNASTICA ARTISTICA ENRICO MATTEI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/\",\"name\":\"Pontinia\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/#\\\/schema\\\/person\\\/e8f3ea5c2616bf2cb206830644808807\",\"name\":\"sportpontinia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g\",\"caption\":\"sportpontinia\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/pontinia\\\/author\\\/sportpontinia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FESTA DELLO SPORT - PONTINIA 2019 - ASD GINNASTICA ARTISTICA ENRICO MATTEI - Pontinia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/05\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\/","og_locale":"it_IT","og_type":"article","og_title":"FESTA DELLO SPORT - PONTINIA 2019 - ASD GINNASTICA ARTISTICA ENRICO MATTEI - Pontinia","og_description":"5^ EDIZIONE FESTA DELLO SPORT &#8211; PONTINIA 2019 &#8220;SPORT BENE COMUNE&#8221; DOMENICA 1 SETTEMBRE 2019 ASD GINNASTICA ARTISTICA ENRICO MATTEI &nbsp; Si tratta un\u2019Associazione sportiva non a fini di lucro, [&hellip;]","og_url":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/05\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\/","og_site_name":"Pontinia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-08-05T16:12:48+00:00","og_image":[{"width":382,"height":453,"url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/08\/logo-mattei-con-indirizzo1.jpg","type":"image\/jpeg"}],"author":"sportpontinia","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sportpontinia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/05\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/05\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\/"},"author":{"name":"sportpontinia","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"headline":"FESTA DELLO SPORT &#8211; PONTINIA 2019 &#8211; ASD GINNASTICA ARTISTICA ENRICO MATTEI","datePublished":"2019-08-05T16:12:48+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/05\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\/"},"wordCount":329,"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/05\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/08\/logo-mattei-con-indirizzo1.jpg","articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/05\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\/","url":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/05\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\/","name":"FESTA DELLO SPORT - PONTINIA 2019 - ASD GINNASTICA ARTISTICA ENRICO MATTEI - Pontinia","isPartOf":{"@id":"https:\/\/comunicacity.net\/pontinia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/05\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/05\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/08\/logo-mattei-con-indirizzo1.jpg","datePublished":"2019-08-05T16:12:48+00:00","author":{"@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/05\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/pontinia\/2019\/08\/05\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/05\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\/#primaryimage","url":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/08\/logo-mattei-con-indirizzo1.jpg","contentUrl":"https:\/\/comunicacity.net\/pontinia\/wp-content\/uploads\/sites\/158\/2019\/08\/logo-mattei-con-indirizzo1.jpg","width":382,"height":453},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/pontinia\/2019\/08\/05\/festa-dello-sport-pontinia-2019-asd-ginnastica-artistica-enrico-mattei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/pontinia\/"},{"@type":"ListItem","position":2,"name":"FESTA DELLO SPORT &#8211; PONTINIA 2019 &#8211; ASD GINNASTICA ARTISTICA ENRICO MATTEI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/pontinia\/#website","url":"https:\/\/comunicacity.net\/pontinia\/","name":"Pontinia","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/pontinia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/pontinia\/#\/schema\/person\/e8f3ea5c2616bf2cb206830644808807","name":"sportpontinia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b1636d50250d139fdd3f06bbc62958639dbe496b9e17d3877ca384679bb6904?s=96&d=mm&r=g","caption":"sportpontinia"},"url":"https:\/\/comunicacity.net\/pontinia\/author\/sportpontinia\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/users\/294"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/comments?post=962"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/962\/revisions"}],"predecessor-version":[{"id":965,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/posts\/962\/revisions\/965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media\/964"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/media?parent=962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/categories?post=962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/pontinia\/wp-json\/wp\/v2\/tags?post=962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}