{"id":10125,"date":"2017-12-16T11:56:15","date_gmt":"2017-12-16T10:56:15","guid":{"rendered":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/16\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\/"},"modified":"2017-12-16T11:56:15","modified_gmt":"2017-12-16T10:56:15","slug":"milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/16\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\/","title":{"rendered":"Milano &#8211; ARRESTATI DAI CARABINIERI I COMPLICI DELL\u2019ATTENTATO DINAMITARDO DI PIOLTELLO. IN MANETTE ANCHE IL FIGLIO DEL CAPO DELLA LOCALE DI \u2018NDRANGHETA"},"content":{"rendered":"<p>I Carabinieri del Comando Provinciale di Milano hanno dato esecuzione a un decreto di fermo di indiziato di delitto emesso dalla D.D.A. del capoluogo nei confronti di 3 soggetti italiani, gi\u00e0 noti alla Giustizia, ritenuti responsabili a vario titolo di estorsione, usura e violenza privata, aggravati perch\u00e9 commessi con modalit\u00e0 mafiose.<br \/>\nIl provvedimento giunge a conclusione degli approfondimenti investigativi condotti dai militari del Nucleo Investigativo di Monza e della Compagnia di Cassano D&#8217;Adda (MI) a seguito dell\u2019attentato dinamitardo commesso nella notte del 10 ottobre scorso, quando venne fatto esplodere un ordigno I.E.D. (Improvised Explosive Device) a Pioltello, davanti alla porta di ingresso dell&#8217;abitazione di un 46enne ecuadoregno. Per il medesimo episodio era gi\u00e0 stato tratto in arresto, il 6 novembre scorso,un altro uomo. Le indagini hanno inoltre appurato che gli autori del reato, nel mese di agosto 2016, avevano concesso un prestito di 3.000 euro a un 32enne ecuadoregno residente a Pioltello, pretendendone la restituzione con interessi usurari di 400 euro mensili, nonch\u00e9 con una penale di 50 euro per ogni giorno di ritardo rispetto al termine pattuito. La vittima era stata ripetutamente minacciata e persino caricata a bordo di un veicolo al cui interno era stata malmenata e seviziata allo scopo di ottenere il pagamento. Gli arrestati sono stati condotti presso il carcere di Opera (MI), dove rimangono a\u00a0 disposizione dell\u2019Autorit\u00e0 Giudiziaria. Ulteriori dettagli saranno divulgati nel corso del consueto incontro con la stampa delle ore 12.00, presso la Sala Stampa del Comando Provinciale di Milano, in via della Moscova nr. 19\/21.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I Carabinieri del Comando Provinciale di Milano hanno dato esecuzione a un decreto di fermo di indiziato di delitto emesso dalla D.D.A. del capoluogo nei confronti di 3 soggetti italiani, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10126,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-10125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forze-dell-ordine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Milano - ARRESTATI DAI CARABINIERI I COMPLICI DELL\u2019ATTENTATO DINAMITARDO DI PIOLTELLO. IN MANETTE ANCHE IL FIGLIO DEL CAPO DELLA LOCALE DI \u2018NDRANGHETA - Portale dei Carabinieri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/16\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Milano - ARRESTATI DAI CARABINIERI I COMPLICI DELL\u2019ATTENTATO DINAMITARDO DI PIOLTELLO. IN MANETTE ANCHE IL FIGLIO DEL CAPO DELLA LOCALE DI \u2018NDRANGHETA - Portale dei Carabinieri\" \/>\n<meta property=\"og:description\" content=\"I Carabinieri del Comando Provinciale di Milano hanno dato esecuzione a un decreto di fermo di indiziato di delitto emesso dalla D.D.A. del capoluogo nei confronti di 3 soggetti italiani, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/16\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\/\" \/>\n<meta property=\"og:site_name\" content=\"Portale dei Carabinieri\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-16T10:56:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2017\/12\/carabinieri-339.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/12\\\/16\\\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/12\\\/16\\\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Milano &#8211; ARRESTATI DAI CARABINIERI I COMPLICI DELL\u2019ATTENTATO DINAMITARDO DI PIOLTELLO. IN MANETTE ANCHE IL FIGLIO DEL CAPO DELLA LOCALE DI \u2018NDRANGHETA\",\"datePublished\":\"2017-12-16T10:56:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/12\\\/16\\\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\\\/\"},\"wordCount\":274,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/12\\\/16\\\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2017\\\/12\\\/carabinieri-339.jpg\",\"articleSection\":[\"Forze dell'Ordine\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/12\\\/16\\\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/12\\\/16\\\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\\\/\",\"name\":\"Milano - ARRESTATI DAI CARABINIERI I COMPLICI DELL\u2019ATTENTATO DINAMITARDO DI PIOLTELLO. IN MANETTE ANCHE IL FIGLIO DEL CAPO DELLA LOCALE DI \u2018NDRANGHETA - Portale dei Carabinieri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/12\\\/16\\\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/12\\\/16\\\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2017\\\/12\\\/carabinieri-339.jpg\",\"datePublished\":\"2017-12-16T10:56:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/12\\\/16\\\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/12\\\/16\\\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/12\\\/16\\\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2017\\\/12\\\/carabinieri-339.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2017\\\/12\\\/carabinieri-339.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/12\\\/16\\\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Milano &#8211; ARRESTATI DAI CARABINIERI I COMPLICI DELL\u2019ATTENTATO DINAMITARDO DI PIOLTELLO. IN MANETTE ANCHE IL FIGLIO DEL CAPO DELLA LOCALE DI \u2018NDRANGHETA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/\",\"name\":\"Portale dei Carabinieri\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Milano - ARRESTATI DAI CARABINIERI I COMPLICI DELL\u2019ATTENTATO DINAMITARDO DI PIOLTELLO. IN MANETTE ANCHE IL FIGLIO DEL CAPO DELLA LOCALE DI \u2018NDRANGHETA - Portale dei Carabinieri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/16\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\/","og_locale":"it_IT","og_type":"article","og_title":"Milano - ARRESTATI DAI CARABINIERI I COMPLICI DELL\u2019ATTENTATO DINAMITARDO DI PIOLTELLO. IN MANETTE ANCHE IL FIGLIO DEL CAPO DELLA LOCALE DI \u2018NDRANGHETA - Portale dei Carabinieri","og_description":"I Carabinieri del Comando Provinciale di Milano hanno dato esecuzione a un decreto di fermo di indiziato di delitto emesso dalla D.D.A. del capoluogo nei confronti di 3 soggetti italiani, [&hellip;]","og_url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/16\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\/","og_site_name":"Portale dei Carabinieri","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-12-16T10:56:15+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2017\/12\/carabinieri-339.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/16\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/16\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Milano &#8211; ARRESTATI DAI CARABINIERI I COMPLICI DELL\u2019ATTENTATO DINAMITARDO DI PIOLTELLO. IN MANETTE ANCHE IL FIGLIO DEL CAPO DELLA LOCALE DI \u2018NDRANGHETA","datePublished":"2017-12-16T10:56:15+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/16\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\/"},"wordCount":274,"commentCount":0,"image":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/16\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2017\/12\/carabinieri-339.jpg","articleSection":["Forze dell'Ordine"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/16\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\/","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/16\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\/","name":"Milano - ARRESTATI DAI CARABINIERI I COMPLICI DELL\u2019ATTENTATO DINAMITARDO DI PIOLTELLO. IN MANETTE ANCHE IL FIGLIO DEL CAPO DELLA LOCALE DI \u2018NDRANGHETA - Portale dei Carabinieri","isPartOf":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/16\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/16\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2017\/12\/carabinieri-339.jpg","datePublished":"2017-12-16T10:56:15+00:00","author":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/16\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/16\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/16\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\/#primaryimage","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2017\/12\/carabinieri-339.jpg","contentUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2017\/12\/carabinieri-339.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/16\/milano-arrestati-dai-carabinieri-i-complici-dellattentato-dinamitardo-di-pioltello-in-manette-anche-il-figlio-del-capo-della-locale-di-ndrangheta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/"},{"@type":"ListItem","position":2,"name":"Milano &#8211; ARRESTATI DAI CARABINIERI I COMPLICI DELL\u2019ATTENTATO DINAMITARDO DI PIOLTELLO. IN MANETTE ANCHE IL FIGLIO DEL CAPO DELLA LOCALE DI \u2018NDRANGHETA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#website","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/","name":"Portale dei Carabinieri","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts\/10125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/comments?post=10125"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts\/10125\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/media\/10126"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/media?parent=10125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/categories?post=10125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/tags?post=10125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}