{"id":10652,"date":"2017-12-23T13:23:22","date_gmt":"2017-12-23T12:23:22","guid":{"rendered":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/23\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\/"},"modified":"2017-12-23T13:23:22","modified_gmt":"2017-12-23T12:23:22","slug":"mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/23\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\/","title":{"rendered":"Mirabella Eclano (AV) &#8211; Produzione e detenzione ai fini di spaccio di sostanze stupefacente: 4 persone arrestate"},"content":{"rendered":"<p>Nella mattinata odierna i Carabinieri della Compagnia di Mirabella Eclano, hanno dato esecuzione nel Comune di Altavilla Irpina ad un\u2019ordinanza di applicazione di misura cautelare emessa dal G.I.P. presso il Tribunale di Avellino nei confronti di 4 persone indagate del reato di produzione e detenzione ai fini di spaccio di sostanze stupefacenti.<br \/>\nIn particolare, il G.I.P. ha disposto:<br \/>\n&#8211; per 2 persone la custodia cautelare in carcere;<br \/>\n&#8211; per altre 2 persone la custodia cautelare in regime di arresti domiciliari.<br \/>\nLe indagini, dirette dalla Procura della Repubblica di Avellino hanno consentito di accertare l\u2019esistenza di una fiorente attivit\u00e0 di spaccio messa in atto dagli indagati\u00a0 &#8211; di et\u00e0 compresa tra i 22 ed i 47 anni &#8211; i quali avevano intessuto una rete di contatti anche con soggetti della provincia di Benevento.\u00a0<br \/>\nL\u2019odierna esecuzione \u00e8 l\u2019atto conclusivo di una lunga attivit\u00e0 avviata alla fine del 2015 quando i Carabinieri del Nucleo Operativo e Radiomobile della Compagnia di Mirabella Eclano accertavano l\u2019attivit\u00e0 di spaccio da parte di uno dei soggetti la cui figura era gi\u00e0 emersa nel corso di precedenti indagini.<br \/>\nGli accertamenti sono proseguiti, poi, fino all\u2019agosto del 2016, con attivit\u00e0 tecniche e tradizionali, sia a carico del predetto che nei confronti di altre persone risultate a loro volta dedite ad un\u2019intensa attivit\u00e0 di smercio di sostanze stupefacenti del tipo cocaina, marijuana e hashish in favore di soggetti provenienti dall\u2019Alta Irpinia e dalla Valle del Calore.<br \/>\n\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella mattinata odierna i Carabinieri della Compagnia di Mirabella Eclano, hanno dato esecuzione nel Comune di Altavilla Irpina ad un\u2019ordinanza di applicazione di misura cautelare emessa dal G.I.P. presso il [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10653,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-10652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forze-dell-ordine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mirabella Eclano (AV) - Produzione e detenzione ai fini di spaccio di sostanze stupefacente: 4 persone arrestate - Portale dei Carabinieri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/23\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mirabella Eclano (AV) - Produzione e detenzione ai fini di spaccio di sostanze stupefacente: 4 persone arrestate - Portale dei Carabinieri\" \/>\n<meta property=\"og:description\" content=\"Nella mattinata odierna i Carabinieri della Compagnia di Mirabella Eclano, hanno dato esecuzione nel Comune di Altavilla Irpina ad un\u2019ordinanza di applicazione di misura cautelare emessa dal G.I.P. presso il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/23\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\/\" \/>\n<meta property=\"og:site_name\" content=\"Portale dei Carabinieri\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-23T12:23:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2017\/12\/carabinieri-582.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/12\\\/23\\\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/12\\\/23\\\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Mirabella Eclano (AV) &#8211; Produzione e detenzione ai fini di spaccio di sostanze stupefacente: 4 persone arrestate\",\"datePublished\":\"2017-12-23T12:23:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/12\\\/23\\\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\\\/\"},\"wordCount\":256,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/12\\\/23\\\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2017\\\/12\\\/carabinieri-582.jpg\",\"articleSection\":[\"Forze dell'Ordine\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/12\\\/23\\\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/12\\\/23\\\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\\\/\",\"name\":\"Mirabella Eclano (AV) - Produzione e detenzione ai fini di spaccio di sostanze stupefacente: 4 persone arrestate - Portale dei Carabinieri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/12\\\/23\\\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/12\\\/23\\\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2017\\\/12\\\/carabinieri-582.jpg\",\"datePublished\":\"2017-12-23T12:23:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/12\\\/23\\\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/12\\\/23\\\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/12\\\/23\\\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2017\\\/12\\\/carabinieri-582.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2017\\\/12\\\/carabinieri-582.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/12\\\/23\\\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mirabella Eclano (AV) &#8211; Produzione e detenzione ai fini di spaccio di sostanze stupefacente: 4 persone arrestate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/\",\"name\":\"Portale dei Carabinieri\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mirabella Eclano (AV) - Produzione e detenzione ai fini di spaccio di sostanze stupefacente: 4 persone arrestate - Portale dei Carabinieri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/23\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\/","og_locale":"it_IT","og_type":"article","og_title":"Mirabella Eclano (AV) - Produzione e detenzione ai fini di spaccio di sostanze stupefacente: 4 persone arrestate - Portale dei Carabinieri","og_description":"Nella mattinata odierna i Carabinieri della Compagnia di Mirabella Eclano, hanno dato esecuzione nel Comune di Altavilla Irpina ad un\u2019ordinanza di applicazione di misura cautelare emessa dal G.I.P. presso il [&hellip;]","og_url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/23\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\/","og_site_name":"Portale dei Carabinieri","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-12-23T12:23:22+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2017\/12\/carabinieri-582.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/23\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/23\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Mirabella Eclano (AV) &#8211; Produzione e detenzione ai fini di spaccio di sostanze stupefacente: 4 persone arrestate","datePublished":"2017-12-23T12:23:22+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/23\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\/"},"wordCount":256,"image":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/23\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2017\/12\/carabinieri-582.jpg","articleSection":["Forze dell'Ordine"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/23\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\/","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/23\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\/","name":"Mirabella Eclano (AV) - Produzione e detenzione ai fini di spaccio di sostanze stupefacente: 4 persone arrestate - Portale dei Carabinieri","isPartOf":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/23\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/23\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2017\/12\/carabinieri-582.jpg","datePublished":"2017-12-23T12:23:22+00:00","author":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/23\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/23\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/23\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\/#primaryimage","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2017\/12\/carabinieri-582.jpg","contentUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2017\/12\/carabinieri-582.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/12\/23\/mirabella-eclano-av-produzione-e-detenzione-ai-fini-di-spaccio-di-sostanze-stupefacente-4-persone-arrestate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/"},{"@type":"ListItem","position":2,"name":"Mirabella Eclano (AV) &#8211; Produzione e detenzione ai fini di spaccio di sostanze stupefacente: 4 persone arrestate"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#website","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/","name":"Portale dei Carabinieri","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts\/10652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/comments?post=10652"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts\/10652\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/media\/10653"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/media?parent=10652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/categories?post=10652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/tags?post=10652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}