{"id":11380,"date":"2018-02-08T11:31:55","date_gmt":"2018-02-08T10:31:55","guid":{"rendered":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2018\/02\/08\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\/"},"modified":"2018-02-08T11:31:55","modified_gmt":"2018-02-08T10:31:55","slug":"territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2018\/02\/08\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\/","title":{"rendered":"Territorio Nazionale &#8211; Cibo sicuro nel settore agroalimentare"},"content":{"rendered":"<p>Controlli a largo raggio, \u00a0dei militari del comando carabinieri politiche agricole e alimentari\u2013 reparti carabinieri tutela agroalimentare torino e salerno &#8211; finalizzati al contrasto delle illegalit\u00e0 nel comparto agroalimentare, \u00a0a tutela del consumatore e degli operatori di settore<br \/>\nA seguito di controlli finalizzati al contrasto delle illegalit\u00e0 nel comparto agroalimentare, militari dei\u00a0 reparti speciali di Torino e Salerno\u00a0 conseguivano i seguenti risultati:<\/p>\n<p>    \u00b7nel settore della macellazione e\u00a0 della lavorazione delle carni, all\u2019interno di salumifici e aziende agricole, in provincia di Biella e Cuneo, \u00a0riscontravano irregolarit\u00e0 amministrative, per 10.000 euro, riconducibili alla mancanza di autorizzazioni da parte dei consorzi di tutela;<br \/>\n    in provincia di Caserta \u00a0e Salerno, sequestrati 5 quintali di prodotti ortofrutticoli e 4.950 uova per carenza di elementi utili per risalire alla provenienza del prodotto;<br \/>\n    Inoltre, sequestrate:<\/p>\n<p>    in provincia di Napoli , 4.560 bottiglie contenenti aperitivi alcolici, per complessivi 1.254 litri, con etichette esclusivamente in lingua polacca e, quindi, per la mancanza d\u2019informazioni a tutela del consumatore;<br \/>\n    ad Amalfi (SA), sequestrate 1.774 bottiglie contenenti limoncello e 346 vasi di bab\u00e0 in liquore di limone, per 520 litri complessivi, con etichette riportanti indebitamente evocazione ai limoni della Costa d\u2019Amalfi IGP mentre, in realt\u00e0, erano stati utilizzato limoni comuni.<\/p>\n<p>Venivano contestate sanzioni per circa 11.000 euro.<br \/>\nProsegue l\u2019attivit\u00e0 preventiva dell\u2019Arma a salvaguardia della sicurezza degli italiani.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Controlli a largo raggio, \u00a0dei militari del comando carabinieri politiche agricole e alimentari\u2013 reparti carabinieri tutela agroalimentare torino e salerno &#8211; finalizzati al contrasto delle illegalit\u00e0 nel comparto agroalimentare, \u00a0a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11381,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-11380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forze-dell-ordine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Territorio Nazionale - Cibo sicuro nel settore agroalimentare - Portale dei Carabinieri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2018\/02\/08\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Territorio Nazionale - Cibo sicuro nel settore agroalimentare - Portale dei Carabinieri\" \/>\n<meta property=\"og:description\" content=\"Controlli a largo raggio, \u00a0dei militari del comando carabinieri politiche agricole e alimentari\u2013 reparti carabinieri tutela agroalimentare torino e salerno &#8211; finalizzati al contrasto delle illegalit\u00e0 nel comparto agroalimentare, \u00a0a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2018\/02\/08\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\/\" \/>\n<meta property=\"og:site_name\" content=\"Portale dei Carabinieri\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-08T10:31:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2018\/02\/carabinieri-57.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2018\\\/02\\\/08\\\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2018\\\/02\\\/08\\\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Territorio Nazionale &#8211; Cibo sicuro nel settore agroalimentare\",\"datePublished\":\"2018-02-08T10:31:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2018\\\/02\\\/08\\\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\\\/\"},\"wordCount\":218,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2018\\\/02\\\/08\\\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2018\\\/02\\\/carabinieri-57.jpg\",\"articleSection\":[\"Forze dell'Ordine\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2018\\\/02\\\/08\\\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2018\\\/02\\\/08\\\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\\\/\",\"name\":\"Territorio Nazionale - Cibo sicuro nel settore agroalimentare - Portale dei Carabinieri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2018\\\/02\\\/08\\\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2018\\\/02\\\/08\\\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2018\\\/02\\\/carabinieri-57.jpg\",\"datePublished\":\"2018-02-08T10:31:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2018\\\/02\\\/08\\\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2018\\\/02\\\/08\\\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2018\\\/02\\\/08\\\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2018\\\/02\\\/carabinieri-57.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2018\\\/02\\\/carabinieri-57.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2018\\\/02\\\/08\\\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Territorio Nazionale &#8211; Cibo sicuro nel settore agroalimentare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/\",\"name\":\"Portale dei Carabinieri\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Territorio Nazionale - Cibo sicuro nel settore agroalimentare - Portale dei Carabinieri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2018\/02\/08\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\/","og_locale":"it_IT","og_type":"article","og_title":"Territorio Nazionale - Cibo sicuro nel settore agroalimentare - Portale dei Carabinieri","og_description":"Controlli a largo raggio, \u00a0dei militari del comando carabinieri politiche agricole e alimentari\u2013 reparti carabinieri tutela agroalimentare torino e salerno &#8211; finalizzati al contrasto delle illegalit\u00e0 nel comparto agroalimentare, \u00a0a [&hellip;]","og_url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2018\/02\/08\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\/","og_site_name":"Portale dei Carabinieri","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-02-08T10:31:55+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2018\/02\/carabinieri-57.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2018\/02\/08\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2018\/02\/08\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Territorio Nazionale &#8211; Cibo sicuro nel settore agroalimentare","datePublished":"2018-02-08T10:31:55+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2018\/02\/08\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\/"},"wordCount":218,"image":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2018\/02\/08\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2018\/02\/carabinieri-57.jpg","articleSection":["Forze dell'Ordine"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2018\/02\/08\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\/","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2018\/02\/08\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\/","name":"Territorio Nazionale - Cibo sicuro nel settore agroalimentare - Portale dei Carabinieri","isPartOf":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2018\/02\/08\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2018\/02\/08\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2018\/02\/carabinieri-57.jpg","datePublished":"2018-02-08T10:31:55+00:00","author":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2018\/02\/08\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/portale-dei-carabinieri\/2018\/02\/08\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2018\/02\/08\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\/#primaryimage","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2018\/02\/carabinieri-57.jpg","contentUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2018\/02\/carabinieri-57.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2018\/02\/08\/territorio-nazionale-cibo-sicuro-nel-settore-agroalimentare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/"},{"@type":"ListItem","position":2,"name":"Territorio Nazionale &#8211; Cibo sicuro nel settore agroalimentare"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#website","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/","name":"Portale dei Carabinieri","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts\/11380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/comments?post=11380"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts\/11380\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/media\/11381"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/media?parent=11380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/categories?post=11380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/tags?post=11380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}