{"id":4021,"date":"2016-11-06T12:00:01","date_gmt":"2016-11-06T11:00:01","guid":{"rendered":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/?p=4021"},"modified":"2016-11-06T12:00:01","modified_gmt":"2016-11-06T11:00:01","slug":"roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/06\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\/","title":{"rendered":"Roma (RM) &#8211; Minaccia giovane con un coltella e lo rapina del tablet e cellulare"},"content":{"rendered":"<p>Aveva da poco rapinato un 13enne romano di un tablet e di un telefono cellulare dopo averlo minacciato con un coltello mentre stava rientrando nella sua abitazione.<br \/>\nIl malvivente, un cittadino albanese di 19 anni, nella Capitale senza fissa dimora e con precedenti, si stava allontanando con il bottino quando \u00e8 incappato in una pattuglia dei Carabinieri della Stazione Roma Montespaccato in via Cardinale Domenica Capranica, a Torrevecchia.<br \/>\nA quel punto il 19enne ha tentato di disfarsi della refurtiva e di eludere il controllo, ma \u00e8 stato notato dai militari che lo hanno immediatamente bloccato.<br \/>\nRintracciata la vittima della rapina, che ha raccontato quanto accaduto pochi istanti prima, i Carabinieri hanno fatto scattare le manette ai polsi del cittadino albanese, portandolo in caserma in attesa del rito direttissimo: dovr\u00e0 rispondere dell\u2019accusa di rapina aggravata.<br \/>\nIl tablet e il telefono sono stati restituiti al 13enne.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aveva da poco rapinato un 13enne romano di un tablet e di un telefono cellulare dopo averlo minacciato con un coltello mentre stava rientrando nella sua abitazione. Il malvivente, un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-4021","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forze-dell-ordine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Roma (RM) - Minaccia giovane con un coltella e lo rapina del tablet e cellulare - Portale dei Carabinieri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/06\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roma (RM) - Minaccia giovane con un coltella e lo rapina del tablet e cellulare - Portale dei Carabinieri\" \/>\n<meta property=\"og:description\" content=\"Aveva da poco rapinato un 13enne romano di un tablet e di un telefono cellulare dopo averlo minacciato con un coltello mentre stava rientrando nella sua abitazione. Il malvivente, un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/06\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\/\" \/>\n<meta property=\"og:site_name\" content=\"Portale dei Carabinieri\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-06T11:00:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/06\\\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/06\\\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Roma (RM) &#8211; Minaccia giovane con un coltella e lo rapina del tablet e cellulare\",\"datePublished\":\"2016-11-06T11:00:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/06\\\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\\\/\"},\"wordCount\":157,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/06\\\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2015\\\/09\\\/carabinieri.jpg\",\"articleSection\":[\"Forze dell'Ordine\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/06\\\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/06\\\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\\\/\",\"name\":\"Roma (RM) - Minaccia giovane con un coltella e lo rapina del tablet e cellulare - Portale dei Carabinieri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/06\\\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/06\\\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2015\\\/09\\\/carabinieri.jpg\",\"datePublished\":\"2016-11-06T11:00:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/06\\\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/06\\\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/06\\\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2015\\\/09\\\/carabinieri.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2015\\\/09\\\/carabinieri.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/06\\\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Roma (RM) &#8211; Minaccia giovane con un coltella e lo rapina del tablet e cellulare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/\",\"name\":\"Portale dei Carabinieri\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Roma (RM) - Minaccia giovane con un coltella e lo rapina del tablet e cellulare - Portale dei Carabinieri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/06\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\/","og_locale":"it_IT","og_type":"article","og_title":"Roma (RM) - Minaccia giovane con un coltella e lo rapina del tablet e cellulare - Portale dei Carabinieri","og_description":"Aveva da poco rapinato un 13enne romano di un tablet e di un telefono cellulare dopo averlo minacciato con un coltello mentre stava rientrando nella sua abitazione. Il malvivente, un [&hellip;]","og_url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/06\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\/","og_site_name":"Portale dei Carabinieri","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2016-11-06T11:00:01+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/06\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/06\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Roma (RM) &#8211; Minaccia giovane con un coltella e lo rapina del tablet e cellulare","datePublished":"2016-11-06T11:00:01+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/06\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\/"},"wordCount":157,"image":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/06\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","articleSection":["Forze dell'Ordine"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/06\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\/","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/06\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\/","name":"Roma (RM) - Minaccia giovane con un coltella e lo rapina del tablet e cellulare - Portale dei Carabinieri","isPartOf":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/06\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/06\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","datePublished":"2016-11-06T11:00:01+00:00","author":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/06\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/06\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/06\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\/#primaryimage","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","contentUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/06\/roma-rm-minaccia-giovane-con-un-coltella-e-lo-rapina-del-tablet-e-cellulare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/"},{"@type":"ListItem","position":2,"name":"Roma (RM) &#8211; Minaccia giovane con un coltella e lo rapina del tablet e cellulare"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#website","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/","name":"Portale dei Carabinieri","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts\/4021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/comments?post=4021"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts\/4021\/revisions"}],"predecessor-version":[{"id":4022,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts\/4021\/revisions\/4022"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/media\/3"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/media?parent=4021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/categories?post=4021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/tags?post=4021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}