{"id":4365,"date":"2016-11-23T15:00:00","date_gmt":"2016-11-23T14:00:00","guid":{"rendered":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/?p=4365"},"modified":"2016-11-23T15:00:00","modified_gmt":"2016-11-23T14:00:00","slug":"lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/23\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\/","title":{"rendered":"Lavello (PZ) &#8211; Tre persone denunciate in stato di libert\u00e0 per violazione delle norme in materia di tutela dei diritti d\u2019autore."},"content":{"rendered":"<p>Prosegue, senza soluzione di continuit\u00e0, l\u2019attivit\u00e0 di prevenzione e repressione posta in essere dai Carabinieri della Compagnia di Venosa (PZ) che, nella giornata di ieri, hanno deferito in stato di libert\u00e0, alla competente Autorit\u00e0 Giudiziaria, tre persone per violazione della Legge 633\/1941 in materia di tutela del diritto d\u2019autore. Infatti, nel corso di mirati servizi di controllo svolti presso tre note attivit\u00e0 commerciali\/ricreative del posto, i militari della Stazione Carabinieri di Lavello, coadiuvati da Ispettori della societ\u00e0 \u201cMediaset Premium S.p.a.\u201d, constatavano l\u2019indebita trasmissione al pubblico, a scopo di lucro, di programmi televisivi criptati, mediante l\u2019utilizzo di tre schede di decodificazione intestate ad altrettante persone, ma riservate contrattualmente ad un uso esclusivamente privato. Pertanto, alla luce di quanto appurato e viste le loro oggettive responsabilit\u00e0 penali in relazione ai reati commessi, gli intestatari delle schede nonch\u00e9 titolari delle attivit\u00e0 in questione venivano denunciati in stato di libert\u00e0, alla Procura della Repubblica di Potenza, per violazione del diritto d\u2019autore e di altri diritti connessi al suo esercizio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prosegue, senza soluzione di continuit\u00e0, l\u2019attivit\u00e0 di prevenzione e repressione posta in essere dai Carabinieri della Compagnia di Venosa (PZ) che, nella giornata di ieri, hanno deferito in stato di [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-4365","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forze-dell-ordine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lavello (PZ) - Tre persone denunciate in stato di libert\u00e0 per violazione delle norme in materia di tutela dei diritti d\u2019autore. - Portale dei Carabinieri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/23\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lavello (PZ) - Tre persone denunciate in stato di libert\u00e0 per violazione delle norme in materia di tutela dei diritti d\u2019autore. - Portale dei Carabinieri\" \/>\n<meta property=\"og:description\" content=\"Prosegue, senza soluzione di continuit\u00e0, l\u2019attivit\u00e0 di prevenzione e repressione posta in essere dai Carabinieri della Compagnia di Venosa (PZ) che, nella giornata di ieri, hanno deferito in stato di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/23\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\/\" \/>\n<meta property=\"og:site_name\" content=\"Portale dei Carabinieri\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-23T14:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/23\\\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/23\\\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Lavello (PZ) &#8211; Tre persone denunciate in stato di libert\u00e0 per violazione delle norme in materia di tutela dei diritti d\u2019autore.\",\"datePublished\":\"2016-11-23T14:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/23\\\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\\\/\"},\"wordCount\":194,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/23\\\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2015\\\/09\\\/carabinieri.jpg\",\"articleSection\":[\"Forze dell'Ordine\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/23\\\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/23\\\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\\\/\",\"name\":\"Lavello (PZ) - Tre persone denunciate in stato di libert\u00e0 per violazione delle norme in materia di tutela dei diritti d\u2019autore. - Portale dei Carabinieri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/23\\\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/23\\\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2015\\\/09\\\/carabinieri.jpg\",\"datePublished\":\"2016-11-23T14:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/23\\\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/23\\\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/23\\\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2015\\\/09\\\/carabinieri.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2015\\\/09\\\/carabinieri.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/23\\\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lavello (PZ) &#8211; Tre persone denunciate in stato di libert\u00e0 per violazione delle norme in materia di tutela dei diritti d\u2019autore.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/\",\"name\":\"Portale dei Carabinieri\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lavello (PZ) - Tre persone denunciate in stato di libert\u00e0 per violazione delle norme in materia di tutela dei diritti d\u2019autore. - Portale dei Carabinieri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/23\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\/","og_locale":"it_IT","og_type":"article","og_title":"Lavello (PZ) - Tre persone denunciate in stato di libert\u00e0 per violazione delle norme in materia di tutela dei diritti d\u2019autore. - Portale dei Carabinieri","og_description":"Prosegue, senza soluzione di continuit\u00e0, l\u2019attivit\u00e0 di prevenzione e repressione posta in essere dai Carabinieri della Compagnia di Venosa (PZ) che, nella giornata di ieri, hanno deferito in stato di [&hellip;]","og_url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/23\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\/","og_site_name":"Portale dei Carabinieri","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2016-11-23T14:00:00+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/23\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/23\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Lavello (PZ) &#8211; Tre persone denunciate in stato di libert\u00e0 per violazione delle norme in materia di tutela dei diritti d\u2019autore.","datePublished":"2016-11-23T14:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/23\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\/"},"wordCount":194,"image":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/23\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","articleSection":["Forze dell'Ordine"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/23\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\/","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/23\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\/","name":"Lavello (PZ) - Tre persone denunciate in stato di libert\u00e0 per violazione delle norme in materia di tutela dei diritti d\u2019autore. - Portale dei Carabinieri","isPartOf":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/23\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/23\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","datePublished":"2016-11-23T14:00:00+00:00","author":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/23\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/23\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/23\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\/#primaryimage","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","contentUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/23\/lavello-pz-tre-persone-denunciate-in-stato-di-liberta-per-violazione-delle-norme-in-materia-di-tutela-dei-diritti-dautore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/"},{"@type":"ListItem","position":2,"name":"Lavello (PZ) &#8211; Tre persone denunciate in stato di libert\u00e0 per violazione delle norme in materia di tutela dei diritti d\u2019autore."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#website","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/","name":"Portale dei Carabinieri","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts\/4365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/comments?post=4365"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts\/4365\/revisions"}],"predecessor-version":[{"id":4366,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts\/4365\/revisions\/4366"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/media\/3"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/media?parent=4365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/categories?post=4365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/tags?post=4365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}