{"id":4425,"date":"2016-11-30T11:30:00","date_gmt":"2016-11-30T10:30:00","guid":{"rendered":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/?p=4425"},"modified":"2016-11-30T11:30:00","modified_gmt":"2016-11-30T10:30:00","slug":"roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/30\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\/","title":{"rendered":"Roma (RM) &#8211; Sequestrati 58 tonnellate di alimenti etnici irregolari"},"content":{"rendered":"<p>In occasione del Giubileo della Misericordia e dell\u2019afflusso di pellegrini di varie aree geografiche nazionali ed internazionali, i Carabinieri del NAS hanno eseguito mirate verifiche alla filiera commerciale alimentare. Secondo programmate strategie di monitoraggio, oltre agli esercizi di vendita al minuto, sono stati eseguiti controlli anche ai magazzini della societ\u00e0 distributrici dedite all\u2019importazione all\u2019ingrosso di materie prime, in particolare destinate, tra l\u2019altro, a ristoranti e negozi etnici della Capitale. Nel corso delle operazioni, il NAS di Roma ha individuato ed ispezionato tre depositi appartenenti ad altrettanti operatori commerciali di vendita all\u2019ingrosso di prodotti extra U.E. situati nell\u2019aree della Capitale.<br \/>\nIn particolare, il pi\u00f9 recente intervento dei Carabinieri del NAS ha consentito di individuare un magazzino abusivo di 500 mq in zona Ardeatina ed eseguire il sequestro penale di 48 tonnellate di alimenti presenti all\u2019interno. Le derrate alimentare (riso, spezie, condimenti e conserve vegetali) erano detenute in cattivo stato di conservazione in quanto poste in ambienti malsani, con infiltrazioni di acqua piovana, presenza di umidit\u00e0 e muffe alle pareti e nella pavimentazione. Inoltre \u00e8 stata riscontrata la presenza di ratti e relative tracce a contatto con le confezioni, la cui presenza aveva determinato anche episodi di foratura degli imballaggi, specie nei sacchi contenenti riso, facilmente aggrediti dai roditori. La potenziale pericolosit\u00e0 insita nelle modalit\u00e0 di stoccaggio, oltre a richiedere l\u2019immediato sequestro degli alimenti, ha determinato il denuncia dell\u2019Autorit\u00e0 giudiziaria dei due titolari della ditta, di origine bengalese. I prodotti, che risultavano regolarmente importati da India, Pakistan e Bangladesh, sarebbero stati destinati principalmente ai negozi etnici della Capitale e della provincia di Roma. Gi\u00e0 in precedenti interventi il NAS di Roma aveva individuato ulteriori due depositi contenenti alimenti irregolari ed operato il sequestro complessivo di circa 1.000 kg di derrate. In un caso il sito controllato, ubicato nel quartiere Esquilino e riconducibile ad un\u2019impresa diretta da un cittadino cinese, deteneva alimenti di origine animale (prodotti a base di carne suina e avicola, uova cent\u2019anni, salumi e latte) importati illecitamente dalla Cina in violazione delle disposizioni comunitarie e nazionali di profilassi sanitaria.<br \/>\nIn un altro magazzino, situato in zona industriale della Prenestina, sono stati sequestrati 750 kg di alimenti (condimenti, olive in salamoia, prodotti caseari, succhi di frutta) riscontrati dai militari in cattivo stato di conservazione. Infatti i prodotti, sebbene importati regolarmente dall\u2019Egitto, presentavano confezioni lacerate e contenuto interno intaccato da muffe, mentre i formaggi e altri alimenti deperibili erano conservati a temperatura ambiente anzich\u00e9 refrigerata come previsto. Anche in questa occasione il gestore dell\u2019azienda \u00e8 stato denunciato alla Procura della Repubblica di Roma.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In occasione del Giubileo della Misericordia e dell\u2019afflusso di pellegrini di varie aree geografiche nazionali ed internazionali, i Carabinieri del NAS hanno eseguito mirate verifiche alla filiera commerciale alimentare. Secondo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-4425","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forze-dell-ordine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Roma (RM) - Sequestrati 58 tonnellate di alimenti etnici irregolari - Portale dei Carabinieri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/30\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roma (RM) - Sequestrati 58 tonnellate di alimenti etnici irregolari - Portale dei Carabinieri\" \/>\n<meta property=\"og:description\" content=\"In occasione del Giubileo della Misericordia e dell\u2019afflusso di pellegrini di varie aree geografiche nazionali ed internazionali, i Carabinieri del NAS hanno eseguito mirate verifiche alla filiera commerciale alimentare. Secondo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/30\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\/\" \/>\n<meta property=\"og:site_name\" content=\"Portale dei Carabinieri\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-30T10:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/30\\\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/30\\\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Roma (RM) &#8211; Sequestrati 58 tonnellate di alimenti etnici irregolari\",\"datePublished\":\"2016-11-30T10:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/30\\\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\\\/\"},\"wordCount\":438,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/30\\\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2015\\\/09\\\/carabinieri.jpg\",\"articleSection\":[\"Forze dell'Ordine\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/30\\\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/30\\\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\\\/\",\"name\":\"Roma (RM) - Sequestrati 58 tonnellate di alimenti etnici irregolari - Portale dei Carabinieri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/30\\\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/30\\\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2015\\\/09\\\/carabinieri.jpg\",\"datePublished\":\"2016-11-30T10:30:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/30\\\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/30\\\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/30\\\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2015\\\/09\\\/carabinieri.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2015\\\/09\\\/carabinieri.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2016\\\/11\\\/30\\\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Roma (RM) &#8211; Sequestrati 58 tonnellate di alimenti etnici irregolari\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/\",\"name\":\"Portale dei Carabinieri\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Roma (RM) - Sequestrati 58 tonnellate di alimenti etnici irregolari - Portale dei Carabinieri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/30\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\/","og_locale":"it_IT","og_type":"article","og_title":"Roma (RM) - Sequestrati 58 tonnellate di alimenti etnici irregolari - Portale dei Carabinieri","og_description":"In occasione del Giubileo della Misericordia e dell\u2019afflusso di pellegrini di varie aree geografiche nazionali ed internazionali, i Carabinieri del NAS hanno eseguito mirate verifiche alla filiera commerciale alimentare. Secondo [&hellip;]","og_url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/30\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\/","og_site_name":"Portale dei Carabinieri","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2016-11-30T10:30:00+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/30\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/30\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Roma (RM) &#8211; Sequestrati 58 tonnellate di alimenti etnici irregolari","datePublished":"2016-11-30T10:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/30\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\/"},"wordCount":438,"image":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/30\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","articleSection":["Forze dell'Ordine"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/30\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\/","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/30\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\/","name":"Roma (RM) - Sequestrati 58 tonnellate di alimenti etnici irregolari - Portale dei Carabinieri","isPartOf":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/30\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/30\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","datePublished":"2016-11-30T10:30:00+00:00","author":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/30\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/30\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/30\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\/#primaryimage","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","contentUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2016\/11\/30\/roma-rm-sequestrati-58-tonnellate-di-alimenti-etnici-irregolari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/"},{"@type":"ListItem","position":2,"name":"Roma (RM) &#8211; Sequestrati 58 tonnellate di alimenti etnici irregolari"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#website","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/","name":"Portale dei Carabinieri","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts\/4425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/comments?post=4425"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts\/4425\/revisions"}],"predecessor-version":[{"id":4426,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts\/4425\/revisions\/4426"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/media\/3"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/media?parent=4425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/categories?post=4425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/tags?post=4425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}